{"id":27716,"date":"2012-06-25T14:06:08","date_gmt":"2012-06-25T12:06:08","guid":{"rendered":"http:\/\/www.article-marketing.eu\/comunicati\/senza-categoria\/riparti-con-eni-ogni-week-end-eni-riduce-eccezionalmente-i-prezzi-dei-carburanti-per-lestate-degli-italiani-2\/"},"modified":"2012-06-25T14:06:08","modified_gmt":"2012-06-25T12:06:08","slug":"riparti-con-eni-ogni-week-end-eni-riduce-eccezionalmente-i-prezzi-dei-carburanti-per-lestate-degli-italiani-2","status":"publish","type":"post","link":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/riparti-con-eni-ogni-week-end-eni-riduce-eccezionalmente-i-prezzi-dei-carburanti-per-lestate-degli-italiani-2\/","title":{"rendered":"Riparti con Eni: ogni week end Eni riduce eccezionalmente i prezzi dei carburanti per l&#8217;estate degli italiani"},"content":{"rendered":"<p>&#8220;Riparti con Eni &#8221; &#8211; La riduzione del prezzo corrisponder&agrave; indicativamente a uno sconto di circa 20 centesimi al litro rispetto al prezzo praticato in modalit&agrave; servito, equivalente ad un risparmio di 10 euro su un pieno da 50 litri.<br \/>Roma, 14 giugno 2012 &ndash; Eni lancia un&#8217;iniziativa straordinaria: dal 16 giugno al 2 settembre, durante il week end, ridurr&agrave; eccezionalmente il prezzo della benzina e del gasolio per tutti i consumatori che faranno rifornimento in modalit&agrave; iperself (ovvero in maniera autonoma) dopo aver effettuato il pagamento mediante gli appositi accettatori di banconote e bancomat. Si tratta di un&#8217;iniziativa unica che rappresenta un segnale forte di vicinanza ai cittadini, e in particolare alle famiglie italiane, da parte della prima azienda petrolifera del Paese.<br \/>La riduzione del prezzo corrisponder&agrave; indicativamente a uno sconto di circa 20 centesimi al litro rispetto al prezzo praticato in modalit&agrave; servito, equivalente ad un risparmio di 10 euro su un pieno da 50 litri. Lo sconto per litro sar&agrave; pari a circa due volte lo sconto massimo finora praticato dalle stazioni no logo e dalla grande distribuzione.<br \/>Lo sconto sar&agrave; disponibile su circa 3.000 stazioni Eni ed Agip, capillarmente diffuse in tutto il territorio italiano, dal sabato alle ore 13 alla mezzanotte della domenica, fino ad esaurimento delle scorte in ciascuna stazione aderente. Per limitare al massimo l&#8217;eventualit&agrave; che gli impianti possano interrompere le vendite nel corso del week end a causa dell&#8217;esaurimento del prodotto, Eni in via eccezionale li rifornir&agrave; anche nel corso della giornata di domenica.<br \/>Allo scopo di facilitare la comunicazione dell&#8217;offerta in maniera trasparente, ogni settimana Eni determiner&agrave;, in base all&#8217;andamento delle quotazioni Platts, due prezzi &ndash; uno per la benzina e l&#8217;altro per il gasolio &ndash; uguali su tutto il territorio nazionale durante gli orari della promozione e validi per le stazioni aderenti ad iperself. I listini dei prezzi continueranno ad essere diversificati per ogni stazione di servizio nel resto della settimana.<br \/>Nel corso dell&#8217;iniziativa, Eni vender&agrave; eccezionalmente al di sotto dei propri costi, investendo sul rapporto con i consumatori italiani, con l&#8217;obiettivo di fornire al Paese un contributo concreto per &#8220;ripartire insieme&#8221;.<br \/>Inoltre, sempre in occasione dei week end interessati da questa operazione, gli eni caf&eacute; rimarranno aperti sino alle ore 24 con un&#8217;offerta di qualit&agrave; a prezzi speciali (colazione a 1,50 euro; pranzo a 5 euro) e promozioni anche su bibite e gelati da asporto.<br \/>&nbsp;<br \/>La modalit&agrave; iperself:<br \/>Iperself, a 5 anni dal suo lancio, &egrave; ormai una consolidata modalit&agrave; di rifornimento di reale convenienza per i consumatori italiani che vogliono risparmiare senza rinunciare alla qualit&agrave; dei carburanti Eni. Oggi circa un terzo dei volumi della rete eni &egrave; acquistato in modalit&agrave; iperself, a testimonianza che una parte importante degli italiani &egrave; disposta a fare rifornimento in completo self service a fronte di un risparmio importante.<br \/>Dallo scorso marzo, Eni ha deciso di estendere l&#8217;offerta iperself dal solo orario di chiusura delle stazioni aderenti alle 24 ore della giornata, sette giorni su sette. I clienti che scelgono di rifornirsi in modalit&agrave; self service, con pagamento mediante accettatore di banconote e bancomat, non possono accumulare punti sulla carta fedelt&agrave; you&amp;eni, ma risparmiano anche nell&#8217;orario di apertura della stazione con uno sconto fino a 10 cents\/litro (sconto rispetto al prezzo praticato sul servito) durante la settimana.<br \/>Anticipando la prevista evoluzione della normativa e rispondendo alla richiesta delle associazioni dei consumatori, nelle stazioni di servizio Eni &egrave; pubblicizzato direttamente il prezzo iperself, senza evidenza dei centesimi di sconto rispetto al prezzo servito. Gli accettatori di banconote collegati agli erogatori iperself sono abilitati anche per il pagamento con bancomat, senza alcuna commissione per il cliente e in tutta comodit&agrave; e sicurezza: basta digitare il pin del bancomat e fare rifornimento senza preselezionare l&#8217;importo. Al&nbsp; termine dell&#8217;erogazione, l&#8217;accettatore rilascia una ricevuta con l&#8217;importo acquistato e senza addebito di alcuna commissione al cliente.&nbsp; <br \/>Con l&#8217;incentivazione del self service, Eni intende promuovere la modalit&agrave; di rifornimento pi&ugrave; diffusa negli altri paesi europei per contenere i costi di distribuzione e quindi anche i prezzi al consumo.<br \/>www.riparticoneni.com<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;Riparti con Eni &#8221; &#8211; La riduzione del prezzo corrisponder&agrave; indicativamente a uno sconto di circa 20 centesimi al litro rispetto al prezzo praticato in modalit&agrave; servito, equivalente ad un risparmio di 10 euro su un pieno da 50 litri.Roma, 14 giugno 2012 &ndash; Eni lancia un&#8217;iniziativa straordinaria: dal 16 giugno al 2 settembre, durante il week end, ridurr&agrave; eccezionalmente il prezzo della benzina e del gasolio per tutti i<\/p>\n<p><a class=\"continue-reading\" href=\"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/riparti-con-eni-ogni-week-end-eni-riduce-eccezionalmente-i-prezzi-dei-carburanti-per-lestate-degli-italiani-2\/\">Continue reading&#8230;<\/a><\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"","footnotes":""},"categories":[190],"tags":[36831],"class_list":["post-27716","post","type-post","status-publish","format-standard","hentry","category-comunicati-stampa","tag-riparti-con-eni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Riparti con Eni: ogni week end Eni riduce eccezionalmente i prezzi dei carburanti per l&#039;estate degli italiani - Article Marketing<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/riparti-con-eni-ogni-week-end-eni-riduce-eccezionalmente-i-prezzi-dei-carburanti-per-lestate-degli-italiani-2\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Riparti con Eni: ogni week end Eni riduce eccezionalmente i prezzi dei carburanti per l&#039;estate degli italiani - Article Marketing\" \/>\n<meta property=\"og:description\" content=\"&#8220;Riparti con Eni &#8221; &#8211; La riduzione del prezzo corrisponder&agrave; indicativamente a uno sconto di circa 20 centesimi al litro rispetto al prezzo praticato in modalit&agrave; servito, equivalente ad un risparmio di 10 euro su un pieno da 50 litri.Roma, 14 giugno 2012 &ndash; Eni lancia un&#8217;iniziativa straordinaria: dal 16 giugno al 2 settembre, durante il week end, ridurr&agrave; eccezionalmente il prezzo della benzina e del gasolio per tutti iContinue reading...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/riparti-con-eni-ogni-week-end-eni-riduce-eccezionalmente-i-prezzi-dei-carburanti-per-lestate-degli-italiani-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Article Marketing\" \/>\n<meta property=\"article:published_time\" content=\"2012-06-25T12:06:08+00:00\" \/>\n<meta name=\"author\" content=\"Redazione Comunicati Stampa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione Comunicati Stampa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/riparti-con-eni-ogni-week-end-eni-riduce-eccezionalmente-i-prezzi-dei-carburanti-per-lestate-degli-italiani-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/riparti-con-eni-ogni-week-end-eni-riduce-eccezionalmente-i-prezzi-dei-carburanti-per-lestate-degli-italiani-2\\\/\"},\"author\":{\"name\":\"Redazione Comunicati Stampa\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"headline\":\"Riparti con Eni: ogni week end Eni riduce eccezionalmente i prezzi dei carburanti per l&#8217;estate degli italiani\",\"datePublished\":\"2012-06-25T12:06:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/riparti-con-eni-ogni-week-end-eni-riduce-eccezionalmente-i-prezzi-dei-carburanti-per-lestate-degli-italiani-2\\\/\"},\"wordCount\":699,\"commentCount\":0,\"keywords\":[\"riparti con eni\"],\"articleSection\":[\"Comunicati stampa\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/riparti-con-eni-ogni-week-end-eni-riduce-eccezionalmente-i-prezzi-dei-carburanti-per-lestate-degli-italiani-2\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/riparti-con-eni-ogni-week-end-eni-riduce-eccezionalmente-i-prezzi-dei-carburanti-per-lestate-degli-italiani-2\\\/\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/riparti-con-eni-ogni-week-end-eni-riduce-eccezionalmente-i-prezzi-dei-carburanti-per-lestate-degli-italiani-2\\\/\",\"name\":\"Riparti con Eni: ogni week end Eni riduce eccezionalmente i prezzi dei carburanti per l'estate degli italiani - Article Marketing\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\"},\"datePublished\":\"2012-06-25T12:06:08+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/riparti-con-eni-ogni-week-end-eni-riduce-eccezionalmente-i-prezzi-dei-carburanti-per-lestate-degli-italiani-2\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/riparti-con-eni-ogni-week-end-eni-riduce-eccezionalmente-i-prezzi-dei-carburanti-per-lestate-degli-italiani-2\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/riparti-con-eni-ogni-week-end-eni-riduce-eccezionalmente-i-prezzi-dei-carburanti-per-lestate-degli-italiani-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Riparti con Eni: ogni week end Eni riduce eccezionalmente i prezzi dei carburanti per l&#8217;estate degli italiani\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\",\"name\":\"Article Marketing\",\"description\":\"article marketing &amp; press release\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\",\"name\":\"Redazione Comunicati Stampa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"caption\":\"Redazione Comunicati Stampa\"},\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/author\\\/redazione-comunicati-stampa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Riparti con Eni: ogni week end Eni riduce eccezionalmente i prezzi dei carburanti per l'estate degli italiani - Article Marketing","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/riparti-con-eni-ogni-week-end-eni-riduce-eccezionalmente-i-prezzi-dei-carburanti-per-lestate-degli-italiani-2\/","og_locale":"it_IT","og_type":"article","og_title":"Riparti con Eni: ogni week end Eni riduce eccezionalmente i prezzi dei carburanti per l'estate degli italiani - Article Marketing","og_description":"&#8220;Riparti con Eni &#8221; &#8211; La riduzione del prezzo corrisponder&agrave; indicativamente a uno sconto di circa 20 centesimi al litro rispetto al prezzo praticato in modalit&agrave; servito, equivalente ad un risparmio di 10 euro su un pieno da 50 litri.Roma, 14 giugno 2012 &ndash; Eni lancia un&#8217;iniziativa straordinaria: dal 16 giugno al 2 settembre, durante il week end, ridurr&agrave; eccezionalmente il prezzo della benzina e del gasolio per tutti iContinue reading...","og_url":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/riparti-con-eni-ogni-week-end-eni-riduce-eccezionalmente-i-prezzi-dei-carburanti-per-lestate-degli-italiani-2\/","og_site_name":"Article Marketing","article_published_time":"2012-06-25T12:06:08+00:00","author":"Redazione Comunicati Stampa","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione Comunicati Stampa","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/riparti-con-eni-ogni-week-end-eni-riduce-eccezionalmente-i-prezzi-dei-carburanti-per-lestate-degli-italiani-2\/#article","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/riparti-con-eni-ogni-week-end-eni-riduce-eccezionalmente-i-prezzi-dei-carburanti-per-lestate-degli-italiani-2\/"},"author":{"name":"Redazione Comunicati Stampa","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"headline":"Riparti con Eni: ogni week end Eni riduce eccezionalmente i prezzi dei carburanti per l&#8217;estate degli italiani","datePublished":"2012-06-25T12:06:08+00:00","mainEntityOfPage":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/riparti-con-eni-ogni-week-end-eni-riduce-eccezionalmente-i-prezzi-dei-carburanti-per-lestate-degli-italiani-2\/"},"wordCount":699,"commentCount":0,"keywords":["riparti con eni"],"articleSection":["Comunicati stampa"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/riparti-con-eni-ogni-week-end-eni-riduce-eccezionalmente-i-prezzi-dei-carburanti-per-lestate-degli-italiani-2\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/riparti-con-eni-ogni-week-end-eni-riduce-eccezionalmente-i-prezzi-dei-carburanti-per-lestate-degli-italiani-2\/","url":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/riparti-con-eni-ogni-week-end-eni-riduce-eccezionalmente-i-prezzi-dei-carburanti-per-lestate-degli-italiani-2\/","name":"Riparti con Eni: ogni week end Eni riduce eccezionalmente i prezzi dei carburanti per l'estate degli italiani - Article Marketing","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website"},"datePublished":"2012-06-25T12:06:08+00:00","author":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"breadcrumb":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/riparti-con-eni-ogni-week-end-eni-riduce-eccezionalmente-i-prezzi-dei-carburanti-per-lestate-degli-italiani-2\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/riparti-con-eni-ogni-week-end-eni-riduce-eccezionalmente-i-prezzi-dei-carburanti-per-lestate-degli-italiani-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/riparti-con-eni-ogni-week-end-eni-riduce-eccezionalmente-i-prezzi-dei-carburanti-per-lestate-degli-italiani-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.article-marketing.eu\/comunicati\/"},{"@type":"ListItem","position":2,"name":"Riparti con Eni: ogni week end Eni riduce eccezionalmente i prezzi dei carburanti per l&#8217;estate degli italiani"}]},{"@type":"WebSite","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website","url":"https:\/\/www.article-marketing.eu\/comunicati\/","name":"Article Marketing","description":"article marketing &amp; press release","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.article-marketing.eu\/comunicati\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017","name":"Redazione Comunicati Stampa","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","caption":"Redazione Comunicati Stampa"},"url":"https:\/\/www.article-marketing.eu\/comunicati\/author\/redazione-comunicati-stampa\/"}]}},"_links":{"self":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/27716","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/comments?post=27716"}],"version-history":[{"count":0,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/27716\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/media?parent=27716"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/categories?post=27716"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/tags?post=27716"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}