{"id":28085,"date":"2012-07-12T15:12:27","date_gmt":"2012-07-12T13:12:27","guid":{"rendered":"http:\/\/www.article-marketing.eu\/comunicati\/senza-categoria\/energia-pulita-dalle-autostrade\/"},"modified":"2012-07-12T15:12:27","modified_gmt":"2012-07-12T13:12:27","slug":"energia-pulita-dalle-autostrade","status":"publish","type":"post","link":"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/energia-pulita-dalle-autostrade\/","title":{"rendered":"Energia pulita dalle autostrade"},"content":{"rendered":"<p>A proposito di ricerca di fonti alternative di energia, non mancano le proposte originali, da parte di studenti e appassionati della materia.. Uno studente di architettura dell&rsquo;Arizona (Usa) ha trovato il modo di produrre energia pulita con un sistema eolico che sfrutta le turbolenze provocate dal passaggio dei veicoli in autostrada. Joe, questo il suo nome, ha osservato le auto sfrecciare sulle larghe autostrade americane, e ha stimato in 70 miglia orarie la media della loro velocit&agrave;. Sapendo che attualmente con 10 miglia orarie (del vento, ndr) si producono 9600 KwH all&rsquo;anno, immaginate quanta energia si potrebbe produrre con le auto che sfrecciano a tali velocit&agrave;. <br \/>Continua a leggere su Archilight:<a href=\"http:\/\/www.archilight.it\/GetPage.pub_do?id=8a8a8ac11d6719be011d6726ceaf0018&amp;_JPFORCEDINFO=8a8a8ac1180899dd011808d140ce0707\">http:\/\/www.archilight.it\/GetPage.pub_do?id=8a8a8ac11d6719be011d6726ceaf0018&amp;_JPFORCEDINFO=8a8a8ac1180899dd011808d140ce0707<\/a><\/p>\n<p>A proposito di ricerca di fonti alternative di energia, non mancano le proposte originali, da parte di studenti e appassionati della materia.. Uno studente di architettura dell&rsquo;Arizona (Usa) ha trovato il modo di produrre energia pulita con un sistema eolico che sfrutta le turbolenze provocate dal passaggio dei veicoli in autostrada. Joe, questo il suo nome, ha osservato le auto sfrecciare sulle larghe autostrade americane, e ha stimato in 70 miglia orarie la media della loro velocit&agrave;. Sapendo che attualmente con 10 miglia orarie (del vento, ndr) si producono 9600 KwH all&rsquo;anno, immaginate quanta energia si potrebbe produrre con le auto che sfrecciano a tali velocit&agrave;.<br \/>Continua a leggere su Archilight:http:\/\/www.archilight.it\/GetPage.pub_do?id=8a8a8ac11d6719be011d6726ceaf0018&amp;_JPFORCEDINFO=8a8a8ac1180899dd011808d140ce0707<\/p>\n<p>A proposito di ricerca di fonti alternative di energia, non mancano le proposte originali, da parte di studenti e appassionati della materia.. Uno studente di architettura dell&rsquo;Arizona (Usa) ha trovato il modo di produrre energia pulita con un sistema eolico che sfrutta le turbolenze provocate dal passaggio dei veicoli in autostrada. Joe, questo il suo nome, ha osservato le auto sfrecciare sulle larghe autostrade americane, e ha stimato in 70 miglia orarie la media della loro velocit&agrave;. Sapendo che attualmente con 10 miglia orarie (del vento, ndr) si producono 9600 KwH all&rsquo;anno, immaginate quanta energia si potrebbe produrre con le auto che sfrecciano a tali velocit&agrave;.<br \/>Continua a leggere su Archilight:http:\/\/www.archilight.it\/GetPage.pub_do?id=8a8a8ac11d6719be011d6726ceaf0018&amp;_JPFORCEDINFO=8a8a8ac1180899dd011808d140ce0707<\/p>\n<p>A proposito di ricerca di fonti alternative di energia, non mancano le proposte originali, da parte di studenti e appassionati della materia.. Uno studente di architettura dell&rsquo;Arizona (Usa) ha trovato il modo di produrre energia pulita con un sistema eolico che sfrutta le turbolenze provocate dal passaggio dei veicoli in autostrada. Joe, questo il suo nome, ha osservato le auto sfrecciare sulle larghe autostrade americane, e ha stimato in 70 miglia orarie la media della loro velocit&agrave;. Sapendo che attualmente con 10 miglia orarie (del vento, ndr) si producono 9600 KwH all&rsquo;anno, immaginate quanta energia si potrebbe produrre con le auto che sfrecciano a tali velocit&agrave;.<br \/>Continua a leggere su Archilight:http:\/\/www.archilight.it\/GetPage.pub_do?id=8a8a8ac11d6719be011d6726ceaf0018&amp;_JPFORCEDINFO=8a8a8ac1180899dd011808d140ce0707<\/p>\n<p>A proposito di ricerca di fonti alternative di energia, non mancano le proposte originali, da parte di studenti e appassionati della materia.. Uno studente di architettura dell&rsquo;Arizona (Usa) ha trovato il modo di produrre energia pulita con un sistema eolico che sfrutta le turbolenze provocate dal passaggio dei veicoli in autostrada. Joe, questo il suo nome, ha osservato le auto sfrecciare sulle larghe autostrade americane, e ha stimato in 70 miglia orarie la media della loro velocit&agrave;. Sapendo che attualmente con 10 miglia orarie (del vento, ndr) si producono 9600 KwH all&rsquo;anno, immaginate quanta energia si potrebbe produrre con le auto che sfrecciano a tali velocit&agrave;.<br \/>Continua a leggere su Archilight:http:\/\/www.archilight.it\/GetPage.pub_do?id=8a8a8ac11d6719be011d6726ceaf0018&amp;_JPFORCEDINFO=8a8a8ac1180899dd011808d140ce0707<\/p>\n<p>A proposito di ricerca di fonti alternative di energia, non mancano le proposte originali, da parte di studenti e appassionati della materia.. Uno studente di architettura dell&rsquo;Arizona (Usa) ha trovato il modo di produrre energia pulita con un sistema eolico che sfrutta le turbolenze provocate dal passaggio dei veicoli in autostrada. Joe, questo il suo nome, ha osservato le auto sfrecciare sulle larghe autostrade americane, e ha stimato in 70 miglia orarie la media della loro velocit&agrave;. Sapendo che attualmente con 10 miglia orarie (del vento, ndr) si producono 9600 KwH all&rsquo;anno, immaginate quanta energia si potrebbe produrre con le auto che sfrecciano a tali velocit&agrave;.<br \/>Continua a leggere su Archilight:http:\/\/www.archilight.it\/GetPage.pub_do?id=8a8a8ac11d6719be011d6726ceaf0018&amp;_JPFORCEDINFO=8a8a8ac1180899dd011808d140ce0707<\/p>\n<p>A proposito di ricerca di fonti alternative di energia, non mancano le proposte originali, da parte di studenti e appassionati della materia.. Uno studente di architettura dell&rsquo;Arizona (Usa) ha trovato il modo di produrre energia pulita con un sistema eolico che sfrutta le turbolenze provocate dal passaggio dei veicoli in autostrada. Joe, questo il suo nome, ha osservato le auto sfrecciare sulle larghe autostrade americane, e ha stimato in 70 miglia orarie la media della loro velocit&agrave;. Sapendo che attualmente con 10 miglia orarie (del vento, ndr) si producono 9600 KwH all&rsquo;anno, immaginate quanta energia si potrebbe produrre con le auto che sfrecciano a tali velocit&agrave;.<br \/>Continua a leggere su Archilight:http:\/\/www.archilight.it\/GetPage.pub_do?id=8a8a8ac11d6719be011d6726ceaf0018&amp;_JPFORCEDINFO=8a8a8ac1180899dd011808d140ce0707<\/p>\n<p>A proposito di ricerca di fonti alternative di energia, non mancano le proposte originali, da parte di studenti e appassionati della materia.. Uno studente di architettura dell&rsquo;Arizona (Usa) ha trovato il modo di produrre energia pulita con un sistema eolico che sfrutta le turbolenze provocate dal passaggio dei veicoli in autostrada. Joe, questo il suo nome, ha osservato le auto sfrecciare sulle larghe autostrade americane, e ha stimato in 70 miglia orarie la media della loro velocit&agrave;. Sapendo che attualmente con 10 miglia orarie (del vento, ndr) si producono 9600 KwH all&rsquo;anno, immaginate quanta energia si potrebbe produrre con le auto che sfrecciano a tali velocit&agrave;.<br \/>Continua a leggere su Archilight:http:\/\/www.archilight.it\/GetPage.pub_do?id=8a8a8ac11d6719be011d6726ceaf0018&amp;_JPFORCEDINFO=8a8a8ac1180899dd011808d140ce0707<\/p>\n<p>A proposito di ricerca di fonti alternative di energia, non mancano le proposte originali, da parte di studenti e appassionati della materia.. Uno studente di architettura dell&rsquo;Arizona (Usa) ha trovato il modo di produrre energia pulita con un sistema eolico che sfrutta le turbolenze provocate dal passaggio dei veicoli in autostrada. Joe, questo il suo nome, ha osservato le auto sfrecciare sulle larghe autostrade americane, e ha stimato in 70 miglia orarie la media della loro velocit&agrave;. Sapendo che attualmente con 10 miglia orarie (del vento, ndr) si producono 9600 KwH all&rsquo;anno, immaginate quanta energia si potrebbe produrre con le auto che sfrecciano a tali velocit&agrave;.<br \/>Continua a leggere su Archilight:http:\/\/www.archilight.it\/GetPage.pub_do?id=8a8a8ac11d6719be011d6726ceaf0018&amp;_JPFORCEDINFO=8a8a8ac1180899dd011808d140ce0707<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A proposito di ricerca di fonti alternative di energia, non mancano le proposte originali, da parte di studenti e appassionati della materia..<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"","footnotes":""},"categories":[27],"tags":[37166,28922],"class_list":["post-28085","post","type-post","status-publish","format-standard","hentry","category-arte-e-cultura","tag-archilgiht","tag-disano-illuminazione"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Energia pulita dalle autostrade - Article Marketing<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/energia-pulita-dalle-autostrade\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Energia pulita dalle autostrade - Article Marketing\" \/>\n<meta property=\"og:description\" content=\"A proposito di ricerca di fonti alternative di energia, non mancano le proposte originali, da parte di studenti e appassionati della materia..\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/energia-pulita-dalle-autostrade\/\" \/>\n<meta property=\"og:site_name\" content=\"Article Marketing\" \/>\n<meta property=\"article:published_time\" content=\"2012-07-12T13:12:27+00:00\" \/>\n<meta name=\"author\" content=\"Redazione Comunicati Stampa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione Comunicati Stampa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/arte-e-cultura\\\/energia-pulita-dalle-autostrade\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/arte-e-cultura\\\/energia-pulita-dalle-autostrade\\\/\"},\"author\":{\"name\":\"Redazione Comunicati Stampa\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"headline\":\"Energia pulita dalle autostrade\",\"datePublished\":\"2012-07-12T13:12:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/arte-e-cultura\\\/energia-pulita-dalle-autostrade\\\/\"},\"wordCount\":1237,\"commentCount\":0,\"keywords\":[\"Archilgiht\",\"Disano Illuminazione\"],\"articleSection\":[\"Arte e cultura\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/arte-e-cultura\\\/energia-pulita-dalle-autostrade\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/arte-e-cultura\\\/energia-pulita-dalle-autostrade\\\/\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/arte-e-cultura\\\/energia-pulita-dalle-autostrade\\\/\",\"name\":\"Energia pulita dalle autostrade - Article Marketing\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\"},\"datePublished\":\"2012-07-12T13:12:27+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/arte-e-cultura\\\/energia-pulita-dalle-autostrade\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/arte-e-cultura\\\/energia-pulita-dalle-autostrade\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/arte-e-cultura\\\/energia-pulita-dalle-autostrade\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Energia pulita dalle autostrade\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\",\"name\":\"Article Marketing\",\"description\":\"article marketing &amp; press release\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\",\"name\":\"Redazione Comunicati Stampa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"caption\":\"Redazione Comunicati Stampa\"},\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/author\\\/redazione-comunicati-stampa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Energia pulita dalle autostrade - Article Marketing","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/energia-pulita-dalle-autostrade\/","og_locale":"it_IT","og_type":"article","og_title":"Energia pulita dalle autostrade - Article Marketing","og_description":"A proposito di ricerca di fonti alternative di energia, non mancano le proposte originali, da parte di studenti e appassionati della materia..","og_url":"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/energia-pulita-dalle-autostrade\/","og_site_name":"Article Marketing","article_published_time":"2012-07-12T13:12:27+00:00","author":"Redazione Comunicati Stampa","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione Comunicati Stampa","Tempo di lettura stimato":"6 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/energia-pulita-dalle-autostrade\/#article","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/energia-pulita-dalle-autostrade\/"},"author":{"name":"Redazione Comunicati Stampa","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"headline":"Energia pulita dalle autostrade","datePublished":"2012-07-12T13:12:27+00:00","mainEntityOfPage":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/energia-pulita-dalle-autostrade\/"},"wordCount":1237,"commentCount":0,"keywords":["Archilgiht","Disano Illuminazione"],"articleSection":["Arte e cultura"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/energia-pulita-dalle-autostrade\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/energia-pulita-dalle-autostrade\/","url":"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/energia-pulita-dalle-autostrade\/","name":"Energia pulita dalle autostrade - Article Marketing","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website"},"datePublished":"2012-07-12T13:12:27+00:00","author":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"breadcrumb":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/energia-pulita-dalle-autostrade\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/energia-pulita-dalle-autostrade\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/energia-pulita-dalle-autostrade\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.article-marketing.eu\/comunicati\/"},{"@type":"ListItem","position":2,"name":"Energia pulita dalle autostrade"}]},{"@type":"WebSite","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website","url":"https:\/\/www.article-marketing.eu\/comunicati\/","name":"Article Marketing","description":"article marketing &amp; press release","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.article-marketing.eu\/comunicati\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017","name":"Redazione Comunicati Stampa","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","caption":"Redazione Comunicati Stampa"},"url":"https:\/\/www.article-marketing.eu\/comunicati\/author\/redazione-comunicati-stampa\/"}]}},"_links":{"self":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/28085","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/comments?post=28085"}],"version-history":[{"count":0,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/28085\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/media?parent=28085"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/categories?post=28085"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/tags?post=28085"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}