{"id":28197,"date":"2012-07-17T17:41:05","date_gmt":"2012-07-17T15:41:05","guid":{"rendered":"http:\/\/www.article-marketing.eu\/comunicati\/senza-categoria\/il-mercato-immobiliare-italiano-ancora-in-calo\/"},"modified":"2018-07-10T05:20:31","modified_gmt":"2018-07-10T03:20:31","slug":"il-mercato-immobiliare-italiano-ancora-in-calo","status":"publish","type":"post","link":"https:\/\/www.article-marketing.eu\/comunicati\/casa\/il-mercato-immobiliare-italiano-ancora-in-calo\/","title":{"rendered":"Il mercato immobiliare italiano ancora in calo"},"content":{"rendered":"<p><strong style=\"margin: 0px; padding: 0px; border: 0px; outline: 0px; vertical-align: baseline; background-color: transparent;\">Il valore delle abitazioni in Italia hanno subito un deprezzamento del 10,5%. Le transazioni nel settore dell&rsquo;immobile residenziale hanno avuto un calo del 5,3% nel primo semestre del 2012. Il mercato ha fatto un balzo di 30 in dietro. Ma la situazione non cambia se si esce dai confini italiani: anche i prezzi a Londra hanno subito una abbattimento senza precedenti.<\/strong><br \/>Anche negli USA il valore delle <strong style=\"margin: 0px; padding: 0px; border: 0px; outline: 0px; vertical-align: baseline; background-color: transparent;\">abitazioni<\/strong> hanno raggiunto il minimo storico e sembra questo il momento pi&ugrave; favorevole per acquistare casa da parte di chi abbia voglia di investire sul suolo a stelle e strisce.<br \/>Le agenzie immobiliari della capitale inglese, hanno ridotto i prezzi per un importo record in luglio. L&rsquo;aumento di offerta di<strong style=\"margin: 0px; padding: 0px; border: 0px; outline: 0px; vertical-align: baseline; background-color: transparent;\"> case in vendita<\/strong> ha fatto innalzare la pressione sul <strong style=\"margin: 0px; padding: 0px; border: 0px; outline: 0px; vertical-align: baseline; background-color: transparent;\">mercato immobiliare<\/strong> della metropoli londinese durante questi mesi estivi, in cui storicamente la domanda subisce un vistoso calo (fonte Rightmove Plc).<br \/>I prezzi sono scesi addirittura del 36% da giugno a una media di 460.000 steriline (circa 715.000 dollari). Difronte a questa situazione la Banca d&rsquo;Inghilterra &egrave; stata costretta a varare un programma finalizzato a rilanciare il credito all&rsquo;economia.<br \/>E nel nostro Paese non va certo meglio: l&rsquo;andamento gi&agrave; negativo del <strong style=\"margin: 0px; padding: 0px; border: 0px; outline: 0px; vertical-align: baseline; background-color: transparent;\">mercato immobiliare italiano<\/strong> &egrave; peggiorato negli ultimi tempi, strozzato da una severa ristrettezza creditizia e dal perdurare della recessione, con l&rsquo;effetto di un tracollo delle compravendite e di un nuovo, seppur contenuto, calo dei prezzi. Il motivo per cui anche in Italia non si sta assistendo al tonfo dei prezzi come in altri Paesi, &egrave; dovuto alla strategia attendista dei venditori, che per&ograve; rischia di logorare il settore.<br \/>Il rapporto di periodo sul mercato del mattone presentato da <strong style=\"margin: 0px; padding: 0px; border: 0px; outline: 0px; vertical-align: baseline; background-color: transparent;\">Nomisma<\/strong>, dipinge l&rsquo;attuale situazione con molte ombre. Si parla di un calo delle transazioni del residenziale del 5,3% nel 2012 con 566.000 operazioni, con il rischio di peggiorare ulteriormente i numeri a breve se i prezzi scenderanno con velocit&agrave; inferiore rispetto al dato tendenziale, e se non miglioreranno le condizioni di accesso al mutuo per le famiglie.<br \/>I prezzi e il credito sono infatti le due grandi variabili che stanno limitando la domanda tenendo bloccato il mercato.<br \/><strong style=\"margin: 0px; padding: 0px; border: 0px; outline: 0px; vertical-align: baseline; background-color: transparent;\">Nomisma<\/strong> evidenzia nel suo rapporto che &egrave; molto difficile che una correzione dei prezzi al ribasso possa venire da parte del settore privato, ma deve venire da parte delle imprese, banche e soggetti istituzionali interessati alle dismissioni immobiliari, in particolare le amministrazioni pubbliche e gli enti previdenziali. Il problema, secondo gli esperti, &egrave; che si &egrave; innescato un meccanismo perverso, in base al quale i soggetti istituzionali stanno ritardando la messa in vendita degli immobili in attesa di una ripresa del mercato, allo scopo di evitare di inserire in bilancio un&rsquo;eccessiva svalutazione degli attivi.<br \/>Ma questa situazione, unita alla chiusura delle linee di finanziamento da parte delle banche, sta pregiudicando qualsiasi possibilit&agrave; di ripresa del mercato facendo crescere la gi&agrave; enorme quantit&agrave; di invenduto e riducendo la capacit&agrave; di assorbimento di quegli immobili a garanzia di crediti in cagliati, se non addirittura gi&agrave; in sofferenza.<br \/>Le nuove operazioni di mutuo, osserva <strong style=\"margin: 0px; padding: 0px; border: 0px; outline: 0px; vertical-align: baseline; background-color: transparent;\">Nomisma<\/strong>, hanno avuto una brusca flessione gi&agrave; a partire dal 2009. Nei primi tre mesi del 2012, i finanziamenti concessi per l&rsquo;acquisto di casa hanno subito con un crollo del 50%, e si stima che anche il secondo trimestre chiuder&agrave; con un consistente decremento (45,5%). Il valore a consuntivo si attester&agrave; poco sotto gli 8 miliardi di euro.<br \/>Per trovare dei volumi nominali reali cos&igrave; contenuti bisogna tornare in dietro nel tempo al 2003.<br \/>In questi 4 anni di calo dei prezzi del mercato immobiliare, le abitazioni e gli uffici si sono deprezzati del 10,5% e gli esercizi commerciali di poco pi&ugrave; dell&rsquo;8%. Nell&rsquo;ultimo hanno, da luglio 2011 a luglio 2012, le abitazioni hanno registrato un calo del 3,5% e si stima che a luglio 2013 il decremento sar&agrave; del 2,4% e si arriver&agrave; a -1,7% nel 2014. Gli uffici passeranno dal -4,4% di luglio 2012 al -2,9% di luglio 2013 e -1,6% di luglio 2014.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il valore delle abitazioni in Italia hanno subito un deprezzamento del 10,5%. Le transazioni nel settore dell\u2019immobile residenziale hanno avuto un calo del 5,3% nel primo semestre del 2012. Il mercato ha fatto un balzo di 30 in dietro. Ma la situazione non cambia se si esce dai confini italiani: anche i prezzi a Londra hanno subito una abbattimento senza precedenti.<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"","footnotes":""},"categories":[390],"tags":[1838,4107,18175],"class_list":["post-28197","post","type-post","status-publish","format-standard","hentry","category-casa","tag-comprare-casa","tag-mercato-immobiliare","tag-vendere-casa"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Il mercato immobiliare italiano ancora in calo - Article Marketing<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.article-marketing.eu\/comunicati\/casa\/il-mercato-immobiliare-italiano-ancora-in-calo\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Il mercato immobiliare italiano ancora in calo - Article Marketing\" \/>\n<meta property=\"og:description\" content=\"Il valore delle abitazioni in Italia hanno subito un deprezzamento del 10,5%. Le transazioni nel settore dell\u2019immobile residenziale hanno avuto un calo del 5,3% nel primo semestre del 2012. Il mercato ha fatto un balzo di 30 in dietro. Ma la situazione non cambia se si esce dai confini italiani: anche i prezzi a Londra hanno subito una abbattimento senza precedenti.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.article-marketing.eu\/comunicati\/casa\/il-mercato-immobiliare-italiano-ancora-in-calo\/\" \/>\n<meta property=\"og:site_name\" content=\"Article Marketing\" \/>\n<meta property=\"article:published_time\" content=\"2012-07-17T15:41:05+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-07-10T03:20:31+00:00\" \/>\n<meta name=\"author\" content=\"Redazione Comunicati Stampa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione Comunicati Stampa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/casa\\\/il-mercato-immobiliare-italiano-ancora-in-calo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/casa\\\/il-mercato-immobiliare-italiano-ancora-in-calo\\\/\"},\"author\":{\"name\":\"Redazione Comunicati Stampa\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"headline\":\"Il mercato immobiliare italiano ancora in calo\",\"datePublished\":\"2012-07-17T15:41:05+00:00\",\"dateModified\":\"2018-07-10T03:20:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/casa\\\/il-mercato-immobiliare-italiano-ancora-in-calo\\\/\"},\"wordCount\":676,\"commentCount\":0,\"keywords\":[\"comprare casa\",\"mercato immobiliare\",\"vendere casa\"],\"articleSection\":[\"Casa\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/casa\\\/il-mercato-immobiliare-italiano-ancora-in-calo\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/casa\\\/il-mercato-immobiliare-italiano-ancora-in-calo\\\/\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/casa\\\/il-mercato-immobiliare-italiano-ancora-in-calo\\\/\",\"name\":\"Il mercato immobiliare italiano ancora in calo - Article Marketing\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\"},\"datePublished\":\"2012-07-17T15:41:05+00:00\",\"dateModified\":\"2018-07-10T03:20:31+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/casa\\\/il-mercato-immobiliare-italiano-ancora-in-calo\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/casa\\\/il-mercato-immobiliare-italiano-ancora-in-calo\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/casa\\\/il-mercato-immobiliare-italiano-ancora-in-calo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Il mercato immobiliare italiano ancora in calo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\",\"name\":\"Article Marketing\",\"description\":\"article marketing &amp; press release\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\",\"name\":\"Redazione Comunicati Stampa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"caption\":\"Redazione Comunicati Stampa\"},\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/author\\\/redazione-comunicati-stampa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Il mercato immobiliare italiano ancora in calo - Article Marketing","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.article-marketing.eu\/comunicati\/casa\/il-mercato-immobiliare-italiano-ancora-in-calo\/","og_locale":"it_IT","og_type":"article","og_title":"Il mercato immobiliare italiano ancora in calo - Article Marketing","og_description":"Il valore delle abitazioni in Italia hanno subito un deprezzamento del 10,5%. Le transazioni nel settore dell\u2019immobile residenziale hanno avuto un calo del 5,3% nel primo semestre del 2012. Il mercato ha fatto un balzo di 30 in dietro. Ma la situazione non cambia se si esce dai confini italiani: anche i prezzi a Londra hanno subito una abbattimento senza precedenti.","og_url":"https:\/\/www.article-marketing.eu\/comunicati\/casa\/il-mercato-immobiliare-italiano-ancora-in-calo\/","og_site_name":"Article Marketing","article_published_time":"2012-07-17T15:41:05+00:00","article_modified_time":"2018-07-10T03:20:31+00:00","author":"Redazione Comunicati Stampa","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione Comunicati Stampa","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.article-marketing.eu\/comunicati\/casa\/il-mercato-immobiliare-italiano-ancora-in-calo\/#article","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/casa\/il-mercato-immobiliare-italiano-ancora-in-calo\/"},"author":{"name":"Redazione Comunicati Stampa","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"headline":"Il mercato immobiliare italiano ancora in calo","datePublished":"2012-07-17T15:41:05+00:00","dateModified":"2018-07-10T03:20:31+00:00","mainEntityOfPage":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/casa\/il-mercato-immobiliare-italiano-ancora-in-calo\/"},"wordCount":676,"commentCount":0,"keywords":["comprare casa","mercato immobiliare","vendere casa"],"articleSection":["Casa"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.article-marketing.eu\/comunicati\/casa\/il-mercato-immobiliare-italiano-ancora-in-calo\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.article-marketing.eu\/comunicati\/casa\/il-mercato-immobiliare-italiano-ancora-in-calo\/","url":"https:\/\/www.article-marketing.eu\/comunicati\/casa\/il-mercato-immobiliare-italiano-ancora-in-calo\/","name":"Il mercato immobiliare italiano ancora in calo - Article Marketing","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website"},"datePublished":"2012-07-17T15:41:05+00:00","dateModified":"2018-07-10T03:20:31+00:00","author":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"breadcrumb":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/casa\/il-mercato-immobiliare-italiano-ancora-in-calo\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.article-marketing.eu\/comunicati\/casa\/il-mercato-immobiliare-italiano-ancora-in-calo\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.article-marketing.eu\/comunicati\/casa\/il-mercato-immobiliare-italiano-ancora-in-calo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.article-marketing.eu\/comunicati\/"},{"@type":"ListItem","position":2,"name":"Il mercato immobiliare italiano ancora in calo"}]},{"@type":"WebSite","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website","url":"https:\/\/www.article-marketing.eu\/comunicati\/","name":"Article Marketing","description":"article marketing &amp; press release","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.article-marketing.eu\/comunicati\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017","name":"Redazione Comunicati Stampa","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","caption":"Redazione Comunicati Stampa"},"url":"https:\/\/www.article-marketing.eu\/comunicati\/author\/redazione-comunicati-stampa\/"}]}},"_links":{"self":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/28197","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/comments?post=28197"}],"version-history":[{"count":1,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/28197\/revisions"}],"predecessor-version":[{"id":61259,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/28197\/revisions\/61259"}],"wp:attachment":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/media?parent=28197"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/categories?post=28197"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/tags?post=28197"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}