{"id":29007,"date":"2012-09-05T17:27:20","date_gmt":"2012-09-05T15:27:20","guid":{"rendered":"http:\/\/www.article-marketing.eu\/comunicati\/senza-categoria\/se-per-chiederla-in-sposa-organizza-un-flash-mob-a-roma-il-caso\/"},"modified":"2012-09-05T17:27:20","modified_gmt":"2012-09-05T15:27:20","slug":"se-per-chiederla-in-sposa-organizza-un-flash-mob-a-roma-il-caso","status":"publish","type":"post","link":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/eventi\/se-per-chiederla-in-sposa-organizza-un-flash-mob-a-roma-il-caso\/","title":{"rendered":"Se per chiederla in sposa organizza un flash mob a Roma: il caso"},"content":{"rendered":"<p>Si chiamano flash mob, o mobilitazioni di massa, che coinvolgono varie persone nell&rsquo;organizzare un&rsquo;azione di gruppo per supportare un&rsquo;idea, manifestare o anche per il solo gusto di fare un&rsquo;attivit&agrave; fuori dalle righe. Questa volta per&ograve; il tutto serviva per creare un effetto sorpresa per chiedere la mano all&rsquo;amata di turno nel pieno centro della citt&agrave; di Roma. <\/p>\n<p> Renato, promesso sposo, porta la propria fidanzata Alessandra a passeggio per Piazza del Popolo a Roma e si fermano ad osservare un gruppo di giovani che ballano a ritmo di musica. Fin qua tutto normale. Il primo indizio &egrave; la canzone che ripete: &ldquo;I think I wanna marry you&rdquo;, ovvero &ldquo;penso di volerti sposare&rdquo;. I giovani continuano a ballare, ma all&rsquo;improvviso si cambia musica e parte la nota canzone di Biagio Antonacci &ldquo;Convivendo&rdquo;. Riorganizzazione generale nella coreografia e l&rsquo;imprevedibile Renato viene &ldquo;trascinato&rdquo; a ballare nel gruppo e lui, con molta disinvoltura (e chiss&agrave; quante prove) balla con tutto il gruppo, cantando la canzone della coppia, rivolto proprio alla ragazza incredula e smarrita. Lei scoppia a piangere capendo che il tutto era stato organizzato per lei dal suo amato Renato. Cala la base musicale e il giovane romantico si inginocchia dinanzi alla sua bella e le chiede di <a href=\"http:\/\/www.glenspose.it\/\" title=\"abbigliamento sposa Roma\">sposarlo<\/a>. Assoluto silenzio tutto attorno, quando i passati, compresa la situazione, hanno gi&agrave; cominciato a filmare tutta l&rsquo;incredibile scena con videocamere e telefonini. Renato si inginocchia, aprendo una scatoletta contente un magnifico anello: la folla esulta entusiasta. La gente, tutta intorno alla coppia, esulta e chiede a questo punto, a gran voce, un bacio fra i due. <\/p>\n<p> Ovviamente il bacio ci sar&agrave; con grandissima emozione dei due, e di tutti i curiosi che nel frattempo avevano attorniato la scena romantica e sui generis. Un modo sicuramente originale per chiedere di sposare la propria amata. <\/p>\n<p> Questo per&ograve; non &egrave; il primo o l&rsquo;ultimo esempio di mobilitazioni di massa, a vario scopo, che da anni hanno sempre pi&ugrave; luogo in giro per il mondo. L&rsquo;evento di Roma in questione &egrave; stato realizzato dalla &ldquo;Roma Flash Mob&rdquo; ( www.romaflashmob.it ), agenzia specializzata in questo tipo di eventi, dei due giovani e brillanti esperti di comunicazione ed eventi di massa Valerio Marco Trapani e Daniele Avanzato. Auguri ai futuri sposi di Roma, in questo caso.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&#8217;agenzia specializzata in mobilitazioni di massa &#8220;Roma Flash Mob&#8221; aiuta Renato, promesso sposo romano, a proporsi con effetto sorpresa all&#8217;amata nel pieno centro di Roma con grande successo.<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"","footnotes":""},"categories":[388],"tags":[37979,339,251,2644],"class_list":["post-29007","post","type-post","status-publish","format-standard","hentry","category-eventi","tag-flash-mob-flashmob","tag-matrimonio","tag-roma","tag-sposi"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Se per chiederla in sposa organizza un flash mob a Roma: il caso - Article Marketing<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/eventi\/se-per-chiederla-in-sposa-organizza-un-flash-mob-a-roma-il-caso\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Se per chiederla in sposa organizza un flash mob a Roma: il caso - Article Marketing\" \/>\n<meta property=\"og:description\" content=\"L&#039;agenzia specializzata in mobilitazioni di massa &quot;Roma Flash Mob&quot; aiuta Renato, promesso sposo romano, a proporsi con effetto sorpresa all&#039;amata nel pieno centro di Roma con grande successo.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/eventi\/se-per-chiederla-in-sposa-organizza-un-flash-mob-a-roma-il-caso\/\" \/>\n<meta property=\"og:site_name\" content=\"Article Marketing\" \/>\n<meta property=\"article:published_time\" content=\"2012-09-05T15:27:20+00:00\" \/>\n<meta name=\"author\" content=\"Redazione Comunicati Stampa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione Comunicati Stampa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/eventi\\\/se-per-chiederla-in-sposa-organizza-un-flash-mob-a-roma-il-caso\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/eventi\\\/se-per-chiederla-in-sposa-organizza-un-flash-mob-a-roma-il-caso\\\/\"},\"author\":{\"name\":\"Redazione Comunicati Stampa\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"headline\":\"Se per chiederla in sposa organizza un flash mob a Roma: il caso\",\"datePublished\":\"2012-09-05T15:27:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/eventi\\\/se-per-chiederla-in-sposa-organizza-un-flash-mob-a-roma-il-caso\\\/\"},\"wordCount\":426,\"commentCount\":0,\"keywords\":[\"flash mob.flashmob\",\"matrimonio\",\"roma\",\"sposi\"],\"articleSection\":[\"Eventi\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/eventi\\\/se-per-chiederla-in-sposa-organizza-un-flash-mob-a-roma-il-caso\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/eventi\\\/se-per-chiederla-in-sposa-organizza-un-flash-mob-a-roma-il-caso\\\/\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/eventi\\\/se-per-chiederla-in-sposa-organizza-un-flash-mob-a-roma-il-caso\\\/\",\"name\":\"Se per chiederla in sposa organizza un flash mob a Roma: il caso - Article Marketing\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\"},\"datePublished\":\"2012-09-05T15:27:20+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/eventi\\\/se-per-chiederla-in-sposa-organizza-un-flash-mob-a-roma-il-caso\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/eventi\\\/se-per-chiederla-in-sposa-organizza-un-flash-mob-a-roma-il-caso\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/eventi\\\/se-per-chiederla-in-sposa-organizza-un-flash-mob-a-roma-il-caso\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Se per chiederla in sposa organizza un flash mob a Roma: il caso\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\",\"name\":\"Article Marketing\",\"description\":\"article marketing &amp; press release\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\",\"name\":\"Redazione Comunicati Stampa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"caption\":\"Redazione Comunicati Stampa\"},\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/author\\\/redazione-comunicati-stampa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Se per chiederla in sposa organizza un flash mob a Roma: il caso - Article Marketing","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/eventi\/se-per-chiederla-in-sposa-organizza-un-flash-mob-a-roma-il-caso\/","og_locale":"it_IT","og_type":"article","og_title":"Se per chiederla in sposa organizza un flash mob a Roma: il caso - Article Marketing","og_description":"L'agenzia specializzata in mobilitazioni di massa \"Roma Flash Mob\" aiuta Renato, promesso sposo romano, a proporsi con effetto sorpresa all'amata nel pieno centro di Roma con grande successo.","og_url":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/eventi\/se-per-chiederla-in-sposa-organizza-un-flash-mob-a-roma-il-caso\/","og_site_name":"Article Marketing","article_published_time":"2012-09-05T15:27:20+00:00","author":"Redazione Comunicati Stampa","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione Comunicati Stampa","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/eventi\/se-per-chiederla-in-sposa-organizza-un-flash-mob-a-roma-il-caso\/#article","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/eventi\/se-per-chiederla-in-sposa-organizza-un-flash-mob-a-roma-il-caso\/"},"author":{"name":"Redazione Comunicati Stampa","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"headline":"Se per chiederla in sposa organizza un flash mob a Roma: il caso","datePublished":"2012-09-05T15:27:20+00:00","mainEntityOfPage":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/eventi\/se-per-chiederla-in-sposa-organizza-un-flash-mob-a-roma-il-caso\/"},"wordCount":426,"commentCount":0,"keywords":["flash mob.flashmob","matrimonio","roma","sposi"],"articleSection":["Eventi"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/eventi\/se-per-chiederla-in-sposa-organizza-un-flash-mob-a-roma-il-caso\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/eventi\/se-per-chiederla-in-sposa-organizza-un-flash-mob-a-roma-il-caso\/","url":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/eventi\/se-per-chiederla-in-sposa-organizza-un-flash-mob-a-roma-il-caso\/","name":"Se per chiederla in sposa organizza un flash mob a Roma: il caso - Article Marketing","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website"},"datePublished":"2012-09-05T15:27:20+00:00","author":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"breadcrumb":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/eventi\/se-per-chiederla-in-sposa-organizza-un-flash-mob-a-roma-il-caso\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/eventi\/se-per-chiederla-in-sposa-organizza-un-flash-mob-a-roma-il-caso\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/eventi\/se-per-chiederla-in-sposa-organizza-un-flash-mob-a-roma-il-caso\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.article-marketing.eu\/comunicati\/"},{"@type":"ListItem","position":2,"name":"Se per chiederla in sposa organizza un flash mob a Roma: il caso"}]},{"@type":"WebSite","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website","url":"https:\/\/www.article-marketing.eu\/comunicati\/","name":"Article Marketing","description":"article marketing &amp; press release","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.article-marketing.eu\/comunicati\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017","name":"Redazione Comunicati Stampa","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","caption":"Redazione Comunicati Stampa"},"url":"https:\/\/www.article-marketing.eu\/comunicati\/author\/redazione-comunicati-stampa\/"}]}},"_links":{"self":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/29007","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/comments?post=29007"}],"version-history":[{"count":0,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/29007\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/media?parent=29007"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/categories?post=29007"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/tags?post=29007"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}