{"id":29542,"date":"2012-09-27T10:47:57","date_gmt":"2012-09-27T08:47:57","guid":{"rendered":""},"modified":"2012-09-27T10:47:57","modified_gmt":"2012-09-27T08:47:57","slug":"v-edizione-conferenza-internazionale-women-and-technologies%25252525252525c2%25252525252525ae-e-nutrition-e-premio-a%2525252525252580cle-tecnovisionarie-%25252525252525c2%25252525252525ae2012a%2525252","status":"publish","type":"post","link":"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/ricerca-e-sviluppo\/v-edizione-conferenza-internazionale-women-and-technologies%25252525252525c2%25252525252525ae-e-nutrition-e-premio-a%2525252525252580cle-tecnovisionarie-%25252525252525c2%25252525252525ae2012a%2525252\/","title":{"rendered":"Conferenza Internazionale Women&#038;Technologies\u00ae: e-Nutrition e Premio \u201cLe Tecnovisionarie \u00ae2012\u201d"},"content":{"rendered":"<p><strong><a href=\"\/uploads\/images\/u_2460\/wt2012_testata.jpg\" class=\"image\"><img loading=\"lazy\" decoding=\"async\" src=\"\/uploads\/images\/u_2460\/wt2012_testata.jpg\" border=\"0\" width=\"553\" height=\"106\" \/><\/a><\/p>\n<p>V edizione<\/strong> <strong>Conferenza Internazionale<em><br \/> <\/em>Women<\/strong><strong>&amp;<\/strong><strong>Technologies&reg;: e-Nutrition<\/strong> <strong>e Premio &ldquo;Le Tecnovisionarie &reg;2012&rdquo;<\/strong> <strong><em><br \/> <\/em><br \/> <\/strong><strong>6 novembre 2012<\/strong> <br \/>Camera di Commercio di Milano, Sala Conferenze<br \/> Via Meravigli 9\/B, Milano <strong> <\/strong> <strong><\/p>\n<p>COMUNICATO STAMPA &ndash; 21.09.2012<\/strong> <\/p>\n<p><strong> <\/strong> &ldquo;Valorizzare il talento femminile negli ambiti della ricerca, dello sviluppo tecnologico e dell&rsquo;innovazione&rdquo; : &egrave; questo l&rsquo;obiettivo della Conferenza Internazionale &ldquo;Women&amp;Technologies&reg; 2008-2015&rdquo;. La Conferenza 2012 che si svolger&agrave; il prossimo 6 Novembre a Milano, sar&agrave; focalizzata sul tema centrale del prossimo Expo 2015: la Nutrizione. <\/p>\n<p>Nata nel 2007 da un&rsquo;idea di Gianna Martinengo, che del rapporto tra tecnologie e innovazione ha fatto uno dei temi principali della sua vita professionale di ricercatrice e imprenditrice, ha raggiunto importanti traguardi di consensi da parte di personalit&agrave; del mondo scientifico, accademico, politico, istituzionale e imprenditoriale, per aver saputo far convergere grandi temi di attualit&agrave; nell&rsquo;ambito di un appuntamento annuale di richiamo e successo nel panorama scientifico internazionale. In questo primo appuntamento del triennio dedicato all&rsquo;<strong>alimentazione<\/strong>, si aprir&agrave; il dibattito di approfondimento su un tema strettamente connesso con la <strong>salute<\/strong>, la <strong>sostenibilit&agrave;<\/strong> e l&rsquo;<strong>innovazione<\/strong> attraverso l&rsquo;articolazione di tre tavole rotonde in cui numerose personalit&agrave; del mondo scientifico, istituzionale e imprenditoriale si confronteranno con l&rsquo;obiettivo di fornire una visione completa al consumatore finale, di quelle che sono le nuove frontiere dell&rsquo;alimentazione, i modelli di sostenibilit&agrave; della filiera e di valorizzazione del territorio e le <em>best practices<\/em> per un&rsquo;informazione trasparente e fruibile. <\/p>\n<p>Coordinano le tavole rotonde Lucilla Titta- IEO, Patrizia Riso &#8211; DeFENS Universit&agrave; degli Studi di Milano e Gianluca Carenzo- Parco Tecnologico Padano. La Conferenza sar&agrave; aperta dall&rsquo;intervento di un ospite di prestigio come Paolo De Castro (Presidente della Commissione per l&rsquo;ambiente, la sanit&agrave; pubblica e la sicurezza alimentare del Parlamento Europeo) e dai saluti di Carlo Sangalli (Presidente della Camera di Commercio di Milano che ospita e supporta la Conferenza), Claudia Sorlini (DeFENS e Presidente del Comitato Strategico della Conferenza) e di Gianna Martinengo (Ideatrice e Chairperson di Women&amp;Technologies&reg;). La partecipazione alla Conferenza &egrave; <strong>gratuita<\/strong> e l&rsquo;inizio dei lavori &egrave; fissato alle <strong>9,00<\/strong> del <strong>6 Novembre 2012<\/strong> presso la <strong>Sala Conferenze <\/strong>della<strong> Camera di Commercio di Milano<\/strong> in via Meravigli 9\/B. Al termine delle tavole rotonde previsto per le 17.30, si svolger&agrave; la cerimonia di premiazione de &#8220;Le Tecnovisionarie&reg;&#8221; 2012, un premio alle donne capaci di &ldquo;inventare il futuro&rdquo; attraverso una visione innovativa, sostenibile ed etica. I premi di dell&rsquo;edizione 2012 sono 7 e articolati su tre categorie tematiche (<strong>Women<\/strong>Health, <strong>Women<\/strong>Sustainability e <strong>Women<\/strong>Innovation), tre categorie ricorrenti (<strong>Women<\/strong>Media, <strong>Women<\/strong>Territory e <strong>Women<\/strong>CEO) e un premio speciale destinato a giovani ricercatrici nel settore dell&rsquo;alimentazione, <strong>Women<\/strong>Future. Conduce la cerimonia di premiazione Rita Querz&egrave;, giornalista del Corriere della Sera. <strong> <\/strong> <strong><\/p>\n<p>Ufficio Stampa:<\/strong><strong> <\/strong><em> <\/em><em>press@womentech.info <\/em>|tel. +39 0287285350<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u201cValorizzare il talento femminile negli ambiti della ricerca, dello sviluppo tecnologico e dell\u2019innovazione\u201d : \u00e8 questo l\u2019obiettivo della Conferenza Internazionale \u201cWomen&#038;Technologies\u00ae 2008-2015\u201d. La Conferenza 2012 che si svolger\u00e0 il prossimo 6 Novembre a Milano, sar\u00e0 focalizzata sul tema centrale del prossimo Expo 2015: la Nutrizione.<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"","footnotes":""},"categories":[77],"tags":[38434],"class_list":["post-29542","post","type-post","status-publish","format-standard","hentry","category-ricerca-e-sviluppo","tag-womentechnologies-2012-women-nutrizione-2012"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Conferenza Internazionale Women&amp;Technologies\u00ae: e-Nutrition e Premio \u201cLe Tecnovisionarie \u00ae2012\u201d - Article Marketing<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/ricerca-e-sviluppo\/v-edizione-conferenza-internazionale-women-and-technologies%252525252525c2%252525252525ae-e-nutrition-e-premio-a%25252525252580cle-tecnovisionarie-%252525252525c2%252525252525ae2012a%25252\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Conferenza Internazionale Women&amp;Technologies\u00ae: e-Nutrition e Premio \u201cLe Tecnovisionarie \u00ae2012\u201d - Article Marketing\" \/>\n<meta property=\"og:description\" content=\"\u201cValorizzare il talento femminile negli ambiti della ricerca, dello sviluppo tecnologico e dell\u2019innovazione\u201d : \u00e8 questo l\u2019obiettivo della Conferenza Internazionale \u201cWomen&amp;Technologies\u00ae 2008-2015\u201d. La Conferenza 2012 che si svolger\u00e0 il prossimo 6 Novembre a Milano, sar\u00e0 focalizzata sul tema centrale del prossimo Expo 2015: la Nutrizione.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/ricerca-e-sviluppo\/v-edizione-conferenza-internazionale-women-and-technologies%252525252525c2%252525252525ae-e-nutrition-e-premio-a%25252525252580cle-tecnovisionarie-%252525252525c2%252525252525ae2012a%25252\/\" \/>\n<meta property=\"og:site_name\" content=\"Article Marketing\" \/>\n<meta property=\"article:published_time\" content=\"2012-09-27T08:47:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.article-marketing.eu\/uploads\/images\/u_2460\/wt2012_testata.jpg\" \/>\n<meta name=\"author\" content=\"Redazione Comunicati Stampa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione Comunicati Stampa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/arte-e-cultura\\\/ricerca-e-sviluppo\\\/v-edizione-conferenza-internazionale-women-and-technologies%25252525252525c2%25252525252525ae-e-nutrition-e-premio-a%2525252525252580cle-tecnovisionarie-%25252525252525c2%25252525252525ae2012a%2525252\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/arte-e-cultura\\\/ricerca-e-sviluppo\\\/v-edizione-conferenza-internazionale-women-and-technologies%25252525252525c2%25252525252525ae-e-nutrition-e-premio-a%2525252525252580cle-tecnovisionarie-%25252525252525c2%25252525252525ae2012a%2525252\\\/\"},\"author\":{\"name\":\"Redazione Comunicati Stampa\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"headline\":\"Conferenza Internazionale Women&#038;Technologies\u00ae: e-Nutrition e Premio \u201cLe Tecnovisionarie \u00ae2012\u201d\",\"datePublished\":\"2012-09-27T08:47:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/arte-e-cultura\\\/ricerca-e-sviluppo\\\/v-edizione-conferenza-internazionale-women-and-technologies%25252525252525c2%25252525252525ae-e-nutrition-e-premio-a%2525252525252580cle-tecnovisionarie-%25252525252525c2%25252525252525ae2012a%2525252\\\/\"},\"wordCount\":490,\"commentCount\":0,\"keywords\":[\"women&amp;technologies 2012; women; nutrizione; 2012\"],\"articleSection\":[\"Ricerca e sviluppo\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/arte-e-cultura\\\/ricerca-e-sviluppo\\\/v-edizione-conferenza-internazionale-women-and-technologies%25252525252525c2%25252525252525ae-e-nutrition-e-premio-a%2525252525252580cle-tecnovisionarie-%25252525252525c2%25252525252525ae2012a%2525252\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/arte-e-cultura\\\/ricerca-e-sviluppo\\\/v-edizione-conferenza-internazionale-women-and-technologies%25252525252525c2%25252525252525ae-e-nutrition-e-premio-a%2525252525252580cle-tecnovisionarie-%25252525252525c2%25252525252525ae2012a%2525252\\\/\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/arte-e-cultura\\\/ricerca-e-sviluppo\\\/v-edizione-conferenza-internazionale-women-and-technologies%25252525252525c2%25252525252525ae-e-nutrition-e-premio-a%2525252525252580cle-tecnovisionarie-%25252525252525c2%25252525252525ae2012a%2525252\\\/\",\"name\":\"Conferenza Internazionale Women&Technologies\u00ae: e-Nutrition e Premio \u201cLe Tecnovisionarie \u00ae2012\u201d - Article Marketing\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\"},\"datePublished\":\"2012-09-27T08:47:57+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/arte-e-cultura\\\/ricerca-e-sviluppo\\\/v-edizione-conferenza-internazionale-women-and-technologies%25252525252525c2%25252525252525ae-e-nutrition-e-premio-a%2525252525252580cle-tecnovisionarie-%25252525252525c2%25252525252525ae2012a%2525252\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/arte-e-cultura\\\/ricerca-e-sviluppo\\\/v-edizione-conferenza-internazionale-women-and-technologies%25252525252525c2%25252525252525ae-e-nutrition-e-premio-a%2525252525252580cle-tecnovisionarie-%25252525252525c2%25252525252525ae2012a%2525252\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/arte-e-cultura\\\/ricerca-e-sviluppo\\\/v-edizione-conferenza-internazionale-women-and-technologies%25252525252525c2%25252525252525ae-e-nutrition-e-premio-a%2525252525252580cle-tecnovisionarie-%25252525252525c2%25252525252525ae2012a%2525252\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Conferenza Internazionale Women&#038;Technologies\u00ae: e-Nutrition e Premio \u201cLe Tecnovisionarie \u00ae2012\u201d\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\",\"name\":\"Article Marketing\",\"description\":\"article marketing &amp; press release\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\",\"name\":\"Redazione Comunicati Stampa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"caption\":\"Redazione Comunicati Stampa\"},\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/author\\\/redazione-comunicati-stampa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Conferenza Internazionale Women&Technologies\u00ae: e-Nutrition e Premio \u201cLe Tecnovisionarie \u00ae2012\u201d - Article Marketing","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/ricerca-e-sviluppo\/v-edizione-conferenza-internazionale-women-and-technologies%252525252525c2%252525252525ae-e-nutrition-e-premio-a%25252525252580cle-tecnovisionarie-%252525252525c2%252525252525ae2012a%25252\/","og_locale":"it_IT","og_type":"article","og_title":"Conferenza Internazionale Women&Technologies\u00ae: e-Nutrition e Premio \u201cLe Tecnovisionarie \u00ae2012\u201d - Article Marketing","og_description":"\u201cValorizzare il talento femminile negli ambiti della ricerca, dello sviluppo tecnologico e dell\u2019innovazione\u201d : \u00e8 questo l\u2019obiettivo della Conferenza Internazionale \u201cWomen&Technologies\u00ae 2008-2015\u201d. La Conferenza 2012 che si svolger\u00e0 il prossimo 6 Novembre a Milano, sar\u00e0 focalizzata sul tema centrale del prossimo Expo 2015: la Nutrizione.","og_url":"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/ricerca-e-sviluppo\/v-edizione-conferenza-internazionale-women-and-technologies%252525252525c2%252525252525ae-e-nutrition-e-premio-a%25252525252580cle-tecnovisionarie-%252525252525c2%252525252525ae2012a%25252\/","og_site_name":"Article Marketing","article_published_time":"2012-09-27T08:47:57+00:00","og_image":[{"url":"https:\/\/www.article-marketing.eu\/uploads\/images\/u_2460\/wt2012_testata.jpg","type":"","width":"","height":""}],"author":"Redazione Comunicati Stampa","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione Comunicati Stampa","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/ricerca-e-sviluppo\/v-edizione-conferenza-internazionale-women-and-technologies%25252525252525c2%25252525252525ae-e-nutrition-e-premio-a%2525252525252580cle-tecnovisionarie-%25252525252525c2%25252525252525ae2012a%2525252\/#article","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/ricerca-e-sviluppo\/v-edizione-conferenza-internazionale-women-and-technologies%25252525252525c2%25252525252525ae-e-nutrition-e-premio-a%2525252525252580cle-tecnovisionarie-%25252525252525c2%25252525252525ae2012a%2525252\/"},"author":{"name":"Redazione Comunicati Stampa","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"headline":"Conferenza Internazionale Women&#038;Technologies\u00ae: e-Nutrition e Premio \u201cLe Tecnovisionarie \u00ae2012\u201d","datePublished":"2012-09-27T08:47:57+00:00","mainEntityOfPage":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/ricerca-e-sviluppo\/v-edizione-conferenza-internazionale-women-and-technologies%25252525252525c2%25252525252525ae-e-nutrition-e-premio-a%2525252525252580cle-tecnovisionarie-%25252525252525c2%25252525252525ae2012a%2525252\/"},"wordCount":490,"commentCount":0,"keywords":["women&amp;technologies 2012; women; nutrizione; 2012"],"articleSection":["Ricerca e sviluppo"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/ricerca-e-sviluppo\/v-edizione-conferenza-internazionale-women-and-technologies%25252525252525c2%25252525252525ae-e-nutrition-e-premio-a%2525252525252580cle-tecnovisionarie-%25252525252525c2%25252525252525ae2012a%2525252\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/ricerca-e-sviluppo\/v-edizione-conferenza-internazionale-women-and-technologies%25252525252525c2%25252525252525ae-e-nutrition-e-premio-a%2525252525252580cle-tecnovisionarie-%25252525252525c2%25252525252525ae2012a%2525252\/","url":"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/ricerca-e-sviluppo\/v-edizione-conferenza-internazionale-women-and-technologies%25252525252525c2%25252525252525ae-e-nutrition-e-premio-a%2525252525252580cle-tecnovisionarie-%25252525252525c2%25252525252525ae2012a%2525252\/","name":"Conferenza Internazionale Women&Technologies\u00ae: e-Nutrition e Premio \u201cLe Tecnovisionarie \u00ae2012\u201d - Article Marketing","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website"},"datePublished":"2012-09-27T08:47:57+00:00","author":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"breadcrumb":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/ricerca-e-sviluppo\/v-edizione-conferenza-internazionale-women-and-technologies%25252525252525c2%25252525252525ae-e-nutrition-e-premio-a%2525252525252580cle-tecnovisionarie-%25252525252525c2%25252525252525ae2012a%2525252\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/ricerca-e-sviluppo\/v-edizione-conferenza-internazionale-women-and-technologies%25252525252525c2%25252525252525ae-e-nutrition-e-premio-a%2525252525252580cle-tecnovisionarie-%25252525252525c2%25252525252525ae2012a%2525252\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/ricerca-e-sviluppo\/v-edizione-conferenza-internazionale-women-and-technologies%25252525252525c2%25252525252525ae-e-nutrition-e-premio-a%2525252525252580cle-tecnovisionarie-%25252525252525c2%25252525252525ae2012a%2525252\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.article-marketing.eu\/comunicati\/"},{"@type":"ListItem","position":2,"name":"Conferenza Internazionale Women&#038;Technologies\u00ae: e-Nutrition e Premio \u201cLe Tecnovisionarie \u00ae2012\u201d"}]},{"@type":"WebSite","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website","url":"https:\/\/www.article-marketing.eu\/comunicati\/","name":"Article Marketing","description":"article marketing &amp; press release","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.article-marketing.eu\/comunicati\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017","name":"Redazione Comunicati Stampa","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","caption":"Redazione Comunicati Stampa"},"url":"https:\/\/www.article-marketing.eu\/comunicati\/author\/redazione-comunicati-stampa\/"}]}},"_links":{"self":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/29542","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/comments?post=29542"}],"version-history":[{"count":0,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/29542\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/media?parent=29542"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/categories?post=29542"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/tags?post=29542"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}