{"id":29711,"date":"2012-10-05T09:26:27","date_gmt":"2012-10-05T07:26:27","guid":{"rendered":"http:\/\/www.article-marketing.eu\/comunicati\/senza-categoria\/openjournalist-racconta-la-realt%2525c3%2525a0-come-la-vivi-tu\/"},"modified":"2018-07-10T05:50:10","modified_gmt":"2018-07-10T03:50:10","slug":"openjournalist-racconta-la-realt%2525c3%2525a0-come-la-vivi-tu","status":"publish","type":"post","link":"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/giornalismo\/openjournalist-racconta-la-realt%2525c3%2525a0-come-la-vivi-tu\/","title":{"rendered":"OPENJOURNALIST &#8211; Racconta la realt\u00e0, come la vivi tu!"},"content":{"rendered":"<p> OpenJournalist &egrave; un progetto di giornalismo partecipativo, libero e indipendente, nato per dare sfogo a tutte quelle idee rifugiate nei milioni di blog sparsi in tutto il mondo.<br \/>Previa una semplice registrazione gratuita, OpenJournalist permette agli utenti di scrivere articoli sulle pi&ugrave; svariate categorie, di condividerli e commentarli, di scambiare idee, pareri e opinioni con i membri della community, partecipando attivamente a questa nuova forma di democrazia mediatica.<br \/>Ad ogni utente &egrave; assegnata una pagina personale che raccoglier&agrave; i propri articoli, diffusi nel web attraverso gli strumenti forniti di base dalla piattaforma, che garantir&agrave; anche un privilegiato posizionamento nei motori di ricerca; a ciascuno poi la possibilit&agrave; di condividerli sui social network per incrementarne la visibilit&agrave;.<br \/>OpenJouralist si propone come sintesi tra le tre grandi sfere della comunicazione\/informazione su internet, ponendosi l&#8217;obiettivo dar visibilit&agrave; agli utenti e annullare la frammentazione delle informazioni e delle notizie che sono distribuite in una infinit&agrave; di spazi &#8220;personali&#8221;.<br \/>Allora, non ci resta che aspettarvi su <a href=\"http:\/\/www.openjournalist.com\" target=\"_self\" title=\"OpenJournalist\">www.openjournalist.com<\/a><\/p>\n<p>Chi siamo<br \/>\nQuante volte guardando il telegiornale o anche leggendo il giornale avete sentito quella sensazione di impotenza, vi siete domandati se &egrave; tutto qui, se la verit&agrave; delle cose &egrave; altrove, se il conformismo ideologico ci sta gradualmente rendendo spettatori passivi nel processo di informazione\/disinformazione sociale?<br \/> Questa &egrave; la tua occasione per far sentire la tua voce! Esci allo scoperto, denuncia le tue preoccupazioni, i tuoi dubbi, le tue perplessit&agrave; e partecipa attivamente alla condivisione della conoscenza.<br \/>\nOpenJournalist &egrave; stato realizzato da quattro ragazzi per dare sfogo a tutte quelle idee rifugiate nei milioni di blog sparsi in tutto il mondo, per dare voce a tutti quei pensieri che, come il tuo, si celano dietro l&rsquo;impossibilit&agrave; mediatica di mostrarsi di fronte ad un pubblico ampio. Grazie ad internet e al meccanismo del social network non &egrave; piu cosi!<br \/>\nCrea la tua schiera di lettori e racconta la tua realt&agrave;!!!<br \/>\nLa storia<br \/>\nL&rsquo;idea di OpenJournalist nasce nel 2007. Da anni nell&rsquo;aria c&rsquo;era sentore di novit&agrave; per quanto riguardava l&rsquo;informazione libera e di dominio pubblico. Molti fatti accaduti e riportati dalle testate giornalistiche ufficiali si contraddicevano a vicenda lasciando perplessit&agrave; ed esitazione sull&rsquo;affidabilit&agrave; delle notizie e sull&rsquo;intera credibilit&agrave; del sistema informativo. Blog, siti internet, forum vengono letteralmente invasi da commenti, relazioni o semplici sfoghi post-traumatici di chi vuol far sentire la propria opinione, il proprio dissenso verso chi crede di avere a che fare con delle menti passive, incapaci di reagire solo perch&eacute; al di l&agrave; di uno schermo o davanti a un semplice foglio.<br \/>\nEd &egrave; in questo campo che si muove OpenJournalist, nell&rsquo;unico spazio dove le idee di massa possono circolare liberamente: il web.<br \/>\nDare la possibilit&agrave; a tutti di scrivere un proprio articolo, confrontarsi con una community attiva e sensibile agli eventi che la circondano, mettere al servizio del popolo di internet un bagaglio culturale e veritiero senza precedenti.<br \/>\nQuesto &egrave; l&rsquo;obiettivo di OpenJournalist&hellip; e come avrebbe detto un Bob Dylan dell&rsquo;era digitale:<br \/> <em>&#8220;The answer is blowin&#8217; in the web!!!&#8221;<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>OpenJournalist \u00e8 un progetto di giornalismo partecipativo, libero e indipendente, nato per dare sfogo a tutte quelle idee rifugiate nei milioni di blog sparsi in tutto il mondo.<br \/>Previa una semplice registrazione gratuita, OpenJournalist permette agli utenti di scrivere articoli sulle pi\u00f9 svariate categorie, di condividerli e commentarli, di scambiare idee, pareri e opinioni con i membri della community, partecipando attivamente a questa nuova forma di democrazia mediatica.<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"","footnotes":""},"categories":[218],"tags":[38628,38626,6135,37137,38625,38624,85,38627,806],"class_list":["post-29711","post","type-post","status-publish","format-standard","hentry","category-giornalismo","tag-berlusconi","tag-bersani","tag-giornalismo-partecipativo","tag-grillo","tag-open-jornalist","tag-openjournalist","tag-politica","tag-renzi","tag-tv"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>OPENJOURNALIST - Racconta la realt\u00e0, come la vivi tu! - Article Marketing<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/giornalismo\/openjournalist-racconta-la-realt%25c3%25a0-come-la-vivi-tu\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"OPENJOURNALIST - Racconta la realt\u00e0, come la vivi tu! - Article Marketing\" \/>\n<meta property=\"og:description\" content=\"OpenJournalist \u00e8 un progetto di giornalismo partecipativo, libero e indipendente, nato per dare sfogo a tutte quelle idee rifugiate nei milioni di blog sparsi in tutto il mondo.Previa una semplice registrazione gratuita, OpenJournalist permette agli utenti di scrivere articoli sulle pi\u00f9 svariate categorie, di condividerli e commentarli, di scambiare idee, pareri e opinioni con i membri della community, partecipando attivamente a questa nuova forma di democrazia mediatica.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/giornalismo\/openjournalist-racconta-la-realt%25c3%25a0-come-la-vivi-tu\/\" \/>\n<meta property=\"og:site_name\" content=\"Article Marketing\" \/>\n<meta property=\"article:published_time\" content=\"2012-10-05T07:26:27+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-07-10T03:50:10+00:00\" \/>\n<meta name=\"author\" content=\"Redazione Comunicati Stampa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione Comunicati Stampa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/arte-e-cultura\\\/giornalismo\\\/openjournalist-racconta-la-realt%2525c3%2525a0-come-la-vivi-tu\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/arte-e-cultura\\\/giornalismo\\\/openjournalist-racconta-la-realt%2525c3%2525a0-come-la-vivi-tu\\\/\"},\"author\":{\"name\":\"Redazione Comunicati Stampa\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"headline\":\"OPENJOURNALIST &#8211; Racconta la realt\u00e0, come la vivi tu!\",\"datePublished\":\"2012-10-05T07:26:27+00:00\",\"dateModified\":\"2018-07-10T03:50:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/arte-e-cultura\\\/giornalismo\\\/openjournalist-racconta-la-realt%2525c3%2525a0-come-la-vivi-tu\\\/\"},\"wordCount\":545,\"commentCount\":0,\"keywords\":[\"berlusconi\",\"bersani\",\"giornalismo partecipativo\",\"grillo\",\"open jornalist\",\"openjournalist\",\"politica\",\"renzi\",\"tv\"],\"articleSection\":[\"Giornalismo\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/arte-e-cultura\\\/giornalismo\\\/openjournalist-racconta-la-realt%2525c3%2525a0-come-la-vivi-tu\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/arte-e-cultura\\\/giornalismo\\\/openjournalist-racconta-la-realt%2525c3%2525a0-come-la-vivi-tu\\\/\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/arte-e-cultura\\\/giornalismo\\\/openjournalist-racconta-la-realt%2525c3%2525a0-come-la-vivi-tu\\\/\",\"name\":\"OPENJOURNALIST - Racconta la realt\u00e0, come la vivi tu! - Article Marketing\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\"},\"datePublished\":\"2012-10-05T07:26:27+00:00\",\"dateModified\":\"2018-07-10T03:50:10+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/arte-e-cultura\\\/giornalismo\\\/openjournalist-racconta-la-realt%2525c3%2525a0-come-la-vivi-tu\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/arte-e-cultura\\\/giornalismo\\\/openjournalist-racconta-la-realt%2525c3%2525a0-come-la-vivi-tu\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/arte-e-cultura\\\/giornalismo\\\/openjournalist-racconta-la-realt%2525c3%2525a0-come-la-vivi-tu\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"OPENJOURNALIST &#8211; Racconta la realt\u00e0, come la vivi tu!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\",\"name\":\"Article Marketing\",\"description\":\"article marketing &amp; press release\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\",\"name\":\"Redazione Comunicati Stampa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"caption\":\"Redazione Comunicati Stampa\"},\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/author\\\/redazione-comunicati-stampa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"OPENJOURNALIST - Racconta la realt\u00e0, come la vivi tu! - Article Marketing","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/giornalismo\/openjournalist-racconta-la-realt%25c3%25a0-come-la-vivi-tu\/","og_locale":"it_IT","og_type":"article","og_title":"OPENJOURNALIST - Racconta la realt\u00e0, come la vivi tu! - Article Marketing","og_description":"OpenJournalist \u00e8 un progetto di giornalismo partecipativo, libero e indipendente, nato per dare sfogo a tutte quelle idee rifugiate nei milioni di blog sparsi in tutto il mondo.Previa una semplice registrazione gratuita, OpenJournalist permette agli utenti di scrivere articoli sulle pi\u00f9 svariate categorie, di condividerli e commentarli, di scambiare idee, pareri e opinioni con i membri della community, partecipando attivamente a questa nuova forma di democrazia mediatica.","og_url":"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/giornalismo\/openjournalist-racconta-la-realt%25c3%25a0-come-la-vivi-tu\/","og_site_name":"Article Marketing","article_published_time":"2012-10-05T07:26:27+00:00","article_modified_time":"2018-07-10T03:50:10+00:00","author":"Redazione Comunicati Stampa","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione Comunicati Stampa","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/giornalismo\/openjournalist-racconta-la-realt%2525c3%2525a0-come-la-vivi-tu\/#article","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/giornalismo\/openjournalist-racconta-la-realt%2525c3%2525a0-come-la-vivi-tu\/"},"author":{"name":"Redazione Comunicati Stampa","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"headline":"OPENJOURNALIST &#8211; Racconta la realt\u00e0, come la vivi tu!","datePublished":"2012-10-05T07:26:27+00:00","dateModified":"2018-07-10T03:50:10+00:00","mainEntityOfPage":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/giornalismo\/openjournalist-racconta-la-realt%2525c3%2525a0-come-la-vivi-tu\/"},"wordCount":545,"commentCount":0,"keywords":["berlusconi","bersani","giornalismo partecipativo","grillo","open jornalist","openjournalist","politica","renzi","tv"],"articleSection":["Giornalismo"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/giornalismo\/openjournalist-racconta-la-realt%2525c3%2525a0-come-la-vivi-tu\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/giornalismo\/openjournalist-racconta-la-realt%2525c3%2525a0-come-la-vivi-tu\/","url":"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/giornalismo\/openjournalist-racconta-la-realt%2525c3%2525a0-come-la-vivi-tu\/","name":"OPENJOURNALIST - Racconta la realt\u00e0, come la vivi tu! - Article Marketing","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website"},"datePublished":"2012-10-05T07:26:27+00:00","dateModified":"2018-07-10T03:50:10+00:00","author":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"breadcrumb":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/giornalismo\/openjournalist-racconta-la-realt%2525c3%2525a0-come-la-vivi-tu\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/giornalismo\/openjournalist-racconta-la-realt%2525c3%2525a0-come-la-vivi-tu\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/giornalismo\/openjournalist-racconta-la-realt%2525c3%2525a0-come-la-vivi-tu\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.article-marketing.eu\/comunicati\/"},{"@type":"ListItem","position":2,"name":"OPENJOURNALIST &#8211; Racconta la realt\u00e0, come la vivi tu!"}]},{"@type":"WebSite","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website","url":"https:\/\/www.article-marketing.eu\/comunicati\/","name":"Article Marketing","description":"article marketing &amp; press release","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.article-marketing.eu\/comunicati\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017","name":"Redazione Comunicati Stampa","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","caption":"Redazione Comunicati Stampa"},"url":"https:\/\/www.article-marketing.eu\/comunicati\/author\/redazione-comunicati-stampa\/"}]}},"_links":{"self":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/29711","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/comments?post=29711"}],"version-history":[{"count":1,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/29711\/revisions"}],"predecessor-version":[{"id":62396,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/29711\/revisions\/62396"}],"wp:attachment":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/media?parent=29711"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/categories?post=29711"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/tags?post=29711"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}