{"id":29794,"date":"2012-10-08T22:15:39","date_gmt":"2012-10-08T20:15:39","guid":{"rendered":"http:\/\/www.article-marketing.eu\/comunicati\/senza-categoria\/zuccari-lancia-in-italia-gli-alimenti-funzionali\/"},"modified":"2012-10-08T22:15:39","modified_gmt":"2012-10-08T20:15:39","slug":"zuccari-lancia-in-italia-gli-alimenti-funzionali","status":"publish","type":"post","link":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/prodotti\/zuccari-lancia-in-italia-gli-alimenti-funzionali\/","title":{"rendered":"ZUCCARI LANCIA IN ITALIA GLI ALIMENTI FUNZIONALI"},"content":{"rendered":"<p><a href=\"http:\/\/www.zuccari.com\">Zuccari<\/a>, leader europea nel settore alimentazione e cosmesi naturale, lancia in Italia gli Alimenti Funzionali, la nuova tendenza del benessere che ha gi&agrave; conquistato gli Stati Uniti e i Paesi pi&ugrave; avanzati dell&rsquo;Europa.<br \/>I Functional Food (cos&igrave; sono riconosciuti all&rsquo;estero) stanno avendo un successo planetario e rappresentano una risposta efficace al consumatore che pretende di alimentarsi con qualit&agrave; e non con quantit&agrave;.<\/p>\n<p><strong>QUANTIT&Aacute; E NON QUALIT&Aacute;: IL PROBLEMA DELL&rsquo;ALIMENTAZIONE <\/strong><br \/>L&rsquo;alimentazione contemporanea &egrave; apparentemente ricca, ma spesso dietro il suo aspetto vivace si nasconde un carattere pi&ugrave; povero. Colture intensive, manipolazione genetica e lavorazioni industriali hanno reso la nostra dieta quotidiana povera per le esigenze dell&rsquo;organismo. Anche le pi&ugrave; semplici lavorazioni industriali depauperano gli alimenti. La pastorizzazione, ad esempio, abbatte la carica batterica ma priva il prodotto della sua naturale attivit&agrave;, mentre la raffinazione separa gli elementi nutritivi attivi dal resto dell&rsquo;alimento.<br \/>Queste manipolazioni sono la risposta all&rsquo;esigenza di velocit&agrave; dettata dai ritmi della vita moderna, ma anche dalla necessit&agrave; di commerciabilit&agrave;: un prodotto in grado di resistere a lungo nonostante trasporti, refrigerazioni, permanenza sul punto vendita e nelle case dei consumatori, viene preferito a un prodotto pi&ugrave; naturale e fragile. Allo stesso modo, un prodotto dall&rsquo;aspetto seriale, che si adatti nella forma e nell&rsquo;aspetto alle esigenze di vendita, avr&agrave; sempre pi&ugrave; valore rispetto a un prodotto non omogeneo e pi&ugrave; difficilmente gestibile.<\/p>\n<p><strong style=\"mso-bidi-font-weight: normal;\">SAZIARE E NUTRIRE: UNA DIFFERENZA NOTEVOLE<\/strong><br \/>Lo scopo di queste lavorazioni &egrave; di saziare in tempi contenuti il maggior numero di consumatori, ma saziare non significa nutrire. Frutta e verdura di ogni tipo si trovano tutto l&rsquo;anno, anche fuori stagione ma il loro valore nutrizionale &egrave; misero perch&eacute; non crescono secondo i ritmi della natura e non hanno tempo di assorbire le sostanze nutritive dal terreno, che a sua volta &egrave; sempre pi&ugrave; sfruttato e impoverito. Questi prodotti, refrigerati e trasportati in tutto il mondo e resi appetibili attraverso trattamenti aggressivi, vengono quindi consumati troppo acerbi o troppo maturi.<br \/>Inoltre, i trattamenti anti-parassitari rendono le piante sempre pi&ugrave; forti e resistenti all&rsquo;attacco di batteri e parassiti i quali si fortificano a loro volta, richiedendo l&rsquo;utilizzo di prodotti sempre pi&ugrave; aggressivi e innescando un vero e proprio circolo vizioso.<\/p>\n<p><strong style=\"mso-bidi-font-weight: normal;\">SCARSO NUTRIMENTO: OGGI IL CONSUMATORE SA E CHIEDE DI PI&ugrave;<\/strong><br \/>Negli ultimi anni per&ograve;, i consumatori si sono dimostrati sensibili a questo fenomeno e si stanno indirizzando sempre di pi&ugrave; alla scelta del nutrimento nel vero senso del termine, senza rinunciare alla praticit&agrave; che, al giorno d&rsquo;oggi, &egrave; fondamentale. Ecco quindi che il mercato degli integratori alimentari diventa un trend in crescita, soprattutto se a esso viene dato un appeal pi&ugrave; alimentare e meno farmaceutico.<\/p>\n<p><strong style=\"mso-bidi-font-weight: normal;\">IL FUNCTIONAL FOOD: LA RIVOLUZIONE DELL&rsquo;INTEGRATORE <\/strong><br \/>Sta crescendo nel mondo il successo dei cosiddetti Alimenti Funzionali (o <em style=\"mso-bidi-font-style: normal;\">Functional Food<\/em>) ovvero alimenti gi&agrave; naturalmente ricchi di particolari attivi, lavorati con grande attenzione in modo da non comprometterne l&rsquo;apporto benefico e, quando possibile, arricchiti ulteriormente con vitamine o attivi. Sono il futuro della nutrizione, in perfetto equilibrio fra l&rsquo;integrazione alimentare e la dieta quotidiana, un vero e proprio boom che non accenna a diminuire negli Stati Uniti e che si sta espandendo in Europa attirando molto interesse sia fra i consumatori che fra gli operatori del settore: dati Mintel evidenziano un valore di mercato, per quanto riguarda gli Alimenti Funzionali, che raggiunger&agrave; in Europa la quota stimata di 1.420 milioni di euro entro il 2016.<\/p>\n<p><strong style=\"mso-bidi-font-weight: normal;\">PER IL CONSUMATORE SOLO VANTAGGI<\/strong><br \/>Gli alimenti funzionali presentano molti vantaggi tutt&rsquo;altro che trascurabili per il consumatore: in un solo gesto egli introduce nutrimento, appaga il gusto, ritrova l&rsquo;efficacia trattante della natura, senza rinunciare alle abitudini moderne.<br \/>L&rsquo;alimento funzionale garantisce:<br \/>&#8211; &#8211; Lo stesso gusto e la stessa carica vitaminica del frutto fresco, ma in ogni mese dell&rsquo;anno senza alcuna diminuzione della qualit&agrave; e con la massima praticit&agrave; di assunzione.<br \/><strong style=\"mso-bidi-font-weight: normal;\"> <\/strong><br \/>&#8211; &#8211; La praticit&agrave;, la piacevolezza e la convenienza di un succo di frutta, ma senza l&rsquo;aggiunta di acqua e zucchero e senza la pastorizzazione che distrugge i principi attivi termolabili.<\/p>\n<p>&#8211; &#8211; Un&rsquo;efficacia superiore a quella degli integratori vitaminici o fitoterapici che &ndash; tra l&rsquo;altro &#8211; hanno spesso un gusto poco gradevole e risultano quindi poco appetibili e incentivanti.<\/p>\n<p>&#8211; &#8211; Niente zuccheri aggiunti, ma solo dell&rsquo;ottimo sucralosio, il dolcificante a zero calorie; niente OGM, niente glutine n&egrave; altri allergeni; basso contenuto di carboidrati. <\/p>\n<p><strong style=\"mso-bidi-font-weight: normal;\"> <\/strong><br \/><strong style=\"mso-bidi-font-weight: normal;\">I PRIMI FUNCTIONAL FOOD: SUPER ARANCIA&reg; E SUPER ANANAS&reg;<\/strong><br \/>Dall&rsquo;analisi attenta del mercato e delle abitudini dei consumatori &egrave; nata <strong style=\"mso-bidi-font-weight: normal;\">Functional Food Division <\/strong>di Zuccari, creata per rispondere in modo appropriato alla crescente domanda di <strong>Alimenti Funzionali ovvero <\/strong>alimenti &#8211; gi&agrave; ricchi in origine di particolari attivi &#8211; che vengono<strong> <\/strong>lavorati attentamente per preservarne l&rsquo;apporto benefico e talvolta addizionati con vitamine o attivi. Nascono cos&igrave; Super Arancia&reg; e Super Ananas&reg; i primi alimenti funzionali del mercato italiano.<\/p>\n<p><strong style=\"mso-bidi-font-weight: normal;\">SUPER ARANCIA&reg;: IL GUSTO E LA SALUTE DI 6 ARANCE SPREMUTE<\/strong><br \/>Le arance, si sa, sono ricche di vitamina C ed &egrave; buona norma iniziare la giornata introducendo nella prima colazione una spremuta di questo agrume, spesso per&ograve; il nostro stile di vita non ci permette di farlo con continuit&agrave;. Ecco quindi che, in risposta alla crescente domanda dei cosiddetti Alimenti Funzionali, gi&agrave; naturalmente ricchi di particolari attivi, la Functional Food Division di Zuccari crea Super Arancia&reg;, il nuovo l&rsquo;integratore alimentare che racchiude tutta la piacevolezza di una sana spremuta e la comodit&agrave; degli stick-pack pronti all&rsquo;uso e da portare sempre con s&egrave;.<br \/>Ogni stick-pack di Super Arancia&reg; contiene:<br \/>&#8211; <strong style=\"mso-bidi-font-weight: normal;\">500mg di vitamina C, pari a quella media contenuta in 6 arance,<\/strong> ovvero il 625% della RDA;<br \/>&#8211; l&rsquo;esclusivo mix <strong style=\"mso-bidi-font-weight: normal;\">TR3chinacea&reg; con 3 variet&agrave; di <\/strong>Echinacea (Echinacea Angustifolia, Echinacea Pallida Britton e Purpurea Moench)<br \/>&#8211; <strong style=\"mso-bidi-font-weight: normal;\">22,5mg di zinco, pari al 225% della RDA<\/strong>, essenziale per riportare in equilibrio il sistema immunitario e affrontare le quattro stagioni con le difese necessarie.<br \/>Super Arancia&reg; si scioglie in 100 ml d&rsquo;acqua e pu&ograve; essere consumato ogni mattina a colazione, proprio come una spremuta d&rsquo;arancia fresca della quale ha tutto il sapore: un ottimo modo per iniziare la giornata con una sana abitudine alimentare.<br \/><strong style=\"mso-bidi-font-weight: normal;\"> <\/strong><br \/><strong style=\"mso-bidi-font-weight: normal;\">SUPER ANANAS&reg;: IN POCHI MESI, UN SUCCESSO ASSOLUTO<\/strong><br \/>Il frutto fresco dell&rsquo;ananas ha riconosciute propriet&agrave; digestive e snellenti: esso aiuta a combattere ritenzione e accumuli sottocutanei localizzati, contrasta gonfiore e pesantezza. In pi&ugrave; &egrave; molto gustoso e piacevole. Ci&ograve; nononostante, l&rsquo;ananas fresco viene di rado introdotto nella dieta quotidiana perch&eacute; poco pratico e di difficile reperibilit&agrave;. Allo stesso modo, gli integratori alimentari a base di ananas non sembrano avere conquistato il consumatore.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Si chiamano Super Arancia\u00ae e Super Ananas\u00ae e sono i primi Alimenti Funzionali italiani. Nati nella Functional Food Division dell\u2019impresa fondata da Stefano Sala, essi rispondono al boom di richieste di prodotti di un\u2019alimentazione di qualit\u00e0 e non di quantit\u00e0. Si tratta di alimenti ricchi di attivi sin dall\u2019origine, gustosi, salutari e di facilissima assunzione in qualunque luogo e momento della giornata. No zuccheri aggiunti, no OGM, no glutine e altri allergeni<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"","footnotes":""},"categories":[212],"tags":[38679,38678,38676,38677,27580],"class_list":["post-29794","post","type-post","status-publish","format-standard","hentry","category-prodotti","tag-alimenti-funzionali","tag-functional-food","tag-super-ananas","tag-super-arancia","tag-zuccari"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>ZUCCARI LANCIA IN ITALIA GLI ALIMENTI FUNZIONALI - Article Marketing<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/prodotti\/zuccari-lancia-in-italia-gli-alimenti-funzionali\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ZUCCARI LANCIA IN ITALIA GLI ALIMENTI FUNZIONALI - Article Marketing\" \/>\n<meta property=\"og:description\" content=\"Si chiamano Super Arancia\u00ae e Super Ananas\u00ae e sono i primi Alimenti Funzionali italiani. Nati nella Functional Food Division dell\u2019impresa fondata da Stefano Sala, essi rispondono al boom di richieste di prodotti di un\u2019alimentazione di qualit\u00e0 e non di quantit\u00e0. Si tratta di alimenti ricchi di attivi sin dall\u2019origine, gustosi, salutari e di facilissima assunzione in qualunque luogo e momento della giornata. No zuccheri aggiunti, no OGM, no glutine e altri allergeni\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/prodotti\/zuccari-lancia-in-italia-gli-alimenti-funzionali\/\" \/>\n<meta property=\"og:site_name\" content=\"Article Marketing\" \/>\n<meta property=\"article:published_time\" content=\"2012-10-08T20:15:39+00:00\" \/>\n<meta name=\"author\" content=\"Redazione Comunicati Stampa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione Comunicati Stampa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/prodotti\\\/zuccari-lancia-in-italia-gli-alimenti-funzionali\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/prodotti\\\/zuccari-lancia-in-italia-gli-alimenti-funzionali\\\/\"},\"author\":{\"name\":\"Redazione Comunicati Stampa\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"headline\":\"ZUCCARI LANCIA IN ITALIA GLI ALIMENTI FUNZIONALI\",\"datePublished\":\"2012-10-08T20:15:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/prodotti\\\/zuccari-lancia-in-italia-gli-alimenti-funzionali\\\/\"},\"wordCount\":1194,\"commentCount\":0,\"keywords\":[\"alimenti funzionali\",\"functional food\",\"super ananas\",\"super arancia\",\"zuccari\"],\"articleSection\":[\"Prodotti\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/prodotti\\\/zuccari-lancia-in-italia-gli-alimenti-funzionali\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/prodotti\\\/zuccari-lancia-in-italia-gli-alimenti-funzionali\\\/\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/prodotti\\\/zuccari-lancia-in-italia-gli-alimenti-funzionali\\\/\",\"name\":\"ZUCCARI LANCIA IN ITALIA GLI ALIMENTI FUNZIONALI - Article Marketing\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\"},\"datePublished\":\"2012-10-08T20:15:39+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/prodotti\\\/zuccari-lancia-in-italia-gli-alimenti-funzionali\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/prodotti\\\/zuccari-lancia-in-italia-gli-alimenti-funzionali\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/prodotti\\\/zuccari-lancia-in-italia-gli-alimenti-funzionali\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ZUCCARI LANCIA IN ITALIA GLI ALIMENTI FUNZIONALI\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\",\"name\":\"Article Marketing\",\"description\":\"article marketing &amp; press release\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\",\"name\":\"Redazione Comunicati Stampa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"caption\":\"Redazione Comunicati Stampa\"},\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/author\\\/redazione-comunicati-stampa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ZUCCARI LANCIA IN ITALIA GLI ALIMENTI FUNZIONALI - Article Marketing","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/prodotti\/zuccari-lancia-in-italia-gli-alimenti-funzionali\/","og_locale":"it_IT","og_type":"article","og_title":"ZUCCARI LANCIA IN ITALIA GLI ALIMENTI FUNZIONALI - Article Marketing","og_description":"Si chiamano Super Arancia\u00ae e Super Ananas\u00ae e sono i primi Alimenti Funzionali italiani. Nati nella Functional Food Division dell\u2019impresa fondata da Stefano Sala, essi rispondono al boom di richieste di prodotti di un\u2019alimentazione di qualit\u00e0 e non di quantit\u00e0. Si tratta di alimenti ricchi di attivi sin dall\u2019origine, gustosi, salutari e di facilissima assunzione in qualunque luogo e momento della giornata. No zuccheri aggiunti, no OGM, no glutine e altri allergeni","og_url":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/prodotti\/zuccari-lancia-in-italia-gli-alimenti-funzionali\/","og_site_name":"Article Marketing","article_published_time":"2012-10-08T20:15:39+00:00","author":"Redazione Comunicati Stampa","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione Comunicati Stampa","Tempo di lettura stimato":"6 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/prodotti\/zuccari-lancia-in-italia-gli-alimenti-funzionali\/#article","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/prodotti\/zuccari-lancia-in-italia-gli-alimenti-funzionali\/"},"author":{"name":"Redazione Comunicati Stampa","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"headline":"ZUCCARI LANCIA IN ITALIA GLI ALIMENTI FUNZIONALI","datePublished":"2012-10-08T20:15:39+00:00","mainEntityOfPage":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/prodotti\/zuccari-lancia-in-italia-gli-alimenti-funzionali\/"},"wordCount":1194,"commentCount":0,"keywords":["alimenti funzionali","functional food","super ananas","super arancia","zuccari"],"articleSection":["Prodotti"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/prodotti\/zuccari-lancia-in-italia-gli-alimenti-funzionali\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/prodotti\/zuccari-lancia-in-italia-gli-alimenti-funzionali\/","url":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/prodotti\/zuccari-lancia-in-italia-gli-alimenti-funzionali\/","name":"ZUCCARI LANCIA IN ITALIA GLI ALIMENTI FUNZIONALI - Article Marketing","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website"},"datePublished":"2012-10-08T20:15:39+00:00","author":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"breadcrumb":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/prodotti\/zuccari-lancia-in-italia-gli-alimenti-funzionali\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/prodotti\/zuccari-lancia-in-italia-gli-alimenti-funzionali\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/prodotti\/zuccari-lancia-in-italia-gli-alimenti-funzionali\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.article-marketing.eu\/comunicati\/"},{"@type":"ListItem","position":2,"name":"ZUCCARI LANCIA IN ITALIA GLI ALIMENTI FUNZIONALI"}]},{"@type":"WebSite","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website","url":"https:\/\/www.article-marketing.eu\/comunicati\/","name":"Article Marketing","description":"article marketing &amp; press release","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.article-marketing.eu\/comunicati\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017","name":"Redazione Comunicati Stampa","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","caption":"Redazione Comunicati Stampa"},"url":"https:\/\/www.article-marketing.eu\/comunicati\/author\/redazione-comunicati-stampa\/"}]}},"_links":{"self":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/29794","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/comments?post=29794"}],"version-history":[{"count":0,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/29794\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/media?parent=29794"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/categories?post=29794"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/tags?post=29794"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}