{"id":30003,"date":"2012-10-15T15:28:40","date_gmt":"2012-10-15T13:28:40","guid":{"rendered":"http:\/\/www.article-marketing.eu\/comunicati\/senza-categoria\/viscom-italia-2012-rinnova-il-business-della-comunicazione-visiva\/"},"modified":"2012-10-15T15:28:40","modified_gmt":"2012-10-15T13:28:40","slug":"viscom-italia-2012-rinnova-il-business-della-comunicazione-visiva","status":"publish","type":"post","link":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/marketing\/viscom-italia-2012-rinnova-il-business-della-comunicazione-visiva\/","title":{"rendered":"Viscom Italia 2012. Rinnova il business della comunicazione visiva"},"content":{"rendered":"<p><a><\/a><a><em>Dinamicit&agrave;, ottimismo e condivisione sono stati gli ingredienti per oltre 17.000 visitatori che hanno colto vantaggiose opportunit&agrave; per un concreto investimento nel futuro della propria azienda.<\/em><\/a><\/p>\n<p>Milano, 15 ottobre 2012 &#8211; In uno scenario di grande trasformazione dove le modalit&agrave; di consumo, le tecniche di informazione e di comunicazione sono in continua evoluzione, il linguaggio visivo rimane il pi&ugrave; potente dei mezzi per arrivare ai propri clienti. Un messaggio chiaro che ha caratterizzato la 24a edizione di Viscom Italia, fiera leader in Europa della comunicazione visiva in programma dal 4 al 6 ottobre, che ha chiuso il sipario registrando 17.009 visitatori. Viscom Italia, pur in un anno complicato per l&#8217;economia europea, continua a rappresentare un appuntamento immancabile e di riferimento per i professionisti del settore.<br \/>\nGrande soddisfazione da parte delle aziende espositrici che hanno scelto ancora una volta come palcoscenico Viscom Italia per raccontare l&rsquo;intera filiera della produzione e della distribuzione della comunicazione visiva in materia di: Insegnistica, Cartellonistica, Stampa Grande Formato, Serigrafia &#8211; Tampografia &#8211; Ricamo &#8211; Incisione &#8211; Fresatura &#8211; Laser &ndash; Packaging &#8211; Labelling Digital Signage &#8211; P.O.P.<br \/> Molti i prodotti, materiali, soluzioni e applicazioni che hanno raccontato una nuova modalit&agrave; di espressione di tutto il settore diventando strumenti duttili e facilmente personalizzabili in grado di venire incontro alle esigenze di molteplici settori, che sempre di pi&ugrave; necessitano delle soluzioni della comunicazione visiva per esprimere al meglio il proprio brand, come il mondo dell&rsquo;architettura, del design, della decorazione di interni, del punto vendita sino alla moda, orgoglio del made in Italy.<br \/>\n<em>&ldquo;Sono molto orgogliosa del risultato di questa rinnovata edizione e della positivit&agrave; che si respirava nei padiglioni da parte di espositori e visitatori &ndash; <\/em>dichiara Paola Sarco, Exhibition Manager di Viscom Italia<em>. Viscom conferma il suo ruolo di fiera dove si ha il piacere di incontrarsi e dove l&rsquo;energia e la voglia di fare si percepiscono nell&rsquo;aria, specialmente in questo momento di transizione economica. Il punto di forza di questa edizione &egrave; stata la capacit&agrave; di presentare nuove contaminazioni ancora inesplorate della comunicazione visiva per creare una vera condivisione di idee e valorizzare le nuove sfide del mercato&rdquo;.<\/em><br \/>\nL&rsquo;affluenza di pubblico conferma l&rsquo;importanza dei consueti appuntamenti tra i quali i <strong>Viscom Forum,<\/strong> trasformati in un vero pantheon deputato all&rsquo;educazione della comunicazione visiva, che hanno proposto 12 seminari con un totale di 823 partecipanti. Un confronto diretto di esperienze hanno messo in luce svariati temi quali: le tecniche di post produzione per la fotografia e l&rsquo;architettura, al rilancio degli spazi dedicati all&rsquo;arte, ai musei, ai teatri fino ad approdare le tecnologie interattive per il punto vendita trasformandoli in spazi multicanali per rilanciare il mercato della grande distribuzione. Il fascino del dietro le quinte di una sfilata valorizzata sempre di pi&ugrave; da soluzioni prese dal comparto del digital signage alle nuove tecniche di stampa e di reconvering che hanno proposto nuove opportunit&agrave; per il reparto dell&rsquo;interior decoration, fino ad arrivare all&rsquo;utilizzo delle immagini per creare una presentazione ad alto impatto visivo e infine la conoscenza delle nuove tecnologie disponibili per mostrare le loro potenzialit&agrave; e reinventare cos&igrave; lavoro, mercato, prodotti o servizi. Anche quest&rsquo;anno il palinsesto dei Forum &egrave; stato realizzato con il coordinamento scientifico a cura del MIP Politecnico di Milano dando cos&igrave; una nuova visione della cultura del fare comunicazione.<br \/>\n Una panoramica completa su quanto pu&ograve; offrire il mercato ma anche un&rsquo;occasione di confronto per trovare nuovi stimoli &egrave; arrivato dall&rsquo;affollatissimo <strong>ViscomLab, <\/strong>l&rsquo;area di dimostrazioni &#8220;live&#8221; dove &egrave; stato possibile sperimentare, con la guida dei professionisti del settore, nuove applicazioni e soluzioni esclusive ed ispirarsi a nuove idee per il lavoro di tutti i giorni. Dalle innovazioni tridimensionali della stampa sublimatica per personalizzare cover per Iphone, alla serigrafia di effetto per dare un tocco fashion alle stampe su t-shirt, dalle nuove tecniche di stampa con plotter eco solventi per soddisfare le richieste del mondo del packaging fino ad arrivare ad uno scenografico allestimento di affreschi digitali per rilanciare le potenzialit&agrave; delle tecnologia.<br \/>\n Condividere strumenti, idee, processi, esperienze, dati, relazioni, sono le parole chiave che riflettono i protagonisti dell&rsquo;innovazione tecnologica e tutti gli attori legati ai processi della comunicazione. Fino a ieri le redini del progetto erano saldamente nelle mani di chi la comunicazione la pensa e la produce, oggi i modelli della rete e della reciprocit&agrave; stanno ridisegnando lo scambio di informazioni e contenuti. Cittadini e consumatori si organizzano in comunit&agrave; che tracciano percorsi autonomi, sviluppano input originali e imparano a crescere ed allearsi acquistando peso nella societ&agrave;. Sulla base di questa nuova rivoluzione si &egrave; costruito il pensiero dell&rsquo;iniziativa <strong>Viscom Makers Campus by Roland Experience Day.<\/strong> Il vasto pubblico ha potuto cos&igrave; ammirare le soluzioni non standardizzate e gli oggetti creati con le tecnologie open source nelle 6 aree tematiche dell&rsquo;evento: <br \/> dall&rsquo;abbigliamento, alle applicazioni Wow non convenzionali, da sistemi interattivi di Arduino: VIC (Visual Interactive Communication) alle moderne tecniche dell&rsquo;incisoria per chiudere con l&rsquo; interior design e l&rsquo;automotive.<br \/>\n Anche lo spazio <strong>Material Connexion Italia<em> <\/em><\/strong>&egrave; stato seguito<strong><em> <\/em><\/strong>con grande attenzione da designer, architetti, progettisti ma anche stampatori e grafici che si sono documentati nella scelta di <strong> materiali e processi produttivi innovativi e sostenibili,<\/strong><strong> <\/strong>grazie ad gamma di inchiostri, pigmenti, adesivi, pellicole, fogli, pannelli, filati, trattamenti e prodotti tessili, oltre a processi e tecnologie mai utilizzati prima per la com<br \/>\nGrande entusiasmo e curiosit&agrave; per la prima vetrina delle eccellenze della comunicazione visiva firmata <strong>Viscom Boutique<\/strong>. Un nuovo modello di shopping experience, un insieme di punti vendita originali, personalizzati con l&rsquo;utilizzo di innovative applicazioni che hanno permesso di trasformare qualsiasi superficie in uno spazio accogliente e di grande impatto visivo. Quattro boutique con diverse tipologie di decorazione: una cioccolateria arredata dagli elementi di design realizzati con le pluripremiate tecnologie di taglio dell&rsquo;azienda <strong>Zund<\/strong>, una boutique lingerie personalizzata dalle decorazioni a parete in transfer digitali di <strong>ShockLine<\/strong>, un negozio coiffeur e e di accessori moda vivacizzate dalle immagini royalty free di <strong>Fotolia<\/strong> stampate in grande formato da <strong>FujiFilm<\/strong>. <br \/> Un esempio di decorazioni per rendere ogni esperienza d&#8217;acquisto coinvolgente, multisensoriale e seducente, completato dalle prestigiose insegne luminose di <strong>Nova Sign Production<\/strong> e dai capi di abbigliamento decorati di strass realizzati con gli incisori computerizzati di <strong>Roland DG Mid Europe<\/strong>. <br \/> Hanno personalizzato l&rsquo;atmosfera gli arredi di Colico, Dival, FuturProject, gli accessori moda di WMilano e il cioccolato T&rsquo;A. Stampatori, serigrafi, insegnisti ma anche direttori commerciali, retailers, marketing manager, shop designer, architetti, imprenditori e agenzie di comunicazione hanno cos&igrave; potuto vedere tutte le novit&agrave; disponibili per rifare il look al proprio brand.<br \/>\nComunicare rispettando l&rsquo;ambiente! L&#8217;appuntamento di quest&#8217;anno &egrave; stato pi&ugrave; che mai all&#8217;insegna della sostenibilit&agrave;, grazie all&#8217;adesione del progetto Impatto Zero&reg; di LifeGate, il primo che in Italia ha concretizzato le direttive del Protocollo di Kyoto, le emissioni di CO2 dell&#8217;evento generate dai consumi energetici, dalla produzione di rifiuti e dall&rsquo;utilizzo di carta saranno compensate con la creazione e tutela di oltre 81.000 mq di foreste in crescita in Bolivia. Viscom Italia ha presentato <strong>Green Trail<\/strong>: un percorso all&#8217;interno della fiera per valorizzare le aziende che hanno prodotti, soluzioni e tecnologie certificate volte al risparmio energetico e all&rsquo;ecosostenibilit&agrave;. Tra le realt&agrave; che hanno partecipato all&rsquo;iniziativa: <strong>Bompan<\/strong>, importatore esclusivo Mimaki in Italia, con nuove stampanti a risparmio energetico; <strong>Cielle<\/strong>, che tra i nuovi prodotti ha lanciato Sigma Green, nuova tavola da taglio ed incisione laser CO2 progettata per ridurre gli sprechi dei materiali ed abbassare il consumo energetico; <br \/> <strong>Hewlett-Packard Italiana<\/strong> con le ultime stampanti con inchiostri a base acqua, senza contenuto di solvente, a prova di VOC; i componenti a basso impatto di <strong>Roland DG Mid Europe<\/strong>, azienda certificata Eco Label&reg;, infine <strong>Zund<\/strong> e i suoi mobili in cartone, 100 per cento sostenibili, personalizzabili e durevoli.<\/p>\n<p>Condividere strumenti, idee, processi, esperienze, dati, relazioni, sono le parole chiave che riflettono i protagonisti dell&rsquo;innovazione tecnologica e tutti gli attori legati ai processi della comunicazione. Fino a ieri le redini del progetto erano saldamente nelle mani di chi la comunicazione la pensa e la produce, oggi i modelli della rete e della reciprocit&agrave; stanno ridisegnando lo scambio di informazioni e contenuti. Cittadini e consumatori si organizzano in comunit&agrave; che tracciano percorsi autonomi, sviluppano input originali e imparano a crescere ed allearsi acquistando peso nella societ&agrave;. Sulla base di questa nuova rivoluzione si &egrave; costruito il pensiero dell&rsquo;iniziativa <strong>Viscom Makers Campus by Roland Experience Day.<\/strong> Il vasto pubblico ha potuto cos&igrave; ammirare le soluzioni non standardizzate e gli oggetti creati con le tecnologie open source nelle 6 aree tematiche dell&rsquo;evento: <br \/> dall&rsquo;abbigliamento, alle applicazioni Wow non convenzionali, da sistemi interattivi di Arduino: VIC (Visual Interactive Communication) alle moderne tecniche dell&rsquo;incisoria per chiudere con l&rsquo; interior design e l&rsquo;automotive.<br \/>\n Anche lo spazio <strong>Material Connexion Italia<em> <\/em><\/strong>&egrave; stato seguito<strong><em> <\/em><\/strong>con grande attenzione da designer, architetti, progettisti ma anche stampatori e grafici che si sono documentati nella scelta di <strong> materiali e processi produttivi innovativi e sostenibili,<\/strong><strong> <\/strong>grazie ad gamma di inchiostri, pigmenti, adesivi, pellicole, fogli, pannelli, filati, trattamenti e prodotti tessili, oltre a processi e tecnologie mai utilizzati prima per la comunicazione visiva.<\/p>\n<p>Per concludere, nel corso della manifestazione, sono stati assegnati i premi ai vincitori dei due concorsi <strong>Viscom Awards<\/strong>: la seconda edizione di <strong>D.I.V.A. Diva Display Viscom Award<\/strong> competizione sulla creativit&agrave; dei POP Producer e il premio biennale de <strong>&ldquo;Il Bulino d&rsquo;Oro&rdquo;<\/strong> dedicato all&rsquo;industria dell&rsquo;incisione e fresatura leggera.<\/p>\n<p>Viscom Italia non si ferma qui e vi da appuntamento con le nuove date <strong>dal 3 al 5 ottobre<\/strong> <strong>2013<\/strong>,<strong> <\/strong>Fieramilano Rho.<br \/>\n<strong> <\/strong><br \/>\n<em> <\/em><br \/>\n<em>Viscom Italia &egrave; organizzata da Reed Exhibitions, leader mondiale nell&#8217;organizzazione di eventi fieristici, saloni specializzati e congressi che gestisce oltre 500 eventi in 39 Paesi. Nel 2011 Reed ha riunito oltre sei milioni di professionisti appartenenti ai vari comparti industriali di tutto il mondo, creando un giro d&rsquo;affari di miliardi di dollari. Attualmente gli eventi Reed si svolgono nelle Americhe, in Europa, Medio Oriente, Asia Pacifica e Africa e sono organizzati da una rete di 33 uffici con personale altamente qualificato. Reed Exhibitions lavora su 44 settori industriali tra eventi trade e consumer e fa parte del Reed Elsevier Group plc, editore leader mondiale e fornitore di informazioni, e della societ&agrave; FTSE 100.<\/em><\/p>\n<p>Per informazioni:<br \/> Viscom Italia Press Office &ndash; Nicola Mirizio &ndash; Tel. +39 02 435170.61 &ndash; nicola.mirizio@reedexpo.it<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dinamicit\u00e0, ottimismo e condivisione sono stati gli ingredienti per oltre 17.000 visitatori che hanno colto vantaggiose opportunit\u00e0 per un concreto investimento nel futuro della propria azienda.<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"","footnotes":""},"categories":[103],"tags":[38860,1481],"class_list":["post-30003","post","type-post","status-publish","format-standard","hentry","category-marketing","tag-comunicazione-visvia","tag-digital-signage"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Viscom Italia 2012. Rinnova il business della comunicazione visiva - Article Marketing<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/marketing\/viscom-italia-2012-rinnova-il-business-della-comunicazione-visiva\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Viscom Italia 2012. Rinnova il business della comunicazione visiva - Article Marketing\" \/>\n<meta property=\"og:description\" content=\"Dinamicit\u00e0, ottimismo e condivisione sono stati gli ingredienti per oltre 17.000 visitatori che hanno colto vantaggiose opportunit\u00e0 per un concreto investimento nel futuro della propria azienda.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/marketing\/viscom-italia-2012-rinnova-il-business-della-comunicazione-visiva\/\" \/>\n<meta property=\"og:site_name\" content=\"Article Marketing\" \/>\n<meta property=\"article:published_time\" content=\"2012-10-15T13:28:40+00:00\" \/>\n<meta name=\"author\" content=\"Redazione Comunicati Stampa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione Comunicati Stampa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/economia-e-lavoro\\\/marketing\\\/viscom-italia-2012-rinnova-il-business-della-comunicazione-visiva\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/economia-e-lavoro\\\/marketing\\\/viscom-italia-2012-rinnova-il-business-della-comunicazione-visiva\\\/\"},\"author\":{\"name\":\"Redazione Comunicati Stampa\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"headline\":\"Viscom Italia 2012. Rinnova il business della comunicazione visiva\",\"datePublished\":\"2012-10-15T13:28:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/economia-e-lavoro\\\/marketing\\\/viscom-italia-2012-rinnova-il-business-della-comunicazione-visiva\\\/\"},\"wordCount\":1793,\"commentCount\":0,\"keywords\":[\"comunicazione visvia\",\"digital signage\"],\"articleSection\":[\"Marketing\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/economia-e-lavoro\\\/marketing\\\/viscom-italia-2012-rinnova-il-business-della-comunicazione-visiva\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/economia-e-lavoro\\\/marketing\\\/viscom-italia-2012-rinnova-il-business-della-comunicazione-visiva\\\/\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/economia-e-lavoro\\\/marketing\\\/viscom-italia-2012-rinnova-il-business-della-comunicazione-visiva\\\/\",\"name\":\"Viscom Italia 2012. Rinnova il business della comunicazione visiva - Article Marketing\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\"},\"datePublished\":\"2012-10-15T13:28:40+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/economia-e-lavoro\\\/marketing\\\/viscom-italia-2012-rinnova-il-business-della-comunicazione-visiva\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/economia-e-lavoro\\\/marketing\\\/viscom-italia-2012-rinnova-il-business-della-comunicazione-visiva\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/economia-e-lavoro\\\/marketing\\\/viscom-italia-2012-rinnova-il-business-della-comunicazione-visiva\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Viscom Italia 2012. Rinnova il business della comunicazione visiva\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\",\"name\":\"Article Marketing\",\"description\":\"article marketing &amp; press release\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\",\"name\":\"Redazione Comunicati Stampa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"caption\":\"Redazione Comunicati Stampa\"},\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/author\\\/redazione-comunicati-stampa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Viscom Italia 2012. Rinnova il business della comunicazione visiva - Article Marketing","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/marketing\/viscom-italia-2012-rinnova-il-business-della-comunicazione-visiva\/","og_locale":"it_IT","og_type":"article","og_title":"Viscom Italia 2012. Rinnova il business della comunicazione visiva - Article Marketing","og_description":"Dinamicit\u00e0, ottimismo e condivisione sono stati gli ingredienti per oltre 17.000 visitatori che hanno colto vantaggiose opportunit\u00e0 per un concreto investimento nel futuro della propria azienda.","og_url":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/marketing\/viscom-italia-2012-rinnova-il-business-della-comunicazione-visiva\/","og_site_name":"Article Marketing","article_published_time":"2012-10-15T13:28:40+00:00","author":"Redazione Comunicati Stampa","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione Comunicati Stampa","Tempo di lettura stimato":"9 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/marketing\/viscom-italia-2012-rinnova-il-business-della-comunicazione-visiva\/#article","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/marketing\/viscom-italia-2012-rinnova-il-business-della-comunicazione-visiva\/"},"author":{"name":"Redazione Comunicati Stampa","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"headline":"Viscom Italia 2012. Rinnova il business della comunicazione visiva","datePublished":"2012-10-15T13:28:40+00:00","mainEntityOfPage":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/marketing\/viscom-italia-2012-rinnova-il-business-della-comunicazione-visiva\/"},"wordCount":1793,"commentCount":0,"keywords":["comunicazione visvia","digital signage"],"articleSection":["Marketing"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/marketing\/viscom-italia-2012-rinnova-il-business-della-comunicazione-visiva\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/marketing\/viscom-italia-2012-rinnova-il-business-della-comunicazione-visiva\/","url":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/marketing\/viscom-italia-2012-rinnova-il-business-della-comunicazione-visiva\/","name":"Viscom Italia 2012. Rinnova il business della comunicazione visiva - Article Marketing","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website"},"datePublished":"2012-10-15T13:28:40+00:00","author":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"breadcrumb":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/marketing\/viscom-italia-2012-rinnova-il-business-della-comunicazione-visiva\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/marketing\/viscom-italia-2012-rinnova-il-business-della-comunicazione-visiva\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/marketing\/viscom-italia-2012-rinnova-il-business-della-comunicazione-visiva\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.article-marketing.eu\/comunicati\/"},{"@type":"ListItem","position":2,"name":"Viscom Italia 2012. Rinnova il business della comunicazione visiva"}]},{"@type":"WebSite","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website","url":"https:\/\/www.article-marketing.eu\/comunicati\/","name":"Article Marketing","description":"article marketing &amp; press release","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.article-marketing.eu\/comunicati\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017","name":"Redazione Comunicati Stampa","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","caption":"Redazione Comunicati Stampa"},"url":"https:\/\/www.article-marketing.eu\/comunicati\/author\/redazione-comunicati-stampa\/"}]}},"_links":{"self":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/30003","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/comments?post=30003"}],"version-history":[{"count":0,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/30003\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/media?parent=30003"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/categories?post=30003"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/tags?post=30003"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}