{"id":30223,"date":"2012-10-24T19:03:02","date_gmt":"2012-10-24T17:03:02","guid":{"rendered":"http:\/\/www.article-marketing.eu\/comunicati\/senza-categoria\/la-certificazione-ambientale-tema-del-programma-tv-jo\/"},"modified":"2012-10-24T19:03:02","modified_gmt":"2012-10-24T17:03:02","slug":"la-certificazione-ambientale-tema-del-programma-tv-jo","status":"publish","type":"post","link":"https:\/\/www.article-marketing.eu\/comunicati\/ambiente\/la-certificazione-ambientale-tema-del-programma-tv-jo\/","title":{"rendered":"La certificazione ambientale tema del programma tv Job"},"content":{"rendered":"<p><strong>In onda su TV7 Triveneta il mattino di venerd&igrave; 26 ottobre, dalle 9 alle 10<\/strong><br \/><strong><em>Tra gli ospiti, il professor Antonio Scipioni, direttore del Master in Gestione Ambientale Strategica dell&#8217;Universit&agrave; di Padova.<\/em><\/strong><br \/>La certificazione ambientale sar&agrave; il tema protagonista della rubrica Jobs, all&#8217;interno del programma TV7 alle 7, in diretta su TV7 Triveneta dalle 9 alle 10 di venerd&igrave; 26 ottobre, dal titolo &#8220;Certificatore professionista nella gestione ambientale e della sostenibilit&agrave;&#8221;.<br \/><strong>La trasmissione condotta da Emiliano Schincaglia vedr&agrave; ospite principale il professor Antonio Scipioni dell&#8217;Universit&agrave; di Padova, docente di Gestione Ambientale Strategica, Corso di laurea magistrale in Ingegneria Chimica e dei Processi industriali, e Direttore del Master Universitario in Gestione Ambientale Strategica.<\/strong><br \/>Assieme a Scipioni saranno presenti in studio il dottor Antonio Girardi, direttore della Fondazione Giacomo Rumor Centro Produttivit&agrave; Veneto (CPV); il dottor Adalberto Osti, Amministratore Unico della societ&agrave; RE&amp;S s.r.l. di Padova, operante nell&rsquo;area della Ricerca e Selezione di Personale; il professor Luigi Fabbris, Ordinario Statistica Sociale dell&#8217;Universit&agrave; di Padova.<br \/>Oltre alla partecipazione di un gruppo di studenti dell&#8217;Universit&agrave; patavina, il programma prevede la testimonianza diretta di alcuni professionisti del settore della gestione ambientale: Sandra Zanellato, responsabile del Sistema di Gestione Ambientale del Comune di Abano Terme; il dottor Dario De Rossi, socio fondatore di un network di professionisti che si propongono alle aziende per integrare la responsabilit&agrave; sociale e ambientale nei processi aziendali attraverso interventi di consulenza strategica; il dottor Stefan Marchioro, direttore di Padova Turismo Terme Euganee; la dottoressa Lorenza Favarato, responsabile monitoraggio dell&rsquo;impianto termovalorizzatore CDR (autorizzazione integrata ambientale).<br \/>Infine, la ricca scaletta contiene anche alcuni interventi audio e video in rete. Grazie a collegamenti Skype parteciperanno l&#8217;ingegner Alessandro Manzardo del CESQA, Centro Studi Qualit&agrave; Ambiente, che parler&agrave; dagli Stati Uniti; l&#8217;ingegner Fabio Gatto dell&#8217;Arpav di Belluno e il dottor Claudio Rosso; presidente del comitato scientifico dell&#8217;AICQ, Associazione Italiana Cultura Qualit&agrave;.<br \/><strong>Durante il programma si evidenzieranno le opportunit&agrave; di lavoro nell&#8217;ambito della certificazione ambientale. Una professione che pu&ograve; essere alla portata di molti neolaureati, per esempio frequentando il master in Gestione Ambientale Strategica dell&#8217;Universit&agrave; di Padova. Il Master intende formare una figura professionale polivalente nell&#8217;ambito del management ambientale, che sappia coniugare le metodologie e le tecniche di misurazione delle problematiche ambientali, con quelle di carattere gestionale, creando economie di scala in grado di realizzare una gestione ambientale strategica.<\/strong><br \/>Il programma sar&agrave; visibile anche durante la settimana, grazie a numerose repliche. Ogni informazione sugli orari &egrave; disponibile al link del sito web dell&#8217;emitente televisiva (http:\/\/www.gruppotv7.com\/articolo.php?id=110944). <br \/>Giuliano Dall&#8217;Oglio<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Durante il programma si evidenzieranno le opportunit\u00e0 di lavoro nell&#8217;ambito della certificazione ambientale. Una professione che pu\u00f2 essere alla portata di molti neolaureati, per esempio frequentando il master in Gestione Ambientale Strategica dell&#8217;Universit\u00e0 di Padova. Il Master intende formare una figura professionale polivalente nell&#8217;ambito del management ambientale, che sappia coniugare le metodologie e le tecniche di misurazione delle problematiche ambientali, con quelle di carattere gestionale, creando economie di scala in grado di realizzare una gestione ambientale strategica.<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"","footnotes":""},"categories":[55],"tags":[96,39089,36548,39091,10368,22704,39090,39088],"class_list":["post-30223","post","type-post","status-publish","format-standard","hentry","category-ambiente","tag-ambiente","tag-antonio-scipioni","tag-certificazione-ambientale","tag-gestione-ambientale-strategica","tag-ingegneria","tag-opportunita-professionali","tag-triveneta","tag-universita-padova"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La certificazione ambientale tema del programma tv Job - Article Marketing<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.article-marketing.eu\/comunicati\/ambiente\/la-certificazione-ambientale-tema-del-programma-tv-jo\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La certificazione ambientale tema del programma tv Job - Article Marketing\" \/>\n<meta property=\"og:description\" content=\"Durante il programma si evidenzieranno le opportunit\u00e0 di lavoro nell&#039;ambito della certificazione ambientale. Una professione che pu\u00f2 essere alla portata di molti neolaureati, per esempio frequentando il master in Gestione Ambientale Strategica dell&#039;Universit\u00e0 di Padova. Il Master intende formare una figura professionale polivalente nell&#039;ambito del management ambientale, che sappia coniugare le metodologie e le tecniche di misurazione delle problematiche ambientali, con quelle di carattere gestionale, creando economie di scala in grado di realizzare una gestione ambientale strategica.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.article-marketing.eu\/comunicati\/ambiente\/la-certificazione-ambientale-tema-del-programma-tv-jo\/\" \/>\n<meta property=\"og:site_name\" content=\"Article Marketing\" \/>\n<meta property=\"article:published_time\" content=\"2012-10-24T17:03:02+00:00\" \/>\n<meta name=\"author\" content=\"Redazione Comunicati Stampa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione Comunicati Stampa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/ambiente\\\/la-certificazione-ambientale-tema-del-programma-tv-jo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/ambiente\\\/la-certificazione-ambientale-tema-del-programma-tv-jo\\\/\"},\"author\":{\"name\":\"Redazione Comunicati Stampa\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"headline\":\"La certificazione ambientale tema del programma tv Job\",\"datePublished\":\"2012-10-24T17:03:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/ambiente\\\/la-certificazione-ambientale-tema-del-programma-tv-jo\\\/\"},\"wordCount\":444,\"commentCount\":0,\"keywords\":[\"ambiente\",\"antonio scipioni\",\"certificazione ambientale\",\"gestione ambientale strategica\",\"ingegneria\",\"opportunit\u00e0 professionali\",\"triveneta\",\"universit\u00e0 padova\"],\"articleSection\":[\"Ambiente\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/ambiente\\\/la-certificazione-ambientale-tema-del-programma-tv-jo\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/ambiente\\\/la-certificazione-ambientale-tema-del-programma-tv-jo\\\/\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/ambiente\\\/la-certificazione-ambientale-tema-del-programma-tv-jo\\\/\",\"name\":\"La certificazione ambientale tema del programma tv Job - Article Marketing\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\"},\"datePublished\":\"2012-10-24T17:03:02+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/ambiente\\\/la-certificazione-ambientale-tema-del-programma-tv-jo\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/ambiente\\\/la-certificazione-ambientale-tema-del-programma-tv-jo\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/ambiente\\\/la-certificazione-ambientale-tema-del-programma-tv-jo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La certificazione ambientale tema del programma tv Job\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\",\"name\":\"Article Marketing\",\"description\":\"article marketing &amp; press release\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\",\"name\":\"Redazione Comunicati Stampa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"caption\":\"Redazione Comunicati Stampa\"},\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/author\\\/redazione-comunicati-stampa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La certificazione ambientale tema del programma tv Job - Article Marketing","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.article-marketing.eu\/comunicati\/ambiente\/la-certificazione-ambientale-tema-del-programma-tv-jo\/","og_locale":"it_IT","og_type":"article","og_title":"La certificazione ambientale tema del programma tv Job - Article Marketing","og_description":"Durante il programma si evidenzieranno le opportunit\u00e0 di lavoro nell'ambito della certificazione ambientale. Una professione che pu\u00f2 essere alla portata di molti neolaureati, per esempio frequentando il master in Gestione Ambientale Strategica dell'Universit\u00e0 di Padova. Il Master intende formare una figura professionale polivalente nell'ambito del management ambientale, che sappia coniugare le metodologie e le tecniche di misurazione delle problematiche ambientali, con quelle di carattere gestionale, creando economie di scala in grado di realizzare una gestione ambientale strategica.","og_url":"https:\/\/www.article-marketing.eu\/comunicati\/ambiente\/la-certificazione-ambientale-tema-del-programma-tv-jo\/","og_site_name":"Article Marketing","article_published_time":"2012-10-24T17:03:02+00:00","author":"Redazione Comunicati Stampa","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione Comunicati Stampa","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.article-marketing.eu\/comunicati\/ambiente\/la-certificazione-ambientale-tema-del-programma-tv-jo\/#article","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/ambiente\/la-certificazione-ambientale-tema-del-programma-tv-jo\/"},"author":{"name":"Redazione Comunicati Stampa","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"headline":"La certificazione ambientale tema del programma tv Job","datePublished":"2012-10-24T17:03:02+00:00","mainEntityOfPage":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/ambiente\/la-certificazione-ambientale-tema-del-programma-tv-jo\/"},"wordCount":444,"commentCount":0,"keywords":["ambiente","antonio scipioni","certificazione ambientale","gestione ambientale strategica","ingegneria","opportunit\u00e0 professionali","triveneta","universit\u00e0 padova"],"articleSection":["Ambiente"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.article-marketing.eu\/comunicati\/ambiente\/la-certificazione-ambientale-tema-del-programma-tv-jo\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.article-marketing.eu\/comunicati\/ambiente\/la-certificazione-ambientale-tema-del-programma-tv-jo\/","url":"https:\/\/www.article-marketing.eu\/comunicati\/ambiente\/la-certificazione-ambientale-tema-del-programma-tv-jo\/","name":"La certificazione ambientale tema del programma tv Job - Article Marketing","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website"},"datePublished":"2012-10-24T17:03:02+00:00","author":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"breadcrumb":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/ambiente\/la-certificazione-ambientale-tema-del-programma-tv-jo\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.article-marketing.eu\/comunicati\/ambiente\/la-certificazione-ambientale-tema-del-programma-tv-jo\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.article-marketing.eu\/comunicati\/ambiente\/la-certificazione-ambientale-tema-del-programma-tv-jo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.article-marketing.eu\/comunicati\/"},{"@type":"ListItem","position":2,"name":"La certificazione ambientale tema del programma tv Job"}]},{"@type":"WebSite","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website","url":"https:\/\/www.article-marketing.eu\/comunicati\/","name":"Article Marketing","description":"article marketing &amp; press release","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.article-marketing.eu\/comunicati\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017","name":"Redazione Comunicati Stampa","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","caption":"Redazione Comunicati Stampa"},"url":"https:\/\/www.article-marketing.eu\/comunicati\/author\/redazione-comunicati-stampa\/"}]}},"_links":{"self":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/30223","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/comments?post=30223"}],"version-history":[{"count":0,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/30223\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/media?parent=30223"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/categories?post=30223"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/tags?post=30223"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}