{"id":30710,"date":"2012-11-14T11:01:09","date_gmt":"2012-11-14T10:01:09","guid":{"rendered":"http:\/\/www.article-marketing.eu\/comunicati\/senza-categoria\/torna-il-garfagnana-in-giallo-2\/"},"modified":"2012-11-14T11:01:09","modified_gmt":"2012-11-14T10:01:09","slug":"torna-il-garfagnana-in-giallo-2","status":"publish","type":"post","link":"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/libri\/torna-il-garfagnana-in-giallo-2\/","title":{"rendered":"Torna il Garfagnana in Giallo"},"content":{"rendered":"<p>Torna il Garfagnana in Giallo il concorso letterario che unisce scrittori provenienti da tutta Italia nella valle delle Terre del Serchio. L&rsquo;evento, curato da Andrea Giannasi, si svolger&agrave; il 24 e il 25 novembre a Castelnuovo di Garfagnana nella storica e suggestiva fortezza di Montalfonso. Ospite d&rsquo;onore lo scrittore Carlo A. Martigli che presenter&agrave; &ldquo;L&rsquo;eretico&rdquo; (Longanesi) che giunge in Garfagnana dopo Loriano Macchiavelli, Mario Spezi e Giampaolo Simi.<br \/> L&rsquo;artista che dipinger&agrave; la copertina dell&rsquo;antologia &egrave; il pittore Roberto Fontirossi che raccoglie il testimone da Riccardo Benvenuti, Antonio Possenti e Gianpaolo Talani che hanno realizzato i quadri delle tre precedenti raccolte.<br \/> L&rsquo;evento &egrave; organizzato dal Giornale di Castelnuovo con il patrocinio del Gal Garfagnana, del Comune di Castelnuovo, della Prospettiva editrice e di AbelBooks.<br \/> Il programma prevede l&rsquo;inaugurazione del Giallo alle 18,30 con Sabina Marchesi e Andrea Giannasi che presentano l&rsquo;antologia con gli autori che vi fanno parte. Otto autori selezionati dai quali uscir&agrave; il vincitore della sezione inediti 2012.<br \/> Inoltre &egrave; prevista la presentazione della cinquina dei libri editi. I finalisti provengono da tutta Italia e rappresentano i giallisti di domani. Quelli che poi incontreremo come autori conosciuti e apprezzati.<br \/> Contemporaneamente il giornalista del Messaggero di Roma, Damiano Celestini, come social media manager inizier&agrave; dalla fortezza di Castelnuovo la diretta Twitter e seguir&agrave; con l&rsquo;hashtag #giallogarfagnana l&rsquo;intero evento.<br \/> Alle 19 lo scrittore &ndash; vincitore del Premio Tedeschi 2008 e autori di Gialli Mondadori &ndash; Enrico Luceri presenta il suo ultimo giallo dal titolo &ldquo;Le strade di sera&rdquo; (Hobby &amp; Work).<br \/> Mentre alle 19,30 sar&agrave; la volta di &ldquo;Scrivere giallo&rdquo; con Fabio Mundadori, autore di &ldquo;Occhi viola&rdquo; (Ego) e Luciana Quattrini autrice di &ldquo;Adriatico. Gli occhi del Puma&rdquo; (Prospettiva). Si parler&agrave; di tecnica di scrittura e delle regole di Van Dine.<br \/> Alle 20 sar&agrave; la volta dell&rsquo;ospite 2012 del Garfagnana in giallo: Carlo A. Martigli sar&agrave; intervistato da Andrea Giannasi. Sar&agrave; occasione per Martigli di parlare del suo ultimo romanzo &ldquo;L&rsquo;eretico&rdquo; (Longanesi). L&rsquo;autore che ha superato le 100mila copie vendute &egrave; livornese di nascita e i suoi romanzi di ambientazione storica sono tradotti in tutto il mondo.<br \/> Alle 21 gli scrittori e partecipanti si sposteranno di pochi metri presso la casa con gli archi &ndash; antica sede della guarnigione estense &ndash; dove si svolger&agrave; la &ldquo;Cena con il delitto&rdquo; a cura della EccoFatto con l&rsquo;attore e giallista Massimo Lerose. Il titolo dello spettacolo delittuoso &egrave; &ldquo;<strong>&ldquo;Il silenzio dei Vitelli&rdquo;<\/strong> scritto da Giorgio Molinari che vede al centro delle indagini il commissario Percuoco, alle prese con l&rsquo;assassinio del famoso costruttore di auto Gianni Vitelli. Sulla scena del delitto ritroveremo la moglie Angela Spread, suo figlio Lapo, e il maggiordomo Flavio Briacone.<br \/> Il costo della cena &egrave; di euro 25 (prenotazioni garfagnanaingiallo@yahoo.it).<br \/> Durante la cena avverr&agrave; la premiazione del Garfagnana in Giallo (editi) e del miglior racconto dell&rsquo;antologia inediti.<br \/> Domenica mattina a partire dalle 10 della mattina presso la Fortezza si terranno workshop letterari curati da Fabio Mundadori.Parteciperanno Andrea Giannasi, Sabina Marchesi, Enrico Luceri, Massimo Lerose.<br \/>\nInfo e note<br \/> <a href=\"http:\/\/garfagnanaingiallo.wordpress.com\/\" target=\"_blank\">http:\/\/garfagnanaingiallo.wordpress.com\/<\/a><br \/>\n&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Garfagnana in Giallo l&#8217;evento letterario creato da Andrea Giannasi che si terr\u00e0 il 24 e il 25 novembre alla Fortezza Montalfonso a Castelnuovo Garfagnana<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"","footnotes":""},"categories":[88],"tags":[36675,36689,39554,1550,39555],"class_list":["post-30710","post","type-post","status-publish","format-standard","hentry","category-libri","tag-andrea-giannasi","tag-garfagnana","tag-garfagnana-in-giallo","tag-giallo","tag-poliziesco"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Torna il Garfagnana in Giallo - Article Marketing<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/libri\/torna-il-garfagnana-in-giallo-2\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Torna il Garfagnana in Giallo - Article Marketing\" \/>\n<meta property=\"og:description\" content=\"Garfagnana in Giallo l&#039;evento letterario creato da Andrea Giannasi che si terr\u00e0 il 24 e il 25 novembre alla Fortezza Montalfonso a Castelnuovo Garfagnana\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/libri\/torna-il-garfagnana-in-giallo-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Article Marketing\" \/>\n<meta property=\"article:published_time\" content=\"2012-11-14T10:01:09+00:00\" \/>\n<meta name=\"author\" content=\"Redazione Comunicati Stampa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione Comunicati Stampa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/arte-e-cultura\\\/libri\\\/torna-il-garfagnana-in-giallo-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/arte-e-cultura\\\/libri\\\/torna-il-garfagnana-in-giallo-2\\\/\"},\"author\":{\"name\":\"Redazione Comunicati Stampa\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"headline\":\"Torna il Garfagnana in Giallo\",\"datePublished\":\"2012-11-14T10:01:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/arte-e-cultura\\\/libri\\\/torna-il-garfagnana-in-giallo-2\\\/\"},\"wordCount\":559,\"commentCount\":0,\"keywords\":[\"andrea giannasi\",\"garfagnana\",\"garfagnana in giallo\",\"giallo\",\"poliziesco\"],\"articleSection\":[\"Libri\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/arte-e-cultura\\\/libri\\\/torna-il-garfagnana-in-giallo-2\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/arte-e-cultura\\\/libri\\\/torna-il-garfagnana-in-giallo-2\\\/\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/arte-e-cultura\\\/libri\\\/torna-il-garfagnana-in-giallo-2\\\/\",\"name\":\"Torna il Garfagnana in Giallo - Article Marketing\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\"},\"datePublished\":\"2012-11-14T10:01:09+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/arte-e-cultura\\\/libri\\\/torna-il-garfagnana-in-giallo-2\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/arte-e-cultura\\\/libri\\\/torna-il-garfagnana-in-giallo-2\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/arte-e-cultura\\\/libri\\\/torna-il-garfagnana-in-giallo-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Torna il Garfagnana in Giallo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\",\"name\":\"Article Marketing\",\"description\":\"article marketing &amp; press release\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\",\"name\":\"Redazione Comunicati Stampa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"caption\":\"Redazione Comunicati Stampa\"},\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/author\\\/redazione-comunicati-stampa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Torna il Garfagnana in Giallo - Article Marketing","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/libri\/torna-il-garfagnana-in-giallo-2\/","og_locale":"it_IT","og_type":"article","og_title":"Torna il Garfagnana in Giallo - Article Marketing","og_description":"Garfagnana in Giallo l'evento letterario creato da Andrea Giannasi che si terr\u00e0 il 24 e il 25 novembre alla Fortezza Montalfonso a Castelnuovo Garfagnana","og_url":"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/libri\/torna-il-garfagnana-in-giallo-2\/","og_site_name":"Article Marketing","article_published_time":"2012-11-14T10:01:09+00:00","author":"Redazione Comunicati Stampa","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione Comunicati Stampa","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/libri\/torna-il-garfagnana-in-giallo-2\/#article","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/libri\/torna-il-garfagnana-in-giallo-2\/"},"author":{"name":"Redazione Comunicati Stampa","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"headline":"Torna il Garfagnana in Giallo","datePublished":"2012-11-14T10:01:09+00:00","mainEntityOfPage":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/libri\/torna-il-garfagnana-in-giallo-2\/"},"wordCount":559,"commentCount":0,"keywords":["andrea giannasi","garfagnana","garfagnana in giallo","giallo","poliziesco"],"articleSection":["Libri"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/libri\/torna-il-garfagnana-in-giallo-2\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/libri\/torna-il-garfagnana-in-giallo-2\/","url":"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/libri\/torna-il-garfagnana-in-giallo-2\/","name":"Torna il Garfagnana in Giallo - Article Marketing","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website"},"datePublished":"2012-11-14T10:01:09+00:00","author":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"breadcrumb":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/libri\/torna-il-garfagnana-in-giallo-2\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/libri\/torna-il-garfagnana-in-giallo-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/libri\/torna-il-garfagnana-in-giallo-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.article-marketing.eu\/comunicati\/"},{"@type":"ListItem","position":2,"name":"Torna il Garfagnana in Giallo"}]},{"@type":"WebSite","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website","url":"https:\/\/www.article-marketing.eu\/comunicati\/","name":"Article Marketing","description":"article marketing &amp; press release","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.article-marketing.eu\/comunicati\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017","name":"Redazione Comunicati Stampa","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","caption":"Redazione Comunicati Stampa"},"url":"https:\/\/www.article-marketing.eu\/comunicati\/author\/redazione-comunicati-stampa\/"}]}},"_links":{"self":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/30710","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/comments?post=30710"}],"version-history":[{"count":0,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/30710\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/media?parent=30710"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/categories?post=30710"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/tags?post=30710"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}