{"id":30895,"date":"2012-11-21T16:18:16","date_gmt":"2012-11-21T15:18:16","guid":{"rendered":"http:\/\/www.article-marketing.eu\/comunicati\/senza-categoria\/cercare-un-file-specifico-su-google\/"},"modified":"2012-11-21T16:18:16","modified_gmt":"2012-11-21T15:18:16","slug":"cercare-un-file-specifico-su-google","status":"publish","type":"post","link":"https:\/\/www.article-marketing.eu\/comunicati\/internet\/blog\/cercare-un-file-specifico-su-google\/","title":{"rendered":"Cercare un file specifico su google"},"content":{"rendered":"<p>E&#8217; possibile cercare su google un&#8217; articolo di con un formato determinato? ad esempio, se avessimo bisogno di cercare un&#8217;argomento (esempio di tipo storico), il formato doc, quindi modificabile con apposito programma, google ci viene incontro. <strong>Filetype:<\/strong><br \/> Ci consente di ricercare tipologie di file differenti fornendo anche un argomento di ricerca. Esempio cerchiamo un file word ( quindi un .doc o docx) che abbia come argomento stellissimo, dobbiamo inserire la query di ricerca<br \/> <strong>Filetype: doc &ldquo;<a href=\"http:\/\/www.stellissimo-contest.it\/\" target=\"_self\" title=\"stellissimo\">stellissimo<\/a>&rdquo;<\/strong> cerca tutti i file .doc(word) con argomento inerente stellissimo<br \/> <strong>Define:<\/strong><br \/> Permette di trovare la definizione del termine cercato<br \/> <strong>Define: albero<\/strong><br \/> Related<br \/> Utile per trovare i siti simili o competitor<br \/> <strong>Related: www.stellissimo-contest.it<\/strong> Related<br \/> Utile per trovare i siti simili o competitor<br \/> <strong>Related: www.stellissimo-contest.it<\/strong><br \/> <strong style=\"mso-bidi-font-weight: normal;\">Info<\/strong><br \/> Comando che restituisce il frammento di descrizione e il link preferito per un determinate url.<br \/> <strong>Info: sitodaverificare.estensione<\/strong><br \/> <strong>Group<\/strong><br \/> Usato solo il google per restringere la ricerca ad un determinato gruppo. Esempio group-seo<br \/> <strong>Inanchor<\/strong><br \/> Simile ad Allinanchor ma con le seguenti peculiarit&agrave;:<br \/> pu&ograve; essere utilizzato assieme ad altri operatori e solo la prima parola dopo il comando far&agrave; parte della ricerca del comando Altri comandi piuttosto simpatici: <strong>weather<\/strong>: ci restituisce le condizioni climatiche. Esempio weather: Roma Daterange: Viene utilizzato per determinare una query all&#8217;interno di un determinato range di date e deve essere utilizzato con questa sintassi: <strong>daterange<\/strong>:startdate-enddate. Vediamo come possiamo utilizzare il comando filetype in modo differente. Se ad esempio volessimo cercare username e password di alcuni siti web.. bene si. Attraberso semplici ricerche &egrave; possibile scoprire file contenenti password e username sia in chiaro sia codificati. Pratica: digitando su google: <strong>filetype<\/strong>:htpasswd htpasswd<br \/> <strong>Intitle<\/strong>: index of passwd passwd.bak questi due hack forniranno l&#8217;elenco dei siti che hanno lasciato scoperti questi file, praticamente tecniche analizzate ci permettono di scoprire dimenticanze o inaccortezze dei webmaster. Se invece dovessimo ricercare delle email e delle informazioni personali esiste un altra tipologia di ricerca che possiamo effettuare: filetype:xls inurl:&#8221;email.xls&#8221; &#8220;phone * * *&#8221; &#8220;adress *&#8221; &#8220;e-mail &#8221; intitle:&#8221;curriculum vitae&#8221; filetype:ctt &#8220;msn&#8221; Queste tipologie di ricerche ci permetteranno di reperire facilmente informazioni dal web. In questo modo ci fingiamo Google per reperire informazioni.<br \/>\nSempre attraverso queste chiavi ci sar&agrave; possibile scoprire alcune vulnerabilit&agrave; dei web server per accedere a documenti o risorse presenti in essi; per esempio per apache 2.0 potremo digitare la seguente stringa nel campo di ricerca di Google:<br \/>\n&#8220;Apache\/2.0 Server at&#8221; intitle: index.of<br \/>\nSono moltissime le query che google mette a disposizione. Per Ogni web server, e per ogni specifica informazione che cerchiamo la query cambia. Su IIS esempio:<br \/>\nServer at dovr&agrave; essere preceduto dalla specifica versione.<br \/>\n&ldquo;Microsoft-IIS\/7.0 Server at&rdquo; intitle:index.of<\/p>\n","protected":false},"excerpt":{"rendered":"<p>E&#8217; possibile cercare su google un&#8217; articolo di con un formato determinato? ad esempio, se avessimo bisogno di cercare un&#8217;argomento (esempio di tipo storico), il formato doc, quindi modificabile con apposito programma, google ci viene incontro.Filetype:<br \/>Ci consente di ricercare tipologie di file differenti fornendo anche un argomento di ricerca. Esempio cerchiamo un file word ( quindi un .doc o docx) che abbia come argomento stellissimo, dobbiamo inserire la query di ricerca<br \/>Filetype: doc \u201cstellissimo\u201d cerca tutti i file .doc(word) con argomento inerente stellissimo<br \/>Define:<br \/>Permette di trovare la definizione del termine cercato<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"","footnotes":""},"categories":[978],"tags":[664,39479,39667],"class_list":["post-30895","post","type-post","status-publish","format-standard","hentry","category-blog","tag-seo-contest","tag-stellissimo","tag-stellissimo-seo"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cercare un file specifico su google - Article Marketing<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.article-marketing.eu\/comunicati\/internet\/blog\/cercare-un-file-specifico-su-google\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cercare un file specifico su google - Article Marketing\" \/>\n<meta property=\"og:description\" content=\"E&#039; possibile cercare su google un&#039; articolo di con un formato determinato? ad esempio, se avessimo bisogno di cercare un&#039;argomento (esempio di tipo storico), il formato doc, quindi modificabile con apposito programma, google ci viene incontro.Filetype:Ci consente di ricercare tipologie di file differenti fornendo anche un argomento di ricerca. Esempio cerchiamo un file word ( quindi un .doc o docx) che abbia come argomento stellissimo, dobbiamo inserire la query di ricercaFiletype: doc \u201cstellissimo\u201d cerca tutti i file .doc(word) con argomento inerente stellissimoDefine:Permette di trovare la definizione del termine cercato\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.article-marketing.eu\/comunicati\/internet\/blog\/cercare-un-file-specifico-su-google\/\" \/>\n<meta property=\"og:site_name\" content=\"Article Marketing\" \/>\n<meta property=\"article:published_time\" content=\"2012-11-21T15:18:16+00:00\" \/>\n<meta name=\"author\" content=\"Redazione Comunicati Stampa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione Comunicati Stampa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/internet\\\/blog\\\/cercare-un-file-specifico-su-google\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/internet\\\/blog\\\/cercare-un-file-specifico-su-google\\\/\"},\"author\":{\"name\":\"Redazione Comunicati Stampa\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"headline\":\"Cercare un file specifico su google\",\"datePublished\":\"2012-11-21T15:18:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/internet\\\/blog\\\/cercare-un-file-specifico-su-google\\\/\"},\"wordCount\":453,\"commentCount\":0,\"keywords\":[\"seo contest\",\"stellissimo\",\"stellissimo seo\"],\"articleSection\":[\"Blog\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/internet\\\/blog\\\/cercare-un-file-specifico-su-google\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/internet\\\/blog\\\/cercare-un-file-specifico-su-google\\\/\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/internet\\\/blog\\\/cercare-un-file-specifico-su-google\\\/\",\"name\":\"Cercare un file specifico su google - Article Marketing\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\"},\"datePublished\":\"2012-11-21T15:18:16+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/internet\\\/blog\\\/cercare-un-file-specifico-su-google\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/internet\\\/blog\\\/cercare-un-file-specifico-su-google\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/internet\\\/blog\\\/cercare-un-file-specifico-su-google\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cercare un file specifico su google\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\",\"name\":\"Article Marketing\",\"description\":\"article marketing &amp; press release\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\",\"name\":\"Redazione Comunicati Stampa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"caption\":\"Redazione Comunicati Stampa\"},\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/author\\\/redazione-comunicati-stampa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cercare un file specifico su google - Article Marketing","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.article-marketing.eu\/comunicati\/internet\/blog\/cercare-un-file-specifico-su-google\/","og_locale":"it_IT","og_type":"article","og_title":"Cercare un file specifico su google - Article Marketing","og_description":"E' possibile cercare su google un' articolo di con un formato determinato? ad esempio, se avessimo bisogno di cercare un'argomento (esempio di tipo storico), il formato doc, quindi modificabile con apposito programma, google ci viene incontro.Filetype:Ci consente di ricercare tipologie di file differenti fornendo anche un argomento di ricerca. Esempio cerchiamo un file word ( quindi un .doc o docx) che abbia come argomento stellissimo, dobbiamo inserire la query di ricercaFiletype: doc \u201cstellissimo\u201d cerca tutti i file .doc(word) con argomento inerente stellissimoDefine:Permette di trovare la definizione del termine cercato","og_url":"https:\/\/www.article-marketing.eu\/comunicati\/internet\/blog\/cercare-un-file-specifico-su-google\/","og_site_name":"Article Marketing","article_published_time":"2012-11-21T15:18:16+00:00","author":"Redazione Comunicati Stampa","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione Comunicati Stampa","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.article-marketing.eu\/comunicati\/internet\/blog\/cercare-un-file-specifico-su-google\/#article","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/internet\/blog\/cercare-un-file-specifico-su-google\/"},"author":{"name":"Redazione Comunicati Stampa","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"headline":"Cercare un file specifico su google","datePublished":"2012-11-21T15:18:16+00:00","mainEntityOfPage":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/internet\/blog\/cercare-un-file-specifico-su-google\/"},"wordCount":453,"commentCount":0,"keywords":["seo contest","stellissimo","stellissimo seo"],"articleSection":["Blog"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.article-marketing.eu\/comunicati\/internet\/blog\/cercare-un-file-specifico-su-google\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.article-marketing.eu\/comunicati\/internet\/blog\/cercare-un-file-specifico-su-google\/","url":"https:\/\/www.article-marketing.eu\/comunicati\/internet\/blog\/cercare-un-file-specifico-su-google\/","name":"Cercare un file specifico su google - Article Marketing","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website"},"datePublished":"2012-11-21T15:18:16+00:00","author":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"breadcrumb":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/internet\/blog\/cercare-un-file-specifico-su-google\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.article-marketing.eu\/comunicati\/internet\/blog\/cercare-un-file-specifico-su-google\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.article-marketing.eu\/comunicati\/internet\/blog\/cercare-un-file-specifico-su-google\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.article-marketing.eu\/comunicati\/"},{"@type":"ListItem","position":2,"name":"Cercare un file specifico su google"}]},{"@type":"WebSite","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website","url":"https:\/\/www.article-marketing.eu\/comunicati\/","name":"Article Marketing","description":"article marketing &amp; press release","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.article-marketing.eu\/comunicati\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017","name":"Redazione Comunicati Stampa","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","caption":"Redazione Comunicati Stampa"},"url":"https:\/\/www.article-marketing.eu\/comunicati\/author\/redazione-comunicati-stampa\/"}]}},"_links":{"self":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/30895","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/comments?post=30895"}],"version-history":[{"count":0,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/30895\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/media?parent=30895"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/categories?post=30895"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/tags?post=30895"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}