{"id":31081,"date":"2012-11-28T16:34:44","date_gmt":"2012-11-28T15:34:44","guid":{"rendered":"http:\/\/www.article-marketing.eu\/comunicati\/senza-categoria\/gli-italiani-combattono-la-crisi-condividendo-la%25252580%25252599auto-e-le-spese\/"},"modified":"2018-07-10T06:03:50","modified_gmt":"2018-07-10T04:03:50","slug":"gli-italiani-combattono-la-crisi-condividendo-la%25252580%25252599auto-e-le-spese","status":"publish","type":"post","link":"https:\/\/www.article-marketing.eu\/comunicati\/motori\/auto\/gli-italiani-combattono-la-crisi-condividendo-la%25252580%25252599auto-e-le-spese\/","title":{"rendered":"Gli italiani combattono la crisi condividendo l\u2019auto e le spese"},"content":{"rendered":"<p><strong><\/strong><br \/>\nSbarca in Italia <strong>carpooling<\/strong>, il nuovo metodo che rivoluziona l&rsquo;idea dell&rsquo;autostop: un&rsquo;automobile da condividere per percorrere lo stesso itinerario, in compagnia e risparmiando tempo e costi.<\/p>\n<p><strong>Sembra che la pratica di condividere l&#8217;auto per andare al lavoro stia prendendo sempre pi&ugrave; piede, <\/strong>non solo all&#8217;estero, ma anche in Italia. Per chi non conoscesse come funziona il carpooling, tramite un sito Internet si pu&ograve; prenotare un passaggio o mettere a disposizione alcuni sedili della propria auto, comunicando destinazione ed eventuali tappe intermedie<\/p>\n<p>In Italia il fenomeno &egrave; arrivato grazie al il<strong> sito web Carpooling.it.<\/strong> Oggi, questa &ldquo;piazza virtuale&rdquo; conta pi&ugrave; di 650 mila offerte\/richieste di passaggio. Ogni mese trasporta pi&ugrave; di 1 milione di persone in 45 paesi e ha pi&ugrave; di 4 milioni di utenti iscritti. A decretare questo successo sono le numerose opportunit&agrave; di passaggio inserite da giovani, prevalentemente fra i 24-35 anni, che devono spostarsi, continuamente, per raggiungere l&rsquo;Universit&agrave; o seguire uno stage, ma anche da lavoratori pendolari che in questo modo risparmiano fino al 75% sui costi della benzina.<\/p>\n<p>Gli utilizzatori del Carpooling hanno una fascia di et&agrave; compresa tra i 22 ed i 48 anni e le donne superano il 38% degli iscritti. Una cos&igrave; elevata quota di pubblico femminile &egrave; stata raggiunta grazie alla possibilit&agrave; di inserire annunci dedicati alle sole donne. Questo sistema ha consentito di superare la naturale diffidenza nel viaggiare in auto con una persona a noi sconosciuta e di offrire una maggiore sicurezza agli utenti.<\/p>\n<p>Anche sui viaggi lunghi occasionali e nel confronto con i mezzi pubblici <strong>la convenienza economica &egrave; evidente<\/strong>: per esempio, per un passaggio da Roma a Milano si richiede solitamente un contributo spese di 30 euro, mentre il biglietto del treno meno caro costa 56 euro e la Freccia bianca 86 euro. Ancora pi&ugrave; conveniente per chi farebbe comunque il viaggio in macchina: da solo dovrebbe accollarsi 120-130 euro di spese tra carburante e pedaggi. Non &egrave; dunque un caso se in questi ultimi mesi gli utenti di questi siti sono in continuo aumento: dal portale BlaBlaCar, che sta facendo una campagna pubblicitaria notevole, ci parlano di un aumento del 150% negli ultimi 4 mesi, e solo il loro sito, relativamente nuovo per l&#8217;Italia, conta gi&agrave; 200mila utenti.<\/p>\n<p><strong>In crescita &egrave;, inoltre, la tendenza a &ldquo;fare carpooling&rdquo; per viaggi in Italia ed Europa.<\/strong><br \/>Ecco che, invece, di optare per il treno, il bus o l&rsquo;aereo, gli italiani, in tempo di crisi e caro benzina, scelgono la formula dell&rsquo;auto di gruppo e cercano altre persone che sono dirette nello stesso punto per condividere le spese viaggi. Il portale registra, in questi ultimi mesi, un incremento dei contatti del 250%<\/p>\n<p>&ldquo;Una diffusione sistematica del carpooling &#8211; <strong>dichiara Daniela Mililli, Country Manager Italia<\/strong> -potrebbe migliorare non solo il nostro modo di spostarci ma anche la qualit&agrave; della vita in molte citt&agrave; italiane riducendo in modo immediato e concreto traffico ed inquinamento.&rdquo;<\/p>\n<p>Disponibili, anche, le applicazioni carpooling per IPhone ed Android, che permettono di consultare, in qualsiasi momento, le richieste e le offerte di passaggio.<br \/>Carpooling.it &egrave; un moderno autostop in stile web che garantisce una sicurezza certificata. Tra le molteplici funzioni offerte dal sito, l&acute;autenticazione della carta d&rsquo;identit&agrave; del guidatore, ma anche un sistema di prenotazione, un meccanismo di feedback tra gli utenti e, l&acute;opzione &ldquo;carpooling per le donne&rdquo;, che permette di rendere visibili le richieste\/offerte di passaggio solo ad un pubblico femminile.<\/p>\n<p>Per informazioni: www.carpooling.it<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sbarca in Italia carpooling, il nuovo metodo che rivoluziona l\u2019idea dell\u2019autostop: un\u2019automobile da condividere per percorrere lo stesso itinerario, in compagnia e risparmiando tempo e costi.<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"","footnotes":""},"categories":[352],"tags":[],"class_list":["post-31081","post","type-post","status-publish","format-standard","hentry","category-auto"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Gli italiani combattono la crisi condividendo l\u2019auto e le spese - Article Marketing<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.article-marketing.eu\/comunicati\/motori\/auto\/gli-italiani-combattono-la-crisi-condividendo-la%252580%252599auto-e-le-spese\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gli italiani combattono la crisi condividendo l\u2019auto e le spese - Article Marketing\" \/>\n<meta property=\"og:description\" content=\"Sbarca in Italia carpooling, il nuovo metodo che rivoluziona l\u2019idea dell\u2019autostop: un\u2019automobile da condividere per percorrere lo stesso itinerario, in compagnia e risparmiando tempo e costi.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.article-marketing.eu\/comunicati\/motori\/auto\/gli-italiani-combattono-la-crisi-condividendo-la%252580%252599auto-e-le-spese\/\" \/>\n<meta property=\"og:site_name\" content=\"Article Marketing\" \/>\n<meta property=\"article:published_time\" content=\"2012-11-28T15:34:44+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-07-10T04:03:50+00:00\" \/>\n<meta name=\"author\" content=\"Redazione Comunicati Stampa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione Comunicati Stampa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/motori\\\/auto\\\/gli-italiani-combattono-la-crisi-condividendo-la%25252580%25252599auto-e-le-spese\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/motori\\\/auto\\\/gli-italiani-combattono-la-crisi-condividendo-la%25252580%25252599auto-e-le-spese\\\/\"},\"author\":{\"name\":\"Redazione Comunicati Stampa\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"headline\":\"Gli italiani combattono la crisi condividendo l\u2019auto e le spese\",\"datePublished\":\"2012-11-28T15:34:44+00:00\",\"dateModified\":\"2018-07-10T04:03:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/motori\\\/auto\\\/gli-italiani-combattono-la-crisi-condividendo-la%25252580%25252599auto-e-le-spese\\\/\"},\"wordCount\":610,\"commentCount\":0,\"articleSection\":[\"Auto\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/motori\\\/auto\\\/gli-italiani-combattono-la-crisi-condividendo-la%25252580%25252599auto-e-le-spese\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/motori\\\/auto\\\/gli-italiani-combattono-la-crisi-condividendo-la%25252580%25252599auto-e-le-spese\\\/\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/motori\\\/auto\\\/gli-italiani-combattono-la-crisi-condividendo-la%25252580%25252599auto-e-le-spese\\\/\",\"name\":\"Gli italiani combattono la crisi condividendo l\u2019auto e le spese - Article Marketing\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\"},\"datePublished\":\"2012-11-28T15:34:44+00:00\",\"dateModified\":\"2018-07-10T04:03:50+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/motori\\\/auto\\\/gli-italiani-combattono-la-crisi-condividendo-la%25252580%25252599auto-e-le-spese\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/motori\\\/auto\\\/gli-italiani-combattono-la-crisi-condividendo-la%25252580%25252599auto-e-le-spese\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/motori\\\/auto\\\/gli-italiani-combattono-la-crisi-condividendo-la%25252580%25252599auto-e-le-spese\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gli italiani combattono la crisi condividendo l\u2019auto e le spese\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\",\"name\":\"Article Marketing\",\"description\":\"article marketing &amp; press release\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\",\"name\":\"Redazione Comunicati Stampa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"caption\":\"Redazione Comunicati Stampa\"},\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/author\\\/redazione-comunicati-stampa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gli italiani combattono la crisi condividendo l\u2019auto e le spese - Article Marketing","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.article-marketing.eu\/comunicati\/motori\/auto\/gli-italiani-combattono-la-crisi-condividendo-la%252580%252599auto-e-le-spese\/","og_locale":"it_IT","og_type":"article","og_title":"Gli italiani combattono la crisi condividendo l\u2019auto e le spese - Article Marketing","og_description":"Sbarca in Italia carpooling, il nuovo metodo che rivoluziona l\u2019idea dell\u2019autostop: un\u2019automobile da condividere per percorrere lo stesso itinerario, in compagnia e risparmiando tempo e costi.","og_url":"https:\/\/www.article-marketing.eu\/comunicati\/motori\/auto\/gli-italiani-combattono-la-crisi-condividendo-la%252580%252599auto-e-le-spese\/","og_site_name":"Article Marketing","article_published_time":"2012-11-28T15:34:44+00:00","article_modified_time":"2018-07-10T04:03:50+00:00","author":"Redazione Comunicati Stampa","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione Comunicati Stampa","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.article-marketing.eu\/comunicati\/motori\/auto\/gli-italiani-combattono-la-crisi-condividendo-la%25252580%25252599auto-e-le-spese\/#article","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/motori\/auto\/gli-italiani-combattono-la-crisi-condividendo-la%25252580%25252599auto-e-le-spese\/"},"author":{"name":"Redazione Comunicati Stampa","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"headline":"Gli italiani combattono la crisi condividendo l\u2019auto e le spese","datePublished":"2012-11-28T15:34:44+00:00","dateModified":"2018-07-10T04:03:50+00:00","mainEntityOfPage":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/motori\/auto\/gli-italiani-combattono-la-crisi-condividendo-la%25252580%25252599auto-e-le-spese\/"},"wordCount":610,"commentCount":0,"articleSection":["Auto"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.article-marketing.eu\/comunicati\/motori\/auto\/gli-italiani-combattono-la-crisi-condividendo-la%25252580%25252599auto-e-le-spese\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.article-marketing.eu\/comunicati\/motori\/auto\/gli-italiani-combattono-la-crisi-condividendo-la%25252580%25252599auto-e-le-spese\/","url":"https:\/\/www.article-marketing.eu\/comunicati\/motori\/auto\/gli-italiani-combattono-la-crisi-condividendo-la%25252580%25252599auto-e-le-spese\/","name":"Gli italiani combattono la crisi condividendo l\u2019auto e le spese - Article Marketing","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website"},"datePublished":"2012-11-28T15:34:44+00:00","dateModified":"2018-07-10T04:03:50+00:00","author":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"breadcrumb":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/motori\/auto\/gli-italiani-combattono-la-crisi-condividendo-la%25252580%25252599auto-e-le-spese\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.article-marketing.eu\/comunicati\/motori\/auto\/gli-italiani-combattono-la-crisi-condividendo-la%25252580%25252599auto-e-le-spese\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.article-marketing.eu\/comunicati\/motori\/auto\/gli-italiani-combattono-la-crisi-condividendo-la%25252580%25252599auto-e-le-spese\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.article-marketing.eu\/comunicati\/"},{"@type":"ListItem","position":2,"name":"Gli italiani combattono la crisi condividendo l\u2019auto e le spese"}]},{"@type":"WebSite","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website","url":"https:\/\/www.article-marketing.eu\/comunicati\/","name":"Article Marketing","description":"article marketing &amp; press release","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.article-marketing.eu\/comunicati\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017","name":"Redazione Comunicati Stampa","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","caption":"Redazione Comunicati Stampa"},"url":"https:\/\/www.article-marketing.eu\/comunicati\/author\/redazione-comunicati-stampa\/"}]}},"_links":{"self":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/31081","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/comments?post=31081"}],"version-history":[{"count":1,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/31081\/revisions"}],"predecessor-version":[{"id":62648,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/31081\/revisions\/62648"}],"wp:attachment":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/media?parent=31081"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/categories?post=31081"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/tags?post=31081"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}