{"id":31225,"date":"2012-12-05T16:08:09","date_gmt":"2012-12-05T15:08:09","guid":{"rendered":"http:\/\/www.article-marketing.eu\/comunicati\/senza-categoria\/un-consumatore-su-quattro-%c3%a8-vittima-di-frodi-con-carte-di-credito-lo-rivela-la%80%99annuale-report-aci-worldwide-global-fraud\/"},"modified":"2012-12-05T16:08:09","modified_gmt":"2012-12-05T15:08:09","slug":"un-consumatore-su-quattro-%c3%a8-vittima-di-frodi-con-carte-di-credito-lo-rivela-la%80%99annuale-report-aci-worldwide-global-fraud","status":"publish","type":"post","link":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/un-consumatore-su-quattro-%c3%a8-vittima-di-frodi-con-carte-di-credito-lo-rivela-la%80%99annuale-report-aci-worldwide-global-fraud\/","title":{"rendered":"Un consumatore su quattro \u00e8 vittima di frodi con carte di credito: lo rivela l\u2019annuale report ACI Worldwide Global Fraud"},"content":{"rendered":"<p>Un intervistato su quattro &egrave; stato vittima, negli ultimi cinque anni, di frodi con carta di credito. Questo il principale risultato emerso dallo studio condotto da ACI Worldwide e Aite Group, sul tema delle frodi relative alle carte di credito, che ha coinvolto oltre 5.200 consumatori di 17 Paesi a livello mondiale. Oltre il 20% degli intervistati ha dichiarato inoltre che ha smesso di utilizzare, o ha cambiato la propria carta, dopo aver subito un atto fraudolento. <br \/>Secondo lo studio gli abitanti del Messico e degli Stati Uniti hanno mostrato la pi&ugrave; alta percentuale di esperienza diretta di una frode con carta, rispettivamente il 44% e 42%, mentre gli abitanti dei Paesi Bassi e della Svezia si sono classificati per il minor livello di frodi con il 12%. L&rsquo;Italia si posiziona con il 24% di cittadini che ha subito una frode. <br \/>&ldquo;I risultati di questo sondaggio mostrano che le frodi con carte sono la pi&ugrave; grande preoccupazione per i consumatori, gli istituti finanziari e i retailer&rdquo;, ha dichiarato Mike Braatz, Senior Vice President, Payments Fraud di ACI Worldwide. &ldquo;Mentre ci sono stati significativi passi avanti nell&rsquo;ambito dello sviluppo di tecnologie per la prevenzione delle frodi, &egrave; chiaro che molto bisogna ancora fare per educare i consumatori su questa tematica e per coinvolgerli quando necessario. Questi risultati dovrebbero servire per allertare gli istituti finanziari e i retailer a restare costantemente vigili, e a guadagnare la fiducia dei consumatori lavorando insieme a loro per combattere le frodi&rdquo;. <br \/>In questo contesto, il report ha rilevato che i livelli di soddisfazione dei consumatori, relativamente al trattamento ricevuto dai gestori delle proprie carte di credito, parte dal tasso pi&ugrave; basso di insoddisfazione in Svezia, con il 13%, fino al pi&ugrave; alto raggiunto proprio dal nostro Paese con il 57%. Per comprendere meglio quali siano invece le iniziative che gli istituti finanziari hanno intrapreso per soddisfare i propri clienti, ACI Worldwide ha chiesto agli intervistati di valutare una serie di attivit&agrave; che hanno migliorato il rapporto con il proprio gestore di carte. Tutti i Paesi Europei coinvolti nel sondaggio hanno segnalato al primo posto la velocit&agrave; con cui l&rsquo;istituto di credito ha identificato la frode e l&rsquo;ha segnalata al cliente, seguita dalla velocit&agrave; di rimborso, rispettivamente il 32% e il 23% degli intervistati in Italia. <br \/>Inoltre, il sondaggio ha evidenziato che: <br \/><strong>Gli istituti finanziari rischiano di perdere i clienti a causa delle frodi<\/strong><br \/>&middot; L&rsquo;attrition rate raggiunge il 21% tra i possessori di carte di credito che hanno subito una frode;<br \/>&middot; Il 46% dei possessori di carte di credito, che hanno sostituito la propria carta dopo aver subito una frode nell&rsquo;ultimo anno, utilizza quella nuova molto meno rispetto alla precedente. In Europa, la Francia ha la pi&ugrave; bassa percentuale di intervistati che utilizza la nuova carta meno di quella precedente con il 25%, seguita dalla Svezia con il 26%. L&rsquo;Italia raggiunge invece il 34% degli intervistati;<br \/>&middot; Dopo aver subito un&rsquo;attivit&agrave; fraudolenta pi&ugrave; del 50% dei possessori di carte utilizza contanti, o un mezzo alternativo di pagamento, invece della propria carta di credito o debito. <br \/><strong>I consumatori che hanno paura del furto d&rsquo;identit&agrave; continuano comunque a tenere comportamenti a rischio<\/strong><\/p>\n<ul style=\"margin-top:0cm\" type=\"disc\"><\/p>\n<li class=\"MsoNormal\" style=\"text-align:justify;line-height:18.0pt;mso-list: l2 level1 lfo2;tab-stops:list 36.0pt\">Dal sondaggio &egrave; emerso che il furto d&rsquo;identit&agrave; &egrave; ci&ograve; che maggiormente preoccupa gli utenti, anche rispetto alle frodi con carte di credito. Infatti, il 49% degli intervistati indica di essere molto preoccupato di subire un attacco alla propria situazione finanziaria;<\/li>\n<p><\/p>\n<li class=\"MsoNormal\" style=\"text-align:justify;line-height:18.0pt;mso-list: l2 level1 lfo2;tab-stops:list 36.0pt\">Molti consumatori continuano ad adottare comportamenti rischiosi, come quello di tenere scritti i propri numeri di PIN, buttare documenti che contengono informazioni sensibili senza distruggerli e utilizzare computer pubblici, o senza software di sicurezza, per servizi di Internet banking o acquisti on line. Queste azioni sottopongono gli utenti a un alto rischio di subire frodi finanziarie. A livello europeo, l&rsquo;Italia, ha la pi&ugrave; alta percentuale di consumatori che scrive il proprio PIN e lo tiene insieme alla carta, con il 17%. <strong><\/strong><\/li>\n<p><\/ul>\n<p><strong> <\/strong><strong style=\"line-height: 18pt;\">I consumatori vogliono collaborare con le banche per prevenire le frodi<\/strong><\/p>\n<ul style=\"margin-top:0cm\" type=\"disc\"><\/p>\n<li class=\"MsoNormal\" style=\"text-align:justify;line-height:18.0pt;mso-list: l0 level1 lfo3;tab-stops:list 36.0pt\">L&rsquo;82% degli intervistati si mostra &ldquo;molto interessato&rdquo; a ricevere una notifica dalla propria banca prima che questa decida di agire, avendo notato attivit&agrave; inusuali sui propri conti o carte;<\/li>\n<p><\/p>\n<li class=\"MsoNormal\" style=\"text-align:justify;line-height:18.0pt;mso-list: l0 level1 lfo3;tab-stops:list 36.0pt\">I consumatori preferiscono un&rsquo;immediata e diretta comunicazione da parte della propria banca, quando viene rilevata un&rsquo;attivit&agrave; fraudolenta. Il metodo con cui preferiscono essere contattati &egrave; ricevere una telefonata al proprio cellulare, seguito dall&rsquo;e-mail e dall&rsquo;SMS. Questo mostra un cambiamento rispetto al 2011 dove essere contattati al telefono era, in ordine di preferenza, al secondo posto. <\/li>\n<p><\/ul>\n<p>&ldquo;Nel 2012 il sondaggio ha dipinto un chiaro quadro della natura e delle minacce relative alle frodi&rdquo;, ha affermato Shirley Inscoe, Senior Analyst di Aite Group. &ldquo;Gli istituti finanziari, gli issuer e i retailer devono coinvolgere i consumatori nella battaglia contro le frodi, educarli all&rsquo;utilizzo di best practice per prevenirle e assicurarli relativamente alle policy adottate. Ottenere la soddisfazione dei clienti, la loro fidelizzazione e mantenere uno &ldquo;share of wallet&rdquo; si pu&ograve; raggiungere solo comunicando con loro e coinvolgendoli nella lotta alle frodi&rdquo;. <br \/>Per leggere il report completo: http:\/\/www.aciworldwide.com\/en\/Annual-fraud-survey\/Request-survey.aspx <br \/><strong>Metodologia<\/strong><br \/>ACI Worldwide, leader a livello internazionale per le soluzioni di gestione dei pagamenti elettronici rivolti a istituti finanziari, retailer e processor, ha condotto, tra luglio e agosto 2012, una ricerca di mercato quantitativa on line, presso un totale di 17 Paesi come segue: <br \/>&middot; Americhe (Nord e Sud America): Brasile, Canada, Messico e Stati Uniti;<br \/>&middot; EMEA (Europa, Medio Oriente e Africa): Francia, Germania, Italia, Paesi Bassi, Sud Africa, Svezia, Emirati Arabi Uniti e Regno Unito;<br \/>&middot; Asia Pacifico: Australia, Cina, India, Indonesia e Singapore. <br \/>In totale sono stati intervistati 5.223 consumatori suddivisi come segue: circa 300, tra uomini e donne, hanno partecipato per ognuno dei 17 Paesi. Sul totale, 5.114 possiedono una o pi&ugrave; tipologie di carte (es. carta di credito, carta di debito, carta di debito pre-pagata). Nel report, i dati relativi alle frodi di carte si focalizzano su questa tipologia di possessori di carte.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pi\u00f9 del 20% di possessori di carte smette di utilizzarle o cambia carta dopo essere stato vittima di una frode<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"","footnotes":""},"categories":[190],"tags":[26635],"class_list":["post-31225","post","type-post","status-publish","format-standard","hentry","category-comunicati-stampa","tag-aci-worldwide"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Un consumatore su quattro \u00e8 vittima di frodi con carte di credito: lo rivela l\u2019annuale report ACI Worldwide Global Fraud - Article Marketing<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/un-consumatore-su-quattro-\u00e8-vittima-di-frodi-con-carte-di-credito-lo-rivela-la??annuale-report-aci-worldwide-global-fraud\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Un consumatore su quattro \u00e8 vittima di frodi con carte di credito: lo rivela l\u2019annuale report ACI Worldwide Global Fraud - Article Marketing\" \/>\n<meta property=\"og:description\" content=\"Pi\u00f9 del 20% di possessori di carte smette di utilizzarle o cambia carta dopo essere stato vittima di una frode\" \/>\n<meta property=\"og:url\" content=\"\" \/>\n<meta property=\"og:site_name\" content=\"Article Marketing\" \/>\n<meta property=\"article:published_time\" content=\"2012-12-05T15:08:09+00:00\" \/>\n<meta name=\"author\" content=\"Redazione Comunicati Stampa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione Comunicati Stampa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/un-consumatore-su-quattro-%c3%a8-vittima-di-frodi-con-carte-di-credito-lo-rivela-la%80%99annuale-report-aci-worldwide-global-fraud\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/un-consumatore-su-quattro-%c3%a8-vittima-di-frodi-con-carte-di-credito-lo-rivela-la%80%99annuale-report-aci-worldwide-global-fraud\\\/\"},\"author\":{\"name\":\"Redazione Comunicati Stampa\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"headline\":\"Un consumatore su quattro \u00e8 vittima di frodi con carte di credito: lo rivela l\u2019annuale report ACI Worldwide Global Fraud\",\"datePublished\":\"2012-12-05T15:08:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/un-consumatore-su-quattro-%c3%a8-vittima-di-frodi-con-carte-di-credito-lo-rivela-la%80%99annuale-report-aci-worldwide-global-fraud\\\/\"},\"wordCount\":1042,\"commentCount\":0,\"keywords\":[\"ACI Worldwide\"],\"articleSection\":[\"Comunicati stampa\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/un-consumatore-su-quattro-%c3%a8-vittima-di-frodi-con-carte-di-credito-lo-rivela-la%80%99annuale-report-aci-worldwide-global-fraud\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/un-consumatore-su-quattro-%c3%a8-vittima-di-frodi-con-carte-di-credito-lo-rivela-la%80%99annuale-report-aci-worldwide-global-fraud\\\/\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/un-consumatore-su-quattro-%c3%a8-vittima-di-frodi-con-carte-di-credito-lo-rivela-la%80%99annuale-report-aci-worldwide-global-fraud\\\/\",\"name\":\"Un consumatore su quattro \u00e8 vittima di frodi con carte di credito: lo rivela l\u2019annuale report ACI Worldwide Global Fraud - Article Marketing\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\"},\"datePublished\":\"2012-12-05T15:08:09+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/un-consumatore-su-quattro-%c3%a8-vittima-di-frodi-con-carte-di-credito-lo-rivela-la%80%99annuale-report-aci-worldwide-global-fraud\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/un-consumatore-su-quattro-%c3%a8-vittima-di-frodi-con-carte-di-credito-lo-rivela-la%80%99annuale-report-aci-worldwide-global-fraud\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/un-consumatore-su-quattro-%c3%a8-vittima-di-frodi-con-carte-di-credito-lo-rivela-la%80%99annuale-report-aci-worldwide-global-fraud\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Un consumatore su quattro \u00e8 vittima di frodi con carte di credito: lo rivela l\u2019annuale report ACI Worldwide Global Fraud\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\",\"name\":\"Article Marketing\",\"description\":\"article marketing &amp; press release\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\",\"name\":\"Redazione Comunicati Stampa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"caption\":\"Redazione Comunicati Stampa\"},\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/author\\\/redazione-comunicati-stampa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Un consumatore su quattro \u00e8 vittima di frodi con carte di credito: lo rivela l\u2019annuale report ACI Worldwide Global Fraud - Article Marketing","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/un-consumatore-su-quattro-\u00e8-vittima-di-frodi-con-carte-di-credito-lo-rivela-la??annuale-report-aci-worldwide-global-fraud\/","og_locale":"it_IT","og_type":"article","og_title":"Un consumatore su quattro \u00e8 vittima di frodi con carte di credito: lo rivela l\u2019annuale report ACI Worldwide Global Fraud - Article Marketing","og_description":"Pi\u00f9 del 20% di possessori di carte smette di utilizzarle o cambia carta dopo essere stato vittima di una frode","og_url":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/un-consumatore-su-quattro-\u00e8-vittima-di-frodi-con-carte-di-credito-lo-rivela-la??annuale-report-aci-worldwide-global-fraud\/","og_site_name":"Article Marketing","article_published_time":"2012-12-05T15:08:09+00:00","author":"Redazione Comunicati Stampa","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione Comunicati Stampa","Tempo di lettura stimato":"5 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/un-consumatore-su-quattro-%c3%a8-vittima-di-frodi-con-carte-di-credito-lo-rivela-la%80%99annuale-report-aci-worldwide-global-fraud\/#article","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/un-consumatore-su-quattro-%c3%a8-vittima-di-frodi-con-carte-di-credito-lo-rivela-la%80%99annuale-report-aci-worldwide-global-fraud\/"},"author":{"name":"Redazione Comunicati Stampa","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"headline":"Un consumatore su quattro \u00e8 vittima di frodi con carte di credito: lo rivela l\u2019annuale report ACI Worldwide Global Fraud","datePublished":"2012-12-05T15:08:09+00:00","mainEntityOfPage":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/un-consumatore-su-quattro-%c3%a8-vittima-di-frodi-con-carte-di-credito-lo-rivela-la%80%99annuale-report-aci-worldwide-global-fraud\/"},"wordCount":1042,"commentCount":0,"keywords":["ACI Worldwide"],"articleSection":["Comunicati stampa"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/un-consumatore-su-quattro-%c3%a8-vittima-di-frodi-con-carte-di-credito-lo-rivela-la%80%99annuale-report-aci-worldwide-global-fraud\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/un-consumatore-su-quattro-%c3%a8-vittima-di-frodi-con-carte-di-credito-lo-rivela-la%80%99annuale-report-aci-worldwide-global-fraud\/","url":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/un-consumatore-su-quattro-%c3%a8-vittima-di-frodi-con-carte-di-credito-lo-rivela-la%80%99annuale-report-aci-worldwide-global-fraud\/","name":"Un consumatore su quattro \u00e8 vittima di frodi con carte di credito: lo rivela l\u2019annuale report ACI Worldwide Global Fraud - Article Marketing","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website"},"datePublished":"2012-12-05T15:08:09+00:00","author":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"breadcrumb":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/un-consumatore-su-quattro-%c3%a8-vittima-di-frodi-con-carte-di-credito-lo-rivela-la%80%99annuale-report-aci-worldwide-global-fraud\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/un-consumatore-su-quattro-%c3%a8-vittima-di-frodi-con-carte-di-credito-lo-rivela-la%80%99annuale-report-aci-worldwide-global-fraud\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/un-consumatore-su-quattro-%c3%a8-vittima-di-frodi-con-carte-di-credito-lo-rivela-la%80%99annuale-report-aci-worldwide-global-fraud\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.article-marketing.eu\/comunicati\/"},{"@type":"ListItem","position":2,"name":"Un consumatore su quattro \u00e8 vittima di frodi con carte di credito: lo rivela l\u2019annuale report ACI Worldwide Global Fraud"}]},{"@type":"WebSite","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website","url":"https:\/\/www.article-marketing.eu\/comunicati\/","name":"Article Marketing","description":"article marketing &amp; press release","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.article-marketing.eu\/comunicati\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017","name":"Redazione Comunicati Stampa","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","caption":"Redazione Comunicati Stampa"},"url":"https:\/\/www.article-marketing.eu\/comunicati\/author\/redazione-comunicati-stampa\/"}]}},"_links":{"self":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/31225","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/comments?post=31225"}],"version-history":[{"count":0,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/31225\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/media?parent=31225"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/categories?post=31225"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/tags?post=31225"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}