{"id":32110,"date":"2013-01-29T22:16:10","date_gmt":"2013-01-29T21:16:10","guid":{"rendered":"http:\/\/www.article-marketing.eu\/comunicati\/senza-categoria\/vicinidibanco-un-viaggio-fra-annuari-e-ricordi-di-scuola\/"},"modified":"2018-10-25T22:01:06","modified_gmt":"2018-10-25T20:01:06","slug":"vicinidibanco-un-viaggio-fra-annuari-e-ricordi-di-scuola","status":"publish","type":"post","link":"https:\/\/www.article-marketing.eu\/comunicati\/istruzione\/scuole\/vicinidibanco-un-viaggio-fra-annuari-e-ricordi-di-scuola\/","title":{"rendered":"ViciniDiBanco, un viaggio fra annuari e ricordi di scuola"},"content":{"rendered":"<p>ViciniDiBanco &egrave; un sito italiano nato con lo scopo di creare annuari scolastici consultabili online&#8230; Avete presente i classici giornalini americani dove, per ogni scuola ed annata, vi sono mostrate tutte le sezioni che vi hanno preso parte?? Questo sito si propone esattamente questo obiettivo. In poche parole si tratta di un sito internet dove gli utenti iscritti partecipano costruttivamente alla creazione di un giornalino virtuale in cui, scelta la scuola e l&#8217;anno scolastico desiderati, si potranno visualizzare tutte le immagini delle varie classi che hanno frequentato quella scuola in quel determinato anno (per esempio, scegliendo l&#8217;annuario del liceo &#8220;Rossi&#8221; per l&#8217;anno 2003\/2004, si potranno vedere le immagini di tutte le classi che hanno frequentato il liceo partendo dalla sezione 1A fino ad arrivare alle classi quinte). Una volta iscritti al portale, verranno infatti chieste all&#8217;utente la classe\/scuola frequentate ed automaticamente, con la foto di classe caricata, verr&aacute; inserita la sua sezione nell&#8217;annuario corrispondente.<br \/>Purtroppo, anche se l&#8217;idea di fondo sembrava essere molto simpatica, quasi nessuno sembrava essere interessato a partecipare a questo progetto, cos&igrave; ViciniDiBanco ha dovuto aggiungere a questo servizio iniziale moltissimi altri che l&#8217;hanno reso molto pi&ugrave; completo ed interessante.<br \/>Tra i molti sono da citare soprattutto questi&#8230;<\/p>\n<p>&#8211; RICREAZIONE VIRTUALE DELLE SEZIONI (&egrave; possibile visualizzare gli alunni delle sezioni delle varie scuole, suddivise per annate. Prendendo sempre il liceo &#8220;Rossi&#8221; e l&#8217;anno scolastico 2003\/2004, si potranno visualizzare tutti gli alunni che hanno frequentato le varie sezioni in quel determinato anno)<br \/>&#8211; INTERAGIRE CON GLI ALTRI UTENTI (grazie alla creazione di un profilo personale al momento dell&#8217;iscrizione &egrave; possibile dichiarare di conoscere gli altri utenti per entrare in contatto con loro e mandare messaggi privati)<br \/>&#8211; SEZIONE PRIVATA CON I COMPAGNI DI CLASSE (una volta dichiarata la classe frequentata, il sistema creera automaticamente una sezione privata dove si possono organizzare rimpatriate e ricordare il passato scolastico attraverso foto, video e dediche) <br \/>&#8211; BLOG DELLA SCUOLA (blog singolo della scuola gestito dagli studenti stessi dove possono scrivere articoli che potrebbero essere utili a tutti gli altri alunni) <br \/>&#8211; MOLTO ALTRO (una bacheca degli annunci per ogni singola scuola dove gli alunni possono scambiare i materiali didattici con gli altri compagni di istituto; una sezione professori dove gli studenti possono dare un&#8217;opinione personale o anonima sui loro docenti; una sezione dove &egrave; possibile chiedere aiuto per i compiti agli altri membri della comunit&aacute;; e molto, molto altro&#8230;) <\/p>\n<p>E voi cosa ne pensate di questo progetto tutto italiano?? Non siete rimasti un po&#8217; incuriositi da questo simpatico sito internet?? Se anche voi volete partecipare alla creazione degli annuari (o semplicemente avete voglia di conoscere altre informazioni), andate a visitare ViciniDiBanco ed entrate a far parte della community!!! <br \/>LINK PER IL SITO: http:\/\/www.vicinidibanco.it<\/p>\n","protected":false},"excerpt":{"rendered":"<p>ViciniDiBanco \u00e8 il primo sito in Italia dedicato agli annuari scolastici e permette di ricreare virtualmente le varie classi per trovare vecchi compagni di scuola.<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"","footnotes":""},"categories":[879],"tags":[40828,40830,40827,40829],"class_list":["post-32110","post","type-post","status-publish","format-standard","hentry","category-scuole","tag-annuari-di-scuola","tag-annuari-scolastici","tag-annuario","tag-ricordi-scuola"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>ViciniDiBanco, un viaggio fra annuari e ricordi di scuola - Article Marketing<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.article-marketing.eu\/comunicati\/istruzione\/scuole\/vicinidibanco-un-viaggio-fra-annuari-e-ricordi-di-scuola\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ViciniDiBanco, un viaggio fra annuari e ricordi di scuola - Article Marketing\" \/>\n<meta property=\"og:description\" content=\"ViciniDiBanco \u00e8 il primo sito in Italia dedicato agli annuari scolastici e permette di ricreare virtualmente le varie classi per trovare vecchi compagni di scuola.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.article-marketing.eu\/comunicati\/istruzione\/scuole\/vicinidibanco-un-viaggio-fra-annuari-e-ricordi-di-scuola\/\" \/>\n<meta property=\"og:site_name\" content=\"Article Marketing\" \/>\n<meta property=\"article:published_time\" content=\"2013-01-29T21:16:10+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-10-25T20:01:06+00:00\" \/>\n<meta name=\"author\" content=\"Redazione Comunicati Stampa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione Comunicati Stampa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/istruzione\\\/scuole\\\/vicinidibanco-un-viaggio-fra-annuari-e-ricordi-di-scuola\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/istruzione\\\/scuole\\\/vicinidibanco-un-viaggio-fra-annuari-e-ricordi-di-scuola\\\/\"},\"author\":{\"name\":\"Redazione Comunicati Stampa\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"headline\":\"ViciniDiBanco, un viaggio fra annuari e ricordi di scuola\",\"datePublished\":\"2013-01-29T21:16:10+00:00\",\"dateModified\":\"2018-10-25T20:01:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/istruzione\\\/scuole\\\/vicinidibanco-un-viaggio-fra-annuari-e-ricordi-di-scuola\\\/\"},\"wordCount\":467,\"commentCount\":0,\"keywords\":[\"annuari di scuola\",\"annuari scolastici\",\"Annuario\",\"ricordi scuola\"],\"articleSection\":[\"Scuole\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/istruzione\\\/scuole\\\/vicinidibanco-un-viaggio-fra-annuari-e-ricordi-di-scuola\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/istruzione\\\/scuole\\\/vicinidibanco-un-viaggio-fra-annuari-e-ricordi-di-scuola\\\/\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/istruzione\\\/scuole\\\/vicinidibanco-un-viaggio-fra-annuari-e-ricordi-di-scuola\\\/\",\"name\":\"ViciniDiBanco, un viaggio fra annuari e ricordi di scuola - Article Marketing\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\"},\"datePublished\":\"2013-01-29T21:16:10+00:00\",\"dateModified\":\"2018-10-25T20:01:06+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/istruzione\\\/scuole\\\/vicinidibanco-un-viaggio-fra-annuari-e-ricordi-di-scuola\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/istruzione\\\/scuole\\\/vicinidibanco-un-viaggio-fra-annuari-e-ricordi-di-scuola\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/istruzione\\\/scuole\\\/vicinidibanco-un-viaggio-fra-annuari-e-ricordi-di-scuola\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ViciniDiBanco, un viaggio fra annuari e ricordi di scuola\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\",\"name\":\"Article Marketing\",\"description\":\"article marketing &amp; press release\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\",\"name\":\"Redazione Comunicati Stampa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"caption\":\"Redazione Comunicati Stampa\"},\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/author\\\/redazione-comunicati-stampa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ViciniDiBanco, un viaggio fra annuari e ricordi di scuola - Article Marketing","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.article-marketing.eu\/comunicati\/istruzione\/scuole\/vicinidibanco-un-viaggio-fra-annuari-e-ricordi-di-scuola\/","og_locale":"it_IT","og_type":"article","og_title":"ViciniDiBanco, un viaggio fra annuari e ricordi di scuola - Article Marketing","og_description":"ViciniDiBanco \u00e8 il primo sito in Italia dedicato agli annuari scolastici e permette di ricreare virtualmente le varie classi per trovare vecchi compagni di scuola.","og_url":"https:\/\/www.article-marketing.eu\/comunicati\/istruzione\/scuole\/vicinidibanco-un-viaggio-fra-annuari-e-ricordi-di-scuola\/","og_site_name":"Article Marketing","article_published_time":"2013-01-29T21:16:10+00:00","article_modified_time":"2018-10-25T20:01:06+00:00","author":"Redazione Comunicati Stampa","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione Comunicati Stampa","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.article-marketing.eu\/comunicati\/istruzione\/scuole\/vicinidibanco-un-viaggio-fra-annuari-e-ricordi-di-scuola\/#article","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/istruzione\/scuole\/vicinidibanco-un-viaggio-fra-annuari-e-ricordi-di-scuola\/"},"author":{"name":"Redazione Comunicati Stampa","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"headline":"ViciniDiBanco, un viaggio fra annuari e ricordi di scuola","datePublished":"2013-01-29T21:16:10+00:00","dateModified":"2018-10-25T20:01:06+00:00","mainEntityOfPage":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/istruzione\/scuole\/vicinidibanco-un-viaggio-fra-annuari-e-ricordi-di-scuola\/"},"wordCount":467,"commentCount":0,"keywords":["annuari di scuola","annuari scolastici","Annuario","ricordi scuola"],"articleSection":["Scuole"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.article-marketing.eu\/comunicati\/istruzione\/scuole\/vicinidibanco-un-viaggio-fra-annuari-e-ricordi-di-scuola\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.article-marketing.eu\/comunicati\/istruzione\/scuole\/vicinidibanco-un-viaggio-fra-annuari-e-ricordi-di-scuola\/","url":"https:\/\/www.article-marketing.eu\/comunicati\/istruzione\/scuole\/vicinidibanco-un-viaggio-fra-annuari-e-ricordi-di-scuola\/","name":"ViciniDiBanco, un viaggio fra annuari e ricordi di scuola - Article Marketing","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website"},"datePublished":"2013-01-29T21:16:10+00:00","dateModified":"2018-10-25T20:01:06+00:00","author":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"breadcrumb":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/istruzione\/scuole\/vicinidibanco-un-viaggio-fra-annuari-e-ricordi-di-scuola\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.article-marketing.eu\/comunicati\/istruzione\/scuole\/vicinidibanco-un-viaggio-fra-annuari-e-ricordi-di-scuola\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.article-marketing.eu\/comunicati\/istruzione\/scuole\/vicinidibanco-un-viaggio-fra-annuari-e-ricordi-di-scuola\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.article-marketing.eu\/comunicati\/"},{"@type":"ListItem","position":2,"name":"ViciniDiBanco, un viaggio fra annuari e ricordi di scuola"}]},{"@type":"WebSite","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website","url":"https:\/\/www.article-marketing.eu\/comunicati\/","name":"Article Marketing","description":"article marketing &amp; press release","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.article-marketing.eu\/comunicati\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017","name":"Redazione Comunicati Stampa","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","caption":"Redazione Comunicati Stampa"},"url":"https:\/\/www.article-marketing.eu\/comunicati\/author\/redazione-comunicati-stampa\/"}]}},"_links":{"self":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/32110","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/comments?post=32110"}],"version-history":[{"count":1,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/32110\/revisions"}],"predecessor-version":[{"id":62839,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/32110\/revisions\/62839"}],"wp:attachment":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/media?parent=32110"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/categories?post=32110"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/tags?post=32110"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}