{"id":32468,"date":"2013-02-15T12:43:12","date_gmt":"2013-02-15T11:43:12","guid":{"rendered":"http:\/\/www.article-marketing.eu\/comunicati\/senza-categoria\/alla-scoperta-di-vinci\/"},"modified":"2018-10-25T22:01:43","modified_gmt":"2018-10-25T20:01:43","slug":"alla-scoperta-di-vinci","status":"publish","type":"post","link":"https:\/\/www.article-marketing.eu\/comunicati\/viaggi-e-vacanze\/agriturismi\/alla-scoperta-di-vinci\/","title":{"rendered":"Alla Scoperta di Vinci&#8230;Agriturismo Le Colline di Vinci"},"content":{"rendered":"<p>Vinci&hellip;. Come Leonardo da Vinci&hellip;come la citt&agrave; che diede tanti Natali a questo genio del passato nato nel lontano 1452&hellip;Una piccola cittadina, incastonata tra le dolci colline toscane, sulle pendici del Montalbano, ricco di vigneti e oliveti secolari.<br \/>Situata nella parte settentrionale della toscana, a renderla ancora pi&ugrave; unica, oltre al fatto che qui trascorse l&rsquo;infanzia Leonardo, prima di essere portato dal padre a Firenze nelle botteghe di artisti e di pittori, &egrave; la forma a &ldquo;mandorla&rdquo; della sua parte pi&ugrave; antica, chiamata per questo motivo &ldquo;Castel della Neve&rdquo;.<br \/>La visione dall&rsquo;alto ricorda un&rsquo;imbarcazione a due alberi, alberi che sono rappresentati dalla torre della Rocca dei Conti Guidi e dal campanile della chiesa di Santa Croce.<br \/>Meta immancabile per i turisti che ogni anno si recano in questi territori, la cittadina di Vinci e le zone circostanti, offrono numerosi spunti e idee per trascorrere una vacanza indimenticabile, sia per le numerose strutture ricettive presenti, sia per le tante attivit&agrave;, escursioni e visite possibili alle vicine citt&agrave; d&rsquo;arte, alle bellezze storiche e naturalistiche.<br \/>Situato infatti in questo piccolo paese, &egrave; un grazioso e tipico Agriturismo Vinci con Piscina, un casolare toscano in pietra, le cui origini risalgono al 1500, ristrutturato mantenendo inalterate le autenticit&agrave; del luogo.<br \/>Da qui si apre un bellissimo panorama su San Miniato e sugli uliveti che circondano l&rsquo;Agriturismo Vinci, rendendolo anche un luogo dove rifugiarsi per rigenerare corpo e mente dallo stress della vita quotidiana, e per un turismo ecologico.<br \/>Ed &egrave; da qui che si parte in primis alla scoperta della casa Natale di Leonrado da Vinci, ad Alchiano, una casa di contadini del &#8216;500 con facciata in pietra. Riaperta al pubblico dopo un accurato intervento di restauro, al sui interno &egrave; stato allestito un museo logico, dove &egrave; possibile trovare varie riproduzioni di disegni leonardiani che raffigurano la campagna toscana e una mappa del Valdarno tracciata dallo stesso Leonardo.<br \/>Ad arricchire e completare il viaggio alla scoperta di questi luoghi vissuti da Leonardo da Vinci &egrave; una visita anche al Museo Leonardiano e al Museo Ideale di Leonardo, situati nel centro storico di Vinci.<br \/>Il primo, rappresenta la raccolta pi&ugrave; ampia dei progetti di Leonardo inventore (modelli per macchine da guerra, da cantiere e da uso scientifico, la bicicletta, gli sci d&#8217;acqua, il paracadute&hellip;); il secondo , primo museo ideale nel mondo, al cui interno sono esposti alcuni dei suoi capolavori pi&ugrave; noti, aperto oggi, nel suggestivo spazio delle cantine del Castello di Vinci.<br \/>Storia, Arte, Cultura&hellip;ma anche buon cibo, prodotti tipici e un immenso patrimonio naturalistico che collega il paese di Vinci ad Alchiano&hellip;Colline, distese di vigneti e oliveti, da scoprire attraverso un interessante percorso chiamato &ldquo;Strada Verde&rdquo;. &hellip;<br \/>Questo e Tanto altro Vi Aspetta a Vinci&hellip;!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Vinci\u2026. Come Leonardo da Vinci\u2026come la citt\u00e0 che diede tanti Natali a questo genio del passato nato nel lontano 1452\u2026Una piccola cittadina, incastonata tra le dolci colline toscane, sulle pendici del Montalbano, ricco di vigneti e oliveti secolari. Situato infatti in questo piccolo paese, \u00e8 un grazioso e tipico Agriturismo Vinci con Piscina, un casolare toscano in pietra, le cui origini risalgono al 1500, ristrutturato mantenendo inalterate le autenticit\u00e0 del luogo.<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"","footnotes":""},"categories":[521],"tags":[41070,41064,41065,41067,41068,27836,41066,41071,41069],"class_list":["post-32468","post","type-post","status-publish","format-standard","hentry","category-agriturismi","tag-agriturismi-a-firenze","tag-agriturismi-firenze","tag-agriturismi-firenze-con-piscina","tag-agriturismi-vinci-con-piscina","tag-agriturismo-a-firenze","tag-agriturismo-firenze","tag-agriturismo-vinci","tag-firenze-agriturismi","tag-firenze-agriturismo"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Alla Scoperta di Vinci...Agriturismo Le Colline di Vinci - Article Marketing<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.article-marketing.eu\/comunicati\/viaggi-e-vacanze\/agriturismi\/alla-scoperta-di-vinci\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Alla Scoperta di Vinci...Agriturismo Le Colline di Vinci - Article Marketing\" \/>\n<meta property=\"og:description\" content=\"Vinci\u2026. Come Leonardo da Vinci\u2026come la citt\u00e0 che diede tanti Natali a questo genio del passato nato nel lontano 1452\u2026Una piccola cittadina, incastonata tra le dolci colline toscane, sulle pendici del Montalbano, ricco di vigneti e oliveti secolari. Situato infatti in questo piccolo paese, \u00e8 un grazioso e tipico Agriturismo Vinci con Piscina, un casolare toscano in pietra, le cui origini risalgono al 1500, ristrutturato mantenendo inalterate le autenticit\u00e0 del luogo.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.article-marketing.eu\/comunicati\/viaggi-e-vacanze\/agriturismi\/alla-scoperta-di-vinci\/\" \/>\n<meta property=\"og:site_name\" content=\"Article Marketing\" \/>\n<meta property=\"article:published_time\" content=\"2013-02-15T11:43:12+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-10-25T20:01:43+00:00\" \/>\n<meta name=\"author\" content=\"Redazione Comunicati Stampa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione Comunicati Stampa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/viaggi-e-vacanze\\\/agriturismi\\\/alla-scoperta-di-vinci\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/viaggi-e-vacanze\\\/agriturismi\\\/alla-scoperta-di-vinci\\\/\"},\"author\":{\"name\":\"Redazione Comunicati Stampa\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"headline\":\"Alla Scoperta di Vinci&#8230;Agriturismo Le Colline di Vinci\",\"datePublished\":\"2013-02-15T11:43:12+00:00\",\"dateModified\":\"2018-10-25T20:01:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/viaggi-e-vacanze\\\/agriturismi\\\/alla-scoperta-di-vinci\\\/\"},\"wordCount\":494,\"commentCount\":0,\"keywords\":[\"Agriturismi a Firenze\",\"Agriturismi Firenze\",\"Agriturismi Firenze con piscina\",\"Agriturismi Vinci con piscina\",\"Agriturismo a Firenze\",\"agriturismo firenze\",\"Agriturismo Vinci\",\"Firenze Agriturismi\",\"Firenze Agriturismo\"],\"articleSection\":[\"Agriturismi\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/viaggi-e-vacanze\\\/agriturismi\\\/alla-scoperta-di-vinci\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/viaggi-e-vacanze\\\/agriturismi\\\/alla-scoperta-di-vinci\\\/\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/viaggi-e-vacanze\\\/agriturismi\\\/alla-scoperta-di-vinci\\\/\",\"name\":\"Alla Scoperta di Vinci...Agriturismo Le Colline di Vinci - Article Marketing\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\"},\"datePublished\":\"2013-02-15T11:43:12+00:00\",\"dateModified\":\"2018-10-25T20:01:43+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/viaggi-e-vacanze\\\/agriturismi\\\/alla-scoperta-di-vinci\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/viaggi-e-vacanze\\\/agriturismi\\\/alla-scoperta-di-vinci\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/viaggi-e-vacanze\\\/agriturismi\\\/alla-scoperta-di-vinci\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Alla Scoperta di Vinci&#8230;Agriturismo Le Colline di Vinci\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\",\"name\":\"Article Marketing\",\"description\":\"article marketing &amp; press release\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\",\"name\":\"Redazione Comunicati Stampa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"caption\":\"Redazione Comunicati Stampa\"},\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/author\\\/redazione-comunicati-stampa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Alla Scoperta di Vinci...Agriturismo Le Colline di Vinci - Article Marketing","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.article-marketing.eu\/comunicati\/viaggi-e-vacanze\/agriturismi\/alla-scoperta-di-vinci\/","og_locale":"it_IT","og_type":"article","og_title":"Alla Scoperta di Vinci...Agriturismo Le Colline di Vinci - Article Marketing","og_description":"Vinci\u2026. Come Leonardo da Vinci\u2026come la citt\u00e0 che diede tanti Natali a questo genio del passato nato nel lontano 1452\u2026Una piccola cittadina, incastonata tra le dolci colline toscane, sulle pendici del Montalbano, ricco di vigneti e oliveti secolari. Situato infatti in questo piccolo paese, \u00e8 un grazioso e tipico Agriturismo Vinci con Piscina, un casolare toscano in pietra, le cui origini risalgono al 1500, ristrutturato mantenendo inalterate le autenticit\u00e0 del luogo.","og_url":"https:\/\/www.article-marketing.eu\/comunicati\/viaggi-e-vacanze\/agriturismi\/alla-scoperta-di-vinci\/","og_site_name":"Article Marketing","article_published_time":"2013-02-15T11:43:12+00:00","article_modified_time":"2018-10-25T20:01:43+00:00","author":"Redazione Comunicati Stampa","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione Comunicati Stampa","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.article-marketing.eu\/comunicati\/viaggi-e-vacanze\/agriturismi\/alla-scoperta-di-vinci\/#article","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/viaggi-e-vacanze\/agriturismi\/alla-scoperta-di-vinci\/"},"author":{"name":"Redazione Comunicati Stampa","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"headline":"Alla Scoperta di Vinci&#8230;Agriturismo Le Colline di Vinci","datePublished":"2013-02-15T11:43:12+00:00","dateModified":"2018-10-25T20:01:43+00:00","mainEntityOfPage":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/viaggi-e-vacanze\/agriturismi\/alla-scoperta-di-vinci\/"},"wordCount":494,"commentCount":0,"keywords":["Agriturismi a Firenze","Agriturismi Firenze","Agriturismi Firenze con piscina","Agriturismi Vinci con piscina","Agriturismo a Firenze","agriturismo firenze","Agriturismo Vinci","Firenze Agriturismi","Firenze Agriturismo"],"articleSection":["Agriturismi"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.article-marketing.eu\/comunicati\/viaggi-e-vacanze\/agriturismi\/alla-scoperta-di-vinci\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.article-marketing.eu\/comunicati\/viaggi-e-vacanze\/agriturismi\/alla-scoperta-di-vinci\/","url":"https:\/\/www.article-marketing.eu\/comunicati\/viaggi-e-vacanze\/agriturismi\/alla-scoperta-di-vinci\/","name":"Alla Scoperta di Vinci...Agriturismo Le Colline di Vinci - Article Marketing","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website"},"datePublished":"2013-02-15T11:43:12+00:00","dateModified":"2018-10-25T20:01:43+00:00","author":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"breadcrumb":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/viaggi-e-vacanze\/agriturismi\/alla-scoperta-di-vinci\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.article-marketing.eu\/comunicati\/viaggi-e-vacanze\/agriturismi\/alla-scoperta-di-vinci\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.article-marketing.eu\/comunicati\/viaggi-e-vacanze\/agriturismi\/alla-scoperta-di-vinci\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.article-marketing.eu\/comunicati\/"},{"@type":"ListItem","position":2,"name":"Alla Scoperta di Vinci&#8230;Agriturismo Le Colline di Vinci"}]},{"@type":"WebSite","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website","url":"https:\/\/www.article-marketing.eu\/comunicati\/","name":"Article Marketing","description":"article marketing &amp; press release","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.article-marketing.eu\/comunicati\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017","name":"Redazione Comunicati Stampa","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","caption":"Redazione Comunicati Stampa"},"url":"https:\/\/www.article-marketing.eu\/comunicati\/author\/redazione-comunicati-stampa\/"}]}},"_links":{"self":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/32468","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/comments?post=32468"}],"version-history":[{"count":1,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/32468\/revisions"}],"predecessor-version":[{"id":62897,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/32468\/revisions\/62897"}],"wp:attachment":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/media?parent=32468"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/categories?post=32468"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/tags?post=32468"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}