{"id":32671,"date":"2013-02-21T16:10:56","date_gmt":"2013-02-21T15:10:56","guid":{"rendered":"http:\/\/www.article-marketing.eu\/comunicati\/senza-categoria\/cosmoprof-2013-rinnova-la-sua-presenza-online-con-un-portale-aggiornato-ricco-di-informazioni\/"},"modified":"2013-02-21T16:10:56","modified_gmt":"2013-02-21T15:10:56","slug":"cosmoprof-2013-rinnova-la-sua-presenza-online-con-un-portale-aggiornato-ricco-di-informazioni","status":"publish","type":"post","link":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/eventi\/cosmoprof-2013-rinnova-la-sua-presenza-online-con-un-portale-aggiornato-ricco-di-informazioni\/","title":{"rendered":"Cosmoprof 2013 rinnova la sua presenza online con un portale aggiornato ricco di informazioni"},"content":{"rendered":"<p>Il pi&ugrave; importante evento fieristico dedicato alla bellezza professionale affida alla web agency Extera un restyle totale di design e gestione dei contenuti. <br \/><strong>Cosmoprof<\/strong> &egrave; l&#8217;evento internazionale pi&ugrave; importante nel settore della bellezza professionale. Anche per l&rsquo;edizione 2013 sono attesi pi&ugrave; di 2300 espositori da pi&ugrave; di 70 paesi in tutto il mondo, pronti a presentare le ultime novit&agrave; legate a estetica e cosmesi ospitati in una superficie di oltre 90.000 metri quadrati. <br \/>Cifre importanti per una fiera conosciuta a livello internazionale che avverte l&#8217;esigenza di offrire ad un pubblico ampio e variegato la possibilit&agrave; di fruire velocemente informazioni di rilievo, in base alle esigenze specifiche dei singoli visitatori. Il tutto senza rinunciare all&rsquo;appeal di una corporate identity imprescindibile da ogni declinazione della comunicazione di <strong>Cosmoprof<\/strong> su ogni tipo di media, tradizionale e nuovo. <strong>Cosmoprof<\/strong> ha quindi scelto di affidarsi alla <strong>web agency Extera<\/strong> per realizzare un portale web in grado di soddisfare i criteri di una user experience veloce e altamente profilata, con l&rsquo;obiettivo di mantenere flessibilit&agrave; e totale autonomia nella gestione dei contenuti.<br \/>La web agency ha fornito a <strong>Cosmoprof<\/strong> gli strumenti necessari per diventare un vero e proprio publisher online. Il sito web dell&#8217;evento fieristico &egrave; diventato cos&igrave; un punto d&rsquo;incontro per gli operatori professionali dell&rsquo;estetica di tutto il mondo. Ogni giorno dell&#8217;anno.<br \/>Un progetto online di tale portata ha richiesto una riorganizzazione completa di tutta la struttura informativa, per poter garantire ad un pubblico cos&igrave; eterogeneo i pi&ugrave; alti standard di performance e usabilit&agrave;. Una navigazione del sito dinamica e adattabile alle necessit&agrave; di visitatori ed espositori si evince fin dal doppio ingresso all&rsquo;area riservata in home page. Gli utenti hanno accesso a contenuti personalizzati in base alle preferenze espresse nella registrazione al portale. <br \/>&Egrave; possibile consultare il portale da qualsiasi dispositivo grazie ad un&rsquo;interfaccia grafica realizzata con parametri di responsive web design, tecnologia che permette la visualizzazione del sito anche su tablet e mobile. L&#8217;ottimizzazione dei contenuti per i motori di ricerca, la promozione su scala mondiale, la consulenza su comunicazione e promozione nei principali social network, completano il quadro di una strategia web completa che vede nella partnership tra <strong>Cosmoprof<\/strong> ed <strong>Extera<\/strong> una sinergia riuscita destinata a crescere in modo proficuo nei prossimi anni. <em>Siti di approfondimento:<\/em><\/p>\n<ul>\n<\/p>\n<li><em>Cosmoprof Worldwide International: <a href=\"http:\/\/www.cosmoprof.it\" target=\"_blank\">http:\/\/www.cosmoprof.it<\/a><\/em><\/li>\n<p><\/p>\n<li><em>Extera web agency: http:\/\/www.extera.com<\/em><\/li>\n<p> \n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>La web agency Extera \u00e8 partner di Cosmoprof 2013 per la realizzazione del nuovo portale. La collaborazione prevede una consulenza di web marketing e SEO.<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"","footnotes":""},"categories":[388],"tags":[41214,41212,41211,41213],"class_list":["post-32671","post","type-post","status-publish","format-standard","hentry","category-eventi","tag-corporate-identity-cosmoprof","tag-gestione-contenuti-onliine","tag-realizzazione-portali-web","tag-sito-cosmoprof"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cosmoprof 2013 rinnova la sua presenza online con un portale aggiornato ricco di informazioni - Article Marketing<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/eventi\/cosmoprof-2013-rinnova-la-sua-presenza-online-con-un-portale-aggiornato-ricco-di-informazioni\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cosmoprof 2013 rinnova la sua presenza online con un portale aggiornato ricco di informazioni - Article Marketing\" \/>\n<meta property=\"og:description\" content=\"La web agency Extera \u00e8 partner di Cosmoprof 2013 per la realizzazione del nuovo portale. La collaborazione prevede una consulenza di web marketing e SEO.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/eventi\/cosmoprof-2013-rinnova-la-sua-presenza-online-con-un-portale-aggiornato-ricco-di-informazioni\/\" \/>\n<meta property=\"og:site_name\" content=\"Article Marketing\" \/>\n<meta property=\"article:published_time\" content=\"2013-02-21T15:10:56+00:00\" \/>\n<meta name=\"author\" content=\"Redazione Comunicati Stampa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione Comunicati Stampa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/eventi\\\/cosmoprof-2013-rinnova-la-sua-presenza-online-con-un-portale-aggiornato-ricco-di-informazioni\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/eventi\\\/cosmoprof-2013-rinnova-la-sua-presenza-online-con-un-portale-aggiornato-ricco-di-informazioni\\\/\"},\"author\":{\"name\":\"Redazione Comunicati Stampa\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"headline\":\"Cosmoprof 2013 rinnova la sua presenza online con un portale aggiornato ricco di informazioni\",\"datePublished\":\"2013-02-21T15:10:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/eventi\\\/cosmoprof-2013-rinnova-la-sua-presenza-online-con-un-portale-aggiornato-ricco-di-informazioni\\\/\"},\"wordCount\":422,\"commentCount\":0,\"keywords\":[\"corporate identity cosmoprof\",\"gestione contenuti onliine\",\"realizzazione portali web\",\"sito cosmoprof\"],\"articleSection\":[\"Eventi\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/eventi\\\/cosmoprof-2013-rinnova-la-sua-presenza-online-con-un-portale-aggiornato-ricco-di-informazioni\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/eventi\\\/cosmoprof-2013-rinnova-la-sua-presenza-online-con-un-portale-aggiornato-ricco-di-informazioni\\\/\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/eventi\\\/cosmoprof-2013-rinnova-la-sua-presenza-online-con-un-portale-aggiornato-ricco-di-informazioni\\\/\",\"name\":\"Cosmoprof 2013 rinnova la sua presenza online con un portale aggiornato ricco di informazioni - Article Marketing\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\"},\"datePublished\":\"2013-02-21T15:10:56+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/eventi\\\/cosmoprof-2013-rinnova-la-sua-presenza-online-con-un-portale-aggiornato-ricco-di-informazioni\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/eventi\\\/cosmoprof-2013-rinnova-la-sua-presenza-online-con-un-portale-aggiornato-ricco-di-informazioni\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/eventi\\\/cosmoprof-2013-rinnova-la-sua-presenza-online-con-un-portale-aggiornato-ricco-di-informazioni\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cosmoprof 2013 rinnova la sua presenza online con un portale aggiornato ricco di informazioni\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\",\"name\":\"Article Marketing\",\"description\":\"article marketing &amp; press release\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\",\"name\":\"Redazione Comunicati Stampa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"caption\":\"Redazione Comunicati Stampa\"},\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/author\\\/redazione-comunicati-stampa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cosmoprof 2013 rinnova la sua presenza online con un portale aggiornato ricco di informazioni - Article Marketing","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/eventi\/cosmoprof-2013-rinnova-la-sua-presenza-online-con-un-portale-aggiornato-ricco-di-informazioni\/","og_locale":"it_IT","og_type":"article","og_title":"Cosmoprof 2013 rinnova la sua presenza online con un portale aggiornato ricco di informazioni - Article Marketing","og_description":"La web agency Extera \u00e8 partner di Cosmoprof 2013 per la realizzazione del nuovo portale. La collaborazione prevede una consulenza di web marketing e SEO.","og_url":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/eventi\/cosmoprof-2013-rinnova-la-sua-presenza-online-con-un-portale-aggiornato-ricco-di-informazioni\/","og_site_name":"Article Marketing","article_published_time":"2013-02-21T15:10:56+00:00","author":"Redazione Comunicati Stampa","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione Comunicati Stampa","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/eventi\/cosmoprof-2013-rinnova-la-sua-presenza-online-con-un-portale-aggiornato-ricco-di-informazioni\/#article","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/eventi\/cosmoprof-2013-rinnova-la-sua-presenza-online-con-un-portale-aggiornato-ricco-di-informazioni\/"},"author":{"name":"Redazione Comunicati Stampa","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"headline":"Cosmoprof 2013 rinnova la sua presenza online con un portale aggiornato ricco di informazioni","datePublished":"2013-02-21T15:10:56+00:00","mainEntityOfPage":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/eventi\/cosmoprof-2013-rinnova-la-sua-presenza-online-con-un-portale-aggiornato-ricco-di-informazioni\/"},"wordCount":422,"commentCount":0,"keywords":["corporate identity cosmoprof","gestione contenuti onliine","realizzazione portali web","sito cosmoprof"],"articleSection":["Eventi"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/eventi\/cosmoprof-2013-rinnova-la-sua-presenza-online-con-un-portale-aggiornato-ricco-di-informazioni\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/eventi\/cosmoprof-2013-rinnova-la-sua-presenza-online-con-un-portale-aggiornato-ricco-di-informazioni\/","url":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/eventi\/cosmoprof-2013-rinnova-la-sua-presenza-online-con-un-portale-aggiornato-ricco-di-informazioni\/","name":"Cosmoprof 2013 rinnova la sua presenza online con un portale aggiornato ricco di informazioni - Article Marketing","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website"},"datePublished":"2013-02-21T15:10:56+00:00","author":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"breadcrumb":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/eventi\/cosmoprof-2013-rinnova-la-sua-presenza-online-con-un-portale-aggiornato-ricco-di-informazioni\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/eventi\/cosmoprof-2013-rinnova-la-sua-presenza-online-con-un-portale-aggiornato-ricco-di-informazioni\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/eventi\/cosmoprof-2013-rinnova-la-sua-presenza-online-con-un-portale-aggiornato-ricco-di-informazioni\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.article-marketing.eu\/comunicati\/"},{"@type":"ListItem","position":2,"name":"Cosmoprof 2013 rinnova la sua presenza online con un portale aggiornato ricco di informazioni"}]},{"@type":"WebSite","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website","url":"https:\/\/www.article-marketing.eu\/comunicati\/","name":"Article Marketing","description":"article marketing &amp; press release","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.article-marketing.eu\/comunicati\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017","name":"Redazione Comunicati Stampa","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","caption":"Redazione Comunicati Stampa"},"url":"https:\/\/www.article-marketing.eu\/comunicati\/author\/redazione-comunicati-stampa\/"}]}},"_links":{"self":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/32671","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/comments?post=32671"}],"version-history":[{"count":0,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/32671\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/media?parent=32671"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/categories?post=32671"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/tags?post=32671"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}