{"id":33386,"date":"2013-03-19T17:39:32","date_gmt":"2013-03-19T16:39:32","guid":{"rendered":"http:\/\/www.article-marketing.eu\/comunicati\/senza-categoria\/aci-worldwide-chiude-il-2012-con-risultati-record\/"},"modified":"2013-03-19T17:39:32","modified_gmt":"2013-03-19T16:39:32","slug":"aci-worldwide-chiude-il-2012-con-risultati-record","status":"publish","type":"post","link":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/aci-worldwide-chiude-il-2012-con-risultati-record\/","title":{"rendered":"ACI Worldwide chiude il 2012 con risultati record"},"content":{"rendered":"<p>&ldquo;Abbiamo chiuso il 2012 con risultati record per quanto riguarda le revenue, le vendite e gli utili,&rdquo; ha affermato il Chief Executive Officer di ACI Worldwide, Philip Heasley. &ldquo;Grazie all&rsquo;integrazione di S1, che &egrave; sostanzialmente completata, abbiamo iniziato il 2013 con un posizionamento che ci permetter&agrave; di accelerare i nostri obiettivi di crescita. Inoltre, la proposta di acquisizione di Online Resources amplier&agrave; il nostro portfolio prodotti con una piattaforma per la gestione dei pagamenti elettronici delle fatture, permettendoci di diventare di fatto l&rsquo;unico player in grado di offrire una Piattaforma di Pagamento Universale,&rdquo; ha concluso Mr. Heasley.<\/p>\n<p>Financial Summary<\/p>\n<p>Vendite <br \/>Gli ordini del quarto trimestre del 2012 hanno raggiunto i 309 milioni di dollari, con un incremento di 138 milioni di dollari, pari all&rsquo;81%, rispetto allo stesso trimestre dell&rsquo;anno precedente. Nello stesso trimestre le vendite, SNET, hanno totalizzato 198 milioni di dollari, con un aumento del 69%, pari a 81 milioni di dollari, se paragonate allo stesso periodo dell&rsquo;anno precedente. S1 ha contribuito per 81 milioni dollari di vendite nel trimestre. Le vendite storiche di ACI sono aumentate di 57 milioni di dollari, pari al 33%, rispetto agli ordini dello stesso trimestre del 2011, che erano di 171 milioni dollari. Per il 2012, le vendite si sono attestate sui 766 milioni di dollari, con un incremento di 210 milioni di dollari, pari al 38%, se paragonate ai 556 milioni di dollari dell&rsquo;anno precedente. S1 ha contribuito per 189 milioni dollari di fatturato alle vendite dell&rsquo;anno.<\/p>\n<p><a>Backlog <\/a><br \/>Il backlog, su un periodo di 60 mesi, &egrave; incrementato di 49 milioni di dollari nel trimestre, raggiungendo i 2.416 miliardi di dollari, rispetto ai 2.367 miliardi del 30 settembre 2012. Il backlog, su un periodo di 12 mesi, &egrave; incrementato invece di 12 milioni di dollari, raggiungendo 596 milioni paragonati ai 584 del 30 settembre 2012.<\/p>\n<p>Revenue<br \/>Le GAAP revenue hanno raggiunto i 224.1 milioni di dollari, con una crescita di 89.1 milioni, pari al 66%, rispetto allo stesso trimestre del 2011. Le revenue storiche di ACI sono cresciute di 40.7 milioni di dollari, pari al 30%, e S1 ha contribuito per 48.4 milioni di revenue nel quarto trimestre 2012. Le non-GAAP revenue hanno totalizzato invece 227.7 milioni, con un aumento di 92.7 milioni, pari al 69%, rispetto al quarto trimestre dell&rsquo;anno precedente. Le non-GAAP revenue non includono l&rsquo;impatto dei risconti passivi, pari a 3.6 milioni di dollari, che avrebbero dovuto essere riconosciuti da S1 nel corso delle normali attivit&agrave;, ma che non sono stati riconosciuti a causa dalle linee guida GAAP relative alla gestione della contabilit&agrave; durante i processi di acquisizione. Le revenue del 2012 sono state di 666.6 milioni di dollari, con una crescita di 201.5 milioni di dollari, pari al 43%. Le revenue storiche di ACI sono aumentate di 39.6 milioni di dollari, pari all&rsquo;8.5%, e S1 ha contributo per 161.9 milioni di dollari sulle revenue annuali. Le non-GAAP revenue sono state di 689 milioni di dollari, con un aumento di 223.9 milioni, pari al 48%, rispetto all&rsquo;anno precedente. <\/p>\n<p>Costi operativi<br \/>Escludendo i costi una tantum relativi all&rsquo;acquisizione di S1 che, rilevati nel quarto trimestre 2012, sono risultati essere di 4.4 e 3.2 milioni di dollari, quelli del 2012 e del 2011 sono rispettivamente cresciuti di 49.3 milioni di dollari, se paragonati allo stesso trimestre dell&rsquo;anno precedente, questo dovuto all&rsquo;aggiunta dei costi operativi di S1, pari a 42.7 milioni, incluso 4.0 milioni di ammortamenti di beni immateriali. Il totale dei costi operativi GAAP, per il quarto trimestre 2012, &egrave; stato di 148.6 milioni di dollari. <\/p>\n<p>Escludendo i costi una tantum riferiti all&rsquo;acquisizione di S1 che, rilevati al 31 dicembre 2012, sono risultati essere di 31.5 e 6.7 milioni di dollari, quelli del 2012 e 2011 sono rispettivamente aumentati di 168.6 milioni di dollari, pari al 43%, dovuto principalmente al sommarsi dei costi operativi di S1, pari a 159 milioni dollari, incluso 13.9 milioni di ammortamenti di beni immateriali. Il totale dei costi operativi GAAP sono stati pari a 592.2 per l&rsquo;anno 2012. La crescita dei costi operativi storici di ACI &egrave; stata guidata principalmente dai costi passivi sul go-live dei progetti.<\/p>\n<p>Ricavi operativi<br \/>I ricavi operativi GAAP sono stati di 75.5 milioni di dollari nell&rsquo;ultimo trimestre 2012. Quelli non-GAAP hanno raggiunto gli 83.6 milioni di dollari, con un aumento di 43.4 milioni, pari al 108%, rispetto allo stesso periodo dell&rsquo;anno precedente. I ricavi operativi non-GAAP non includono 3.6 milioni di aggiustamenti di risconti passivi, dovuti alla gestione della contabilit&agrave; durante i processi di acquisizione, e l&rsquo;impatto di 4.4 milioni di dollari di spese una tantum relative all&rsquo;acquisizione di S1.<br \/>L&#8217;utile operativo, per l&#8217;intero anno 2012, &egrave; stato di 74.4 milioni di dollari, rispetto ai 66.2 del 2011. Escludendo 22.5 milioni di dollari di risconti passivi, dovuti alla gestione della contabilit&agrave; durante i processi di acquisizione, e l&#8217;impatto di 31.5 milioni dollari di spese una tantum relative all&rsquo;acquisizione di S1, l&rsquo;utile operativo &egrave; aumentato di 55.4 milioni di dollari, pari al 76%, raggiungendo i 128.3 milioni. <\/p>\n<p>Adjusted EBITDA<br \/>L&rsquo;Adjusted EBITDA &egrave; cresciuto di 101.1 milioni di dollari, con un aumento di 49.2 milioni, pari al 95%, se paragonato allo stesso trimestre dell&rsquo;anno precedente. L&rsquo;Adjusted EBITDA non include 3.6 milioni di euro di risconti passivi, che avrebbero dovuto essere riconosciuti da S1 nel corso della normale attivit&agrave;, ma che non sono stati riconosciuti a causa delle regole GAAP relative alla gestione della contabilit&agrave; nei processi di acquisizione e 4.4 milioni di dollari di costi una tantum dovuti all&rsquo;acquisizione stessa. L&rsquo;Adjusted EBITDA, per il 2012, &egrave; stato di 191.4 milioni di dollari, con una crescita di 78.9 milioni, pari al 70%, rispetto ai 112.6 milioni del 2011. <\/p>\n<p>Liquidit&agrave;<br \/>ACI Worldwide ha chiuso l&rsquo;anno, al 31 dicembre 2012, con 76.3 milioni di dollari di cassa. Durante l&rsquo;ultimo trimestre l&rsquo;azienda ha restituito a IBM 20.7 milioni di dollari in prestiti rimborsabili, relativi all&rsquo;alleanza tra le due aziende, e 10.4 milioni di debiti. ACI ha concluso l&rsquo;anno con un saldo di debiti pari a 374.3 milioni. Al 31 dicembre 2012, l&rsquo;azienda possedeva oltre 62 milioni di prestiti non utilizzati nella propria linea di credito rotativo.<\/p>\n<p>Flusso di cassa operativo<br \/>Il flusso di cassa operativo del quarto trimestre 2012 e quello totale del 2012 sono stati rispettivamente di 23.6 e 23.5 milioni di dollari. Su entrambi ha influito il rimanente degli ordini e dei ricavi dell&rsquo;anno. Il flusso di cassa operativo del quarto trimestre 2011 e quello di tutto il 2011 sono stati rispettivamente di 30.0 e 67.2 milioni di dollari.<\/p>\n<p>Altre spese<br \/>Le altre spese per il quarto trimestre del 2012 sono state pari a 1.5 milioni di dollari, con un aumento di 0.5 milioni, rispetto alle spese dello stesso periodo dell&rsquo;anno precedente, che erano di 1.0 milioni. Le altre spese riferite a tutto il 2012 sono state di 9.1 milioni, paragonate ai 1.9 milioni del 2011. L&rsquo;incremento delle spese &egrave; dovuto principalmente 8.0 milioni di dollari di aumento di interessi, relativi ai prestiti parzialmente compensati, e da 1.6 milioni di dollari sulle quote di S1, precedentemente disponibili per la vendita.<\/p>\n<p>Tasse<br \/>Le imposte sui ricavi nel trimestre sono state di 24.3 milioni di dollari, pari al 33% di aliquota effettiva, rispetto alle tasse dello steso periodo dell&rsquo;anno precedente, che erano di 12.1 milioni, pari al 34%. Le imposte sui ricavi per l&rsquo;anno che si &egrave; concluso a dicembre 2012 sono state di 16.4 milioni, pari al 25% di aliquota effettiva, rispetto ai 18.5 milioni, 29% di aliquota effettiva del 2011. La diminuzione dell&rsquo;aliquota effettiva &egrave; dovuta alla riduzione dei ricavi domestici, che si basano sulle aliquote degli Stati Uniti, e all&rsquo;aumento dei proventi esteri, con aliquote fiscali pi&ugrave; basse. <\/p>\n<p>Risultato netto e utile diluito per azione <br \/>L&rsquo;utile netto per il trimestre, che si &egrave; concluso il 31 dicembre 2012, &egrave; stato di 49.7 milioni di dollari, rispetto ai 23.9 milioni dello stesso periodo dell&rsquo;anno precedente. Gli utili GAAP per azione dell&rsquo;ultimo trimestre del 2012 sono stati di 1.24 dollari per azione, rispetto ai 0.70 dello stesso periodo dell&rsquo;anno precedente. Escludendo l&rsquo;impatto delle tasse, pari a 4.4 milioni di dollari, dovute alle spese una tantum relative all&rsquo;acquisizione di S1, e 3.6 milioni di risconti passivi che avrebbero dovuto essere riconosciuti da S1 nel corso della normale attivit&agrave;, ma che non sono stati riconosciuti a causa delle regole relative alla gestione della contabilit&agrave; nei processi di acquisizione, l&rsquo;utile netto per azione &egrave; stato di 1.37 dollari, contro 0.76 per azione dell&rsquo;anno precedente, oltre l&rsquo;81%. Gli utili GAAP per azione, alla fine del dicembre 2012, erano di 1.22 dollari rispetto 1.34 dell&rsquo;anno che si &egrave; concluso a dicembre 2011. Escludendo l&rsquo;impatto delle tasse-adjusted, pari a 31.5 milioni di dollari, dovuto alle spese una tantum relative all&rsquo;acquisizione di S1, e 22.5 milioni di risconti passivi che avrebbero dovuto essere riconosciuti da S1 nel corso della normale attivit&agrave;, ma che non sono stati riconosciuti a causa delle regole relative alla gestione della contabilit&agrave; durante i processi di acquisizione, gli utili per azione sono stati di 2.10 dollari, contro gli 1.47 dell&rsquo;anno precedente, oltre il 43%.<\/p>\n<p>Media ponderata delle azioni in circolazione<br \/>Il totale della media ponderata delle azioni in circolazione &egrave; stato di 39.9 milioni al 31 dicembre 2012, paragonato ai 34.2 milioni del 31 dicembre 2011. Il numero della media ponderata di azioni in circolazione &egrave; cresciuto di 5.9 milioni, a causa dell&rsquo;emissione di azioni relative all&rsquo;acquisizione di S1 Corporation. <\/p>\n<p>Previsioni 2013 <br \/>ACI si basa su tre parametri per l&rsquo;anno 2013, e prevede di raggiungere una revenue che si attester&agrave; tra 765 e 785 milioni di dollari, ricavi operativi tra i 150 e 160 milioni e l&rsquo;Adjusted EBITDA tra i 230 e 240 milioni di dollari.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>ACI Worldwide chiude il 2012 con risultati record. Ecco il Financial Summary e le previsioni 2013<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"","footnotes":""},"categories":[190],"tags":[26635],"class_list":["post-33386","post","type-post","status-publish","format-standard","hentry","category-comunicati-stampa","tag-aci-worldwide"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>ACI Worldwide chiude il 2012 con risultati record - Article Marketing<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/aci-worldwide-chiude-il-2012-con-risultati-record\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ACI Worldwide chiude il 2012 con risultati record - Article Marketing\" \/>\n<meta property=\"og:description\" content=\"ACI Worldwide chiude il 2012 con risultati record. Ecco il Financial Summary e le previsioni 2013\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/aci-worldwide-chiude-il-2012-con-risultati-record\/\" \/>\n<meta property=\"og:site_name\" content=\"Article Marketing\" \/>\n<meta property=\"article:published_time\" content=\"2013-03-19T16:39:32+00:00\" \/>\n<meta name=\"author\" content=\"Redazione Comunicati Stampa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione Comunicati Stampa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/aci-worldwide-chiude-il-2012-con-risultati-record\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/aci-worldwide-chiude-il-2012-con-risultati-record\\\/\"},\"author\":{\"name\":\"Redazione Comunicati Stampa\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"headline\":\"ACI Worldwide chiude il 2012 con risultati record\",\"datePublished\":\"2013-03-19T16:39:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/aci-worldwide-chiude-il-2012-con-risultati-record\\\/\"},\"wordCount\":1553,\"commentCount\":0,\"keywords\":[\"ACI Worldwide\"],\"articleSection\":[\"Comunicati stampa\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/aci-worldwide-chiude-il-2012-con-risultati-record\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/aci-worldwide-chiude-il-2012-con-risultati-record\\\/\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/aci-worldwide-chiude-il-2012-con-risultati-record\\\/\",\"name\":\"ACI Worldwide chiude il 2012 con risultati record - Article Marketing\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\"},\"datePublished\":\"2013-03-19T16:39:32+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/aci-worldwide-chiude-il-2012-con-risultati-record\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/aci-worldwide-chiude-il-2012-con-risultati-record\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/aci-worldwide-chiude-il-2012-con-risultati-record\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ACI Worldwide chiude il 2012 con risultati record\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\",\"name\":\"Article Marketing\",\"description\":\"article marketing &amp; press release\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\",\"name\":\"Redazione Comunicati Stampa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"caption\":\"Redazione Comunicati Stampa\"},\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/author\\\/redazione-comunicati-stampa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ACI Worldwide chiude il 2012 con risultati record - Article Marketing","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/aci-worldwide-chiude-il-2012-con-risultati-record\/","og_locale":"it_IT","og_type":"article","og_title":"ACI Worldwide chiude il 2012 con risultati record - Article Marketing","og_description":"ACI Worldwide chiude il 2012 con risultati record. Ecco il Financial Summary e le previsioni 2013","og_url":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/aci-worldwide-chiude-il-2012-con-risultati-record\/","og_site_name":"Article Marketing","article_published_time":"2013-03-19T16:39:32+00:00","author":"Redazione Comunicati Stampa","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione Comunicati Stampa","Tempo di lettura stimato":"8 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/aci-worldwide-chiude-il-2012-con-risultati-record\/#article","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/aci-worldwide-chiude-il-2012-con-risultati-record\/"},"author":{"name":"Redazione Comunicati Stampa","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"headline":"ACI Worldwide chiude il 2012 con risultati record","datePublished":"2013-03-19T16:39:32+00:00","mainEntityOfPage":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/aci-worldwide-chiude-il-2012-con-risultati-record\/"},"wordCount":1553,"commentCount":0,"keywords":["ACI Worldwide"],"articleSection":["Comunicati stampa"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/aci-worldwide-chiude-il-2012-con-risultati-record\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/aci-worldwide-chiude-il-2012-con-risultati-record\/","url":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/aci-worldwide-chiude-il-2012-con-risultati-record\/","name":"ACI Worldwide chiude il 2012 con risultati record - Article Marketing","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website"},"datePublished":"2013-03-19T16:39:32+00:00","author":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"breadcrumb":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/aci-worldwide-chiude-il-2012-con-risultati-record\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/aci-worldwide-chiude-il-2012-con-risultati-record\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/aci-worldwide-chiude-il-2012-con-risultati-record\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.article-marketing.eu\/comunicati\/"},{"@type":"ListItem","position":2,"name":"ACI Worldwide chiude il 2012 con risultati record"}]},{"@type":"WebSite","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website","url":"https:\/\/www.article-marketing.eu\/comunicati\/","name":"Article Marketing","description":"article marketing &amp; press release","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.article-marketing.eu\/comunicati\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017","name":"Redazione Comunicati Stampa","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","caption":"Redazione Comunicati Stampa"},"url":"https:\/\/www.article-marketing.eu\/comunicati\/author\/redazione-comunicati-stampa\/"}]}},"_links":{"self":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/33386","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/comments?post=33386"}],"version-history":[{"count":0,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/33386\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/media?parent=33386"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/categories?post=33386"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/tags?post=33386"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}