{"id":33417,"date":"2013-03-20T16:05:33","date_gmt":"2013-03-20T15:05:33","guid":{"rendered":"http:\/\/www.article-marketing.eu\/comunicati\/senza-categoria\/la-crisi-come-testimonianza-di-una-ir-responsabilit%c3%a0-sociale\/"},"modified":"2013-03-20T16:05:33","modified_gmt":"2013-03-20T15:05:33","slug":"la-crisi-come-testimonianza-di-una-ir-responsabilit%c3%a0-sociale","status":"publish","type":"post","link":"https:\/\/www.article-marketing.eu\/comunicati\/societa\/news-e-attualita\/la-crisi-come-testimonianza-di-una-ir-responsabilit%c3%a0-sociale\/","title":{"rendered":"La crisi come testimonianza di una (ir)responsabilit\u00e0 sociale"},"content":{"rendered":"<p>Parlare di &ldquo;Responsabilit&agrave;&rdquo; o di &ldquo;Irresponsabilit&agrave;&rdquo; sociale d&rsquo;impresa rinvia al tema delle<br \/>scelte, in presenza di conflitti tra valori, di dilemmi circa la scelta dei valori da applicare in<br \/>specifici contesti, dove urge optare tra valori confliggenti o addirittura escludenti. Rinvia<br \/>dunque a scelte etiche, che si pongono come contemperamento di valori.<br \/>Utile per comprendere le dimensioni di un&rsquo;azienda etica &egrave; riprendere la distinzione<br \/>hegeliana tra le tre sfere della normativit&agrave;: moralit&agrave;, diritto ed eticit&agrave;.<br \/>&#8211; La moralit&agrave; riguarda i valori personali dettati dalla coscienza individuale: nel caso<br \/>dell&rsquo;azienda, ci&ograve; che l&rsquo;imprenditore, i manager e tutti quanti operano in azienda, reputano<br \/>giusto o sbagliato.<br \/>&#8211; Il diritto rinvia alle norme dettate dallo Stato, regole dirette a diminuire le tensioni, che lo<br \/>stesso sanziona con i tribunali e con la forza esecutiva. Si pensi, a titolo di esempio, ai<br \/>doveri di natura strettamente giuridica cui un&rsquo;impresa &egrave; tenuta. Tra tutti, i reati di<br \/>bancarotta, di falso nelle comunicazioni sociali, gli illeciti commessi dagli amministratori.<br \/>&#8211; L&rsquo;eticit&agrave; riguarda quei diritti\/doveri che sono condivisi in una relazione duratura e<br \/>relativamente stabile tra pi&ugrave; soggetti.<br \/>Con riferimento specifico al contesto aziendale, non si pu&ograve; cos&igrave; parlare di &ldquo;etica&rdquo; in<br \/>presenza di comportamenti prescritti dal diritto, n&eacute; di comportamenti riconducibili alla<br \/>&ldquo;coscienza&rdquo; dell&rsquo;imprenditore o del vertice. L&rsquo;etica riguarda invece quelle scelte e quei<br \/>comportamenti che sono l&rsquo;esito di un incontro tra l&rsquo;azienda e i suoi &ldquo;stakeholder&rdquo;, termine<br \/>riferito a quanti hanno interessi specifici nei confronti dei comportamenti aziendali,<br \/>proprio in quanto ne possono essere influenzati. Qualifica cos&igrave; in modo diretto la &ldquo;mission&rdquo;<br \/>della organizzazione, riferendola a una forma di &ldquo;governance&rdquo; fondata su un profondo<br \/>rispetto di tutti gli &ldquo;stakeholder&rdquo;, in base a un modello di valori condivisi. Questo implica<br \/>che si vada oltre la mera prospettiva degli interessi degli azionisti &ndash; che limita la<br \/>responsabilit&agrave; aziendale all&rsquo;obbligo morale del miglioramento del profitto degli investitori<br \/>&ndash; abbracciando la visione della stakeholder theory, aperta a un ampio rispetto dei diritti di<br \/>tutti i portatori di interessi.<br \/>Perch&eacute; si possa parlare dunque di impresa &ldquo;etica&rdquo; occorre che la stessa:<br \/>1. definisca i propri valori chiave;<br \/>2. prenda in considerazione gli effetti del suo agire sugli stakeholder;<br \/>3. presti attenzione a beni intangibili quali la reputazione, il dialogo o la trasparenza;<br \/>4. ottimizzi le esternalit&agrave; positive come l&rsquo;occupazione e lo sviluppo socio-economico;<br \/>5. faccia il possibile per ridurre le esternalit&agrave; negative come l&rsquo;inquinamento e in generale<br \/>gli squilibri sociali e ambientali.<br \/>Sono questi i temi che costituiscono il cuore dei cosiddetti &ldquo;Comportamenti Socialmente<br \/>Responsabili&rdquo;, si parla pertanto di Corporate Social Responsibility (CSR).<br \/>Sul rapporto tra performance sociale e performance economica, da anni gli studiosi si sono<br \/>confrontati senza giungere a conclusioni univoche. Le posizioni dominanti sono le due<br \/>seguenti:<br \/>A) Non sussiste conflitto tra ruolo economico e ruolo sociale dell&rsquo;impresa. Gi&agrave; Drucker<br \/>aveva rilevato il legame esistente tra &ldquo;responsabilit&agrave; sociale&rdquo; e &ldquo;performance economica&rdquo;,<br \/>sostenendo che la responsabilit&agrave; sociale di un&rsquo;impresa consiste nel trasformare un<br \/>interesse pubblico in un&rsquo;opportunit&agrave; di guadagno per l&rsquo;azienda, in modo tale che interesse<br \/>pubblico e interesse aziendale vengano a coincidere.<br \/>B) La contrapposizione tra finalit&agrave; economiche e finalit&agrave; sociali esiste semmai nel breve<br \/>termine, in quanto nel lungo periodo &egrave; l&rsquo;integrazione tra equilibrio economico ed equilibrio<br \/>sociale a garantire la sopravvivenza e lo sviluppo aziendale. Se in specifici momenti<br \/>decisionali la ricerca di opportunit&agrave; economiche pu&ograve; essere in contrasto con considerazioni<br \/>di natura sociale, in una prospettiva di lungo periodo i comportamenti socialmente<br \/>responsabili risultano &ldquo;complementari&rdquo; rispetto all&rsquo;obiettivo del profitto, contribuendo ad<br \/>innalzare la redditivit&agrave; dell&rsquo;impresa. Tale relazione di complementariet&agrave; pu&ograve; spiegarsi nei<br \/>termini seguenti.<br \/>1. L&rsquo;assunzione e l&rsquo;adempimento di obblighi sociali contribuisce in misura significativa alla<br \/>reputazione e alla creazione di un&rsquo;immagine positiva dell&rsquo;impresa nelle percezioni degli<br \/>stakeholder (interni ed esterni); ci&ograve; ha le due seguenti implicazioni:<br \/>&#8211; favorisce la formazione del &ldquo;consenso sociale&rdquo;, che &egrave; alla base della &ldquo;legittimazione<br \/>sociale&rdquo; dell&rsquo;impresa, indispensabile per continuare ad operare proficuamente<br \/>nell&rsquo;ambiente in cui essa &egrave; inserita e dal quale trae le risorse necessarie per l&rsquo;attuazione<br \/>delle proprie strategie di sviluppo.<br \/>&#8211; consolida la fiducia che gli stakeholder possiedono nei confronti dell&rsquo;impresa,<br \/>contribuendo cos&igrave; a facilitare gli scambi e a ridurre i &ldquo;costi transazionali&rdquo;, impliciti in ogni<br \/>relazione. Viene in proposito elaborato il concetto di &ldquo;catena dell&rsquo;affidabilit&agrave;&rdquo;, che si<br \/>sviluppa a partire dai comportamenti socialmente responsabili, guidati da principi<br \/>realmente etici, che consentirebbero all&rsquo;impresa di guadagnare la fiducia e quindi la<br \/>fidelizzazione dei propri stakeholders.<br \/>La reputazione, l&rsquo;immagine aziendale, la cultura organizzativa, la fiducia, ecc. sono tutte<br \/>risorse intangibili che, in quanto difficilmente imitabili da parte delle imprese concorrenti,<br \/>possono costituire una fonte rilevante del vantaggio competitivo aziendale, fondato sulla<br \/>&ldquo;differenziazione&rdquo; rispetto ai concorrenti.<br \/>2. L&rsquo;implementazione di programmi volti a migliorare il benessere del personale determina<br \/>una serie di benefici, quali: l&rsquo;aumento della produttivit&agrave; del lavoro, la riduzione del tasso di<br \/>assenteismo, la maggiore capacit&agrave; di attrarre e di mantenere i &ldquo;talenti&rdquo; migliori, ecc. In<br \/>proposito, emblematico risulta il caso della Luxottica &#8211; azienda italiana leader nella<br \/>produzione e vendita di occhiali &#8211; la quale nel 2009, in accordo con le organizzazioni<br \/>sindacali, ha attivato un programma finalizzato a supportare il potere di acquisto reale dei<br \/>dipendenti, fornendo una serie di benefit non monetari, complementari alla retribuzione<br \/>monetaria. La motivazione alla base di tale iniziativa &egrave; stata proprio la considerazione che<br \/>una migliore qualit&agrave; della vita dei dipendenti costituisce una premessa indispensabile per<br \/>una maggiore produttivit&agrave; ed efficacia del lavoro.<br \/>3. L&rsquo;impegno sociale e ambientale pu&ograve; stimolare l&rsquo;identificazione di nuove opportunit&agrave; di<br \/>business, le quali possono essere fonti di innovazione di prodotto e di processo. Si pensi, ad<br \/>esempio, ai nuovi prodotti che incorporano tecnologie per ridurre l&rsquo;impatto ambientale<br \/>derivante dal loro uso nel settore degli elettrodomestici bianchi o delle automobili. Inoltre,<br \/>le iniziative volte a migliorare l&rsquo;ambiente di lavoro all&rsquo;interno dell&rsquo;organizzazione aziendale<br \/>possono contribuire a creare un ambiente, che stimoli la creativit&agrave; e la generazione di<br \/>nuove idee da parte del personale. Le azioni socialmente responsabili possono contribuire<br \/>alla capacit&agrave; innovativa dell&rsquo;impresa anche sotto un altro punto di vista: nel contesto<br \/>attuale, l&rsquo;innovazione &egrave; sempre pi&ugrave; il frutto della collaborazione tra la singola azienda e i<br \/>soggetti esterni; se la prima ha sviluppato una &ldquo;buona&rdquo; rete di relazioni con gli<br \/>stakeholders, avr&agrave; maggiori possibilit&agrave; di realizzare innovazioni di successo, grazie alla<br \/>loro disponibilit&agrave; a collaborare.<br \/>Tra performance economica e performance sociale esiste un rapporto di trade-off, poich&eacute;<br \/>tenere comportamenti socialmente responsabili comporta il sostenimento di costi, che<br \/>possono impattare sui prezzi e quindi sulla competitivit&agrave; aziendale o comunque ridurre il<br \/>margine di profitto.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Parlare di \u201cResponsabilit\u00e0\u201d o di \u201cIrresponsabilit\u00e0\u201d sociale d\u2019impresa rinvia al tema delle<\/p>\n<p>scelte, in presenza di conflitti tra valori, di dilemmi circa la scelta dei valori da applicare in<\/p>\n<p>specifici contesti, dove urge optare tra valori confliggenti o addirittura escludenti.<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"","footnotes":""},"categories":[81],"tags":[2760,1825],"class_list":["post-33417","post","type-post","status-publish","format-standard","hentry","category-news-e-attualita","tag-crisi","tag-responsabilita"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La crisi come testimonianza di una (ir)responsabilit\u00e0 sociale - Article Marketing<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.article-marketing.eu\/comunicati\/societa\/news-e-attualita\/la-crisi-come-testimonianza-di-una-ir-responsabilit\u00e0-sociale\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La crisi come testimonianza di una (ir)responsabilit\u00e0 sociale - Article Marketing\" \/>\n<meta property=\"og:description\" content=\"Parlare di \u201cResponsabilit\u00e0\u201d o di \u201cIrresponsabilit\u00e0\u201d sociale d\u2019impresa rinvia al tema dellescelte, in presenza di conflitti tra valori, di dilemmi circa la scelta dei valori da applicare inspecifici contesti, dove urge optare tra valori confliggenti o addirittura escludenti.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.article-marketing.eu\/comunicati\/societa\/news-e-attualita\/la-crisi-come-testimonianza-di-una-ir-responsabilit\u00e0-sociale\/\" \/>\n<meta property=\"og:site_name\" content=\"Article Marketing\" \/>\n<meta property=\"article:published_time\" content=\"2013-03-20T15:05:33+00:00\" \/>\n<meta name=\"author\" content=\"Redazione Comunicati Stampa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione Comunicati Stampa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/societa\\\/news-e-attualita\\\/la-crisi-come-testimonianza-di-una-ir-responsabilit%c3%a0-sociale\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/societa\\\/news-e-attualita\\\/la-crisi-come-testimonianza-di-una-ir-responsabilit%c3%a0-sociale\\\/\"},\"author\":{\"name\":\"Redazione Comunicati Stampa\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"headline\":\"La crisi come testimonianza di una (ir)responsabilit\u00e0 sociale\",\"datePublished\":\"2013-03-20T15:05:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/societa\\\/news-e-attualita\\\/la-crisi-come-testimonianza-di-una-ir-responsabilit%c3%a0-sociale\\\/\"},\"wordCount\":1183,\"commentCount\":0,\"keywords\":[\"crisi\",\"responsabilit\u00e0\"],\"articleSection\":[\"News e Attualit\u00e0\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/societa\\\/news-e-attualita\\\/la-crisi-come-testimonianza-di-una-ir-responsabilit%c3%a0-sociale\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/societa\\\/news-e-attualita\\\/la-crisi-come-testimonianza-di-una-ir-responsabilit%c3%a0-sociale\\\/\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/societa\\\/news-e-attualita\\\/la-crisi-come-testimonianza-di-una-ir-responsabilit%c3%a0-sociale\\\/\",\"name\":\"La crisi come testimonianza di una (ir)responsabilit\u00e0 sociale - Article Marketing\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\"},\"datePublished\":\"2013-03-20T15:05:33+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/societa\\\/news-e-attualita\\\/la-crisi-come-testimonianza-di-una-ir-responsabilit%c3%a0-sociale\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/societa\\\/news-e-attualita\\\/la-crisi-come-testimonianza-di-una-ir-responsabilit%c3%a0-sociale\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/societa\\\/news-e-attualita\\\/la-crisi-come-testimonianza-di-una-ir-responsabilit%c3%a0-sociale\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La crisi come testimonianza di una (ir)responsabilit\u00e0 sociale\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\",\"name\":\"Article Marketing\",\"description\":\"article marketing &amp; press release\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\",\"name\":\"Redazione Comunicati Stampa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"caption\":\"Redazione Comunicati Stampa\"},\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/author\\\/redazione-comunicati-stampa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La crisi come testimonianza di una (ir)responsabilit\u00e0 sociale - Article Marketing","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.article-marketing.eu\/comunicati\/societa\/news-e-attualita\/la-crisi-come-testimonianza-di-una-ir-responsabilit\u00e0-sociale\/","og_locale":"it_IT","og_type":"article","og_title":"La crisi come testimonianza di una (ir)responsabilit\u00e0 sociale - Article Marketing","og_description":"Parlare di \u201cResponsabilit\u00e0\u201d o di \u201cIrresponsabilit\u00e0\u201d sociale d\u2019impresa rinvia al tema dellescelte, in presenza di conflitti tra valori, di dilemmi circa la scelta dei valori da applicare inspecifici contesti, dove urge optare tra valori confliggenti o addirittura escludenti.","og_url":"https:\/\/www.article-marketing.eu\/comunicati\/societa\/news-e-attualita\/la-crisi-come-testimonianza-di-una-ir-responsabilit\u00e0-sociale\/","og_site_name":"Article Marketing","article_published_time":"2013-03-20T15:05:33+00:00","author":"Redazione Comunicati Stampa","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione Comunicati Stampa","Tempo di lettura stimato":"6 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.article-marketing.eu\/comunicati\/societa\/news-e-attualita\/la-crisi-come-testimonianza-di-una-ir-responsabilit%c3%a0-sociale\/#article","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/societa\/news-e-attualita\/la-crisi-come-testimonianza-di-una-ir-responsabilit%c3%a0-sociale\/"},"author":{"name":"Redazione Comunicati Stampa","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"headline":"La crisi come testimonianza di una (ir)responsabilit\u00e0 sociale","datePublished":"2013-03-20T15:05:33+00:00","mainEntityOfPage":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/societa\/news-e-attualita\/la-crisi-come-testimonianza-di-una-ir-responsabilit%c3%a0-sociale\/"},"wordCount":1183,"commentCount":0,"keywords":["crisi","responsabilit\u00e0"],"articleSection":["News e Attualit\u00e0"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.article-marketing.eu\/comunicati\/societa\/news-e-attualita\/la-crisi-come-testimonianza-di-una-ir-responsabilit%c3%a0-sociale\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.article-marketing.eu\/comunicati\/societa\/news-e-attualita\/la-crisi-come-testimonianza-di-una-ir-responsabilit%c3%a0-sociale\/","url":"https:\/\/www.article-marketing.eu\/comunicati\/societa\/news-e-attualita\/la-crisi-come-testimonianza-di-una-ir-responsabilit%c3%a0-sociale\/","name":"La crisi come testimonianza di una (ir)responsabilit\u00e0 sociale - Article Marketing","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website"},"datePublished":"2013-03-20T15:05:33+00:00","author":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"breadcrumb":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/societa\/news-e-attualita\/la-crisi-come-testimonianza-di-una-ir-responsabilit%c3%a0-sociale\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.article-marketing.eu\/comunicati\/societa\/news-e-attualita\/la-crisi-come-testimonianza-di-una-ir-responsabilit%c3%a0-sociale\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.article-marketing.eu\/comunicati\/societa\/news-e-attualita\/la-crisi-come-testimonianza-di-una-ir-responsabilit%c3%a0-sociale\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.article-marketing.eu\/comunicati\/"},{"@type":"ListItem","position":2,"name":"La crisi come testimonianza di una (ir)responsabilit\u00e0 sociale"}]},{"@type":"WebSite","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website","url":"https:\/\/www.article-marketing.eu\/comunicati\/","name":"Article Marketing","description":"article marketing &amp; press release","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.article-marketing.eu\/comunicati\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017","name":"Redazione Comunicati Stampa","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","caption":"Redazione Comunicati Stampa"},"url":"https:\/\/www.article-marketing.eu\/comunicati\/author\/redazione-comunicati-stampa\/"}]}},"_links":{"self":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/33417","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/comments?post=33417"}],"version-history":[{"count":0,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/33417\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/media?parent=33417"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/categories?post=33417"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/tags?post=33417"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}