{"id":33956,"date":"2013-04-15T13:20:39","date_gmt":"2013-04-15T11:20:39","guid":{"rendered":"http:\/\/www.article-marketing.eu\/comunicati\/senza-categoria\/medaglia-da%80%99oro-per-la%80%99olio-extravergine-biologico-il-frantoio-oleario-f-lli-pace-vince-il-premio-biol-2013-2\/"},"modified":"2013-04-15T13:20:39","modified_gmt":"2013-04-15T11:20:39","slug":"medaglia-da%80%99oro-per-la%80%99olio-extravergine-biologico-il-frantoio-oleario-f-lli-pace-vince-il-premio-biol-2013-2","status":"publish","type":"post","link":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/medaglia-da%80%99oro-per-la%80%99olio-extravergine-biologico-il-frantoio-oleario-f-lli-pace-vince-il-premio-biol-2013-2\/","title":{"rendered":"Medaglia d\u2019oro per l\u2019olio Extravergine Biologico, il Frantoio F.lli Pace vince il Premio Biol 2013"},"content":{"rendered":"<p>L&rsquo;<strong style=\"mso-bidi-font-weight: normal;\"><a href=\"http:\/\/www.oliopace.it\/it\/\" target=\"_blank\" title=\"olio extravergine biologico\">olio Extravergine Biologico<\/a> <\/strong>del Frantoio Oleario F.lli Pace ha ricevuto la <strong style=\"mso-bidi-font-weight: normal;\">GOLD MEDAL<\/strong> alla XVIII edizione del Premio Internazionale Biol, un concorso annuale che stila la classifica dei migliori oli biologici provenienti da tutto il mondo.<\/p>\n<p>Il Frantoio Pace ha conseguito il prestigioso premio per il terzo anno consecutivo, conquistando un posto importante tra i migliori produttori di oli Extravergini Biologici, non solo in Italia ma in tutto il mondo. I 27 esperti della giuria internazionale del Premio Biol, coordinata dal capo panel Giorgio Cardone, hanno assaggiato 350 oli provenienti da Arabia Saudita, Argentina, Italia, Cile, Germania, Grecia, Israele, Libano, Portogallo, Slovenia, Spagna, Tunisia, Turchia, Marocco e Francia. <br \/>L&rsquo;impegno di un&rsquo;azienda che produce olio da generazioni &egrave; stato premiato anche in considerazione dell&rsquo;importanza che le varianti biologiche stanno acquistando sul mercato. L&#8217;olio Extravergine di Oliva Biologico &egrave; un prodotto certificato dall&#8217;ente Bioagricert Srl in conformit&agrave; al Reg. CE 834\/07. <br \/>Oltre alla certificazione dell&rsquo;Olio Biologico, il Frantoio Oleario F.lli Pace, al fine di raggiungere la massima soddisfazione dei clienti attraverso un miglioramento costante dell&rsquo;organizzazione aziendale, ha implementato, da oltre 10 anni, diverse certificazioni su base volontaria, controllate e certificate dall&rsquo;Organismo di Controllo Internazionale SGS: Sistema di Qualit&agrave; Aziendale in conformit&agrave; alla norma ISO 9001; Sistema Qualit&agrave; Ambientale in conformit&agrave; alla norma ISO 14001; Certificazione di Prodotto in conformit&agrave; a quanto previsto dallo schema sulla certificazione volontaria dei prodotti agroalimentari.<br \/>Il prodotto, che si pu&ograve; acquistare direttamente online dal sito www.oliopace.it, &egrave; ottenuto tramite la produzione a freddo di olive di variet&agrave; prevalentemente Peranzana. Il processo produttivo non utilizza trattamenti di tipo chimico o antiparassitario. L&rsquo;olio si presenta con un colore verde brillante tendente al giallo dorato e si contraddistingue per un profumo fresco di frutto maturo.<br \/>Come l&rsquo;<strong style=\"mso-bidi-font-weight: normal;\">olio extravergine biologico<\/strong>, tutti i prodotti del Frantoio puntano ad essere fortemente identitari. Il compito dei F.lli Pace &egrave; infatti quello di valorizzare i prodotti della Basilicata in Italia e nel mondo. Il Frantoio Oleario Fratelli Pace &egrave; regolarmente iscritto nell&rsquo;elenco delle aziende di trasformazione dei prodotti da agricoltura biologica della regione Basilicata. Curando tutta la filiera olivicola, <strong style=\"mso-bidi-font-weight: normal;\">dalla raccolta delle olive fino alla fase di vendita diretta alle famiglie,<\/strong> riesce a garantire un olio di elevata qualit&agrave; artigianale, prodotto con passione e amore.<\/p>\n<p>&Egrave; possibile ordinare i prodotti del Frantoio Oleario Pace direttamente online sul sito www.oliopace.it, scrivendo all&rsquo;indirizzo di posta elettronica contatti@oliopace.it o contattando direttamente il Frantoio al<strong style=\"mso-bidi-font-weight: normal;\"> numero verde<\/strong> <strong style=\"mso-bidi-font-weight: normal;\">800.800.860.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il premio Biol 2013 riconosce la qualit\u00e0 dell\u2019olio Extravergine d\u2019Oliva Biologico del Frantoio Oleario F.lli Pace.<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"","footnotes":""},"categories":[190],"tags":[42265,42267,42264,42266],"class_list":["post-33956","post","type-post","status-publish","format-standard","hentry","category-comunicati-stampa","tag-gold-medal","tag-olio-di-oliva-extravergine-biologico","tag-olio-extravergine-biologico","tag-premio-biol"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Medaglia d\u2019oro per l\u2019olio Extravergine Biologico, il Frantoio F.lli Pace vince il Premio Biol 2013 - Article Marketing<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/medaglia-da??oro-per-la??olio-extravergine-biologico-il-frantoio-oleario-f-lli-pace-vince-il-premio-biol-2013-2\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Medaglia d\u2019oro per l\u2019olio Extravergine Biologico, il Frantoio F.lli Pace vince il Premio Biol 2013 - Article Marketing\" \/>\n<meta property=\"og:description\" content=\"Il premio Biol 2013 riconosce la qualit\u00e0 dell\u2019olio Extravergine d\u2019Oliva Biologico del Frantoio Oleario F.lli Pace.\" \/>\n<meta property=\"og:url\" content=\"\" \/>\n<meta property=\"og:site_name\" content=\"Article Marketing\" \/>\n<meta property=\"article:published_time\" content=\"2013-04-15T11:20:39+00:00\" \/>\n<meta name=\"author\" content=\"Redazione Comunicati Stampa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione Comunicati Stampa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/medaglia-da%80%99oro-per-la%80%99olio-extravergine-biologico-il-frantoio-oleario-f-lli-pace-vince-il-premio-biol-2013-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/medaglia-da%80%99oro-per-la%80%99olio-extravergine-biologico-il-frantoio-oleario-f-lli-pace-vince-il-premio-biol-2013-2\\\/\"},\"author\":{\"name\":\"Redazione Comunicati Stampa\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"headline\":\"Medaglia d\u2019oro per l\u2019olio Extravergine Biologico, il Frantoio F.lli Pace vince il Premio Biol 2013\",\"datePublished\":\"2013-04-15T11:20:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/medaglia-da%80%99oro-per-la%80%99olio-extravergine-biologico-il-frantoio-oleario-f-lli-pace-vince-il-premio-biol-2013-2\\\/\"},\"wordCount\":449,\"commentCount\":0,\"keywords\":[\"gold medal\",\"olio di oliva extravergine biologico\",\"olio extravergine biologico\",\"premio biol\"],\"articleSection\":[\"Comunicati stampa\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/medaglia-da%80%99oro-per-la%80%99olio-extravergine-biologico-il-frantoio-oleario-f-lli-pace-vince-il-premio-biol-2013-2\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/medaglia-da%80%99oro-per-la%80%99olio-extravergine-biologico-il-frantoio-oleario-f-lli-pace-vince-il-premio-biol-2013-2\\\/\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/medaglia-da%80%99oro-per-la%80%99olio-extravergine-biologico-il-frantoio-oleario-f-lli-pace-vince-il-premio-biol-2013-2\\\/\",\"name\":\"Medaglia d\u2019oro per l\u2019olio Extravergine Biologico, il Frantoio F.lli Pace vince il Premio Biol 2013 - Article Marketing\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\"},\"datePublished\":\"2013-04-15T11:20:39+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/medaglia-da%80%99oro-per-la%80%99olio-extravergine-biologico-il-frantoio-oleario-f-lli-pace-vince-il-premio-biol-2013-2\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/medaglia-da%80%99oro-per-la%80%99olio-extravergine-biologico-il-frantoio-oleario-f-lli-pace-vince-il-premio-biol-2013-2\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/medaglia-da%80%99oro-per-la%80%99olio-extravergine-biologico-il-frantoio-oleario-f-lli-pace-vince-il-premio-biol-2013-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Medaglia d\u2019oro per l\u2019olio Extravergine Biologico, il Frantoio F.lli Pace vince il Premio Biol 2013\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\",\"name\":\"Article Marketing\",\"description\":\"article marketing &amp; press release\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\",\"name\":\"Redazione Comunicati Stampa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"caption\":\"Redazione Comunicati Stampa\"},\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/author\\\/redazione-comunicati-stampa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Medaglia d\u2019oro per l\u2019olio Extravergine Biologico, il Frantoio F.lli Pace vince il Premio Biol 2013 - Article Marketing","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/medaglia-da??oro-per-la??olio-extravergine-biologico-il-frantoio-oleario-f-lli-pace-vince-il-premio-biol-2013-2\/","og_locale":"it_IT","og_type":"article","og_title":"Medaglia d\u2019oro per l\u2019olio Extravergine Biologico, il Frantoio F.lli Pace vince il Premio Biol 2013 - Article Marketing","og_description":"Il premio Biol 2013 riconosce la qualit\u00e0 dell\u2019olio Extravergine d\u2019Oliva Biologico del Frantoio Oleario F.lli Pace.","og_url":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/medaglia-da??oro-per-la??olio-extravergine-biologico-il-frantoio-oleario-f-lli-pace-vince-il-premio-biol-2013-2\/","og_site_name":"Article Marketing","article_published_time":"2013-04-15T11:20:39+00:00","author":"Redazione Comunicati Stampa","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione Comunicati Stampa","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/medaglia-da%80%99oro-per-la%80%99olio-extravergine-biologico-il-frantoio-oleario-f-lli-pace-vince-il-premio-biol-2013-2\/#article","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/medaglia-da%80%99oro-per-la%80%99olio-extravergine-biologico-il-frantoio-oleario-f-lli-pace-vince-il-premio-biol-2013-2\/"},"author":{"name":"Redazione Comunicati Stampa","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"headline":"Medaglia d\u2019oro per l\u2019olio Extravergine Biologico, il Frantoio F.lli Pace vince il Premio Biol 2013","datePublished":"2013-04-15T11:20:39+00:00","mainEntityOfPage":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/medaglia-da%80%99oro-per-la%80%99olio-extravergine-biologico-il-frantoio-oleario-f-lli-pace-vince-il-premio-biol-2013-2\/"},"wordCount":449,"commentCount":0,"keywords":["gold medal","olio di oliva extravergine biologico","olio extravergine biologico","premio biol"],"articleSection":["Comunicati stampa"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/medaglia-da%80%99oro-per-la%80%99olio-extravergine-biologico-il-frantoio-oleario-f-lli-pace-vince-il-premio-biol-2013-2\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/medaglia-da%80%99oro-per-la%80%99olio-extravergine-biologico-il-frantoio-oleario-f-lli-pace-vince-il-premio-biol-2013-2\/","url":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/medaglia-da%80%99oro-per-la%80%99olio-extravergine-biologico-il-frantoio-oleario-f-lli-pace-vince-il-premio-biol-2013-2\/","name":"Medaglia d\u2019oro per l\u2019olio Extravergine Biologico, il Frantoio F.lli Pace vince il Premio Biol 2013 - Article Marketing","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website"},"datePublished":"2013-04-15T11:20:39+00:00","author":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"breadcrumb":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/medaglia-da%80%99oro-per-la%80%99olio-extravergine-biologico-il-frantoio-oleario-f-lli-pace-vince-il-premio-biol-2013-2\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/medaglia-da%80%99oro-per-la%80%99olio-extravergine-biologico-il-frantoio-oleario-f-lli-pace-vince-il-premio-biol-2013-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/medaglia-da%80%99oro-per-la%80%99olio-extravergine-biologico-il-frantoio-oleario-f-lli-pace-vince-il-premio-biol-2013-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.article-marketing.eu\/comunicati\/"},{"@type":"ListItem","position":2,"name":"Medaglia d\u2019oro per l\u2019olio Extravergine Biologico, il Frantoio F.lli Pace vince il Premio Biol 2013"}]},{"@type":"WebSite","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website","url":"https:\/\/www.article-marketing.eu\/comunicati\/","name":"Article Marketing","description":"article marketing &amp; press release","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.article-marketing.eu\/comunicati\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017","name":"Redazione Comunicati Stampa","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","caption":"Redazione Comunicati Stampa"},"url":"https:\/\/www.article-marketing.eu\/comunicati\/author\/redazione-comunicati-stampa\/"}]}},"_links":{"self":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/33956","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/comments?post=33956"}],"version-history":[{"count":0,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/33956\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/media?parent=33956"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/categories?post=33956"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/tags?post=33956"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}