{"id":34315,"date":"2013-05-06T17:15:10","date_gmt":"2013-05-06T15:15:10","guid":{"rendered":""},"modified":"2018-10-25T22:07:35","modified_gmt":"2018-10-25T20:07:35","slug":"alda-teodorani-intervista-dino-caterini-il-fondatore-della-scuola-internazionale-di-comics-di-fronte-alla-regina-del-noir-italiano-i-segreti-di-35-anni-di-successi-e-la%25252580%25252599inizio-di-un","status":"publish","type":"post","link":"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/giornalismo\/alda-teodorani-intervista-dino-caterini-il-fondatore-della-scuola-internazionale-di-comics-di-fronte-alla-regina-del-noir-italiano-i-segreti-di-35-anni-di-successi-e-la%25252580%25252599inizio-di-un\/","title":{"rendered":"ALDA TEODORANI INTERVISTA DINO CATERINI."},"content":{"rendered":"<p>La Scuola Internazionale di Comics, fondata dall&rsquo;eclettico disegnatore Dino Caterini (oggi Direttore Generale di tutte le sedi) &egrave; nata nel 1979 e ha svolto nel corso degli anni un&rsquo;attivit&agrave; di grande spessore sia a livello sociale che a livello didattico, proponendo corsi che spaziano a 360&deg; nelle arti figurative, grafiche, digitali e letterarie e impegnandosi in ambito sociale a supportare iniziative culturali, associazioni onlus e stringendo legami con altre realt&agrave; formative in ambito internazionale. La Scuola si distingue per i suoi particolari metodi di insegnamento che privilegiano uno stretto contatto con gli allievi e stimolano ognuno di loro a cercare il proprio percorso personale e a esprimere al meglio il proprio talento. Dedicando soprattutto i suoi sforzi all&rsquo;alta formazione professionale, la Scuola vanta una forte presenza dei suoi ex allievi nell&rsquo;ambito editoriale: il 60% degli autori italiani del momento &egrave; uscito dalla Scuola Internazionale di Comics. Dal 1979, la Scuola Internazionale di Comics si &egrave; espansa su una notevole area di interesse nel territorio nazionale e all&rsquo;inizio del 2013 vanta la sua presenza nelle citt&agrave; di Roma, Firenze, Jesi, Pescara, Torino, Padova, Reggio Emilia, Brescia e Napoli. Nell&rsquo;ambito del fumetto e dell&rsquo;illustrazione, la Scuola ha collaborato con numerose associazioni operanti nel sociale, umanitarie e animaliste, come Unicef, Amnesty International, Animalisti italiani, Emergency, WWF, L.A.V. Lega Anti Vivisezione, Avis, e ha realizzato il calendario 2013 della Polizia di Stato sui bozzetti dei ragazzi dell&rsquo;istituto penale minorile di Nisida. <strong>Ecco il testo dell&rsquo;intervista di Alda Teodorani a Dino Caterini<\/strong> Oggi ho incontrato Dino Caterini, con il quale mi lega un sodalizio professionale che dura da 15 anni, per qualcosa di diverso: gli ho proposto di intervistarlo. Ho intervistato, nel corso del tempo, attori, registi, scrittori (solo per fare qualche nome in ordine sparso: Brandon Lee, Mel Gibson, Dario Argento, Giampiero Mughini, Asia Argento, Luciano De Crescenzo, Tinto Brass e tanti altri) eppure mai il <em>mio <\/em>direttore, oltre che mio amico e persona che gode di tutta la mia stima da tanti anni. Per questo oggi ho deciso di incontrarlo in questa veste tanto diversa. <strong>Direttore, grazie innanzitutto di aver accettato di essere intervistato. Siamo alle soglie del 35esimo anno di attivit&agrave; della sua grande idea: <\/strong><strong>quella della Scuola Internazionale di Comics, che in pratica &egrave; operativa dal 1979: come nasce l&rsquo;idea di crearla e perch&eacute; questo nome?<\/strong> Nel 1978 ero un disegnatore e avevo uno studio disegnatore, il lavoro era troppo e mi serviva qualcuno per alleggerire il carico, fu cos&igrave; che presi del personale, ma era pi&ugrave; il tempo che impiegavo a spiegare cosa fare che quello che serviva per lavorare. <br \/>Questa esperienza mi spinse a fondare una scuola nel 1979 che chiamai &ldquo;Scuola Italiana del fumetto&rdquo;, che visto il successo divent&ograve; in pochi anni una s.r.l. e prese il titolo di &ldquo;Scuola Internazionale di Comics&rdquo;. L&rsquo;aggettivo internazionale serv&igrave; per dare un respiro pi&ugrave; ampio alla scuola; gi&agrave; allora molti studenti venivano dall&rsquo;estero per studiare da noi e oggi sono sempre di pi&ugrave;. Con la nuova sede di Chicago, che abbiamo appena aperto, la scuola di fatto ha una sua sede in USA, nell&rsquo;Illinois; abbiamo molti contatti con editori di tutto il mondo, che hanno pubblicato e pubblicheranno i lavori dei nostri migliori studenti, abbiamo un corso che di fatto si svolge in Giappone con insegnanti scelti tra mangaka professionisti, abbiamo viaggi premio all&rsquo;estero per i nostri migliori studenti, per ora a Cuba e a Tokio, le novit&agrave; aumentano di giorno in giorno!&raquo; Inaugurata lo scorso marzo, la <strong>School International of Comics di Chicago <\/strong>&egrave; la nuova avventura intrapresa da Dino Caterini, che punta agli USA per la nascita e la formazione di nuovi talenti. <strong>Ci parla della scelta di aprire una scuola a Chicago? <\/strong> Innanzitutto gli USA, con tutte le loro contraddizioni, sono il paese che premia l&rsquo;iniziativa privata e d&agrave; modo a chiunque abbia un po&rsquo; di genialit&agrave; di emergere. Quale nuovo terreno quindi migliore di questo? Negli USA la Scuola intende proporsi come valida alternativa a chi cerca una scuola <em>undergraduate <\/em>di specializzazione su materie pratiche e che, al tempo stesso, non richieda investimenti di denaro tipici della formazione universitaria statunitense, che non solo &egrave; costosissima ma richiede un impegno elevato nel corso del tempo, e a volte gli studenti sono costretti a firmare veri e propri prestiti universitari. La Scuola Internazionale di Comics nella sua sede di Chicago intende presentarsi inoltre come reale alternativa per i ragazzi che posseggono talento e predisposizione ma che non hanno la possibilit&agrave; di formarsi a un livello accademico che &ndash; oltre alla formazione piuttosto generica e allargata &ndash; propone costi spesso insostenibili, quindi per molti ragazzi l&rsquo;idea di diventare disegnatori di fumetto (o di operare nel settore delle arti figurative, grafiche, digitali) resta un sogno nel cassetto. Senza un mentore che ti dia la possibilit&agrave; di vedere dove stai sbagliando la tua attivit&agrave; resta sommersa, non c&rsquo;&egrave; confronto, non c&rsquo;&egrave; crescita. Come succede nella sede italiana della Scuola, la formazione &egrave; suddivisa in vari settori: come vedremo, il metodo di studio particolarmente articolato consentir&agrave; agli allievi di ottenere una formazione valida in ambito internazionale. Niente pi&ugrave; frontiere. La scuola si trova al 1651 di West Hubbard Street, l&rsquo;indirizzo del sito &egrave; http:\/\/www.schoolofcomics.us\/it\/&raquo; <strong> <\/strong> <strong>Qual &egrave; il metodo di studio nella sua Scuola?<\/strong> &laquo;Il metodo di studio presso la Scuola Internazionale di Comics &egrave; finalizzato all&rsquo;alta formazione e specializzazione professionale degli allievi che si consegue attraverso programmi costantemente aggiornati con le novit&agrave; relative ai settori di appartenenza. Poi l&rsquo;insegnamento che coinvolge i professionisti delle relative discipline, e questo &egrave; un modello che nel corso del tempo ha dato ottimi risultati. In tutte le sedi della Scuola abbiamo materiale audiovisivo che aiuta nello svolgimento dei programmi di studio, oltre al confronto diretto con gli insegnanti appartenenti ai vari settori editoriali e di varie nazionalit&agrave;. Il tutto &egrave; organizzato in lezioni teoriche e pratiche, i cui risultati si consolidano con il lavoro a casa, in cui gli allievi mettono in atto le tecniche acquisite durante le lezioni e quindi si esaminano grazie a verifiche periodiche e tramite esami di fine anno. Il risultato &egrave; garantito dal bagaglio di esperienza della Scuola Internazionale di Comics, che nel tempo ha dimostrato di dedicarsi pi&ugrave; alla qualit&agrave; e al buon rendimento del suo insegnamento che alla quantit&agrave; di ore: questo permette di proporre un numero minore di ore di frequenza che consente una fisiologica diminuzione dei costi dei corsi pur mantenendo alta la qualit&agrave;. E qui entra in gioco la professione e la professionalit&agrave;: a fine corso, grazie alle abilit&agrave; acquisite, gli allievi potranno pi&ugrave; facilmente inserirsi in un ambito professionale internazionale con competenze richieste dal mercato mondiale dell&rsquo;editoria e delle arti grafiche (anche nel nascente mercato degli ebook, in forte espansione) e in special modo in Francia, Spagna, Italia e, of course, in Usa, dove la genialit&agrave; italiana si confronta con il rigore organizzativo statunitense.&raquo; Nei suoi tanti anni di esperienza nel settore della formazione professionale la Scuola Internazionale di Comics ha sempre raggiunto l&rsquo;eccellenza grazie ai suoi insegnanti altamente qualificati. Squadra che vince non si cambia dunque e lo stesso ingrediente di successo viene utilizzato oltreoceano, con una serie di nomi illustri e importanti come <strong>Paolo Eleuteri Serpieri<\/strong>, autore di <em>Druuna, <\/em>conosciuto negli USA per la rivista <em>Heavy Metal; <\/em>lo sceneggiatore <strong>Roberto Dal Pr&agrave;<\/strong>; il creatore grafico di <em>Martin Myst&egrave;re<\/em><strong> Giancarlo Alessandrini<\/strong>; <strong>Giorgio Cavazzano <\/strong>storico disegnatore Disney; tra gli autori americani invece <strong>Alex Ross <\/strong>uno dei grandi disegnatori di supereroi e <strong>Brian Azzarello, <\/strong>sceneggiatore della DC, celebre per il suo Joker. <strong>Cosa direbbe a un giovane che cerca un futuro in questo ambito?<\/strong> &laquo;Di frequentare la nostra scuola (sorride) e di non arrendersi mai!&raquo;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il fondatore della Scuola Internazionale di Comics di fronte alla regina del noir italiano. I segreti di 35 anni di successi e l\u2019inizio di un nuovo capitolo: la conquista dell\u2019America.<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"","footnotes":""},"categories":[218],"tags":[],"class_list":["post-34315","post","type-post","status-publish","format-standard","hentry","category-giornalismo"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>ALDA TEODORANI INTERVISTA DINO CATERINI. - Article Marketing<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/giornalismo\/alda-teodorani-intervista-dino-caterini-il-fondatore-della-scuola-internazionale-di-comics-di-fronte-alla-regina-del-noir-italiano-i-segreti-di-35-anni-di-successi-e-la%252580%252599inizio-di-un\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ALDA TEODORANI INTERVISTA DINO CATERINI. - Article Marketing\" \/>\n<meta property=\"og:description\" content=\"Il fondatore della Scuola Internazionale di Comics di fronte alla regina del noir italiano. I segreti di 35 anni di successi e l\u2019inizio di un nuovo capitolo: la conquista dell\u2019America.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/giornalismo\/alda-teodorani-intervista-dino-caterini-il-fondatore-della-scuola-internazionale-di-comics-di-fronte-alla-regina-del-noir-italiano-i-segreti-di-35-anni-di-successi-e-la%252580%252599inizio-di-un\/\" \/>\n<meta property=\"og:site_name\" content=\"Article Marketing\" \/>\n<meta property=\"article:published_time\" content=\"2013-05-06T15:15:10+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-10-25T20:07:35+00:00\" \/>\n<meta name=\"author\" content=\"Redazione Comunicati Stampa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione Comunicati Stampa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/arte-e-cultura\\\/giornalismo\\\/alda-teodorani-intervista-dino-caterini-il-fondatore-della-scuola-internazionale-di-comics-di-fronte-alla-regina-del-noir-italiano-i-segreti-di-35-anni-di-successi-e-la%25252580%25252599inizio-di-un\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/arte-e-cultura\\\/giornalismo\\\/alda-teodorani-intervista-dino-caterini-il-fondatore-della-scuola-internazionale-di-comics-di-fronte-alla-regina-del-noir-italiano-i-segreti-di-35-anni-di-successi-e-la%25252580%25252599inizio-di-un\\\/\"},\"author\":{\"name\":\"Redazione Comunicati Stampa\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"headline\":\"ALDA TEODORANI INTERVISTA DINO CATERINI.\",\"datePublished\":\"2013-05-06T15:15:10+00:00\",\"dateModified\":\"2018-10-25T20:07:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/arte-e-cultura\\\/giornalismo\\\/alda-teodorani-intervista-dino-caterini-il-fondatore-della-scuola-internazionale-di-comics-di-fronte-alla-regina-del-noir-italiano-i-segreti-di-35-anni-di-successi-e-la%25252580%25252599inizio-di-un\\\/\"},\"wordCount\":1361,\"commentCount\":0,\"articleSection\":[\"Giornalismo\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/arte-e-cultura\\\/giornalismo\\\/alda-teodorani-intervista-dino-caterini-il-fondatore-della-scuola-internazionale-di-comics-di-fronte-alla-regina-del-noir-italiano-i-segreti-di-35-anni-di-successi-e-la%25252580%25252599inizio-di-un\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/arte-e-cultura\\\/giornalismo\\\/alda-teodorani-intervista-dino-caterini-il-fondatore-della-scuola-internazionale-di-comics-di-fronte-alla-regina-del-noir-italiano-i-segreti-di-35-anni-di-successi-e-la%25252580%25252599inizio-di-un\\\/\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/arte-e-cultura\\\/giornalismo\\\/alda-teodorani-intervista-dino-caterini-il-fondatore-della-scuola-internazionale-di-comics-di-fronte-alla-regina-del-noir-italiano-i-segreti-di-35-anni-di-successi-e-la%25252580%25252599inizio-di-un\\\/\",\"name\":\"ALDA TEODORANI INTERVISTA DINO CATERINI. - Article Marketing\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\"},\"datePublished\":\"2013-05-06T15:15:10+00:00\",\"dateModified\":\"2018-10-25T20:07:35+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/arte-e-cultura\\\/giornalismo\\\/alda-teodorani-intervista-dino-caterini-il-fondatore-della-scuola-internazionale-di-comics-di-fronte-alla-regina-del-noir-italiano-i-segreti-di-35-anni-di-successi-e-la%25252580%25252599inizio-di-un\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/arte-e-cultura\\\/giornalismo\\\/alda-teodorani-intervista-dino-caterini-il-fondatore-della-scuola-internazionale-di-comics-di-fronte-alla-regina-del-noir-italiano-i-segreti-di-35-anni-di-successi-e-la%25252580%25252599inizio-di-un\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/arte-e-cultura\\\/giornalismo\\\/alda-teodorani-intervista-dino-caterini-il-fondatore-della-scuola-internazionale-di-comics-di-fronte-alla-regina-del-noir-italiano-i-segreti-di-35-anni-di-successi-e-la%25252580%25252599inizio-di-un\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ALDA TEODORANI INTERVISTA DINO CATERINI.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\",\"name\":\"Article Marketing\",\"description\":\"article marketing &amp; press release\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\",\"name\":\"Redazione Comunicati Stampa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"caption\":\"Redazione Comunicati Stampa\"},\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/author\\\/redazione-comunicati-stampa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ALDA TEODORANI INTERVISTA DINO CATERINI. - Article Marketing","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/giornalismo\/alda-teodorani-intervista-dino-caterini-il-fondatore-della-scuola-internazionale-di-comics-di-fronte-alla-regina-del-noir-italiano-i-segreti-di-35-anni-di-successi-e-la%252580%252599inizio-di-un\/","og_locale":"it_IT","og_type":"article","og_title":"ALDA TEODORANI INTERVISTA DINO CATERINI. - Article Marketing","og_description":"Il fondatore della Scuola Internazionale di Comics di fronte alla regina del noir italiano. I segreti di 35 anni di successi e l\u2019inizio di un nuovo capitolo: la conquista dell\u2019America.","og_url":"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/giornalismo\/alda-teodorani-intervista-dino-caterini-il-fondatore-della-scuola-internazionale-di-comics-di-fronte-alla-regina-del-noir-italiano-i-segreti-di-35-anni-di-successi-e-la%252580%252599inizio-di-un\/","og_site_name":"Article Marketing","article_published_time":"2013-05-06T15:15:10+00:00","article_modified_time":"2018-10-25T20:07:35+00:00","author":"Redazione Comunicati Stampa","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione Comunicati Stampa","Tempo di lettura stimato":"7 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/giornalismo\/alda-teodorani-intervista-dino-caterini-il-fondatore-della-scuola-internazionale-di-comics-di-fronte-alla-regina-del-noir-italiano-i-segreti-di-35-anni-di-successi-e-la%25252580%25252599inizio-di-un\/#article","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/giornalismo\/alda-teodorani-intervista-dino-caterini-il-fondatore-della-scuola-internazionale-di-comics-di-fronte-alla-regina-del-noir-italiano-i-segreti-di-35-anni-di-successi-e-la%25252580%25252599inizio-di-un\/"},"author":{"name":"Redazione Comunicati Stampa","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"headline":"ALDA TEODORANI INTERVISTA DINO CATERINI.","datePublished":"2013-05-06T15:15:10+00:00","dateModified":"2018-10-25T20:07:35+00:00","mainEntityOfPage":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/giornalismo\/alda-teodorani-intervista-dino-caterini-il-fondatore-della-scuola-internazionale-di-comics-di-fronte-alla-regina-del-noir-italiano-i-segreti-di-35-anni-di-successi-e-la%25252580%25252599inizio-di-un\/"},"wordCount":1361,"commentCount":0,"articleSection":["Giornalismo"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/giornalismo\/alda-teodorani-intervista-dino-caterini-il-fondatore-della-scuola-internazionale-di-comics-di-fronte-alla-regina-del-noir-italiano-i-segreti-di-35-anni-di-successi-e-la%25252580%25252599inizio-di-un\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/giornalismo\/alda-teodorani-intervista-dino-caterini-il-fondatore-della-scuola-internazionale-di-comics-di-fronte-alla-regina-del-noir-italiano-i-segreti-di-35-anni-di-successi-e-la%25252580%25252599inizio-di-un\/","url":"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/giornalismo\/alda-teodorani-intervista-dino-caterini-il-fondatore-della-scuola-internazionale-di-comics-di-fronte-alla-regina-del-noir-italiano-i-segreti-di-35-anni-di-successi-e-la%25252580%25252599inizio-di-un\/","name":"ALDA TEODORANI INTERVISTA DINO CATERINI. - Article Marketing","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website"},"datePublished":"2013-05-06T15:15:10+00:00","dateModified":"2018-10-25T20:07:35+00:00","author":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"breadcrumb":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/giornalismo\/alda-teodorani-intervista-dino-caterini-il-fondatore-della-scuola-internazionale-di-comics-di-fronte-alla-regina-del-noir-italiano-i-segreti-di-35-anni-di-successi-e-la%25252580%25252599inizio-di-un\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/giornalismo\/alda-teodorani-intervista-dino-caterini-il-fondatore-della-scuola-internazionale-di-comics-di-fronte-alla-regina-del-noir-italiano-i-segreti-di-35-anni-di-successi-e-la%25252580%25252599inizio-di-un\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/giornalismo\/alda-teodorani-intervista-dino-caterini-il-fondatore-della-scuola-internazionale-di-comics-di-fronte-alla-regina-del-noir-italiano-i-segreti-di-35-anni-di-successi-e-la%25252580%25252599inizio-di-un\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.article-marketing.eu\/comunicati\/"},{"@type":"ListItem","position":2,"name":"ALDA TEODORANI INTERVISTA DINO CATERINI."}]},{"@type":"WebSite","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website","url":"https:\/\/www.article-marketing.eu\/comunicati\/","name":"Article Marketing","description":"article marketing &amp; press release","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.article-marketing.eu\/comunicati\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017","name":"Redazione Comunicati Stampa","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","caption":"Redazione Comunicati Stampa"},"url":"https:\/\/www.article-marketing.eu\/comunicati\/author\/redazione-comunicati-stampa\/"}]}},"_links":{"self":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/34315","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/comments?post=34315"}],"version-history":[{"count":1,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/34315\/revisions"}],"predecessor-version":[{"id":63152,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/34315\/revisions\/63152"}],"wp:attachment":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/media?parent=34315"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/categories?post=34315"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/tags?post=34315"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}