{"id":35721,"date":"2013-07-11T12:57:52","date_gmt":"2013-07-11T10:57:52","guid":{"rendered":"http:\/\/www.article-marketing.eu\/comunicati\/senza-categoria\/la-torneria-automatica-per-la-tornitura-dei-metalli\/"},"modified":"2018-10-25T22:11:09","modified_gmt":"2018-10-25T20:11:09","slug":"la-torneria-automatica-per-la-tornitura-dei-metalli","status":"publish","type":"post","link":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/la-torneria-automatica-per-la-tornitura-dei-metalli\/","title":{"rendered":"La torneria automatica per la tornitura dei metalli"},"content":{"rendered":"<p>Se parliamo di <strong>tornitura dei metalli<\/strong> per la produzione di elementi per la meccanica di precisione, senza dubbio la <strong>torneria automatica<\/strong> rappresenta il luogo lavorativo ideale per la produzione in serie di componenti.<br \/>La necessit&agrave; di incrementare i ritmi di produzione, dovuta ad una domanda sempre pi&ugrave; elevata e in combinazione con invenzioni e scoperte epocali come la produzione di energia elettrica e il motore a scoppio, ha portato ad un&rsquo;evoluzione sostanziale delle operazioni di <em>tornitura e fresatura<\/em> tipiche per la realizzazione di componenti meccanici di precisione. In particolare l&rsquo;implementazione di <strong>macchine automatizzate<\/strong> ha dato un notevole impulso alla classica tornitura dei metalli, tanto che oggi si parla comunemente di <strong>torneria automatica<\/strong>.<br \/><strong>Eredi Baitelli &egrave; una torneria metallica certificata che si occupa di tornitura metallica di precisione da oltre 50 anni. Eredi Baitelli &egrave; una delle tornerie metalliche pi&ugrave; quotate a livello internazionale.<\/strong><br \/>I pezzi torniti di Eredi Baitelli vengono realizzati con professionalit&agrave; e competenza e l&rsquo;azienda stessa &egrave; ormai nel mondo garanzia di qualit&agrave; assoluta nella tornitura.<br \/><strong>Eredi Baitelli esegue lavori di tornitura metallica ad altissima precisione su diversi materiali metallici per diversi settori di applicazione.<\/strong><br \/><strong>Scopri le caratteristiche tecniche dei prodotti che possiamo realizzare<\/strong><br \/><strong>Scopri il nostro parco macchine<\/strong><br \/><strong>Scopri i settori di applicazione dei nostri prodotti<\/strong><strong><\/strong><br \/>Il <strong>servizio di torneria automatica<\/strong> &egrave; pensato per soddisfare tutte le esigenze, rispondendo allo stesso tempo agli standard pi&ugrave; alti di qualit&agrave; e sicurezza:<\/p>\n<ul style=\"text-align: justify;\"><\/p>\n<li>Fresatura<\/li>\n<p><\/p>\n<li>Filettatura<\/li>\n<p><\/p>\n<li>Lavorazioni su specifiche e disegno del cliente<\/li>\n<p><\/ul>\n<p><strong>Come si &egrave; arrivati alla torneria automatica <\/strong><br \/>Operazioni ripetitive e complesse per l&#8217;uomo oggi vengono realizzate attraverso la tecnologia dell&#8217;<strong>automazione industriale.<\/strong><br \/>I sistemi automatici venivano utilizzati dall&#8217;uomo fin dall&#8217;antichit&agrave;. Con l&rsquo;avvento della rivoluzione industriale, l&#8217;automazione &egrave; stata definita come la tecnologia necessaria per realizzare macchine in grado di sostituire uno o pi&ugrave; attributi dell&#8217;uomo nell&#8217;effettuare un lavoro.<br \/>Uno dei casi attualmente pi&ugrave; avanzati e particolari di automazione, &egrave; quello delle <strong>macchine utensili<\/strong> che consentono la realizzazione di manufatti sostituendosi all&#8217;uomo nel fornire energia, destrezza, diligenza, giudizio e valutazione<br \/>Gli obiettivi principali dell&#8217;<strong>ingegneria dell&#8217;automazione <\/strong>sono: far si che le macchine automatiche possano svolgere in autonomia lavori ripetitivi, costruire macchine che possano compiere operazioni che un operatore umano non potrebbe compiere perch&eacute; richiedono <strong>troppa precisione o velocit&agrave;<\/strong> e sviluppare macchinari automatici che possano lavorare in ambienti che sono ostili o pericolosi per l&#8217;uomo.<br \/>Le macchine per la <strong>torneria automatica<\/strong> rappresentano l&rsquo;evoluzione del tornio meccanico e sono <strong>comandate da computer<\/strong>.<br \/>Le macchine<strong> per la <em>torneria automatica<\/em><\/strong> sono<strong> <\/strong>in grado di eseguire movimenti precisi una volta impostata la tipologia di lavorazione. La disponibilit&agrave; di queste apparecchiature garantisce prestazioni di alto livello.<br \/>La differenza tra le macchine per la torneria tradizionali e quelle di <em>torneria automatica<\/em> sta nel fatto che l&rsquo;intera sequenza di operazioni pu&ograve; essere programmata e poi rieseguita un infinito numero di volte ottenendo sempre lo stesso precisissimo risultato e producendo quindi un gran numero di pezzi in serie.<br \/>La <em>torneria automatica<\/em> quindi realizza interamente cicli di lavorazione, programmi e quant&#8217;altro richieda l&#8217;esecuzione di particolari a disegno e o a campione fornitoci dal cliente.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Se parliamo di tornitura dei metalli per la produzione di elementi per la meccanica di precisione, senza dubbio la torneria automatica rappresenta il luogo lavorativo ideale per la produzione in serie di componenti.<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"","footnotes":""},"categories":[190],"tags":[4767],"class_list":["post-35721","post","type-post","status-publish","format-standard","hentry","category-comunicati-stampa","tag-torneria-automatica"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La torneria automatica per la tornitura dei metalli - Article Marketing<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/la-torneria-automatica-per-la-tornitura-dei-metalli\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La torneria automatica per la tornitura dei metalli - Article Marketing\" \/>\n<meta property=\"og:description\" content=\"Se parliamo di tornitura dei metalli per la produzione di elementi per la meccanica di precisione, senza dubbio la torneria automatica rappresenta il luogo lavorativo ideale per la produzione in serie di componenti.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/la-torneria-automatica-per-la-tornitura-dei-metalli\/\" \/>\n<meta property=\"og:site_name\" content=\"Article Marketing\" \/>\n<meta property=\"article:published_time\" content=\"2013-07-11T10:57:52+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-10-25T20:11:09+00:00\" \/>\n<meta name=\"author\" content=\"Redazione Comunicati Stampa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione Comunicati Stampa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/la-torneria-automatica-per-la-tornitura-dei-metalli\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/la-torneria-automatica-per-la-tornitura-dei-metalli\\\/\"},\"author\":{\"name\":\"Redazione Comunicati Stampa\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"headline\":\"La torneria automatica per la tornitura dei metalli\",\"datePublished\":\"2013-07-11T10:57:52+00:00\",\"dateModified\":\"2018-10-25T20:11:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/la-torneria-automatica-per-la-tornitura-dei-metalli\\\/\"},\"wordCount\":535,\"commentCount\":0,\"keywords\":[\"torneria automatica\"],\"articleSection\":[\"Comunicati stampa\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/la-torneria-automatica-per-la-tornitura-dei-metalli\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/la-torneria-automatica-per-la-tornitura-dei-metalli\\\/\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/la-torneria-automatica-per-la-tornitura-dei-metalli\\\/\",\"name\":\"La torneria automatica per la tornitura dei metalli - Article Marketing\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\"},\"datePublished\":\"2013-07-11T10:57:52+00:00\",\"dateModified\":\"2018-10-25T20:11:09+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/la-torneria-automatica-per-la-tornitura-dei-metalli\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/la-torneria-automatica-per-la-tornitura-dei-metalli\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/la-torneria-automatica-per-la-tornitura-dei-metalli\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La torneria automatica per la tornitura dei metalli\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\",\"name\":\"Article Marketing\",\"description\":\"article marketing &amp; press release\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\",\"name\":\"Redazione Comunicati Stampa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"caption\":\"Redazione Comunicati Stampa\"},\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/author\\\/redazione-comunicati-stampa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La torneria automatica per la tornitura dei metalli - Article Marketing","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/la-torneria-automatica-per-la-tornitura-dei-metalli\/","og_locale":"it_IT","og_type":"article","og_title":"La torneria automatica per la tornitura dei metalli - Article Marketing","og_description":"Se parliamo di tornitura dei metalli per la produzione di elementi per la meccanica di precisione, senza dubbio la torneria automatica rappresenta il luogo lavorativo ideale per la produzione in serie di componenti.","og_url":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/la-torneria-automatica-per-la-tornitura-dei-metalli\/","og_site_name":"Article Marketing","article_published_time":"2013-07-11T10:57:52+00:00","article_modified_time":"2018-10-25T20:11:09+00:00","author":"Redazione Comunicati Stampa","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione Comunicati Stampa","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/la-torneria-automatica-per-la-tornitura-dei-metalli\/#article","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/la-torneria-automatica-per-la-tornitura-dei-metalli\/"},"author":{"name":"Redazione Comunicati Stampa","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"headline":"La torneria automatica per la tornitura dei metalli","datePublished":"2013-07-11T10:57:52+00:00","dateModified":"2018-10-25T20:11:09+00:00","mainEntityOfPage":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/la-torneria-automatica-per-la-tornitura-dei-metalli\/"},"wordCount":535,"commentCount":0,"keywords":["torneria automatica"],"articleSection":["Comunicati stampa"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/la-torneria-automatica-per-la-tornitura-dei-metalli\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/la-torneria-automatica-per-la-tornitura-dei-metalli\/","url":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/la-torneria-automatica-per-la-tornitura-dei-metalli\/","name":"La torneria automatica per la tornitura dei metalli - Article Marketing","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website"},"datePublished":"2013-07-11T10:57:52+00:00","dateModified":"2018-10-25T20:11:09+00:00","author":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"breadcrumb":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/la-torneria-automatica-per-la-tornitura-dei-metalli\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/la-torneria-automatica-per-la-tornitura-dei-metalli\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/la-torneria-automatica-per-la-tornitura-dei-metalli\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.article-marketing.eu\/comunicati\/"},{"@type":"ListItem","position":2,"name":"La torneria automatica per la tornitura dei metalli"}]},{"@type":"WebSite","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website","url":"https:\/\/www.article-marketing.eu\/comunicati\/","name":"Article Marketing","description":"article marketing &amp; press release","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.article-marketing.eu\/comunicati\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017","name":"Redazione Comunicati Stampa","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","caption":"Redazione Comunicati Stampa"},"url":"https:\/\/www.article-marketing.eu\/comunicati\/author\/redazione-comunicati-stampa\/"}]}},"_links":{"self":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/35721","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/comments?post=35721"}],"version-history":[{"count":2,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/35721\/revisions"}],"predecessor-version":[{"id":63362,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/35721\/revisions\/63362"}],"wp:attachment":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/media?parent=35721"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/categories?post=35721"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/tags?post=35721"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}