{"id":36005,"date":"2013-07-28T11:08:44","date_gmt":"2013-07-28T09:08:44","guid":{"rendered":"http:\/\/www.article-marketing.eu\/comunicati\/senza-categoria\/indocina-in-viaggio-tra-splendidi-paesi-ricchi-di-storia-tradizioni-cultura-e-natura\/"},"modified":"2013-07-28T11:08:44","modified_gmt":"2013-07-28T09:08:44","slug":"indocina-in-viaggio-tra-splendidi-paesi-ricchi-di-storia-tradizioni-cultura-e-natura","status":"publish","type":"post","link":"https:\/\/www.article-marketing.eu\/comunicati\/viaggi-e-vacanze\/destinazioni\/indocina-in-viaggio-tra-splendidi-paesi-ricchi-di-storia-tradizioni-cultura-e-natura\/","title":{"rendered":"Indocina: in viaggio tra splendidi paesi ricchi di storia, tradizioni, cultura e natura!"},"content":{"rendered":"<p>la <strong>Thailandia<\/strong> e la <strong>Malesia peninsulare<\/strong>. Nel corso della sua storia sono nati grandi regni, senza che nessuno li abbia mai potuti unire, in contrapposizione al grande impero cinese che varie volte sottomise le popolazioni locali spingendole sempre pi&ugrave; a sud nell&rsquo;esigenza di controllare le vie commerciali fra l&rsquo;India e l&rsquo;Occidente.<br \/>\nA cura dei <strong>Consulenti di viaggio online Evolution Travel Bruno Bottaro e Nicola Paci<\/strong> con la <strong>collaborazione di Federica Biondi e Luca Girardi<\/strong> il <strong>nuovo portale Indocina<\/strong> nasce da una grande passione per quest&rsquo;area del mondo e dal desiderio di poter mettere a disposizione della nostra clientela il sapere e l&rsquo;esperienza di chi ne cura il progetto.<br \/>\nEcco le risposte alle nostre domande di Federica Biondi e Luca Girardi:<br \/>\n<strong>1. Quali sono le caratteristiche principali di questo nuovo portale Evolution Travel dedicato all&rsquo; Indocina?<\/strong><br \/>\n<em>Federica Biondi, Consulente di viaggi online Evolution Travel: <\/em>Questo portale contiene tantissimi viaggi che vogliono far scoprire ai viaggiatori dei paesi bellissimi ricchi di storia, tradizioni, cultura e soprattutto di gente. Tutti i viaggi del portale Indocina sono completamente personalizzabili per consentire al cliente di viaggiare secondo le sue esigenze, e consigliandolo sul miglior itinerario a seconda del tempo a disposizione, del periodo e del tipo di viaggio che vuole fare. Amo dire che &ldquo;cucio i viaggi&rdquo; addosso alle persone perch&egrave; &egrave; fondamentale capire le esigenze del cliente per confezionare il suo viaggio su misura. Che sia Vietnam, Birmania, Thailandia, Cambogia, Laos potremo sempre distinguerci dalla concorrenza per la qualit&agrave; dei nostri servizi e soprattutto per la nostra conoscenza dei luoghi che mettiamo al servizio del cliente.<br \/>\n<em>Luca Girardi, Consulente di viaggi online Evolution Travel: <\/em>Abbiamo voluto aprire questo portale, per completare la gi&agrave; ampia offerta della nostra agenzia sull&rsquo;Oriente.<br \/>\n<strong>2. Prima di partire: cosa &egrave; importante sapere?<\/strong><br \/>\n<em>Federica Biondi, Consulente di viaggi online Evolution Travel: <\/em>Prima di partire &egrave; importante conoscere il paese che si vuole visitare. Sia dal punto di vista geografico, che storico, che climatico. Spesso i clienti sono indecisi tra varie destinazioni; spesso non conoscono il clima o la conformazione geografica e quindi lo chiedono. E&rsquo; importante sempre informare il cliente sulle usanze del luogo ed anche sul tempo meteorologico che pu&ograve; trovare. Il clima &egrave; molto vario negli stati dell&rsquo;estremo oriente ed anche all&rsquo;interno di uno stesso stato. E&rsquo; quindi necessario consigliare bene il cliente sul periodo di viaggio e sulle localit&agrave; da visitare in un dato periodo.<br \/>\n<em>Luca Girardi, Consulente di viaggi online Evolution Travel: <\/em>La cosa sicuramente importante &egrave; conoscere la situazione climatica del periodo in cui si vuole partire, facendo in modo di visitare i paesi nel loro periodo migliore.<br \/>\n<strong><br \/> 3. Vietnam, Cambogia, Laos, Birmania, Thailandia, Malesia: che tipologie di vacanza si possono fare in questi paesi?<\/strong><br \/>\n<em>Federica Biondi, Consulente di viaggi online Evolution Travel: <\/em>In queste destinazioni si fanno vari tipi di viaggio. Il <strong>Vietnam<\/strong> &egrave; un paese che permette di scoprire paesaggi unici come la<strong> Baia di Halong<\/strong>, indescrivibile se non la si vede, di conoscere la storia vietnamita anche la pi&ugrave; cruda e recente legata al nostro secolo e soprattutto di venire a contatto con una popolazione multietnica soprattutto arrivando fino a Sapa. La <strong>Cambogia<\/strong> colpisce innanzitutto per il <strong>sito archeologico di Angkor<\/strong>: un valore inestimabile nel quale &egrave; necessario stare almeno due giorni per vederne una minima parte! Il <strong>Laos<\/strong> &egrave; gente, paesaggi e natura. La <strong>Thailandia<\/strong> &egrave; storia e mare: non si pu&ograve; andare in Thailandia senza arrivare al <strong>Triangolo d&rsquo; Oro<\/strong> e non si pu&ograve; non andare al mare: <strong>Phuket, Krabi, Kho Samui<\/strong> e tanto tanto altro. La <strong>Birmania<\/strong> &egrave; storia e spiritualit&agrave;: un viaggio in mezzo alla religione, ai<strong> monaci di Mandalay<\/strong>, ai <strong>Bhudda<\/strong> che si trovano ovunque; &egrave; gente, contatto con il popolo; &egrave; paesaggi: <strong>Bagan<\/strong> con le sue pagode sterminate; &egrave; mare! Un pease assolutamente affascinante e, direi, unico al mondo. La <strong>Malesia<\/strong> &egrave; natura e modernit&agrave;. E&rsquo; il paese pi&ugrave; &ldquo;occidentale&rdquo; dell&rsquo;Oriente. <strong>Kuala Lumpur<\/strong> &egrave; una citt&agrave; moderna e cosmopolita, il <strong>Borneo<\/strong> &egrave; la parte della natura e del mare. Insomma che viaggi si possono fare? Di tutto! Dalle mia poche parole su ogni paese si evince che si pu&ograve; trovare di tutto. Bisogna essere viaggiatori; non si pu&ograve; pensare di andare in questi luoghi per fare una vacanza sedentaria. Sono tutti paesi nei quali &egrave; necessario muoversi per ammirare le bellezze che ciascun luogo offre. E tutti i nostri programmi hanno questa finalit&agrave; unendo spesso il viaggio ad un soggiorno mare per consentire al cliente di rilassarsi prima di rientrare.<br \/>\n<em>Luca Girardi, Consulente di viaggi online Evolution Travel:<\/em> Un viaggio in questa zona del mondo offre veramente tutto, cultura, natura, uno dei mari pi&ugrave; belli del mondo, e tanta spiritualit&agrave;.<br \/>\n<strong>4. Quali sono di solito le impressioni di chi torna da un viaggio in queste destinazioni?<\/strong><br \/> <em>Federica Biondi, Consulente di viaggi online Evolution Travel: <\/em>Le impressioni? L&rsquo; infinit&agrave; di emozioni e sensazioni nonch&egrave; i bellissimi ricordi che ognuno porta con s&eacute;. Non &egrave; semplice descrivere a parole tutto ci&ograve;: dico spesso che il &ldquo;mal d&rsquo; Oriente&rdquo; &egrave; un po&rsquo; come il &ldquo;mal d&rsquo; Africa&rdquo;. A me &egrave; successo cos&igrave;. Per tanti anni ho rimandato il mio primo viaggio in Oriente, ma quando sono andata in Birmania sono rimasta talmente colpita dai paesaggi, dalla natura, dal calore delle persone che in due anni ho visitato Vietnam, Laos, Cambogia, Malesia e Thailandia. L&rsquo;odore delle strade, i rumori, i sorrisi delle persone e gli scorci dei paesaggi sono impressi nella mia memoria.<br \/>\n<em>Luca Girardi, Consulente di viaggi online Evolution Travel: <\/em>Solitamente chi viaggia in queste destinazioni torna felice ed appagato, sicuramente con la mente pi&ugrave; aperta, la sensazione di essere stato veramente lontano da casa e, soprattutto, con la voglia di visitare un altro paese della zona.<br \/>\n<strong>5. Quali sono i punti di forza delle offerte del portale Evolution Travel &ldquo;Indocina&rdquo;?<\/strong><br \/>\n<em>Federica Biondi, Consulente di viaggi online Evolution Travel: <\/em>I punti di forza del portale Indocina sono il fatto di contenere viaggi per tutti i target di clienti, per tutte le esigenze e anche per tutte le &ldquo;tasche&rdquo;. E poi, fondamentale, la consulenza di persone (noi) che conosciamo quelle destinazioni e quindi possiamo (e dobbiamo) guidare il cliente nelle sue scelte.<br \/> <em>Luca Girardi, Consulente di viaggi online Evolution Travel:<\/em> I punti di forza dell&rsquo;offerta Evolution Travel sono personalizzazione e qualit&agrave;. Viaggiando continuamente in questi paesi (ne ho visitati 4 negli ultimi 2 anni), so consigliare quello che ritengo essere il meglio al cliente, personalizzandolo al massimo e cercando di esaudire tutti i desideri del viaggiatore.<br \/>\n<strong>6. Foreste pluviali, scintillanti metropoli e paradisi tropicali&hellip; come Consulenti di viaggi Evolution Travel, in che modo costruite il viaggio di chi per la prima volta sceglie queste destinazioni?<br \/> <\/strong><em>Federica Biondi, Consulente di viaggi online Evolution Travel: <\/em>Un viaggio in uno di questi paesi <strong>&egrave; un viaggio e non &egrave; una vacanza<\/strong>. Bisogna capire cosa cerca il cliente: non si pu&ograve; &ldquo;consigliare&rdquo; un viaggio standard. Se il cliente &egrave; appassionato di natura vanno bene tutte le destinazioni; se vuole vedere delle metropoli non possiamo consigliare il Laos o la Cambogia, se vuole la storia suggerisco Cambogia, Laos e Birmania. Insomma non &egrave; facile consigliare senza avere una base. Sicuramente la destinazione pi&ugrave; &ldquo;semplice&rdquo; per un primo avvicinamento all&rsquo;Oriente &egrave; la Thailandia; da l&igrave; si pu&ograve; passare al Vietnam e poi scoprire qualche paese meno conosciuto come la Birmania o il Laos. Direi che &egrave; un modo da scoprire e sicuramente se ne rimane affascinati ed indubbiamente pronti per ripartire e tornarci!<br \/>\n<em>Luca Girardi, Consulente di viaggi online Evolution Travel: <\/em>Un lungo colloquio con il cliente &egrave; essenziale per capire le sue esigenze ed aspettative, dopo di che, come dicevo, forte della mia conoscenza e passione per questi paesi, costruisco l&rsquo;itinerario il pi&ugrave; possibile su misura.<\/p>\n<p><a href=\"http:\/\/blog.evolutiontravel.net\/2013\/05\/28\/indocina-in-viaggio-tra-splendidi-paesi-ricchi-di-storia-tradizioni-cultura-e-natura\/\">http:\/\/blog.evolutiontravel.net\/2013\/05\/28\/indocina-in-viaggio-tra-splendidi-paesi-ricchi-di-storia-tradizioni-cultura-e-natura\/<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ricca di cultura e tradizione l\u2019Indocina comprende il Laos, la Cambogia, il Vietnam, la Birmania, la Thailandia e la Malesia peninsulare.<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"","footnotes":""},"categories":[143],"tags":[20562,31229,44032,44036,44035,44033,44034],"class_list":["post-36005","post","type-post","status-publish","format-standard","hentry","category-destinazioni","tag-cambogia","tag-evolution-travel","tag-indocina","tag-malesia","tag-portale-indocina","tag-viaggi-birmania","tag-viaggi-vietnam"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Indocina: in viaggio tra splendidi paesi ricchi di storia, tradizioni, cultura e natura! - Article Marketing<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.article-marketing.eu\/comunicati\/viaggi-e-vacanze\/destinazioni\/indocina-in-viaggio-tra-splendidi-paesi-ricchi-di-storia-tradizioni-cultura-e-natura\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Indocina: in viaggio tra splendidi paesi ricchi di storia, tradizioni, cultura e natura! - Article Marketing\" \/>\n<meta property=\"og:description\" content=\"Ricca di cultura e tradizione l\u2019Indocina comprende il Laos, la Cambogia, il Vietnam, la Birmania, la Thailandia e la Malesia peninsulare.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.article-marketing.eu\/comunicati\/viaggi-e-vacanze\/destinazioni\/indocina-in-viaggio-tra-splendidi-paesi-ricchi-di-storia-tradizioni-cultura-e-natura\/\" \/>\n<meta property=\"og:site_name\" content=\"Article Marketing\" \/>\n<meta property=\"article:published_time\" content=\"2013-07-28T09:08:44+00:00\" \/>\n<meta name=\"author\" content=\"Redazione Comunicati Stampa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione Comunicati Stampa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/viaggi-e-vacanze\\\/destinazioni\\\/indocina-in-viaggio-tra-splendidi-paesi-ricchi-di-storia-tradizioni-cultura-e-natura\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/viaggi-e-vacanze\\\/destinazioni\\\/indocina-in-viaggio-tra-splendidi-paesi-ricchi-di-storia-tradizioni-cultura-e-natura\\\/\"},\"author\":{\"name\":\"Redazione Comunicati Stampa\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"headline\":\"Indocina: in viaggio tra splendidi paesi ricchi di storia, tradizioni, cultura e natura!\",\"datePublished\":\"2013-07-28T09:08:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/viaggi-e-vacanze\\\/destinazioni\\\/indocina-in-viaggio-tra-splendidi-paesi-ricchi-di-storia-tradizioni-cultura-e-natura\\\/\"},\"wordCount\":1373,\"commentCount\":0,\"keywords\":[\"cambogia\",\"evolution travel\",\"Indocina\",\"Malesia\",\"Portale Indocina\",\"Viaggi Birmania\",\"Viaggi Vietnam\"],\"articleSection\":[\"Destinazioni\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/viaggi-e-vacanze\\\/destinazioni\\\/indocina-in-viaggio-tra-splendidi-paesi-ricchi-di-storia-tradizioni-cultura-e-natura\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/viaggi-e-vacanze\\\/destinazioni\\\/indocina-in-viaggio-tra-splendidi-paesi-ricchi-di-storia-tradizioni-cultura-e-natura\\\/\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/viaggi-e-vacanze\\\/destinazioni\\\/indocina-in-viaggio-tra-splendidi-paesi-ricchi-di-storia-tradizioni-cultura-e-natura\\\/\",\"name\":\"Indocina: in viaggio tra splendidi paesi ricchi di storia, tradizioni, cultura e natura! - Article Marketing\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\"},\"datePublished\":\"2013-07-28T09:08:44+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/viaggi-e-vacanze\\\/destinazioni\\\/indocina-in-viaggio-tra-splendidi-paesi-ricchi-di-storia-tradizioni-cultura-e-natura\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/viaggi-e-vacanze\\\/destinazioni\\\/indocina-in-viaggio-tra-splendidi-paesi-ricchi-di-storia-tradizioni-cultura-e-natura\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/viaggi-e-vacanze\\\/destinazioni\\\/indocina-in-viaggio-tra-splendidi-paesi-ricchi-di-storia-tradizioni-cultura-e-natura\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Indocina: in viaggio tra splendidi paesi ricchi di storia, tradizioni, cultura e natura!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\",\"name\":\"Article Marketing\",\"description\":\"article marketing &amp; press release\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\",\"name\":\"Redazione Comunicati Stampa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"caption\":\"Redazione Comunicati Stampa\"},\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/author\\\/redazione-comunicati-stampa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Indocina: in viaggio tra splendidi paesi ricchi di storia, tradizioni, cultura e natura! - Article Marketing","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.article-marketing.eu\/comunicati\/viaggi-e-vacanze\/destinazioni\/indocina-in-viaggio-tra-splendidi-paesi-ricchi-di-storia-tradizioni-cultura-e-natura\/","og_locale":"it_IT","og_type":"article","og_title":"Indocina: in viaggio tra splendidi paesi ricchi di storia, tradizioni, cultura e natura! - Article Marketing","og_description":"Ricca di cultura e tradizione l\u2019Indocina comprende il Laos, la Cambogia, il Vietnam, la Birmania, la Thailandia e la Malesia peninsulare.","og_url":"https:\/\/www.article-marketing.eu\/comunicati\/viaggi-e-vacanze\/destinazioni\/indocina-in-viaggio-tra-splendidi-paesi-ricchi-di-storia-tradizioni-cultura-e-natura\/","og_site_name":"Article Marketing","article_published_time":"2013-07-28T09:08:44+00:00","author":"Redazione Comunicati Stampa","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione Comunicati Stampa","Tempo di lettura stimato":"7 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.article-marketing.eu\/comunicati\/viaggi-e-vacanze\/destinazioni\/indocina-in-viaggio-tra-splendidi-paesi-ricchi-di-storia-tradizioni-cultura-e-natura\/#article","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/viaggi-e-vacanze\/destinazioni\/indocina-in-viaggio-tra-splendidi-paesi-ricchi-di-storia-tradizioni-cultura-e-natura\/"},"author":{"name":"Redazione Comunicati Stampa","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"headline":"Indocina: in viaggio tra splendidi paesi ricchi di storia, tradizioni, cultura e natura!","datePublished":"2013-07-28T09:08:44+00:00","mainEntityOfPage":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/viaggi-e-vacanze\/destinazioni\/indocina-in-viaggio-tra-splendidi-paesi-ricchi-di-storia-tradizioni-cultura-e-natura\/"},"wordCount":1373,"commentCount":0,"keywords":["cambogia","evolution travel","Indocina","Malesia","Portale Indocina","Viaggi Birmania","Viaggi Vietnam"],"articleSection":["Destinazioni"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.article-marketing.eu\/comunicati\/viaggi-e-vacanze\/destinazioni\/indocina-in-viaggio-tra-splendidi-paesi-ricchi-di-storia-tradizioni-cultura-e-natura\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.article-marketing.eu\/comunicati\/viaggi-e-vacanze\/destinazioni\/indocina-in-viaggio-tra-splendidi-paesi-ricchi-di-storia-tradizioni-cultura-e-natura\/","url":"https:\/\/www.article-marketing.eu\/comunicati\/viaggi-e-vacanze\/destinazioni\/indocina-in-viaggio-tra-splendidi-paesi-ricchi-di-storia-tradizioni-cultura-e-natura\/","name":"Indocina: in viaggio tra splendidi paesi ricchi di storia, tradizioni, cultura e natura! - Article Marketing","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website"},"datePublished":"2013-07-28T09:08:44+00:00","author":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"breadcrumb":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/viaggi-e-vacanze\/destinazioni\/indocina-in-viaggio-tra-splendidi-paesi-ricchi-di-storia-tradizioni-cultura-e-natura\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.article-marketing.eu\/comunicati\/viaggi-e-vacanze\/destinazioni\/indocina-in-viaggio-tra-splendidi-paesi-ricchi-di-storia-tradizioni-cultura-e-natura\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.article-marketing.eu\/comunicati\/viaggi-e-vacanze\/destinazioni\/indocina-in-viaggio-tra-splendidi-paesi-ricchi-di-storia-tradizioni-cultura-e-natura\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.article-marketing.eu\/comunicati\/"},{"@type":"ListItem","position":2,"name":"Indocina: in viaggio tra splendidi paesi ricchi di storia, tradizioni, cultura e natura!"}]},{"@type":"WebSite","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website","url":"https:\/\/www.article-marketing.eu\/comunicati\/","name":"Article Marketing","description":"article marketing &amp; press release","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.article-marketing.eu\/comunicati\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017","name":"Redazione Comunicati Stampa","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","caption":"Redazione Comunicati Stampa"},"url":"https:\/\/www.article-marketing.eu\/comunicati\/author\/redazione-comunicati-stampa\/"}]}},"_links":{"self":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/36005","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/comments?post=36005"}],"version-history":[{"count":0,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/36005\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/media?parent=36005"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/categories?post=36005"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/tags?post=36005"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}