{"id":36036,"date":"2013-07-30T17:04:56","date_gmt":"2013-07-30T15:04:56","guid":{"rendered":"http:\/\/www.article-marketing.eu\/comunicati\/senza-categoria\/4words-innovazione-digitale-a-supporto-del-business\/"},"modified":"2018-10-25T22:13:19","modified_gmt":"2018-10-25T20:13:19","slug":"4words-innovazione-digitale-a-supporto-del-business","status":"publish","type":"post","link":"https:\/\/www.article-marketing.eu\/comunicati\/computer\/software\/4words-innovazione-digitale-a-supporto-del-business\/","title":{"rendered":"II l ristorante diventa social mobile grazie all\u2019app iRestaurant di 4words"},"content":{"rendered":"<p>Il ristorante diventa social mobile grazie all&rsquo;app <strong>iRestaurant <\/strong>di 4words by San Marco Informatica Spa<br \/><br style=\"font-family: Verdana, Geneva, sans-serif; font-size: 14px; line-height: 19px;\" \/>Basta men&ugrave;, o peggio ancora basta elenco dei piatti a voce, da oggi al ristorante potrete vedervi allungare dal cameriere un iPad men&ugrave; con installato l&rsquo;iRestaurant, una soluzione software mobile a 360&deg; che rende la presentazione delle pietanze e delle bevande una esperienza interattiva nuova ed emozionante per il cliente. <br style=\"font-family: Verdana, Geneva, sans-serif; font-size: 14px; line-height: 19px;\" \/>Un viaggio tra immagini, colori e descrizioni che permetteranno di conoscere al meglio la filosofia dello chef e la natura dei suoi piatti.<br style=\"font-family: Verdana, Geneva, sans-serif; font-size: 14px; line-height: 19px;\" \/>L&rsquo;iRestaurant si rivela molto riuscito anche all&rsquo;entrata del locale, per dare il benvenuto ai clienti e per presentarne le delizie anche nella fase di attesa prima dell&rsquo;assegnazione del tavolo.<br style=\"font-family: Verdana, Geneva, sans-serif; font-size: 14px; line-height: 19px;\" \/>E&rsquo; possibile rendere l&rsquo;applicazione pubblica, cio&egrave; il cliente la pu&ograve; installare sul proprio iPad o iPhone ed essere costantemente aggiornato sulle novit&agrave; e proposte di cambi men&ugrave; del ristorante, sugli eventi, sulle promozioni e sulle serate speciali.<br style=\"font-family: Verdana, Geneva, sans-serif; font-size: 14px; line-height: 19px;\" \/>Con iRestaurant &egrave; inoltre possibile gestire la carta dei vini, con la possibilit&agrave; di consultarli singolarmente oppure di vederne l&rsquo;abbinamento con i piatti proposti dal men&ugrave;.<br style=\"font-family: Verdana, Geneva, sans-serif; font-size: 14px; line-height: 19px;\" \/>Inoltre iRestaurant contribuisce a rendere &ldquo;social&rdquo; il ristorante, permettendo la condivisione delle ricette, dei piatti pi&ugrave; richiesti, nonch&eacute; dei video sulla loro preparazione.<br style=\"font-family: Verdana, Geneva, sans-serif; font-size: 14px; line-height: 19px;\" \/>Visto da vicino, l&rsquo;applicazione risulta facile e gradevole da usare, la navigazione per l&rsquo;utente immediata ed intuitiva, una griglia scorrevole mostra le voci del men&ugrave; raggruppate per categoria, ogni voce nella fase di ricerca &egrave; affiancata da una immagine fotografica ingrandibile utile a descrivere anche visivamente il piatto in consultazione, dalla consultazione &egrave; quindi possibile richiamare la ricetta in dettaglio e visionare il video sulla preparazione del piatto, l&rsquo;abbinamento consigliato dei vini ed in fine il prezzo.<br style=\"font-family: Verdana, Geneva, sans-serif; font-size: 14px; line-height: 19px;\" \/>L&rsquo;applicazione dispone inoltre di funzioni avanzate che permettono off-line di assegnare le pietanze presenti nel men&ugrave; ed ordinate dal cliente su prenotazione direttamente ad un tavolo virtuale, ordinazione inviabile anche via email alla cucina del ristorante, permettendo di effettuare una prenotazione ed ordinazione da parte del cliente anche in camera ( o dalla stessa camera) nel caso di un ristorante relativo ad un hotel.<br style=\"font-family: Verdana, Geneva, sans-serif; font-size: 14px; line-height: 19px;\" \/>Non solo, iRestaurant consente quindi di generare una ordinazione che pu&ograve; essere inviata da parte del cliente direttamente da casa, creando una interazione fra cliente e ristorante anche fuori dai locali dello stesso, facilitando quindi un rapporto di fidelizzazione della clientela. Link : http:\/\/www.4words.it\/it\/prodotti\/apps-cataloghi\/icm-ristorazione<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Basta men\u00f9, o peggio ancora basta elenco dei piatti a voce, da oggi al ristorante potrete vedervi allungare dal cameriere un iPad men\u00f9 con installato l\u2019iRestaurant, una soluzione software mobile a 360\u00b0 che rende la presentazione delle pietanze e delle bevande una esperienza interattiva nuova ed emozionante per il cliente. <br \/>Un viaggio tra immagini, colori e descrizioni che permetteranno di conoscere al meglio la filosofia dello chef e la natura dei suoi piatti.<br \/>L\u2019iRestaurant si rivela molto riuscito anche all\u2019entrata del locale, per dare il benvenuto ai clienti e per presentarne le delizie anche nella fase di attesa prima dell\u2019assegnazione del tavolo.<br \/>E\u2019 possibile rendere l\u2019applicazione pubblica, cio\u00e8 il cliente la pu\u00f2 installare sul proprio iPad o iPhone ed essere costantemente aggiornato sulle novit\u00e0 e proposte di cambi men\u00f9 del ristorante, sugli eventi, sulle promozioni e sulle serate speciali.<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"","footnotes":""},"categories":[123],"tags":[44091,44090,44092,44093,44089],"class_list":["post-36036","post","type-post","status-publish","format-standard","hentry","category-software","tag-applicazioni-mobile-per-hotel","tag-applicazioni-mobile-per-ristoranti","tag-apps-mobile-hotel","tag-apps-mobile-ristoranti","tag-iresturant"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>II l ristorante diventa social mobile grazie all\u2019app iRestaurant di 4words - Article Marketing<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.article-marketing.eu\/comunicati\/computer\/software\/4words-innovazione-digitale-a-supporto-del-business\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"II l ristorante diventa social mobile grazie all\u2019app iRestaurant di 4words - Article Marketing\" \/>\n<meta property=\"og:description\" content=\"Basta men\u00f9, o peggio ancora basta elenco dei piatti a voce, da oggi al ristorante potrete vedervi allungare dal cameriere un iPad men\u00f9 con installato l\u2019iRestaurant, una soluzione software mobile a 360\u00b0 che rende la presentazione delle pietanze e delle bevande una esperienza interattiva nuova ed emozionante per il cliente. Un viaggio tra immagini, colori e descrizioni che permetteranno di conoscere al meglio la filosofia dello chef e la natura dei suoi piatti.L\u2019iRestaurant si rivela molto riuscito anche all\u2019entrata del locale, per dare il benvenuto ai clienti e per presentarne le delizie anche nella fase di attesa prima dell\u2019assegnazione del tavolo.E\u2019 possibile rendere l\u2019applicazione pubblica, cio\u00e8 il cliente la pu\u00f2 installare sul proprio iPad o iPhone ed essere costantemente aggiornato sulle novit\u00e0 e proposte di cambi men\u00f9 del ristorante, sugli eventi, sulle promozioni e sulle serate speciali.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.article-marketing.eu\/comunicati\/computer\/software\/4words-innovazione-digitale-a-supporto-del-business\/\" \/>\n<meta property=\"og:site_name\" content=\"Article Marketing\" \/>\n<meta property=\"article:published_time\" content=\"2013-07-30T15:04:56+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-10-25T20:13:19+00:00\" \/>\n<meta name=\"author\" content=\"Redazione Comunicati Stampa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione Comunicati Stampa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/computer\\\/software\\\/4words-innovazione-digitale-a-supporto-del-business\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/computer\\\/software\\\/4words-innovazione-digitale-a-supporto-del-business\\\/\"},\"author\":{\"name\":\"Redazione Comunicati Stampa\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"headline\":\"II l ristorante diventa social mobile grazie all\u2019app iRestaurant di 4words\",\"datePublished\":\"2013-07-30T15:04:56+00:00\",\"dateModified\":\"2018-10-25T20:13:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/computer\\\/software\\\/4words-innovazione-digitale-a-supporto-del-business\\\/\"},\"wordCount\":443,\"commentCount\":0,\"keywords\":[\"applicazioni mobile per hotel\",\"applicazioni mobile per ristoranti\",\"apps mobile hotel\",\"apps mobile ristoranti\",\"iresturant\"],\"articleSection\":[\"Software\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/computer\\\/software\\\/4words-innovazione-digitale-a-supporto-del-business\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/computer\\\/software\\\/4words-innovazione-digitale-a-supporto-del-business\\\/\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/computer\\\/software\\\/4words-innovazione-digitale-a-supporto-del-business\\\/\",\"name\":\"II l ristorante diventa social mobile grazie all\u2019app iRestaurant di 4words - Article Marketing\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\"},\"datePublished\":\"2013-07-30T15:04:56+00:00\",\"dateModified\":\"2018-10-25T20:13:19+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/computer\\\/software\\\/4words-innovazione-digitale-a-supporto-del-business\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/computer\\\/software\\\/4words-innovazione-digitale-a-supporto-del-business\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/computer\\\/software\\\/4words-innovazione-digitale-a-supporto-del-business\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"II l ristorante diventa social mobile grazie all\u2019app iRestaurant di 4words\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\",\"name\":\"Article Marketing\",\"description\":\"article marketing &amp; press release\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\",\"name\":\"Redazione Comunicati Stampa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"caption\":\"Redazione Comunicati Stampa\"},\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/author\\\/redazione-comunicati-stampa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"II l ristorante diventa social mobile grazie all\u2019app iRestaurant di 4words - Article Marketing","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.article-marketing.eu\/comunicati\/computer\/software\/4words-innovazione-digitale-a-supporto-del-business\/","og_locale":"it_IT","og_type":"article","og_title":"II l ristorante diventa social mobile grazie all\u2019app iRestaurant di 4words - Article Marketing","og_description":"Basta men\u00f9, o peggio ancora basta elenco dei piatti a voce, da oggi al ristorante potrete vedervi allungare dal cameriere un iPad men\u00f9 con installato l\u2019iRestaurant, una soluzione software mobile a 360\u00b0 che rende la presentazione delle pietanze e delle bevande una esperienza interattiva nuova ed emozionante per il cliente. Un viaggio tra immagini, colori e descrizioni che permetteranno di conoscere al meglio la filosofia dello chef e la natura dei suoi piatti.L\u2019iRestaurant si rivela molto riuscito anche all\u2019entrata del locale, per dare il benvenuto ai clienti e per presentarne le delizie anche nella fase di attesa prima dell\u2019assegnazione del tavolo.E\u2019 possibile rendere l\u2019applicazione pubblica, cio\u00e8 il cliente la pu\u00f2 installare sul proprio iPad o iPhone ed essere costantemente aggiornato sulle novit\u00e0 e proposte di cambi men\u00f9 del ristorante, sugli eventi, sulle promozioni e sulle serate speciali.","og_url":"https:\/\/www.article-marketing.eu\/comunicati\/computer\/software\/4words-innovazione-digitale-a-supporto-del-business\/","og_site_name":"Article Marketing","article_published_time":"2013-07-30T15:04:56+00:00","article_modified_time":"2018-10-25T20:13:19+00:00","author":"Redazione Comunicati Stampa","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione Comunicati Stampa","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.article-marketing.eu\/comunicati\/computer\/software\/4words-innovazione-digitale-a-supporto-del-business\/#article","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/computer\/software\/4words-innovazione-digitale-a-supporto-del-business\/"},"author":{"name":"Redazione Comunicati Stampa","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"headline":"II l ristorante diventa social mobile grazie all\u2019app iRestaurant di 4words","datePublished":"2013-07-30T15:04:56+00:00","dateModified":"2018-10-25T20:13:19+00:00","mainEntityOfPage":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/computer\/software\/4words-innovazione-digitale-a-supporto-del-business\/"},"wordCount":443,"commentCount":0,"keywords":["applicazioni mobile per hotel","applicazioni mobile per ristoranti","apps mobile hotel","apps mobile ristoranti","iresturant"],"articleSection":["Software"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.article-marketing.eu\/comunicati\/computer\/software\/4words-innovazione-digitale-a-supporto-del-business\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.article-marketing.eu\/comunicati\/computer\/software\/4words-innovazione-digitale-a-supporto-del-business\/","url":"https:\/\/www.article-marketing.eu\/comunicati\/computer\/software\/4words-innovazione-digitale-a-supporto-del-business\/","name":"II l ristorante diventa social mobile grazie all\u2019app iRestaurant di 4words - Article Marketing","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website"},"datePublished":"2013-07-30T15:04:56+00:00","dateModified":"2018-10-25T20:13:19+00:00","author":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"breadcrumb":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/computer\/software\/4words-innovazione-digitale-a-supporto-del-business\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.article-marketing.eu\/comunicati\/computer\/software\/4words-innovazione-digitale-a-supporto-del-business\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.article-marketing.eu\/comunicati\/computer\/software\/4words-innovazione-digitale-a-supporto-del-business\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.article-marketing.eu\/comunicati\/"},{"@type":"ListItem","position":2,"name":"II l ristorante diventa social mobile grazie all\u2019app iRestaurant di 4words"}]},{"@type":"WebSite","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website","url":"https:\/\/www.article-marketing.eu\/comunicati\/","name":"Article Marketing","description":"article marketing &amp; press release","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.article-marketing.eu\/comunicati\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017","name":"Redazione Comunicati Stampa","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","caption":"Redazione Comunicati Stampa"},"url":"https:\/\/www.article-marketing.eu\/comunicati\/author\/redazione-comunicati-stampa\/"}]}},"_links":{"self":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/36036","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/comments?post=36036"}],"version-history":[{"count":1,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/36036\/revisions"}],"predecessor-version":[{"id":63420,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/36036\/revisions\/63420"}],"wp:attachment":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/media?parent=36036"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/categories?post=36036"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/tags?post=36036"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}