{"id":36085,"date":"2013-08-05T15:44:14","date_gmt":"2013-08-05T13:44:14","guid":{"rendered":"http:\/\/www.article-marketing.eu\/comunicati\/senza-categoria\/lettura-dei-tarocchi\/"},"modified":"2013-08-05T15:44:14","modified_gmt":"2013-08-05T13:44:14","slug":"lettura-dei-tarocchi","status":"publish","type":"post","link":"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/scienze\/lettura-dei-tarocchi\/","title":{"rendered":"tarocchi : quali sono le origini di questo strumento divinatorio"},"content":{"rendered":"<p>i tarocchi hanno una storia molto antica ed affascinante, c&#8217;&egrave; chi pensa che siano stati creati nel medioevo, e che siano arrivati a noi senza alcun cambiamento, altri invece pensano che siano oggetti molto pi&ugrave; antichi, addirittura risalenti a diversi secoli prima la venuta di cristo. <br \/> Tra gli esperti studiosi fautori della origine antecenedte a Cristo, vi sono diverse correnti di pensiero. C&egrave; chi crede attribuisce l&#8217; origine dei tarocchi all&#8217; Egitto, chi invece &egrave; convinto dell&#8217; origine ancor pi&ugrave; vecchia in Cina, e molti sostengono che invece siano stati creati in Italia a cavallo del XV e XVI secolo. <br \/> questa sembra la tesi pi&ugrave; da avvalorare, per una quantit&agrave; di documentazione ritrovata che fa da prova alla teoria. Nelle altre teorie, invece esistono solo una serie di supposizioni nate per le grosse analogie tra i tarocchi e altri oggetti divinatori simili. <br \/> Partendo dalla teoria pi&ugrave; certa, ovvero quella che dice che siano stati inventati in Italia, pi&ugrave; precisamente nell&#8217; Italia del nord, possiamo dire quindi ( grazie alla documentazione trovata) che i tarocchi siano arrivati nelle mani dei nostri cartomanti nella versione originale. <br \/> i tarocchi vengono utilizzati dai cartomanti un po come succede per l&#8217;oroscopo, infatti si suddivide per tre grandi aree la consulenza che deriver&agrave; dalla lettura dei tarocchi.<\/p>\n<ul>\n<li>tarocchi amore<\/li>\n<li>tarocchi salute<\/li>\n<li>tarocchi denaro<\/li>\n<\/ul>\n<p>queste sono le tre grandi aree tematiche della nostra vita che pi&ugrave; ci danno ansia e pi&ugrave; cerchiamo di trovare soluzioni o conoscere in anticipo i risultati di eventi accaduti. L&#8217; uomo da sempre &egrave; curioso di sapere se una cosa che gli crea disagio si concluder&agrave;, in che tempi ed in che modo. tornando all&#8217; origine dei tarocchi guardiamo un po pi&ugrave; a fondo il tutto. Come dicevmo, si &egrave; propensi nel dir che siano stati creati in Italia, per via delle documentazioni ritrovate ma ancora non &egrave; stata data un origine ufficiale e certa per i tarocchi. le altre teorie invece furono messe a punto da un famoso massone francese antoine Court De Gebelin che sosteneva fermamente la sua teoria , ovvero quella dell&#8217; origine Egizia. la teoria invece che sostiene siano stati creati i tarocchi in Cina, deriva dall&#8217; analogia di alcuni aspetti con carte divinatorie utilizzate dagli antichi maghi Cinesi operanti alla corte degli Imperatori che si susseguirono negli anni. Il nome delle carte simili ai tarocchi &egrave; Ching. come sono composti i Tarocchi? i tarocchi che conosciamo e che sono arrivati fino ai giorni nostri, sono composti da due mazzi di carte denominati arcani maggiori ed arcani minori. gli arcani maggiori sono costituiti da 22 carte illustrate, con figure umane o animali o mitologiche corrispondenti anche al nome di trionfi. gli arcani minori invece sono costituiti da 56 carte che ( questa &egrave; un altra prova della provenienza Italiana) raffigurano i quattro semi della tradizione italiana, che sono : denari, coppe, spade e bastoni. quindi le cinquantasei carte degli arcani minori sono divise in altre quattro categorie, ognuna di esse &egrave; costituita da quattordici carte defiite carte di corte , e raffiguranti anch&#8217; esse figure umane o animali.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>l&#8217; origine dei tarocchi \u00e8 un argomento che continua a creare un alone di mistero ed alimenta ancor di pi\u00f9 il fascino di questo meraviglioso strumento divinatorio, usato dalle cartomanti di tutto il mondo per creare consulenze dopo letture di tarocchi.<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"","footnotes":""},"categories":[30],"tags":[10267,2252,30814],"class_list":["post-36085","post","type-post","status-publish","format-standard","hentry","category-scienze","tag-lettura-dei-tarocchi","tag-tarocchi","tag-tarocchi-amore"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>tarocchi : quali sono le origini di questo strumento divinatorio - Article Marketing<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/scienze\/lettura-dei-tarocchi\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"tarocchi : quali sono le origini di questo strumento divinatorio - Article Marketing\" \/>\n<meta property=\"og:description\" content=\"l&#039; origine dei tarocchi \u00e8 un argomento che continua a creare un alone di mistero ed alimenta ancor di pi\u00f9 il fascino di questo meraviglioso strumento divinatorio, usato dalle cartomanti di tutto il mondo per creare consulenze dopo letture di tarocchi.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/scienze\/lettura-dei-tarocchi\/\" \/>\n<meta property=\"og:site_name\" content=\"Article Marketing\" \/>\n<meta property=\"article:published_time\" content=\"2013-08-05T13:44:14+00:00\" \/>\n<meta name=\"author\" content=\"Redazione Comunicati Stampa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione Comunicati Stampa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/arte-e-cultura\\\/scienze\\\/lettura-dei-tarocchi\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/arte-e-cultura\\\/scienze\\\/lettura-dei-tarocchi\\\/\"},\"author\":{\"name\":\"Redazione Comunicati Stampa\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"headline\":\"tarocchi : quali sono le origini di questo strumento divinatorio\",\"datePublished\":\"2013-08-05T13:44:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/arte-e-cultura\\\/scienze\\\/lettura-dei-tarocchi\\\/\"},\"wordCount\":525,\"commentCount\":0,\"keywords\":[\"lettura dei tarocchi\",\"tarocchi\",\"tarocchi amore\"],\"articleSection\":[\"Scienze\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/arte-e-cultura\\\/scienze\\\/lettura-dei-tarocchi\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/arte-e-cultura\\\/scienze\\\/lettura-dei-tarocchi\\\/\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/arte-e-cultura\\\/scienze\\\/lettura-dei-tarocchi\\\/\",\"name\":\"tarocchi : quali sono le origini di questo strumento divinatorio - Article Marketing\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\"},\"datePublished\":\"2013-08-05T13:44:14+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/arte-e-cultura\\\/scienze\\\/lettura-dei-tarocchi\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/arte-e-cultura\\\/scienze\\\/lettura-dei-tarocchi\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/arte-e-cultura\\\/scienze\\\/lettura-dei-tarocchi\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"tarocchi : quali sono le origini di questo strumento divinatorio\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\",\"name\":\"Article Marketing\",\"description\":\"article marketing &amp; press release\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\",\"name\":\"Redazione Comunicati Stampa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"caption\":\"Redazione Comunicati Stampa\"},\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/author\\\/redazione-comunicati-stampa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"tarocchi : quali sono le origini di questo strumento divinatorio - Article Marketing","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/scienze\/lettura-dei-tarocchi\/","og_locale":"it_IT","og_type":"article","og_title":"tarocchi : quali sono le origini di questo strumento divinatorio - Article Marketing","og_description":"l' origine dei tarocchi \u00e8 un argomento che continua a creare un alone di mistero ed alimenta ancor di pi\u00f9 il fascino di questo meraviglioso strumento divinatorio, usato dalle cartomanti di tutto il mondo per creare consulenze dopo letture di tarocchi.","og_url":"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/scienze\/lettura-dei-tarocchi\/","og_site_name":"Article Marketing","article_published_time":"2013-08-05T13:44:14+00:00","author":"Redazione Comunicati Stampa","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione Comunicati Stampa","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/scienze\/lettura-dei-tarocchi\/#article","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/scienze\/lettura-dei-tarocchi\/"},"author":{"name":"Redazione Comunicati Stampa","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"headline":"tarocchi : quali sono le origini di questo strumento divinatorio","datePublished":"2013-08-05T13:44:14+00:00","mainEntityOfPage":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/scienze\/lettura-dei-tarocchi\/"},"wordCount":525,"commentCount":0,"keywords":["lettura dei tarocchi","tarocchi","tarocchi amore"],"articleSection":["Scienze"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/scienze\/lettura-dei-tarocchi\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/scienze\/lettura-dei-tarocchi\/","url":"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/scienze\/lettura-dei-tarocchi\/","name":"tarocchi : quali sono le origini di questo strumento divinatorio - Article Marketing","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website"},"datePublished":"2013-08-05T13:44:14+00:00","author":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"breadcrumb":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/scienze\/lettura-dei-tarocchi\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/scienze\/lettura-dei-tarocchi\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/scienze\/lettura-dei-tarocchi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.article-marketing.eu\/comunicati\/"},{"@type":"ListItem","position":2,"name":"tarocchi : quali sono le origini di questo strumento divinatorio"}]},{"@type":"WebSite","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website","url":"https:\/\/www.article-marketing.eu\/comunicati\/","name":"Article Marketing","description":"article marketing &amp; press release","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.article-marketing.eu\/comunicati\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017","name":"Redazione Comunicati Stampa","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","caption":"Redazione Comunicati Stampa"},"url":"https:\/\/www.article-marketing.eu\/comunicati\/author\/redazione-comunicati-stampa\/"}]}},"_links":{"self":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/36085","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/comments?post=36085"}],"version-history":[{"count":0,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/36085\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/media?parent=36085"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/categories?post=36085"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/tags?post=36085"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}