{"id":3647,"date":"2009-12-12T16:48:46","date_gmt":"2009-12-12T15:48:46","guid":{"rendered":"http:\/\/www.article-marketing.eu\/comunicati\/senza-categoria\/la-faccia-nascosta-della-crisi\/"},"modified":"2009-12-12T16:48:46","modified_gmt":"2009-12-12T15:48:46","slug":"la-faccia-nascosta-della-crisi","status":"publish","type":"post","link":"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/giornalismo\/la-faccia-nascosta-della-crisi\/","title":{"rendered":"La faccia nascosta della crisi"},"content":{"rendered":"<p>Sta affondando &#8211; in alcuni punti<br \/>\ndi ben un centimetro l&#8217;anno &#8211; l&#8217;isola di Dubai a forma di palma , ossia<br \/>\nl&#8217;ultimo simbolo dell&#8217;enorme bolla creditizia che ha scatenato<br \/>\nl&#8217;attuale crisi economica. Lo sprofondamentodi Palm Jumeirah, destinata<br \/>\na essere &quot;riconquistata&quot; dal mare, pu\u00f2 essere considerata una metafora<br \/>\ndell&#8217;attuale situazione economica.<br \/>Il crack dell&#8217;Emirato ha infatti<br \/>\nrammentato che l&#8217;enorme volume di indebitamento accumulato negli anni<br \/>\nnon ha subito erosioni. Anzi, in questi ultimi mesi \u00e8 fortemente<br \/>\naumentato soprattutto come debito pubblico statale. La questione non<br \/>\nriguarda solo l&#8217;Emirato di Dubai o le finanze statali della grecia (il<br \/>\ncui debito \u00e8 stato declassato dalle agenzie di rating), ma Paesi come<br \/>\ngli Stati Uniti e la Gran Bretagna, che quest&#8217;anno registreranno un<br \/>\ndeficit pubblico superiore al 10% del Pil, e persino il Giappone, dove<br \/>\nper la prima volta dalla fine della seconda guerra mondiale l&#8217;emissione<br \/>\ndi obbligazioni statali superer\u00e0 l&#8217;intero gettito fiscale del Paese del<br \/>\nSol Levante.<br \/>Non sorprende che il rischio del debito torni a pesare<br \/>\nsui mercati finanziari, i quali si stanno lentamente risvegliando dal<br \/>\nsogno nel quale tutto si sarebbe presto rimesso a posto. Non sorprende<br \/>\nnemmeno che queste preoccupazioni non vengano pi\u00f9 occultate dalle<br \/>\nautorit\u00e0 monetarie. Mario Draghi, governatore della Banca d&#8217;Italia e<br \/>\npresidente del Financial Stability Board, ha infatti dichiarato che vi<br \/>\n\u00e8 un&#8217;enorme quantit\u00e0 di debito pubblico e privato destinata a venire a<br \/>\nmaturazione nei prossimi anni. Ad esempio &#8211; ha spiegato &#8211; &quot; vi sono 4<br \/>\nmila miliardi di dollari di debito privato di bassa qualit\u00e0 garantito<br \/>\nda propriet\u00e0 immobiliari; vi \u00e8 poi l&#8217;enorme quantit\u00e0 di debito pubblico<br \/>\ndegli Stati Uniti, della Gran Bretagna, dell&#8217;Italia, della Grecia,<br \/>\ndella Spagna, della Germania e cos\u00ec via&quot;. E ha concluso :&quot; Considerando<br \/>\nle migliaia di miliardi di debiti bancari, cui bisogna aggiungere il<br \/>\ndebito pubblico, se per varie ragioni i tassi di interesse dovessero<br \/>\nsalire, potrebbe materializzarsi un rischio per i debiti sovrani&quot;.<br \/>Tradotto<br \/>\nin parole povere, se il costo del denaro dovesse cominciare a salire vi<br \/>\nsarebbero rischi di nuovi fallimenti bancari e pure il rischio di<br \/>\ninsolvenza di alcuni Stati con conseguenti crisi valutarie. La montagna<br \/>\ndi migliaia di miliardi di debito, esorcizzata a partire dall&#8217;inizio di<br \/>\nmarzo dalle immissioni di liquidit\u00e0 delle banche centrali e dal rally<br \/>\ndelle borse, non \u00e8 miracolosamente scomparsa: oggi incombe non pi\u00f9 solo<br \/>\nsul sistema finanziario, ma sulle obbligazioni statali e sulla solidit\u00e0<br \/>\ndelle valute. Dunque l&#8217;enorme dispendio di risorse pubbliche per<br \/>\nsalvare il sistema bancario, ossia il trasferimento ai contribuenti<br \/>\ndelle ingenti perdite accumulate dal sistema finanziario, potrebbe<br \/>\navere come risultato solo quello di aver fatto guadagnare un po&#8217; di<br \/>\ntempo.<br \/>Anche la tanto decantata ripresa dell&#8217;economia assomiglia pi\u00f9<br \/>\nad un&#8217;illusione che alla realt\u00e0. Gli interventi di Governi e banche<br \/>\ncentrali hanno frenato il ritmo di contrazione dell&#8217;economia e hanno<br \/>\npermesso una stabilizzazione a bassi livelli dell&#8217;attivit\u00e0 produttiva.<br \/>\nMa ora emergono i primi segnali di una possibile ricaduta in<br \/>\nrecessione. Essi provengono dal Giapponr\u00ece, dove il Governo ha dovuto<br \/>\nvarare un nuovo piano di stimolo fiscale di 83 miliardi di dollari;<br \/>\ndagli Stati Uniti, dove l&#8217;indice del settore pi\u00f9 importante<br \/>\ndell&#8217;economia, quello dei servizi, segnala una contrazione<br \/>\ndell&#8217;attivit\u00e0 e dove il presidente Obama ha annunciato un piano da 200<br \/>\nmiliardi per la creazione di nuovi posti di lavoro, al fine di<br \/>\ncombattere una disoccupazione che ufficialmente si aggira attorno al<br \/>\n10%, ma che in realt\u00e0 supera il 16%.<br \/>Anche in Europa vi sono segnali<br \/>\nnon incoraggianti. Ad esempio, in ottobre \u00e8 diminuita la produzione<br \/>\nindustriale tedesca, un dato che non parla certamente a favore di una<br \/>\nsolida ripresa.<br \/>Ma \u00e8 soprattutto il mercato del lavoro a mettere in<br \/>\ndubbio i facili entusiasmi. Il numero delle persone senza lavoro \u00e8<br \/>\ndestinato purtroppo a salire ulteriormente, poich\u00e8 , come \u00e8 accaduto in<br \/>\nmolti Paesi europei, il ricorso al lavoro ridotto ha rinviato le<br \/>\ndecisioni di licenziamento.<br \/>Dunque le misure di Governi e banche<br \/>\ncentrali non sembrano essere adeguate all&#8217;entit\u00e0 di questa crisi. Si \u00e8<br \/>\nipotizzato che ricreando la fiducia nel settore finanziario si<br \/>\nsarebbero create le premesse per smaltire i miliardi e miliardi di<br \/>\nperdite ancora nascosti nei bilanci delle banche (secondo il Fondo<br \/>\nmonetario internazionale le banche hanno finora denunciato solo la met\u00e0<br \/>\ndelle loro perdite), per ridurre l&#8217;enorme indebitamento che grava su<br \/>\nfamiglie, imprese e Stati e quindi per rilanciare l&#8217;economia. Invece<br \/>\ndalla crisi \u00e8 improbabile che si esca se non si affronta alla radice la<br \/>\nrealt\u00e0 dell&#8217;enorme quantit\u00e0 di debiti inesigibili e delle perdite<br \/>\nancora nascoste nel sistema finanziario.<br \/>Non \u00e8 quanto \u00e8 stato fatto<br \/>\nfinora n\u00e8 quello che \u00e8 prevedibile si faccia nel prossimo futuro,<br \/>\npoich\u00e8 l&#8217;opzione di ripartire dal rilancio dell&#8217;economia reale continua<br \/>\nad essere fortemente avversata dal sistema finanziario internazionale,<br \/>\nil cui potere di influenza sulle scelte politiche non \u00e8 affatto<br \/>\nscemato, nonostante abbia contribuito a creare questa crisi.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Affonda, anche di un centimetro l&#8217;anno in alcuni punti, l&#8217;isola di Dubai a forma di palma, ossia l&#8217;ultimo simbolo dell&#8217;enorme bolla creditizia che ha scatenato l&#8217;attuale crisi finanziaria. Lo sprofondamento di Palm Jumeirah pu\u00f2 essere considerata una metafora dell&#8217;attuale situazione economica.<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"","footnotes":""},"categories":[218],"tags":[],"class_list":["post-3647","post","type-post","status-publish","format-standard","hentry","category-giornalismo"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La faccia nascosta della crisi - Article Marketing<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/giornalismo\/la-faccia-nascosta-della-crisi\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La faccia nascosta della crisi - Article Marketing\" \/>\n<meta property=\"og:description\" content=\"Affonda, anche di un centimetro l&#039;anno in alcuni punti, l&#039;isola di Dubai a forma di palma, ossia l&#039;ultimo simbolo dell&#039;enorme bolla creditizia che ha scatenato l&#039;attuale crisi finanziaria. Lo sprofondamento di Palm Jumeirah pu\u00f2 essere considerata una metafora dell&#039;attuale situazione economica.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/giornalismo\/la-faccia-nascosta-della-crisi\/\" \/>\n<meta property=\"og:site_name\" content=\"Article Marketing\" \/>\n<meta property=\"article:published_time\" content=\"2009-12-12T15:48:46+00:00\" \/>\n<meta name=\"author\" content=\"Redazione Comunicati Stampa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione Comunicati Stampa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/arte-e-cultura\\\/giornalismo\\\/la-faccia-nascosta-della-crisi\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/arte-e-cultura\\\/giornalismo\\\/la-faccia-nascosta-della-crisi\\\/\"},\"author\":{\"name\":\"Redazione Comunicati Stampa\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"headline\":\"La faccia nascosta della crisi\",\"datePublished\":\"2009-12-12T15:48:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/arte-e-cultura\\\/giornalismo\\\/la-faccia-nascosta-della-crisi\\\/\"},\"wordCount\":780,\"commentCount\":0,\"articleSection\":[\"Giornalismo\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/arte-e-cultura\\\/giornalismo\\\/la-faccia-nascosta-della-crisi\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/arte-e-cultura\\\/giornalismo\\\/la-faccia-nascosta-della-crisi\\\/\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/arte-e-cultura\\\/giornalismo\\\/la-faccia-nascosta-della-crisi\\\/\",\"name\":\"La faccia nascosta della crisi - Article Marketing\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\"},\"datePublished\":\"2009-12-12T15:48:46+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/arte-e-cultura\\\/giornalismo\\\/la-faccia-nascosta-della-crisi\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/arte-e-cultura\\\/giornalismo\\\/la-faccia-nascosta-della-crisi\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/arte-e-cultura\\\/giornalismo\\\/la-faccia-nascosta-della-crisi\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La faccia nascosta della crisi\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\",\"name\":\"Article Marketing\",\"description\":\"article marketing &amp; press release\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\",\"name\":\"Redazione Comunicati Stampa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"caption\":\"Redazione Comunicati Stampa\"},\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/author\\\/redazione-comunicati-stampa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La faccia nascosta della crisi - Article Marketing","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/giornalismo\/la-faccia-nascosta-della-crisi\/","og_locale":"it_IT","og_type":"article","og_title":"La faccia nascosta della crisi - Article Marketing","og_description":"Affonda, anche di un centimetro l'anno in alcuni punti, l'isola di Dubai a forma di palma, ossia l'ultimo simbolo dell'enorme bolla creditizia che ha scatenato l'attuale crisi finanziaria. Lo sprofondamento di Palm Jumeirah pu\u00f2 essere considerata una metafora dell'attuale situazione economica.","og_url":"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/giornalismo\/la-faccia-nascosta-della-crisi\/","og_site_name":"Article Marketing","article_published_time":"2009-12-12T15:48:46+00:00","author":"Redazione Comunicati Stampa","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione Comunicati Stampa","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/giornalismo\/la-faccia-nascosta-della-crisi\/#article","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/giornalismo\/la-faccia-nascosta-della-crisi\/"},"author":{"name":"Redazione Comunicati Stampa","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"headline":"La faccia nascosta della crisi","datePublished":"2009-12-12T15:48:46+00:00","mainEntityOfPage":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/giornalismo\/la-faccia-nascosta-della-crisi\/"},"wordCount":780,"commentCount":0,"articleSection":["Giornalismo"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/giornalismo\/la-faccia-nascosta-della-crisi\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/giornalismo\/la-faccia-nascosta-della-crisi\/","url":"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/giornalismo\/la-faccia-nascosta-della-crisi\/","name":"La faccia nascosta della crisi - Article Marketing","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website"},"datePublished":"2009-12-12T15:48:46+00:00","author":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"breadcrumb":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/giornalismo\/la-faccia-nascosta-della-crisi\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/giornalismo\/la-faccia-nascosta-della-crisi\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/giornalismo\/la-faccia-nascosta-della-crisi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.article-marketing.eu\/comunicati\/"},{"@type":"ListItem","position":2,"name":"La faccia nascosta della crisi"}]},{"@type":"WebSite","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website","url":"https:\/\/www.article-marketing.eu\/comunicati\/","name":"Article Marketing","description":"article marketing &amp; press release","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.article-marketing.eu\/comunicati\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017","name":"Redazione Comunicati Stampa","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","caption":"Redazione Comunicati Stampa"},"url":"https:\/\/www.article-marketing.eu\/comunicati\/author\/redazione-comunicati-stampa\/"}]}},"_links":{"self":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/3647","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/comments?post=3647"}],"version-history":[{"count":0,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/3647\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/media?parent=3647"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/categories?post=3647"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/tags?post=3647"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}