{"id":37449,"date":"2013-10-15T17:11:04","date_gmt":"2013-10-15T15:11:04","guid":{"rendered":"http:\/\/www.article-marketing.eu\/comunicati\/senza-categoria\/ubi-banca-carta-enjoy-tutto-quello-che-si-deve-sapere\/"},"modified":"2018-10-25T22:14:39","modified_gmt":"2018-10-25T20:14:39","slug":"ubi-banca-carta-enjoy-tutto-quello-che-si-deve-sapere","status":"publish","type":"post","link":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/ubi-banca-carta-enjoy-tutto-quello-che-si-deve-sapere\/","title":{"rendered":"UBI BANCA, Carta Enjoy tutto quello che si deve sapere"},"content":{"rendered":"<p><strong style=\"color: #ffffff; font-family: Arial, Tahoma, Helvetica, FreeSans, sans-serif; font-size: 13px; line-height: 18px; background-color: #000000;\">QUI UBI<\/strong>, possiamo dire che <strong style=\"color: #ffffff; font-family: Arial, Tahoma, Helvetica, FreeSans, sans-serif; font-size: 13px; line-height: 18px; background-color: #000000;\">UBI BANCA<\/strong> con la sua carta ricaricabile e con <strong style=\"color: #ffffff; font-family: Arial, Tahoma, Helvetica, FreeSans, sans-serif; font-size: 13px; line-height: 18px; background-color: #000000;\">Iban<\/strong> &egrave; oggi uno dei principali player nel panorama bancario italiano, detiene con una quota di mercato superiore al 5% e vanta una presenza significativa nelle regioni a pi&ugrave; alto potenziale del Paese.<strong style=\"color: #ffffff; font-family: Arial, Tahoma, Helvetica, FreeSans, sans-serif; font-size: 13px; line-height: 18px; background-color: #000000;\">UBI<\/strong> Banca &egrave; un Gruppo cooperativo, quotato alla Borsa di Milano e incluso nell&#8217;indice <strong style=\"color: #ffffff; font-family: Arial, Tahoma, Helvetica, FreeSans, sans-serif; font-size: 13px; line-height: 18px; background-color: #000000;\">FTSE MIB<\/strong>. Uno dei suoi migliori prodotti &egrave; proprio quello di Carta Enjoy che al momento &egrave; disponibile in un&#8217;unica versione quella (ricaricabile) e grazie alla presenza di un proprio identificativo IBAN, oltre ad<br style=\"color: #ffffff; font-family: Arial, Tahoma, Helvetica, FreeSans, sans-serif; font-size: 13px; line-height: 18px; background-color: #000000;\" \/> un proprio numero Carta consente di eseguire la seguente operativit&agrave; bancaria: <br \/> <strong>UBI BANCA, Carta Enjoy<\/strong> di UBI permette le seguenti operazioni: Invio di bonifici in Euro, in Italia e all&#8217;estero, ovviamente permette la ricezione di bonifici in Euro e\/o altra moneta dall&#8217;Italia e\/o dall&#8217;estero, l&#8217;accredito dello stipendio direttamente sulla <strong>Carta<\/strong>, prelevamento di contanti agli sportelli automatici, la domiciliazione delle utenze molto importante oggi, ricariche di telefono cellulare, Carta Enjoy permette anche gli acquisti nei negozi che espongono il logo MasterCard e mediante tecniche di comunicazione a distanza, il controllo del saldo e dei movimenti della Carta; <br \/> Ma la <strong>carta Enjoy di UBI BANCA<\/strong> permette anche tante altre operazioni come trasferimenti di denaro peer-to-peer (P2P) tra Carte Enjoy ma poi ovviamente non permette di effettuare alcune operazioni come pagamento di MAV, bollettini postali e bollettini FRECCIA, invio di bonifici esteri e\/o in divisa diversa dall&#8217;Euro, rilascio blocchetto assegni, collegamento con altri rapporti tra cui dossier Titoli, Carte di Credito, di debito e Multifunzione, transazioni strumenti finanziari, assicurazioni e gestione di portafoglio, finanziamenti, affidamenti e mutui, versamento di assegni Ma adesso vediamo quali sono le principali condizioni economiche di UBI BANCA: <br \/> ? Commissioni di ricarica: <br \/> &ndash; in Filiale (in contanti e\/o con addebito in c\/c) euro 3,00 <br \/> &ndash; tramite ATM del Gruppo (con <strong>Carta PagoBANCOMAT<\/strong>) euro 1,00 <br \/> &ndash; tramite Qui UBI Internet Banking (Peer to Peer con addebito su altra <strong>Carta Enjoy<\/strong>) esente <br \/> &ndash; tramite Qui UBI Internet Banking (con addebito su conto corrente) euro 0,50 <br \/> &ndash; tramite Qui UBI Contact Center (Peer to Peer con addebito su altra <strong>Carta Enjoy<\/strong>) esente <br \/> (servizio attualmente non disponibile) &ndash; tramite Qui UBI Contact Center (con addebito su conto corrente) euro 0,50 <br \/> ? Costo di emissione (una tantum) euro 2,00 <br \/> ? Canone mensile (posticipato) euro 1,00 <br \/> ? Costo di riemissione della Carta a scadenza euro 2,00 <br \/> ? Costo di riemissione\/sostituzione della Carta per furto, smarrimento, deterioramento esente <br \/> ? Commissione di caricamento iniziale esente <br \/> ? Commissione di rimborso della Carta esente Servizio Qui UBI <br \/> Commissione per operazioni di prelievo: <br \/> &ndash; tramite Filiale del Gruppo euro 5,00 <br \/> &ndash; tramite ATM del Gruppo esente <br \/> &ndash; tramite ATM di altre Banche in Italia esente <br \/> &ndash; tramite ATM all&#8217;estero euro 5,00 <\/p>\n<p> <strong>Massimali<\/strong> <br \/> ? Limite di utilizzo e giacenza massima euro 20.000,00 ? Caricamento iniziale obbligatorio importo maggiore o uguale a euro 25,00 ? Massimale di prelevamento giornaliero da ATM euro 250,00 ? Massimale di prelevamento mensile da ATM euro 3.000,00 8 aprile <br \/> ? Massimale complessivo giornaliero per operazioni di pagamento POS e prelevamento da ATM euro 1.250,00 <br \/> ? Massimale complessivo mensile per operazioni di pagamento POS e prelevamento da ATM euro 6.000,00 <br \/> ? Massimale di pagamento POS giornaliero euro 1.000,00 <br \/> ? Massimale di pagamento POS mensile euro 3.000,00 <br \/> ? Massimale di pagamento POS contact-less euro 25,00 (servizio attualmente non disponibile) <br \/> ? Massimo di ricarica per operazione con Carta PagoBANCOMAT euro 250,00 <br \/> ? Numero massimo di ricariche giornaliero con PagoBANCOMAT 5 <br \/> ? Massimo di ricarica per operazione da Qui UBI euro 1.000,00 <br \/> ? Massimo di ricarica per operazione da Servizio Clienti euro 1.000,00 <br \/> ? Imposta di bollo su contratto euro 14,62 (a carico della Banca fino al 30 giugno 2010, successivamente a carico Cliente) <br \/> <strong>BONIFICI<\/strong> <br \/> ESECUZIONE DI DISPOSIZIONE DI BONIFICO DA ADDEBITARE SULLA CARTA DI MONETA ELETTRONICA <br \/> Disposizioni presentate allo Sportello <br \/> ? Bonifici ordinari nostre Filiali: &ndash; commissioni euro 3,00 <br \/> ? Bonifici ordinari Banche del Gruppo: &ndash; commissioni euro 3,00 <br \/> ? Bonifici ordinari altre Banche: &ndash; commissioni euro 4,00 <br \/> ? Bonifici ordinari emolumenti nostre Filiali: &ndash; commissioni euro 2,50 <br \/> ? Bonifici per emolumenti Banche del Gruppo: &ndash; commissioni euro 2,50 <br \/> ? Bonifici per emolumenti altre Banche: &ndash; commissioni euro 2,50 <\/p>\n<p> Disposizioni presentate tramite Internet Banking <br \/> ? Bonifici ordinari stessa Filiale: &ndash; commissioni euro 0,50 <\/p>\n<p> Disposizioni inoltrate tramite Phone Banking <br \/> ? Bonifici ordinari stessa Filiale: &ndash; commissioni euro 0,50 <br \/> ? Bonifici ordinari nostre Filiali:<\/p>\n<ul style=\"padding: 0px 2.5em; margin: 0.5em 0px; line-height: 18px; list-style-position: initial; list-style-image: initial; color: #ffffff; font-family: Arial, Tahoma, Helvetica, FreeSans, sans-serif; font-size: 13px; background-color: #000000;\">\n<li style=\"padding: 0.25em 0px; margin: 0px 0px 0.25em; border: none;\"> commissioni euro 0,50 <\/li>\n<\/ul>\n<p> Ecco questo &egrave; tutto quello che si doveva sapere sulla <strong>CARTA ENJOY di UBI BANCA<\/strong>, per richiedere un appuntamento in banca basta andare a questo indirizzo http:\/\/publiorachannel.blogspot.it\/p\/pubblicita.html<\/p>\n","protected":false},"excerpt":{"rendered":"<p>QUI UBI, possiamo dire che UBI BANCA con la sua carta ricaricabile e con Iban \u00e8 oggi uno dei principali player nel panorama bancario italiano, detiene con una quota di mercato superiore al 5% e vanta una presenza significativa nelle regioni a pi\u00f9 alto potenziale del Paese.UBI Banca \u00e8 un Gruppo cooperativo, quotato alla Borsa di Milano e incluso nell&#8217;indice FTSE MIB. Uno dei suoi migliori prodotti \u00e8 proprio quello di Carta Enjoy che al momento \u00e8 disponibile in un&#8217;unica versione quella (ricaricabile) e grazie alla presenza di un proprio identificativo IBAN, oltre ad<br \/>un proprio numero Carta consente di eseguire la seguente operativit\u00e0 bancaria:<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"","footnotes":""},"categories":[59],"tags":[45161,6597,45162,45160],"class_list":["post-37449","post","type-post","status-publish","format-standard","hentry","category-economia-e-lavoro","tag-banca-ubi","tag-carta-di-credito","tag-qui-ubi","tag-ubi-banca"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>UBI BANCA, Carta Enjoy tutto quello che si deve sapere - Article Marketing<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/ubi-banca-carta-enjoy-tutto-quello-che-si-deve-sapere\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"UBI BANCA, Carta Enjoy tutto quello che si deve sapere - Article Marketing\" \/>\n<meta property=\"og:description\" content=\"QUI UBI, possiamo dire che UBI BANCA con la sua carta ricaricabile e con Iban \u00e8 oggi uno dei principali player nel panorama bancario italiano, detiene con una quota di mercato superiore al 5% e vanta una presenza significativa nelle regioni a pi\u00f9 alto potenziale del Paese.UBI Banca \u00e8 un Gruppo cooperativo, quotato alla Borsa di Milano e incluso nell&#039;indice FTSE MIB. Uno dei suoi migliori prodotti \u00e8 proprio quello di Carta Enjoy che al momento \u00e8 disponibile in un&#039;unica versione quella (ricaricabile) e grazie alla presenza di un proprio identificativo IBAN, oltre adun proprio numero Carta consente di eseguire la seguente operativit\u00e0 bancaria:\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/ubi-banca-carta-enjoy-tutto-quello-che-si-deve-sapere\/\" \/>\n<meta property=\"og:site_name\" content=\"Article Marketing\" \/>\n<meta property=\"article:published_time\" content=\"2013-10-15T15:11:04+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-10-25T20:14:39+00:00\" \/>\n<meta name=\"author\" content=\"Redazione Comunicati Stampa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione Comunicati Stampa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/economia-e-lavoro\\\/ubi-banca-carta-enjoy-tutto-quello-che-si-deve-sapere\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/economia-e-lavoro\\\/ubi-banca-carta-enjoy-tutto-quello-che-si-deve-sapere\\\/\"},\"author\":{\"name\":\"Redazione Comunicati Stampa\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"headline\":\"UBI BANCA, Carta Enjoy tutto quello che si deve sapere\",\"datePublished\":\"2013-10-15T15:11:04+00:00\",\"dateModified\":\"2018-10-25T20:14:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/economia-e-lavoro\\\/ubi-banca-carta-enjoy-tutto-quello-che-si-deve-sapere\\\/\"},\"wordCount\":716,\"commentCount\":0,\"keywords\":[\"banca ubi\",\"carta di credito\",\"qui ubi\",\"ubi banca\"],\"articleSection\":[\"Economia e lavoro\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/economia-e-lavoro\\\/ubi-banca-carta-enjoy-tutto-quello-che-si-deve-sapere\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/economia-e-lavoro\\\/ubi-banca-carta-enjoy-tutto-quello-che-si-deve-sapere\\\/\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/economia-e-lavoro\\\/ubi-banca-carta-enjoy-tutto-quello-che-si-deve-sapere\\\/\",\"name\":\"UBI BANCA, Carta Enjoy tutto quello che si deve sapere - Article Marketing\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\"},\"datePublished\":\"2013-10-15T15:11:04+00:00\",\"dateModified\":\"2018-10-25T20:14:39+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/economia-e-lavoro\\\/ubi-banca-carta-enjoy-tutto-quello-che-si-deve-sapere\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/economia-e-lavoro\\\/ubi-banca-carta-enjoy-tutto-quello-che-si-deve-sapere\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/economia-e-lavoro\\\/ubi-banca-carta-enjoy-tutto-quello-che-si-deve-sapere\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"UBI BANCA, Carta Enjoy tutto quello che si deve sapere\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\",\"name\":\"Article Marketing\",\"description\":\"article marketing &amp; press release\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\",\"name\":\"Redazione Comunicati Stampa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"caption\":\"Redazione Comunicati Stampa\"},\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/author\\\/redazione-comunicati-stampa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"UBI BANCA, Carta Enjoy tutto quello che si deve sapere - Article Marketing","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/ubi-banca-carta-enjoy-tutto-quello-che-si-deve-sapere\/","og_locale":"it_IT","og_type":"article","og_title":"UBI BANCA, Carta Enjoy tutto quello che si deve sapere - Article Marketing","og_description":"QUI UBI, possiamo dire che UBI BANCA con la sua carta ricaricabile e con Iban \u00e8 oggi uno dei principali player nel panorama bancario italiano, detiene con una quota di mercato superiore al 5% e vanta una presenza significativa nelle regioni a pi\u00f9 alto potenziale del Paese.UBI Banca \u00e8 un Gruppo cooperativo, quotato alla Borsa di Milano e incluso nell'indice FTSE MIB. Uno dei suoi migliori prodotti \u00e8 proprio quello di Carta Enjoy che al momento \u00e8 disponibile in un'unica versione quella (ricaricabile) e grazie alla presenza di un proprio identificativo IBAN, oltre adun proprio numero Carta consente di eseguire la seguente operativit\u00e0 bancaria:","og_url":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/ubi-banca-carta-enjoy-tutto-quello-che-si-deve-sapere\/","og_site_name":"Article Marketing","article_published_time":"2013-10-15T15:11:04+00:00","article_modified_time":"2018-10-25T20:14:39+00:00","author":"Redazione Comunicati Stampa","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione Comunicati Stampa","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/ubi-banca-carta-enjoy-tutto-quello-che-si-deve-sapere\/#article","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/ubi-banca-carta-enjoy-tutto-quello-che-si-deve-sapere\/"},"author":{"name":"Redazione Comunicati Stampa","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"headline":"UBI BANCA, Carta Enjoy tutto quello che si deve sapere","datePublished":"2013-10-15T15:11:04+00:00","dateModified":"2018-10-25T20:14:39+00:00","mainEntityOfPage":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/ubi-banca-carta-enjoy-tutto-quello-che-si-deve-sapere\/"},"wordCount":716,"commentCount":0,"keywords":["banca ubi","carta di credito","qui ubi","ubi banca"],"articleSection":["Economia e lavoro"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/ubi-banca-carta-enjoy-tutto-quello-che-si-deve-sapere\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/ubi-banca-carta-enjoy-tutto-quello-che-si-deve-sapere\/","url":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/ubi-banca-carta-enjoy-tutto-quello-che-si-deve-sapere\/","name":"UBI BANCA, Carta Enjoy tutto quello che si deve sapere - Article Marketing","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website"},"datePublished":"2013-10-15T15:11:04+00:00","dateModified":"2018-10-25T20:14:39+00:00","author":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"breadcrumb":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/ubi-banca-carta-enjoy-tutto-quello-che-si-deve-sapere\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/ubi-banca-carta-enjoy-tutto-quello-che-si-deve-sapere\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/ubi-banca-carta-enjoy-tutto-quello-che-si-deve-sapere\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.article-marketing.eu\/comunicati\/"},{"@type":"ListItem","position":2,"name":"UBI BANCA, Carta Enjoy tutto quello che si deve sapere"}]},{"@type":"WebSite","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website","url":"https:\/\/www.article-marketing.eu\/comunicati\/","name":"Article Marketing","description":"article marketing &amp; press release","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.article-marketing.eu\/comunicati\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017","name":"Redazione Comunicati Stampa","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","caption":"Redazione Comunicati Stampa"},"url":"https:\/\/www.article-marketing.eu\/comunicati\/author\/redazione-comunicati-stampa\/"}]}},"_links":{"self":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/37449","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/comments?post=37449"}],"version-history":[{"count":1,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/37449\/revisions"}],"predecessor-version":[{"id":63593,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/37449\/revisions\/63593"}],"wp:attachment":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/media?parent=37449"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/categories?post=37449"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/tags?post=37449"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}