{"id":38000,"date":"2013-11-10T17:59:36","date_gmt":"2013-11-10T16:59:36","guid":{"rendered":"http:\/\/www.article-marketing.eu\/comunicati\/senza-categoria\/a-venti-anni-dalla-scomparsa-il-mondo-della%252580%252599arte-rende-omaggio-a-novella-parigini-con-una-mostra-e-diverse-altre-iniziative-in-calendario-a-palazzo-margutta-dal-21-al-30-novembre\/"},"modified":"2013-11-10T17:59:36","modified_gmt":"2013-11-10T16:59:36","slug":"a-venti-anni-dalla-scomparsa-il-mondo-della%252580%252599arte-rende-omaggio-a-novella-parigini-con-una-mostra-e-diverse-altre-iniziative-in-calendario-a-palazzo-margutta-dal-21-al-30-novembre","status":"publish","type":"post","link":"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/a-venti-anni-dalla-scomparsa-il-mondo-della%252580%252599arte-rende-omaggio-a-novella-parigini-con-una-mostra-e-diverse-altre-iniziative-in-calendario-a-palazzo-margutta-dal-21-al-30-novembre\/","title":{"rendered":"A Palazzo Margutta il mondo dell\u2019arte omaggia Novella Parigini con una mostra dal 21 al 30 novembre"},"content":{"rendered":"<p><em style=\"mso-bidi-font-style: normal;\">Roma, 21 novembre 2013 &ndash;<\/em> <strong style=\"mso-bidi-font-weight: normal;\">Da gioved&igrave; 21 novembre la Galleria &ldquo;Il Mondo dell&rsquo;Arte&rdquo; ospita, in occasione dei venti anni dalla sua scomparsa, una retrospettiva dal titolo &ldquo;Novella Parigini. Un mito preannunciato&rdquo; e una serie di iniziative <\/strong>dedicate all&rsquo;artista che <strong style=\"mso-bidi-font-weight: normal;\">ha segnato <\/strong>con la sua pittura <strong style=\"mso-bidi-font-weight: normal;\">la storia dell&rsquo;arte contemporanea<\/strong>,<strong style=\"mso-bidi-font-weight: normal;\"> <\/strong>rappresentando il secolo passato, ed &egrave; stata il simbolo della Dolce Vita.<\/p>\n<p>L&rsquo;esposizione &#8211; a ingresso libero e <strong style=\"mso-bidi-font-weight: normal;\">in programma a Palazzo Margutta (Via Margutta, 55) fino al 30 novembre<\/strong> &ndash; racconta, attraverso un&rsquo;<strong style=\"mso-bidi-font-weight: normal;\">ampia<\/strong> <strong style=\"mso-bidi-font-weight: normal;\">raccolta di opere realizzate durante una lunga esperienza artistica, la pittrice e permette di conoscere il costume e la cultura degli anni &lsquo;50 e &rsquo;60 attraverso un intreccio quasi surreale tra i maggiori protagonisti di quei tempi. <\/strong><br \/><strong style=\"mso-bidi-font-weight: normal;\"><\/strong><br \/>Accanto ai quadri<strong style=\"mso-bidi-font-weight: normal;\"> <\/strong>di dimensioni diverse, sui quali campeggiano<strong style=\"mso-bidi-font-weight: normal;\"> figure androgine e creature surreali a met&agrave; tra la donna e il gatto, ma anche paesaggi sognanti dalla natura lussureggiante e dolcissime Madonne velate<\/strong>, un <strong style=\"mso-bidi-font-weight: normal;\">video-testimonianza<\/strong>, in cui l&rsquo;artista racconta s&eacute; stessa, la propria vita e il proprio pensiero, e una serie di <strong style=\"mso-bidi-font-weight: normal;\">gigantografie<\/strong> che riproducono alcune testate dell&rsquo;epoca e le <strong style=\"mso-bidi-font-weight: normal;\">lettere<\/strong> nelle quali il Vate suggerisce il nome di Novella a Emilia, la madre dell&rsquo;artista, affidandole anche le istruzioni di un infallibile talismano da lui regalatole.<em style=\"mso-bidi-font-style: normal;\"><\/em><\/p>\n<p>Nata a Chiusi da un&rsquo;aristocratica famiglia senese, <strong style=\"mso-bidi-font-weight: normal;\">Novella cresce negli ambienti intellettuali parigini<\/strong>. Nella capitale francese, dove si trasferisce ancora giovanissima, frequenta l&rsquo;Accademia delle Beaux Arts e vende i propri quadri in strada pur di riuscire a mantenersi in quella<strong> cultura internazionale fatta di personaggi del calibro di Jean-Paul Sartre e Simone de Beauvoir, madre del movimento femminista, Jean Genet e il poeta Jean Cocteau, amico di Picasso, Matisse e Man Ray, che la formano come donna ricca di spirito e d&rsquo;intelligenza.<\/strong> Conosce prima l&rsquo;esistenzialismo, di cui diventer&agrave; ambasciatrice, e poi il surrealismo. <strong>Esuberante, disinvolta, assetata di vita, <\/strong><strong style=\"mso-bidi-font-weight: normal;\">interprete di un pensiero libero<\/strong>, la Parigini, rientrata in Italia, diventa la<strong> protagonista indiscussa dell&rsquo;arte romana, signora della &ldquo;Dolce Vita&rdquo; <\/strong>celebrata da Fellini.<strong> Nel suo studio<\/strong>, di Via Margutta, da lei eletta a palcoscenico delle sue avventure esistenziali e artistiche, <strong>passano le personalit&agrave; dell&rsquo;arte e del cinema di tutto il mondo<\/strong>: da Dal&igrave; a De Chirico, da Sartre a Cocteau e poi i grandi divi di casa nostra, come Sophia Loren e Vittorio Gassman, e le star internazionali Tyrone Power, Linda Christian, Ava Gardner, Marlon Brando e l&rsquo;amica di sempre Ursula Andress. Fine conoscitrice del <em>jet set <\/em>internazionale, <strong>riesce a fare della mondanit&agrave; un&rsquo;arte nell&rsquo;arte.<\/strong> Nel 1954 &egrave; a New York dove <strong>allestisce grandi mostre<\/strong>, ma a ospitare le sue esposizioni saranno presto diverse tra le pi&ugrave; importanti citt&agrave; del mondo. I suoi lavori figurano in importanti collezioni e musei del mondo. <strong>Prima artista europea a esporre in Cina, riceve l&rsquo;omaggio anche dalle poste francesi che le dedicano un francobollo.<\/strong><strong style=\"mso-bidi-font-weight: normal;\"><\/strong><\/p>\n<p>La sua <strong style=\"mso-bidi-font-weight: normal;\">tecnica, straordinaria nel dosaggio, nell&rsquo;accordo cromatico, nella leggerezza e nella precisione del tratto<\/strong>, la sua rara maestria nel disegno non cessano di stupire. Ma &egrave; soprattutto una questione di contenuti, di <strong style=\"mso-bidi-font-weight: normal;\">ricchezza del mondo espressivo che determinano la costante fonte di fascino del suo temperamento intimistico, romantico, sognatore<\/strong>. Le figure femminili dai grandi occhi felini e gli zigomi pronunciati, che se riportate agli anni &rsquo;50 dimostrano l&rsquo;<strong style=\"mso-bidi-font-weight: normal;\">incredibile modernit&agrave; di questa pittrice<\/strong>, e i gatti, diventati nel tempo un suo alter ego, sono protagonisti inconfondibili di una contrapposizione tra edonismo ed etica formale, ma rimangono capaci di privilegiare l&rsquo;<strong style=\"mso-bidi-font-weight: normal;\">espressione libera da qualsiasi legame politico o sentimentale per far emergere una nuova figura d&rsquo;esempio all&rsquo;impegno femminile.<\/strong><\/p>\n<p>In omaggio a questo <strong style=\"mso-bidi-font-weight: normal;\">personaggio dallo straordinario talento e dalla profonda umanit&agrave;<\/strong>, nota ai rotocalchi mondiali per le sue trasgressioni e i suoi eccessi, e <strong style=\"mso-bidi-font-weight: normal;\">indiscussa icona della libert&agrave; e dell&rsquo;uguaglianza dei diritti della donna<\/strong>, per l&rsquo;intera durata dell&rsquo;esposizione ogni sera alle 19.00 attrici professioniste, coordinate da Virginia Barrett, promotrice del progetto &ldquo;Donne d&rsquo;amore&rdquo;, giunto quest&rsquo;anno alla sua quarta edizione, <strong style=\"mso-bidi-font-weight: normal;\">reciteranno, a titolo di denuncia contro il femminicidio e i tanti gravi episodi di violenze rivolti contro le donne, poesie tratte dal libro <em style=\"mso-bidi-font-style: normal;\">Lorma<\/em>, <\/strong>presentato da una prefazione di Vittorio Sgarbi, e <strong style=\"mso-bidi-font-weight: normal;\">scritto dal poeta vicentino Enrico Hullweck<\/strong> e monologhi su vari temi al femminile suggeriti da numerosi autori ed autrici. Profondamente affascinato dalla figura e dalla pittura della Parigini, Hullweck, che fin da giovane aveva iniziato a recarsi a Roma e a frequentare i dintorni di Via Margutta nella speranza di conoscere personalmente l&rsquo;artista della Dolce Vita, le &egrave; sempre rimasto legato tanto che quest&rsquo;amicizia virtuale, celebrata grazie a una mostra alla Basilica Palladiana, da lui fortemente voluta ai tempi in cui era primo cittadino di Vicenza, continua ancora oggi a ispirare diversi suoi testi, poesie, monologhi e altri scritti.<br \/><em style=\"mso-bidi-font-style: normal;\"><\/em><br \/>La retrospettiva e tutte le altre iniziative a essa collegate vogliono essere il <strong style=\"mso-bidi-font-weight: normal;\">tributo con il quale Elvino Echeoni e Remo Panacchia<\/strong>, rispettivamente direttore artistico e gallerista de &ldquo;Il Mondo dell&rsquo;Arte&rdquo;,<strong style=\"mso-bidi-font-weight: normal;\"> unitamente a Benedetta Parigini, figlia dell&rsquo;artista, rendono omaggio alla donna e alla pittrice, oltre all&rsquo;indissolubile legame che con lei si &egrave; creato <\/strong>e che &egrave; stato<strong style=\"mso-bidi-font-weight: normal;\"> celebrato <\/strong>anche<strong style=\"mso-bidi-font-weight: normal;\"> nel libro <\/strong>firmato da Il Mondo dell&rsquo;Arte<strong style=\"mso-bidi-font-weight: normal;\"> &ldquo;Novella Parigini. Un mito preannunciato&rdquo;. <\/strong><br \/><em style=\"mso-bidi-font-style: normal;\"><\/em><br \/>&ldquo;Quella di Novella Parigini &ndash; ha spiegato il Maestro <strong style=\"mso-bidi-font-weight: normal;\">Elvino Echeoni, direttore artistico de &ldquo;Il Mondo dell&rsquo;Arte&rdquo; e<\/strong> <strong style=\"mso-bidi-font-weight: normal;\">Presidente dell&rsquo;Associazione Margutta Arte <\/strong>&#8211; &egrave; una pittura profonda, fatta di una perfezione sottile da cui emerge con forza un mondo intimo che &egrave;, allo stesso tempo, estremamente ricco di emozioni e simboli personali ma anche capace di sottrarsi alla moda e all&rsquo;effimero e rimanere fedele a un proprio universo di sentimenti, emozioni, sogni&rdquo;. <\/p>\n<p>&ldquo;La sua opera, nella costante evoluzione delle tecniche e dei moduli espressivi, ribadisce &ndash; conclude Echeoni &#8211; quella tensione emotiva che la caratterizza e che si &egrave; mantenuta valida malgrado il trascorrere del tempo&rdquo;. <strong style=\"mso-bidi-font-weight: normal;\"><\/strong><br \/><strong style=\"mso-bidi-font-weight: normal;\"><\/strong><br \/><strong style=\"mso-bidi-font-weight: normal;\">L&rsquo;organizzazione della mostra, realizzata con il contributo della Banca di Credito Cooperativo di Roma, &egrave; stata curata da Il Mondo dell&rsquo;Arte.<\/strong><br \/>L&rsquo;appuntamento per il <strong style=\"mso-bidi-font-weight: normal;\">vernissage &egrave;<\/strong> <strong style=\"mso-bidi-font-weight: normal;\">fissato<\/strong> per <strong style=\"mso-bidi-font-weight: normal;\">gioved&igrave; 21 novembre 2013 dalle 18.00 alle 22.00.<\/strong><\/p>\n<p><strong style=\"mso-bidi-font-weight: normal;\"><\/strong><\/p>\n<p><strong style=\"mso-bidi-font-weight: normal;\"><\/strong><br \/>Galleria Il Mondo dell&rsquo;Arte &ldquo;Palazzo Margutta&rdquo; (<a href=\"http:\/\/www.ilmondodellarte.com\/\">www.ilmondodellarte.com<\/a>) &#8211; Via Margutta, 55 Roma<br \/>Mostra dell&rsquo;artista:<strong style=\"mso-bidi-font-weight: normal;\"> Novella Parigini. <\/strong><br \/>Vernissage cocktail <strong style=\"mso-bidi-font-weight: normal;\">gioved&igrave; 21 novembre 2013, ore 18.00 &#8211; 22.00.<\/strong><br \/><strong style=\"mso-bidi-font-weight: normal;\">Lettura di poesie del poeta Enrico Hullweck e altri monologhi suggeriti da altri autori: venerd&igrave; 22, sabato 23 e domenica 24 novembre a partire dalle ore 19.00.<\/strong><br \/>La mostra si protrarr&agrave; <strong style=\"mso-bidi-font-weight: normal;\">fino al 30 novembre 2013<\/strong>: dalle 10.30 alle 13.00 e dalle 16.00 alle 20.00 (luned&igrave; mattina chiuso).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>In esposizione, in programma a Via Margutta 55, le opere pi\u00f9 rappresentative della pittrice, ma anche un video in cui l\u2019artista si racconta, una serie di gigantografie che riproducono alcune testate dell\u2019epoca e le lettere nelle quali D\u2019Annunzio consiglia il nome di Novella alla madre dell\u2019artista.<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"","footnotes":""},"categories":[27],"tags":[171,33314,33315,45472,33313,1001,3383],"class_list":["post-38000","post","type-post","status-publish","format-standard","hentry","category-arte-e-cultura","tag-arte","tag-elvino-echeoni","tag-il-mondo-dellarte","tag-novella-parigini","tag-palazzo-margutta","tag-pittura","tag-via-margutta"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>A Palazzo Margutta il mondo dell\u2019arte omaggia Novella Parigini con una mostra dal 21 al 30 novembre - Article Marketing<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/a-venti-anni-dalla-scomparsa-il-mondo-della%2580%2599arte-rende-omaggio-a-novella-parigini-con-una-mostra-e-diverse-altre-iniziative-in-calendario-a-palazzo-margutta-dal-21-al-30-novembre\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"A Palazzo Margutta il mondo dell\u2019arte omaggia Novella Parigini con una mostra dal 21 al 30 novembre - Article Marketing\" \/>\n<meta property=\"og:description\" content=\"In esposizione, in programma a Via Margutta 55, le opere pi\u00f9 rappresentative della pittrice, ma anche un video in cui l\u2019artista si racconta, una serie di gigantografie che riproducono alcune testate dell\u2019epoca e le lettere nelle quali D\u2019Annunzio consiglia il nome di Novella alla madre dell\u2019artista.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/a-venti-anni-dalla-scomparsa-il-mondo-della%2580%2599arte-rende-omaggio-a-novella-parigini-con-una-mostra-e-diverse-altre-iniziative-in-calendario-a-palazzo-margutta-dal-21-al-30-novembre\/\" \/>\n<meta property=\"og:site_name\" content=\"Article Marketing\" \/>\n<meta property=\"article:published_time\" content=\"2013-11-10T16:59:36+00:00\" \/>\n<meta name=\"author\" content=\"Redazione Comunicati Stampa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione Comunicati Stampa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/arte-e-cultura\\\/a-venti-anni-dalla-scomparsa-il-mondo-della%252580%252599arte-rende-omaggio-a-novella-parigini-con-una-mostra-e-diverse-altre-iniziative-in-calendario-a-palazzo-margutta-dal-21-al-30-novembre\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/arte-e-cultura\\\/a-venti-anni-dalla-scomparsa-il-mondo-della%252580%252599arte-rende-omaggio-a-novella-parigini-con-una-mostra-e-diverse-altre-iniziative-in-calendario-a-palazzo-margutta-dal-21-al-30-novembre\\\/\"},\"author\":{\"name\":\"Redazione Comunicati Stampa\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"headline\":\"A Palazzo Margutta il mondo dell\u2019arte omaggia Novella Parigini con una mostra dal 21 al 30 novembre\",\"datePublished\":\"2013-11-10T16:59:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/arte-e-cultura\\\/a-venti-anni-dalla-scomparsa-il-mondo-della%252580%252599arte-rende-omaggio-a-novella-parigini-con-una-mostra-e-diverse-altre-iniziative-in-calendario-a-palazzo-margutta-dal-21-al-30-novembre\\\/\"},\"wordCount\":1171,\"commentCount\":0,\"keywords\":[\"arte\",\"Elvino Echeoni\",\"Il Mondo dell'Arte\",\"Novella Parigini\",\"Palazzo Margutta\",\"pittura\",\"Via Margutta\"],\"articleSection\":[\"Arte e cultura\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/arte-e-cultura\\\/a-venti-anni-dalla-scomparsa-il-mondo-della%252580%252599arte-rende-omaggio-a-novella-parigini-con-una-mostra-e-diverse-altre-iniziative-in-calendario-a-palazzo-margutta-dal-21-al-30-novembre\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/arte-e-cultura\\\/a-venti-anni-dalla-scomparsa-il-mondo-della%252580%252599arte-rende-omaggio-a-novella-parigini-con-una-mostra-e-diverse-altre-iniziative-in-calendario-a-palazzo-margutta-dal-21-al-30-novembre\\\/\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/arte-e-cultura\\\/a-venti-anni-dalla-scomparsa-il-mondo-della%252580%252599arte-rende-omaggio-a-novella-parigini-con-una-mostra-e-diverse-altre-iniziative-in-calendario-a-palazzo-margutta-dal-21-al-30-novembre\\\/\",\"name\":\"A Palazzo Margutta il mondo dell\u2019arte omaggia Novella Parigini con una mostra dal 21 al 30 novembre - Article Marketing\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\"},\"datePublished\":\"2013-11-10T16:59:36+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/arte-e-cultura\\\/a-venti-anni-dalla-scomparsa-il-mondo-della%252580%252599arte-rende-omaggio-a-novella-parigini-con-una-mostra-e-diverse-altre-iniziative-in-calendario-a-palazzo-margutta-dal-21-al-30-novembre\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/arte-e-cultura\\\/a-venti-anni-dalla-scomparsa-il-mondo-della%252580%252599arte-rende-omaggio-a-novella-parigini-con-una-mostra-e-diverse-altre-iniziative-in-calendario-a-palazzo-margutta-dal-21-al-30-novembre\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/arte-e-cultura\\\/a-venti-anni-dalla-scomparsa-il-mondo-della%252580%252599arte-rende-omaggio-a-novella-parigini-con-una-mostra-e-diverse-altre-iniziative-in-calendario-a-palazzo-margutta-dal-21-al-30-novembre\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"A Palazzo Margutta il mondo dell\u2019arte omaggia Novella Parigini con una mostra dal 21 al 30 novembre\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\",\"name\":\"Article Marketing\",\"description\":\"article marketing &amp; press release\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\",\"name\":\"Redazione Comunicati Stampa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"caption\":\"Redazione Comunicati Stampa\"},\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/author\\\/redazione-comunicati-stampa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"A Palazzo Margutta il mondo dell\u2019arte omaggia Novella Parigini con una mostra dal 21 al 30 novembre - Article Marketing","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/a-venti-anni-dalla-scomparsa-il-mondo-della%2580%2599arte-rende-omaggio-a-novella-parigini-con-una-mostra-e-diverse-altre-iniziative-in-calendario-a-palazzo-margutta-dal-21-al-30-novembre\/","og_locale":"it_IT","og_type":"article","og_title":"A Palazzo Margutta il mondo dell\u2019arte omaggia Novella Parigini con una mostra dal 21 al 30 novembre - Article Marketing","og_description":"In esposizione, in programma a Via Margutta 55, le opere pi\u00f9 rappresentative della pittrice, ma anche un video in cui l\u2019artista si racconta, una serie di gigantografie che riproducono alcune testate dell\u2019epoca e le lettere nelle quali D\u2019Annunzio consiglia il nome di Novella alla madre dell\u2019artista.","og_url":"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/a-venti-anni-dalla-scomparsa-il-mondo-della%2580%2599arte-rende-omaggio-a-novella-parigini-con-una-mostra-e-diverse-altre-iniziative-in-calendario-a-palazzo-margutta-dal-21-al-30-novembre\/","og_site_name":"Article Marketing","article_published_time":"2013-11-10T16:59:36+00:00","author":"Redazione Comunicati Stampa","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione Comunicati Stampa","Tempo di lettura stimato":"6 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/a-venti-anni-dalla-scomparsa-il-mondo-della%252580%252599arte-rende-omaggio-a-novella-parigini-con-una-mostra-e-diverse-altre-iniziative-in-calendario-a-palazzo-margutta-dal-21-al-30-novembre\/#article","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/a-venti-anni-dalla-scomparsa-il-mondo-della%252580%252599arte-rende-omaggio-a-novella-parigini-con-una-mostra-e-diverse-altre-iniziative-in-calendario-a-palazzo-margutta-dal-21-al-30-novembre\/"},"author":{"name":"Redazione Comunicati Stampa","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"headline":"A Palazzo Margutta il mondo dell\u2019arte omaggia Novella Parigini con una mostra dal 21 al 30 novembre","datePublished":"2013-11-10T16:59:36+00:00","mainEntityOfPage":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/a-venti-anni-dalla-scomparsa-il-mondo-della%252580%252599arte-rende-omaggio-a-novella-parigini-con-una-mostra-e-diverse-altre-iniziative-in-calendario-a-palazzo-margutta-dal-21-al-30-novembre\/"},"wordCount":1171,"commentCount":0,"keywords":["arte","Elvino Echeoni","Il Mondo dell'Arte","Novella Parigini","Palazzo Margutta","pittura","Via Margutta"],"articleSection":["Arte e cultura"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/a-venti-anni-dalla-scomparsa-il-mondo-della%252580%252599arte-rende-omaggio-a-novella-parigini-con-una-mostra-e-diverse-altre-iniziative-in-calendario-a-palazzo-margutta-dal-21-al-30-novembre\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/a-venti-anni-dalla-scomparsa-il-mondo-della%252580%252599arte-rende-omaggio-a-novella-parigini-con-una-mostra-e-diverse-altre-iniziative-in-calendario-a-palazzo-margutta-dal-21-al-30-novembre\/","url":"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/a-venti-anni-dalla-scomparsa-il-mondo-della%252580%252599arte-rende-omaggio-a-novella-parigini-con-una-mostra-e-diverse-altre-iniziative-in-calendario-a-palazzo-margutta-dal-21-al-30-novembre\/","name":"A Palazzo Margutta il mondo dell\u2019arte omaggia Novella Parigini con una mostra dal 21 al 30 novembre - Article Marketing","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website"},"datePublished":"2013-11-10T16:59:36+00:00","author":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"breadcrumb":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/a-venti-anni-dalla-scomparsa-il-mondo-della%252580%252599arte-rende-omaggio-a-novella-parigini-con-una-mostra-e-diverse-altre-iniziative-in-calendario-a-palazzo-margutta-dal-21-al-30-novembre\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/a-venti-anni-dalla-scomparsa-il-mondo-della%252580%252599arte-rende-omaggio-a-novella-parigini-con-una-mostra-e-diverse-altre-iniziative-in-calendario-a-palazzo-margutta-dal-21-al-30-novembre\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/a-venti-anni-dalla-scomparsa-il-mondo-della%252580%252599arte-rende-omaggio-a-novella-parigini-con-una-mostra-e-diverse-altre-iniziative-in-calendario-a-palazzo-margutta-dal-21-al-30-novembre\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.article-marketing.eu\/comunicati\/"},{"@type":"ListItem","position":2,"name":"A Palazzo Margutta il mondo dell\u2019arte omaggia Novella Parigini con una mostra dal 21 al 30 novembre"}]},{"@type":"WebSite","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website","url":"https:\/\/www.article-marketing.eu\/comunicati\/","name":"Article Marketing","description":"article marketing &amp; press release","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.article-marketing.eu\/comunicati\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017","name":"Redazione Comunicati Stampa","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","caption":"Redazione Comunicati Stampa"},"url":"https:\/\/www.article-marketing.eu\/comunicati\/author\/redazione-comunicati-stampa\/"}]}},"_links":{"self":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/38000","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/comments?post=38000"}],"version-history":[{"count":0,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/38000\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/media?parent=38000"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/categories?post=38000"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/tags?post=38000"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}