{"id":38202,"date":"2013-11-19T18:47:13","date_gmt":"2013-11-19T17:47:13","guid":{"rendered":"http:\/\/www.article-marketing.eu\/comunicati\/senza-categoria\/un-viaggio-nella-splendida-tivoli-amata-da-catullo-sallustio-e-orazio-presso-victoria-hotel-terme\/"},"modified":"2013-11-19T18:47:13","modified_gmt":"2013-11-19T17:47:13","slug":"un-viaggio-nella-splendida-tivoli-amata-da-catullo-sallustio-e-orazio-presso-victoria-hotel-terme","status":"publish","type":"post","link":"https:\/\/www.article-marketing.eu\/comunicati\/viaggi-e-vacanze\/un-viaggio-nella-splendida-tivoli-amata-da-catullo-sallustio-e-orazio-presso-victoria-hotel-terme\/","title":{"rendered":"Un viaggio nella splendida Tivoli amata da Catullo, Sallustio e Orazio presso Victoria Hotel Terme"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.trovabenessere.it\/images\/Hotels\/H0059VictoriaTermeHotel\/H0059VictoriaTermeHotel2.jpg\" border=\"0\" alt=\"Un viaggio nella splendida Tivoli tanto amata da Catullo, Sallustio e Orazio presso Victoria Hotel Terme\" width=\"580\" height=\"380\" \/>Situato nell&#8217;incantevole citt&agrave; di Tivoli, gi&agrave; amata dagli antichi e illustri personaggi famosi come Catullo, Mecenate, Sallustio e Orazio, per la mitezza del clima e la bellezza dei luoghi limitrofi. Il Victoria Terme Hotel sapr&agrave; accontentare il pi&ugrave; intimo desiderio di benessere, grazie alle magnifiche attrezzature di cui dispone, fra le quali una piscina termale coperta ed un centro benessere, con servizi in loco di trattamenti per la bellezza del proprio corpo.<br \/>\n<br \/>Leggi tutto su: <a href=\"http:\/\/www.trovabenessere.it\/lazio-hotel\/247-il-maestoso-victoria-terme-hotel-4-stelle-e-situato-nell-incantevole-citta-di-tivoli.html\" target=\"_blank\" title=\"http:\/\/www.trovabenessere.it\/lazio-hotel\/247-il-maestoso-victoria-terme-hotel-4-stelle-e-situato-nell-incantevole-citta-di-tivoli.html\">www.TrovaBenessere.it<\/a><\/p>\n<p>L&rsquo;area wellness &ldquo;La Via del Benessere&rdquo; &egrave; composta da: sauna, bagno turco, idromassaggio lombare cervicale, ascensionale, Vasche kneipp, percorso vascolare, doccia aromatizzata, piscina termale riscaldata, Zona relax, servizio tisaneria. Una parte altrettanto importante per il cliente &egrave; il piacere gustativo, il quale trover&agrave; il giusto appagamento presso il ristorante suggestivo, dove il palato sar&agrave; premiato con assolute delizie, servite durante la colazione, il pranzo e la cena. Dopo quest&#8217;ultima sar&agrave; possibile riposare in una delle camere, complete dei maggiori comfort, nessun dettaglio &egrave; lasciato al caso, dal materasso memory foarm alla possibilit&agrave; di una vasca Jacuzzi, che permetter&agrave; al cliente di farsi coccolare un altro po&#8217; grazie ai frequenti getti di acqua solforosa proveniente dalle Acque Albule.Famose fin dall&#8217;antichit&agrave;, soprattutto ai tempi dell&#8217;imperatore Augusto, le Acque Albule sono le sorgenti sulfuree pi&ugrave; abbondanti del centro Italia, conosciute per il loro colore bianco-bluastro dovuto all&#8217;alta concentrazione di minerali, contenuti insieme al solfuro e al carbonato di calce sono attualmente note all&#8217;interno dell&#8217;omonimo centro termale che offre numerose soluzioni terapeutiche: dalla fango-terapia alla balneoterapia fino all&#8217;idromassaggio termale, e tanti altri trattamenti per diversi disturbi che affaticano il corpo e la mente. Inoltre il cliente ha la possibilit&agrave; di visitare una delle pi&ugrave; maestose e imponenti regge dell&#8217;era romana, Villa Adriana, Villa D&rsquo;Este e Villa Gregoriana, patrimoni dell&rsquo;UNESCO facilmente raggiungibili, per unire anche l&rsquo;imperdibile aspetto culturale. Un indimenticabile soggiorno attende chi sceglier&agrave; di alloggiare nel Victoria Terme Hotel.<\/p>\n<p>Scopri gli Hotels ed i Resort di lusso pi&ugrave; prestigiosi presenti sul territorio italiano, dalle coste calde del Mar Mediterraneo, alla campagna toscana, alle piu&rsquo; conosciute grandi citt&agrave; , fino alle aree montane d&rsquo;eccellenza. TrovaBenessere.it: guida esperta per la cultura d&rsquo;alta classe.Le pi&ugrave; belle Spas d&rsquo;Italia dove l&rsquo;acqua fonte di purificazione e di rigenerazione fa da protagonista!. Qui potrai vivere momenti di totale relax e rigenerare corpo e spirito per un cammino verso il pi&ugrave; puro benessere.Trova Benessere da spazio e valore alle migliori Day Spa, Beauty Farms ed Hotels, Centri Termali e Centri Benessere e Fitness presenti sul territorio italiano ed europeo. Cultura ormai facente parte della nostra quotidianit&agrave;, ma con ancora molto potenziale da esprimere, lo &#8220;star bene&#8221; generalmente inteso, sa catalizzare l&#8217;attenzione di un vastissimo pubblico, sempre pi&ugrave; attento alla cura di s&egrave; e del proprio benessere psico-fisico.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Situato nell&#8217;incantevole citt\u00e0 di Tivoli, gi\u00e0 amata dagli antichi e illustri personaggi famosi come Catullo, Mecenate, Sallustio e Orazio, per la mitezza del clima e la bellezza dei luoghi limitrofi.<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"","footnotes":""},"categories":[280],"tags":[1235,255,251,121],"class_list":["post-38202","post","type-post","status-publish","format-standard","hentry","category-viaggi-e-vacanze","tag-benessere","tag-hotel","tag-roma","tag-terme"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Un viaggio nella splendida Tivoli amata da Catullo, Sallustio e Orazio presso Victoria Hotel Terme - Article Marketing<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.article-marketing.eu\/comunicati\/viaggi-e-vacanze\/un-viaggio-nella-splendida-tivoli-amata-da-catullo-sallustio-e-orazio-presso-victoria-hotel-terme\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Un viaggio nella splendida Tivoli amata da Catullo, Sallustio e Orazio presso Victoria Hotel Terme - Article Marketing\" \/>\n<meta property=\"og:description\" content=\"Situato nell&#039;incantevole citt\u00e0 di Tivoli, gi\u00e0 amata dagli antichi e illustri personaggi famosi come Catullo, Mecenate, Sallustio e Orazio, per la mitezza del clima e la bellezza dei luoghi limitrofi.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.article-marketing.eu\/comunicati\/viaggi-e-vacanze\/un-viaggio-nella-splendida-tivoli-amata-da-catullo-sallustio-e-orazio-presso-victoria-hotel-terme\/\" \/>\n<meta property=\"og:site_name\" content=\"Article Marketing\" \/>\n<meta property=\"article:published_time\" content=\"2013-11-19T17:47:13+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.trovabenessere.it\/images\/Hotels\/H0059VictoriaTermeHotel\/H0059VictoriaTermeHotel2.jpg\" \/>\n<meta name=\"author\" content=\"Redazione Comunicati Stampa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione Comunicati Stampa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/viaggi-e-vacanze\\\/un-viaggio-nella-splendida-tivoli-amata-da-catullo-sallustio-e-orazio-presso-victoria-hotel-terme\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/viaggi-e-vacanze\\\/un-viaggio-nella-splendida-tivoli-amata-da-catullo-sallustio-e-orazio-presso-victoria-hotel-terme\\\/\"},\"author\":{\"name\":\"Redazione Comunicati Stampa\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"headline\":\"Un viaggio nella splendida Tivoli amata da Catullo, Sallustio e Orazio presso Victoria Hotel Terme\",\"datePublished\":\"2013-11-19T17:47:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/viaggi-e-vacanze\\\/un-viaggio-nella-splendida-tivoli-amata-da-catullo-sallustio-e-orazio-presso-victoria-hotel-terme\\\/\"},\"wordCount\":512,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/viaggi-e-vacanze\\\/un-viaggio-nella-splendida-tivoli-amata-da-catullo-sallustio-e-orazio-presso-victoria-hotel-terme\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.trovabenessere.it\\\/images\\\/Hotels\\\/H0059VictoriaTermeHotel\\\/H0059VictoriaTermeHotel2.jpg\",\"keywords\":[\"benessere\",\"hotel\",\"roma\",\"terme\"],\"articleSection\":[\"Viaggi e vacanze\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/viaggi-e-vacanze\\\/un-viaggio-nella-splendida-tivoli-amata-da-catullo-sallustio-e-orazio-presso-victoria-hotel-terme\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/viaggi-e-vacanze\\\/un-viaggio-nella-splendida-tivoli-amata-da-catullo-sallustio-e-orazio-presso-victoria-hotel-terme\\\/\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/viaggi-e-vacanze\\\/un-viaggio-nella-splendida-tivoli-amata-da-catullo-sallustio-e-orazio-presso-victoria-hotel-terme\\\/\",\"name\":\"Un viaggio nella splendida Tivoli amata da Catullo, Sallustio e Orazio presso Victoria Hotel Terme - Article Marketing\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/viaggi-e-vacanze\\\/un-viaggio-nella-splendida-tivoli-amata-da-catullo-sallustio-e-orazio-presso-victoria-hotel-terme\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/viaggi-e-vacanze\\\/un-viaggio-nella-splendida-tivoli-amata-da-catullo-sallustio-e-orazio-presso-victoria-hotel-terme\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.trovabenessere.it\\\/images\\\/Hotels\\\/H0059VictoriaTermeHotel\\\/H0059VictoriaTermeHotel2.jpg\",\"datePublished\":\"2013-11-19T17:47:13+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/viaggi-e-vacanze\\\/un-viaggio-nella-splendida-tivoli-amata-da-catullo-sallustio-e-orazio-presso-victoria-hotel-terme\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/viaggi-e-vacanze\\\/un-viaggio-nella-splendida-tivoli-amata-da-catullo-sallustio-e-orazio-presso-victoria-hotel-terme\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/viaggi-e-vacanze\\\/un-viaggio-nella-splendida-tivoli-amata-da-catullo-sallustio-e-orazio-presso-victoria-hotel-terme\\\/#primaryimage\",\"url\":\"http:\\\/\\\/www.trovabenessere.it\\\/images\\\/Hotels\\\/H0059VictoriaTermeHotel\\\/H0059VictoriaTermeHotel2.jpg\",\"contentUrl\":\"http:\\\/\\\/www.trovabenessere.it\\\/images\\\/Hotels\\\/H0059VictoriaTermeHotel\\\/H0059VictoriaTermeHotel2.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/viaggi-e-vacanze\\\/un-viaggio-nella-splendida-tivoli-amata-da-catullo-sallustio-e-orazio-presso-victoria-hotel-terme\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Un viaggio nella splendida Tivoli amata da Catullo, Sallustio e Orazio presso Victoria Hotel Terme\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\",\"name\":\"Article Marketing\",\"description\":\"article marketing &amp; press release\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\",\"name\":\"Redazione Comunicati Stampa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"caption\":\"Redazione Comunicati Stampa\"},\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/author\\\/redazione-comunicati-stampa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Un viaggio nella splendida Tivoli amata da Catullo, Sallustio e Orazio presso Victoria Hotel Terme - Article Marketing","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.article-marketing.eu\/comunicati\/viaggi-e-vacanze\/un-viaggio-nella-splendida-tivoli-amata-da-catullo-sallustio-e-orazio-presso-victoria-hotel-terme\/","og_locale":"it_IT","og_type":"article","og_title":"Un viaggio nella splendida Tivoli amata da Catullo, Sallustio e Orazio presso Victoria Hotel Terme - Article Marketing","og_description":"Situato nell'incantevole citt\u00e0 di Tivoli, gi\u00e0 amata dagli antichi e illustri personaggi famosi come Catullo, Mecenate, Sallustio e Orazio, per la mitezza del clima e la bellezza dei luoghi limitrofi.","og_url":"https:\/\/www.article-marketing.eu\/comunicati\/viaggi-e-vacanze\/un-viaggio-nella-splendida-tivoli-amata-da-catullo-sallustio-e-orazio-presso-victoria-hotel-terme\/","og_site_name":"Article Marketing","article_published_time":"2013-11-19T17:47:13+00:00","og_image":[{"url":"http:\/\/www.trovabenessere.it\/images\/Hotels\/H0059VictoriaTermeHotel\/H0059VictoriaTermeHotel2.jpg","type":"","width":"","height":""}],"author":"Redazione Comunicati Stampa","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione Comunicati Stampa","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.article-marketing.eu\/comunicati\/viaggi-e-vacanze\/un-viaggio-nella-splendida-tivoli-amata-da-catullo-sallustio-e-orazio-presso-victoria-hotel-terme\/#article","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/viaggi-e-vacanze\/un-viaggio-nella-splendida-tivoli-amata-da-catullo-sallustio-e-orazio-presso-victoria-hotel-terme\/"},"author":{"name":"Redazione Comunicati Stampa","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"headline":"Un viaggio nella splendida Tivoli amata da Catullo, Sallustio e Orazio presso Victoria Hotel Terme","datePublished":"2013-11-19T17:47:13+00:00","mainEntityOfPage":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/viaggi-e-vacanze\/un-viaggio-nella-splendida-tivoli-amata-da-catullo-sallustio-e-orazio-presso-victoria-hotel-terme\/"},"wordCount":512,"commentCount":0,"image":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/viaggi-e-vacanze\/un-viaggio-nella-splendida-tivoli-amata-da-catullo-sallustio-e-orazio-presso-victoria-hotel-terme\/#primaryimage"},"thumbnailUrl":"http:\/\/www.trovabenessere.it\/images\/Hotels\/H0059VictoriaTermeHotel\/H0059VictoriaTermeHotel2.jpg","keywords":["benessere","hotel","roma","terme"],"articleSection":["Viaggi e vacanze"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.article-marketing.eu\/comunicati\/viaggi-e-vacanze\/un-viaggio-nella-splendida-tivoli-amata-da-catullo-sallustio-e-orazio-presso-victoria-hotel-terme\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.article-marketing.eu\/comunicati\/viaggi-e-vacanze\/un-viaggio-nella-splendida-tivoli-amata-da-catullo-sallustio-e-orazio-presso-victoria-hotel-terme\/","url":"https:\/\/www.article-marketing.eu\/comunicati\/viaggi-e-vacanze\/un-viaggio-nella-splendida-tivoli-amata-da-catullo-sallustio-e-orazio-presso-victoria-hotel-terme\/","name":"Un viaggio nella splendida Tivoli amata da Catullo, Sallustio e Orazio presso Victoria Hotel Terme - Article Marketing","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/viaggi-e-vacanze\/un-viaggio-nella-splendida-tivoli-amata-da-catullo-sallustio-e-orazio-presso-victoria-hotel-terme\/#primaryimage"},"image":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/viaggi-e-vacanze\/un-viaggio-nella-splendida-tivoli-amata-da-catullo-sallustio-e-orazio-presso-victoria-hotel-terme\/#primaryimage"},"thumbnailUrl":"http:\/\/www.trovabenessere.it\/images\/Hotels\/H0059VictoriaTermeHotel\/H0059VictoriaTermeHotel2.jpg","datePublished":"2013-11-19T17:47:13+00:00","author":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"breadcrumb":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/viaggi-e-vacanze\/un-viaggio-nella-splendida-tivoli-amata-da-catullo-sallustio-e-orazio-presso-victoria-hotel-terme\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.article-marketing.eu\/comunicati\/viaggi-e-vacanze\/un-viaggio-nella-splendida-tivoli-amata-da-catullo-sallustio-e-orazio-presso-victoria-hotel-terme\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.article-marketing.eu\/comunicati\/viaggi-e-vacanze\/un-viaggio-nella-splendida-tivoli-amata-da-catullo-sallustio-e-orazio-presso-victoria-hotel-terme\/#primaryimage","url":"http:\/\/www.trovabenessere.it\/images\/Hotels\/H0059VictoriaTermeHotel\/H0059VictoriaTermeHotel2.jpg","contentUrl":"http:\/\/www.trovabenessere.it\/images\/Hotels\/H0059VictoriaTermeHotel\/H0059VictoriaTermeHotel2.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.article-marketing.eu\/comunicati\/viaggi-e-vacanze\/un-viaggio-nella-splendida-tivoli-amata-da-catullo-sallustio-e-orazio-presso-victoria-hotel-terme\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.article-marketing.eu\/comunicati\/"},{"@type":"ListItem","position":2,"name":"Un viaggio nella splendida Tivoli amata da Catullo, Sallustio e Orazio presso Victoria Hotel Terme"}]},{"@type":"WebSite","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website","url":"https:\/\/www.article-marketing.eu\/comunicati\/","name":"Article Marketing","description":"article marketing &amp; press release","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.article-marketing.eu\/comunicati\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017","name":"Redazione Comunicati Stampa","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","caption":"Redazione Comunicati Stampa"},"url":"https:\/\/www.article-marketing.eu\/comunicati\/author\/redazione-comunicati-stampa\/"}]}},"_links":{"self":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/38202","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/comments?post=38202"}],"version-history":[{"count":0,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/38202\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/media?parent=38202"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/categories?post=38202"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/tags?post=38202"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}