{"id":38341,"date":"2013-12-18T16:42:57","date_gmt":"2013-12-18T15:42:57","guid":{"rendered":"http:\/\/www.article-marketing.eu\/comunicati\/senza-categoria\/article_6-19\/"},"modified":"2013-12-18T16:42:57","modified_gmt":"2013-12-18T15:42:57","slug":"article_6-19","status":"publish","type":"post","link":"https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/article_6-19\/","title":{"rendered":"Le cure termali della cittadina di Abano terme apportano benefici ed effetti terapeutici per anziani e per i bambini"},"content":{"rendered":"<p>Le <strong style=\"margin: 0px; padding: 0px;\">cure termali<\/strong> ad Abano e nelle molteplici citt&agrave; e localit&agrave; termali della nostra penisola sono dei offrono dei trattamenti con finalit&agrave; terapeutiche e curative, disintossicanti o riabilitative, che sfruttano i benefici effetti della <strong style=\"margin: 0px; padding: 0px;\">acque sorgive<\/strong>, le cui propriet&agrave; terapeutiche dipendono dai loro elementi costituenti, tra cui zolfo, iodio, cloro, ferro, elementi di calcio e microelementi di altre sostanze, dalla temperatura naturale, dalle caratteristiche chimiche e fisiche e dalla qualit&agrave; chimico-fisiche.<br \/>Il metodo di cura attraverso le acque termali viene definito <strong style=\"margin: 0px; padding: 0px;\">crenoterapia (<\/strong>dal greco<em style=\"margin: 0px; padding: 0px;\">cren&eacute; <\/em>&ndash; sorgente) e si divide in due tipologie: interna ed esterna. La crenoterapia interna avviene attraverso l&rsquo;assunzione dell&rsquo;acqua minerale termale, mentre la crenoterapia esterna, la pi&ugrave; nota, utilizza la balneoterapia, i fanghi e le grotte.<br \/>Le <strong style=\"margin: 0px; padding: 0px;\">acque termali<\/strong> di Abano terme vengono assunte, infatti, sia per via orale che utilizzate sottoforma di bagni, fanghi, aerosol e irrigazioni. Le patologie osteoarticolari, respiratorie, dermatologiche, ginecologiche, gastroenteriche, a carico dell&rsquo;apparato urinario sono tra quelle che traggono maggiori vantaggi dai trattamenti termali. Si ricorre alle cure termali proprio in caso di affezioni all&rsquo;apparato respiratorio, quali asma, bronchite, sinusite, patologie della pelle, quali eczemi e psoriasi, malattie del sistema osteoarticolare, come l&rsquo;artrosi, o disfunzioni delle vie urinarie, calcolosi, e del sistema digestivo, dispepsia.<br \/>Nello specifico le acque termali vengono utilizzate nella cura delle patologie piu disparate a carico del sistema respiratoro ed osteo articolare, ma con finalit&agrave; preventive e disintossicanti, l le principali patologie ed ambiti di applicazione riguardano quindi le vie respiratorie, le cure osteoarticolari e ginecologiche, nonch&egrave; per la cura della pelle, in caso di eczema, dermatiti e altre eruzioni cutanee. Le <strong style=\"margin: 0px; padding: 0px;\">acque bicarbonate<\/strong>, per l&rsquo;alto potere disintossicante, alleviano i sintomi di disturbi come gastrite, calcolosi, gotta, malattie del fegato, diabete. Le <strong style=\"margin: 0px; padding: 0px;\">acque cloruro-sodiche<\/strong> contrastano le malattie del fegato, gastrite, la colite e la stitichezza. Infine le <strong style=\"margin: 0px; padding: 0px;\">acque arsenicali e ferruginose<\/strong> sono molto benefiche in caso di malattie della pelle e anemia.<br \/>Durante le cure, di qualsiasi natura esse siano, l&rsquo;organismo &egrave; sicuramente sottoposto ad una forte azione di stimolo, come dimostrato dalla cosiddetta &ldquo;crisi termale&rdquo; che interviene dopo qualche giorno dall&rsquo;inizio della terapia. Inoltre, pur se gli effetti positivi possono farsi sentire entro breve tempo, affinch&eacute; la cura sia davvero efficace dovrebbe avere una durata media di almeno dieci giorni e andrebbe ripetuta per alcuni anni.<br \/>I <strong style=\"margin: 0px; padding: 0px;\">benefici delle terme<\/strong> vanno oltre quelli specificatamente sanitari, investendo l&rsquo;individuo nel suo complesso equilibrio psicofisico e promuovendo un benessere globale. Le terapie, infatti, vengono recepite positivamente dall&rsquo;organismo, contribuendo a determinarne la risoluzione delle patologie e la loro corretta gestione anche a livello psichico.<br \/>Le cure termali ad Abano terme hanno benefici effetti anche nella cura di specifiche patologie nei <strong style=\"margin: 0px; padding: 0px;\">bambini<\/strong>. Le acque termali agiscono sulla mucosa bronchiale rendendo il muco pi&ugrave; fluido, e quindi pi&ugrave; facilmente espettorabile, e agiscono benevolmente sulla produzione di immunoglobuline, stimolando, per esempio, la produzione di<em style=\"margin: 0px; padding: 0px;\">IgA <\/em>(immunoglobuline A), notoriamente carenti fino al terzo anno di et&agrave;, e inibendo la produzione di <em style=\"margin: 0px; padding: 0px;\">IgE<\/em>(immunoglobuline E), notoriamente in eccesso nei bambini allergici o iperreattivi. Inoltre, i frequenti episodi infettivi delle prime vie respiratorie tendono ad esaurire le poche scorte di IgA fisiologicamente presenti nella prima infanzia. La terapia inalatoria con acque termali tenderebbe a ripristinarne la giusta concentrazione.<br \/>Una struttura consigliata per le cure ad Abano Terme : <a href=\"http:\/\/www.europaterme.it\">www.europaterme.it<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le cure termali ad Abano e nelle molteplici citt\u00e0 e localit\u00e0 termali della nostra penisola sono dei offrono dei trattamenti con finalit\u00e0 terapeutiche e curative, disintossicanti o riabilitative, che sfruttano i benefici effetti della acque sorgive, le cui propriet\u00e0 terapeutiche dipendono dai loro elementi costituenti, tra cui zolfo, iodio, cloro, ferro, elementi di calcio e microelementi di altre sostanze, dalla temperatura naturale, dalle caratteristiche chimiche e fisiche e dalla qualit\u00e0 chimico-fisiche.<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"","footnotes":""},"categories":[265],"tags":[8596,16025,45659,45660,45658,6003],"class_list":["post-38341","post","type-post","status-publish","format-standard","hentry","category-salute-e-benessere","tag-abano-terme","tag-cure-termali","tag-fanghi-termali","tag-strutture-termali","tag-trattamenti-termali","tag-veneto"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Le cure termali della cittadina di Abano terme apportano benefici ed effetti terapeutici per anziani e per i bambini - Article Marketing<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/article_6-19\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le cure termali della cittadina di Abano terme apportano benefici ed effetti terapeutici per anziani e per i bambini - Article Marketing\" \/>\n<meta property=\"og:description\" content=\"Le cure termali ad Abano e nelle molteplici citt\u00e0 e localit\u00e0 termali della nostra penisola sono dei offrono dei trattamenti con finalit\u00e0 terapeutiche e curative, disintossicanti o riabilitative, che sfruttano i benefici effetti della acque sorgive, le cui propriet\u00e0 terapeutiche dipendono dai loro elementi costituenti, tra cui zolfo, iodio, cloro, ferro, elementi di calcio e microelementi di altre sostanze, dalla temperatura naturale, dalle caratteristiche chimiche e fisiche e dalla qualit\u00e0 chimico-fisiche.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/article_6-19\/\" \/>\n<meta property=\"og:site_name\" content=\"Article Marketing\" \/>\n<meta property=\"article:published_time\" content=\"2013-12-18T15:42:57+00:00\" \/>\n<meta name=\"author\" content=\"Redazione Comunicati Stampa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione Comunicati Stampa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/salute-e-benessere\\\/article_6-19\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/salute-e-benessere\\\/article_6-19\\\/\"},\"author\":{\"name\":\"Redazione Comunicati Stampa\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"headline\":\"Le cure termali della cittadina di Abano terme apportano benefici ed effetti terapeutici per anziani e per i bambini\",\"datePublished\":\"2013-12-18T15:42:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/salute-e-benessere\\\/article_6-19\\\/\"},\"wordCount\":595,\"commentCount\":0,\"keywords\":[\"abano terme\",\"cure termali\",\"fanghi termali\",\"strutture termali\",\"trattamenti termali\",\"veneto\"],\"articleSection\":[\"Salute e benessere\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/salute-e-benessere\\\/article_6-19\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/salute-e-benessere\\\/article_6-19\\\/\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/salute-e-benessere\\\/article_6-19\\\/\",\"name\":\"Le cure termali della cittadina di Abano terme apportano benefici ed effetti terapeutici per anziani e per i bambini - Article Marketing\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\"},\"datePublished\":\"2013-12-18T15:42:57+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/salute-e-benessere\\\/article_6-19\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/salute-e-benessere\\\/article_6-19\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/salute-e-benessere\\\/article_6-19\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Le cure termali della cittadina di Abano terme apportano benefici ed effetti terapeutici per anziani e per i bambini\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\",\"name\":\"Article Marketing\",\"description\":\"article marketing &amp; press release\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\",\"name\":\"Redazione Comunicati Stampa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"caption\":\"Redazione Comunicati Stampa\"},\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/author\\\/redazione-comunicati-stampa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Le cure termali della cittadina di Abano terme apportano benefici ed effetti terapeutici per anziani e per i bambini - Article Marketing","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/article_6-19\/","og_locale":"it_IT","og_type":"article","og_title":"Le cure termali della cittadina di Abano terme apportano benefici ed effetti terapeutici per anziani e per i bambini - Article Marketing","og_description":"Le cure termali ad Abano e nelle molteplici citt\u00e0 e localit\u00e0 termali della nostra penisola sono dei offrono dei trattamenti con finalit\u00e0 terapeutiche e curative, disintossicanti o riabilitative, che sfruttano i benefici effetti della acque sorgive, le cui propriet\u00e0 terapeutiche dipendono dai loro elementi costituenti, tra cui zolfo, iodio, cloro, ferro, elementi di calcio e microelementi di altre sostanze, dalla temperatura naturale, dalle caratteristiche chimiche e fisiche e dalla qualit\u00e0 chimico-fisiche.","og_url":"https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/article_6-19\/","og_site_name":"Article Marketing","article_published_time":"2013-12-18T15:42:57+00:00","author":"Redazione Comunicati Stampa","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione Comunicati Stampa","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/article_6-19\/#article","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/article_6-19\/"},"author":{"name":"Redazione Comunicati Stampa","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"headline":"Le cure termali della cittadina di Abano terme apportano benefici ed effetti terapeutici per anziani e per i bambini","datePublished":"2013-12-18T15:42:57+00:00","mainEntityOfPage":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/article_6-19\/"},"wordCount":595,"commentCount":0,"keywords":["abano terme","cure termali","fanghi termali","strutture termali","trattamenti termali","veneto"],"articleSection":["Salute e benessere"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/article_6-19\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/article_6-19\/","url":"https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/article_6-19\/","name":"Le cure termali della cittadina di Abano terme apportano benefici ed effetti terapeutici per anziani e per i bambini - Article Marketing","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website"},"datePublished":"2013-12-18T15:42:57+00:00","author":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"breadcrumb":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/article_6-19\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/article_6-19\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/article_6-19\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.article-marketing.eu\/comunicati\/"},{"@type":"ListItem","position":2,"name":"Le cure termali della cittadina di Abano terme apportano benefici ed effetti terapeutici per anziani e per i bambini"}]},{"@type":"WebSite","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website","url":"https:\/\/www.article-marketing.eu\/comunicati\/","name":"Article Marketing","description":"article marketing &amp; press release","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.article-marketing.eu\/comunicati\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017","name":"Redazione Comunicati Stampa","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","caption":"Redazione Comunicati Stampa"},"url":"https:\/\/www.article-marketing.eu\/comunicati\/author\/redazione-comunicati-stampa\/"}]}},"_links":{"self":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/38341","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/comments?post=38341"}],"version-history":[{"count":0,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/38341\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/media?parent=38341"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/categories?post=38341"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/tags?post=38341"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}