{"id":38428,"date":"2014-01-22T12:40:54","date_gmt":"2014-01-22T11:40:54","guid":{"rendered":"http:\/\/www.article-marketing.eu\/comunicati\/senza-categoria\/rockwell-automation-amplia-il-suo-portafoglio-di-prodotti-dedicati-alle-infrastrutture-di-rete-per-aiutare-i-tecnici-nella-progettazione-di-reti-industriali-pi%c3%b9-sicure-ed-affidabili-2\/"},"modified":"2014-01-22T12:40:54","modified_gmt":"2014-01-22T11:40:54","slug":"rockwell-automation-amplia-il-suo-portafoglio-di-prodotti-dedicati-alle-infrastrutture-di-rete-per-aiutare-i-tecnici-nella-progettazione-di-reti-industriali-pi%c3%b9-sicure-ed-affidabili-2","status":"publish","type":"post","link":"https:\/\/www.article-marketing.eu\/comunicati\/computer\/software\/rockwell-automation-amplia-il-suo-portafoglio-di-prodotti-dedicati-alle-infrastrutture-di-rete-per-aiutare-i-tecnici-nella-progettazione-di-reti-industriali-pi%c3%b9-sicure-ed-affidabili-2\/","title":{"rendered":"Rockwell Automation amplia il suo portafoglio di prodotti dedicati alle infrastrutture di rete per aiutare i tecnici nella progettazione di reti industriali pi\u00f9 sicure ed affidabili"},"content":{"rendered":"<p>Milano, 22 gennaio 2014 &#8211; Rockwell Automation amplia la sua famiglia di switch e router industriali Allen- Bradley Stratix e annuncia nuovi prodotti wireless e dedicati alla sicurezza, progettati per soddisfare le esigenze di rete dell&rsquo;industria. Tra le estensioni: Stratix 5700 per la gestione di switch Ethernet industriali che incorpora funzionalit&agrave; di traduzione degli indirizzi di rete (NAT- Network Address Translation), il router a servizi integrati Stratix 5900, nuove opzioni per fibra ottica e Power over Ethernet (PoE) per gli switch Stratix 5700, Stratix 8000 e Stratix 8300. Tra i nuovi prodotti in arrivo nei primi mesi del 2014, ci sono lo switch Allen- Bradley ArmorStratix 5700 e l&rsquo;Access Point wireless Stratix 5100. Questa importante espansione del portfolio consentir&agrave; ai produttori di costruire infrastrutture di rete pi&ugrave; unificate, sicure ed economicamente convenienti, partendo dai sistemi aziendali fino ad arrivare ai terminali usati in produzione.<\/p>\n<p>&#8220;Le aziende stanno migrando verso reti EtherNet\/IP standard per sfruttare meglio le tecnologie e le funzionalit&agrave; di big data, cloud computing e virtualizzazione &#8220;, dichiara Rachael Conrad, business manager, Reti e Sicurezza, Rockwell Automation. &#8220;Questa tendenza verso le reti EtherNet\/IP ha messo anche in evidenza l&#8217;importanza di disporre di un ambiente globale protetto che va dai sistemi aziendali fino ai terminali.&#8221;<br \/>Grazie all&rsquo;utilizzo del software leader mondiale nelle infrastrutture di rete, Cisco IOS, il portafoglio Stratix offre un&rsquo;integrazione pi&ugrave; affidabile di servizi business-critical e un maggiore supporto che va dalla produzione fino ai sistemi aziendali.<\/p>\n<p>&#8220;Abbiamo notato che i progetti di Ethernet industriale &#8211; compresa la selezione e l&#8217;installazione di switch Ethernet &ndash; sono sempre pi&ugrave; una responsabilit&agrave; condivisa tra i tecnici del controllo di sistema e quelli di rete&#8221;, sostiene Bryan Tantzen, senior director , Internet of Things group, Cisco Systems. &#8220;Questa condivisione &egrave; una delle ragioni della collaborazione tra Cisco e Rockwell Automation che ha lo scopo di fornire soluzioni progettate per soddisfare le richieste di entrambi. Il portafoglio Stratix consente loro di utilizzare gli strumenti di Cisco e Rockwell Automation gi&agrave; conosciuti per consentire una gestione pi&ugrave; semplice .&#8221;<\/p>\n<p>La gamma completa di switch Ethernet industriali Stratix verr&agrave; presentata nel corso della <a href=\"http:\/\/www.rockwellautomation.com\/events\/automation-fair\/overview.page?utm_source=padillacrt-newsrelease5&amp;utm_medium=email&amp;utm_content=textlink-automationfairoverview&amp;utm_campaign=PadillaCRT-NewsRelease\">Automation Fair<\/a>, l&#8217;evento annuale di Rockwell Automaton. <\/p>\n<p><strong>Lo switch Stratix 5700 con funzionalit&agrave; di traduzione degli indirizzi di rete (NAT) <\/strong>&#8211; Molti costruttori di macchine (OEM) hanno adottato EtherNet \/ IP per le loro reti di macchine al fine di semplificare la difficile integrazione di queste in una rete pi&ugrave; ampia. Lo switch Ethernet industriale Stratix 5700 con funzionalit&agrave; NAT consente elevate prestazioni e l&#8217;integrazione semplificata delle mappe di indirizzi IP, da un insieme di indirizzi IP a livello di computer locali alla pi&ugrave; ampia rete dell&#8217;impianto dell&#8217;utente finale. Grazie alle funzionalit&agrave; NAT, &egrave; possibile fornire macchine standard che gli utenti possono facilmente installare e collegare insieme senza dover specificare indirizzi IP univoci ai costruttori di macchine.<br \/><strong> <\/strong><br \/><strong>Il router di servizi Stratix 5900<\/strong> &#8211; Il primo router a servizi integrati incluso nel portafoglio di infrastrutture di rete Rockwell Automation; fornisce servizi di routing e di sicurezza esclusivi per reti di livello 2 o 3. In un unico prodotto sono disponibili una rete privata virtuale ( VPN ), firewall e funzionalit&agrave; NAT. Queste funzionalit&agrave; consentono al router Stratix 5900 di fornire collegamenti protetti da una rete sicura a un sito remoto utilizzando una connessione VPN site-to-site attraverso una rete e una rete non sicura. Il firewall &egrave;, inoltre, in grado di offrire un ulteriore livello di protezione tra le macchine e la rete di impianto, e pu&ograve; aiutare il costruttore a integrare e salvaguardare le prestazioni della macchina quando &egrave; collegata ad una rete d&rsquo;impianto pi&ugrave; grande.<\/p>\n<p><strong>Power over Ethernet ( PoE) e funzionalit&agrave; potenziate per fibra ottica<\/strong> &#8211; Mentre il numero di dispositivi collegati ad un impianto continua a crescere, l&rsquo;alimentazione energetica e i cavi di rete diventano sempre pi&ugrave; costosi e di difficile implementazione, tanto da limitare la flessibilit&agrave; del processo produttivo. PoE e PoE+ forniscono connettivit&agrave; Ethernet e alimentazione a un dispositivo finale utilizzando lo stesso cavo. Questo consente di ridurre i costi di cablaggio e di migliorare nel contempo la flessibilit&agrave; di gestione degli impianti, consentendo alle macchine e ai dispositivi di essere facilmente spostati e riconfigurati senza dover utilizzare nuovi cavi di alimentazione o di rete, che oltre ad essere costosi possono richiedere del tempo per la loro implementazione. PoE &egrave; l&rsquo;ideale per collegare dei dispositivi (ad esempio, punti di accesso wireless , telecamere IP, telefoni e scanner di codici a barre ).<\/p>\n<p>Pu&ograve; anche essere difficile valutare la distanza di installazione dei dispositivi: quelli che utilizzano cavi in rame in genere devono essere distanti non pi&ugrave; di 100 metri l&#8217;uno dall&#8217;altro, limitando lo spazio in cui questi possono essere installati nell&#8217;impianto o in un sito. L&rsquo;utilizzo della fibra amplia notevolmente la capacit&agrave; di connessione tra i dispositivi . Lo switch Stratix 5700 offre ora sei porte per fibra ottica, mentre Stratix 8000 e Stratix 8300 sono ora dotati di quattro e otto porte con moduli di espansione small form &#8211; factor pluggable ( SFP ), fino a un massimo di 14 porte. I prodotti Stratix fanno uso della tecnologia transceiver SFP per la connettivit&agrave; in fibra ottica, che pu&ograve; supportare qualsiasi combinazione di fibre singole e multimodali, massimizzando la flessibilit&agrave; di implementazione degli switch in un impianto.<\/p>\n<p><strong>Lo switch ArmorStratix 5700<\/strong> &ndash; Dotato di protezione IP67 rinforzata, lo switch ArmorStratix 5700 pu&ograve; essere montato all&#8217;esterno del quadro elettrico riducendone le dimensioni complessive e i costi, nonch&eacute; l&rsquo;ingombro. Con configurazioni da otto a 24 porte , lo switch ArmorStratix 5700 fornisce inoltre opzioni per Giga and Power over Ethernet ( PoE ) a 10 e 18 porte . Utilizza gli stessi IOS e set di funzionalit&agrave; della famiglia di switch Stratix 5700.<\/p>\n<p><strong>Acccess Point wireless Stratix 5100<\/strong> &#8211; Negli ambienti di produzione, l&rsquo;uso del wireless si &egrave; esteso oltre la posta elettronica di un PC, configurazioni, ecc ed &egrave; ora usato anche per applicazioni &#8220;mission critical&#8221; o real-time. L&rsquo;Access Point wireless Stratix 5100 sfrutta lo standard wireless 802.11N che fornisce multiple-input e multiple -output (MIMO) , dual-band 2,4 GHz e 5 GHz radio, e l&#8217;aggregazione dei pacchetti per una maggiore velocit&agrave;, affidabilit&agrave; , flessibilit&agrave; e segmentazione necessarie nelle applicazioni in real-time. L&rsquo;Access Point wireless Stratix 5100 &egrave; ideale per soluzioni autonome o point- to-point, dove la manutenzione dei cavi di rete in uso pu&ograve; essere difficile e costosa.<\/p>\n<p><strong>Per ulteriori informazioni:<\/strong><br \/>&middot; Stratix Family High-Resolution Graphic<strong>:<\/strong><br \/>http:\/\/flic.kr\/p\/h84Dpj<br \/><strong> <\/strong><br \/>&middot; La famiglia di switch e router industriali Allen- Bradley Stratix <strong><\/strong><br \/>http:\/\/ab.rockwellautomation.com\/Networks-and-Communications\/Ethernet-IP-Infrastructure#\/tab3<strong><\/strong><br \/><strong> <\/strong><\/p>\n<p>Rockwell Automation, (NYSE: ROK), &egrave; leader mondiale nella fornitura soluzioni per l&rsquo;automazione, per il controllo e per l&rsquo;IT che aiutano i produttori a ottenere vantaggio competitivo nel proprio business in modo sostenibile. Con sede a Milwaukee, Wisconsin, USA, la societ&agrave; impiega circa 22.000 dipendenti e serve clienti in pi&ugrave; di 80 paesi.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La linea degli switch ora comprende un router a servizi integrati, la traduzione degli indirizzi di rete, Power over Ethernet e funzionalit\u00e0 potenziate per le trasmissioni su fibra<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"","footnotes":""},"categories":[123],"tags":[45708,42947,9662,43528,45709,19453,43529,4257,28226,45706,1649,42946,45707],"class_list":["post-38428","post","type-post","status-publish","format-standard","hentry","category-software","tag-allen","tag-automation","tag-automazione","tag-big","tag-bradley","tag-cloud","tag-data","tag-fibra","tag-ottica","tag-power-over-the-internet","tag-reti","tag-rockwell","tag-statix"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Rockwell Automation amplia il suo portafoglio di prodotti dedicati alle infrastrutture di rete per aiutare i tecnici nella progettazione di reti industriali pi\u00f9 sicure ed affidabili - Article Marketing<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.article-marketing.eu\/comunicati\/computer\/software\/rockwell-automation-amplia-il-suo-portafoglio-di-prodotti-dedicati-alle-infrastrutture-di-rete-per-aiutare-i-tecnici-nella-progettazione-di-reti-industriali-pi\u00f9-sicure-ed-affidabili-2\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rockwell Automation amplia il suo portafoglio di prodotti dedicati alle infrastrutture di rete per aiutare i tecnici nella progettazione di reti industriali pi\u00f9 sicure ed affidabili - Article Marketing\" \/>\n<meta property=\"og:description\" content=\"La linea degli switch ora comprende un router a servizi integrati, la traduzione degli indirizzi di rete, Power over Ethernet e funzionalit\u00e0 potenziate per le trasmissioni su fibra\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.article-marketing.eu\/comunicati\/computer\/software\/rockwell-automation-amplia-il-suo-portafoglio-di-prodotti-dedicati-alle-infrastrutture-di-rete-per-aiutare-i-tecnici-nella-progettazione-di-reti-industriali-pi\u00f9-sicure-ed-affidabili-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Article Marketing\" \/>\n<meta property=\"article:published_time\" content=\"2014-01-22T11:40:54+00:00\" \/>\n<meta name=\"author\" content=\"Redazione Comunicati Stampa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione Comunicati Stampa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/computer\\\/software\\\/rockwell-automation-amplia-il-suo-portafoglio-di-prodotti-dedicati-alle-infrastrutture-di-rete-per-aiutare-i-tecnici-nella-progettazione-di-reti-industriali-pi%c3%b9-sicure-ed-affidabili-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/computer\\\/software\\\/rockwell-automation-amplia-il-suo-portafoglio-di-prodotti-dedicati-alle-infrastrutture-di-rete-per-aiutare-i-tecnici-nella-progettazione-di-reti-industriali-pi%c3%b9-sicure-ed-affidabili-2\\\/\"},\"author\":{\"name\":\"Redazione Comunicati Stampa\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"headline\":\"Rockwell Automation amplia il suo portafoglio di prodotti dedicati alle infrastrutture di rete per aiutare i tecnici nella progettazione di reti industriali pi\u00f9 sicure ed affidabili\",\"datePublished\":\"2014-01-22T11:40:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/computer\\\/software\\\/rockwell-automation-amplia-il-suo-portafoglio-di-prodotti-dedicati-alle-infrastrutture-di-rete-per-aiutare-i-tecnici-nella-progettazione-di-reti-industriali-pi%c3%b9-sicure-ed-affidabili-2\\\/\"},\"wordCount\":1177,\"commentCount\":0,\"keywords\":[\"allen\",\"Automation\",\"automazione\",\"big\",\"bradley\",\"cloud\",\"data\",\"fibra\",\"Ottica\",\"power over the internet\",\"reti\",\"Rockwell\",\"statix\"],\"articleSection\":[\"Software\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/computer\\\/software\\\/rockwell-automation-amplia-il-suo-portafoglio-di-prodotti-dedicati-alle-infrastrutture-di-rete-per-aiutare-i-tecnici-nella-progettazione-di-reti-industriali-pi%c3%b9-sicure-ed-affidabili-2\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/computer\\\/software\\\/rockwell-automation-amplia-il-suo-portafoglio-di-prodotti-dedicati-alle-infrastrutture-di-rete-per-aiutare-i-tecnici-nella-progettazione-di-reti-industriali-pi%c3%b9-sicure-ed-affidabili-2\\\/\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/computer\\\/software\\\/rockwell-automation-amplia-il-suo-portafoglio-di-prodotti-dedicati-alle-infrastrutture-di-rete-per-aiutare-i-tecnici-nella-progettazione-di-reti-industriali-pi%c3%b9-sicure-ed-affidabili-2\\\/\",\"name\":\"Rockwell Automation amplia il suo portafoglio di prodotti dedicati alle infrastrutture di rete per aiutare i tecnici nella progettazione di reti industriali pi\u00f9 sicure ed affidabili - Article Marketing\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\"},\"datePublished\":\"2014-01-22T11:40:54+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/computer\\\/software\\\/rockwell-automation-amplia-il-suo-portafoglio-di-prodotti-dedicati-alle-infrastrutture-di-rete-per-aiutare-i-tecnici-nella-progettazione-di-reti-industriali-pi%c3%b9-sicure-ed-affidabili-2\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/computer\\\/software\\\/rockwell-automation-amplia-il-suo-portafoglio-di-prodotti-dedicati-alle-infrastrutture-di-rete-per-aiutare-i-tecnici-nella-progettazione-di-reti-industriali-pi%c3%b9-sicure-ed-affidabili-2\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/computer\\\/software\\\/rockwell-automation-amplia-il-suo-portafoglio-di-prodotti-dedicati-alle-infrastrutture-di-rete-per-aiutare-i-tecnici-nella-progettazione-di-reti-industriali-pi%c3%b9-sicure-ed-affidabili-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Rockwell Automation amplia il suo portafoglio di prodotti dedicati alle infrastrutture di rete per aiutare i tecnici nella progettazione di reti industriali pi\u00f9 sicure ed affidabili\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\",\"name\":\"Article Marketing\",\"description\":\"article marketing &amp; press release\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\",\"name\":\"Redazione Comunicati Stampa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"caption\":\"Redazione Comunicati Stampa\"},\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/author\\\/redazione-comunicati-stampa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Rockwell Automation amplia il suo portafoglio di prodotti dedicati alle infrastrutture di rete per aiutare i tecnici nella progettazione di reti industriali pi\u00f9 sicure ed affidabili - Article Marketing","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.article-marketing.eu\/comunicati\/computer\/software\/rockwell-automation-amplia-il-suo-portafoglio-di-prodotti-dedicati-alle-infrastrutture-di-rete-per-aiutare-i-tecnici-nella-progettazione-di-reti-industriali-pi\u00f9-sicure-ed-affidabili-2\/","og_locale":"it_IT","og_type":"article","og_title":"Rockwell Automation amplia il suo portafoglio di prodotti dedicati alle infrastrutture di rete per aiutare i tecnici nella progettazione di reti industriali pi\u00f9 sicure ed affidabili - Article Marketing","og_description":"La linea degli switch ora comprende un router a servizi integrati, la traduzione degli indirizzi di rete, Power over Ethernet e funzionalit\u00e0 potenziate per le trasmissioni su fibra","og_url":"https:\/\/www.article-marketing.eu\/comunicati\/computer\/software\/rockwell-automation-amplia-il-suo-portafoglio-di-prodotti-dedicati-alle-infrastrutture-di-rete-per-aiutare-i-tecnici-nella-progettazione-di-reti-industriali-pi\u00f9-sicure-ed-affidabili-2\/","og_site_name":"Article Marketing","article_published_time":"2014-01-22T11:40:54+00:00","author":"Redazione Comunicati Stampa","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione Comunicati Stampa","Tempo di lettura stimato":"6 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.article-marketing.eu\/comunicati\/computer\/software\/rockwell-automation-amplia-il-suo-portafoglio-di-prodotti-dedicati-alle-infrastrutture-di-rete-per-aiutare-i-tecnici-nella-progettazione-di-reti-industriali-pi%c3%b9-sicure-ed-affidabili-2\/#article","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/computer\/software\/rockwell-automation-amplia-il-suo-portafoglio-di-prodotti-dedicati-alle-infrastrutture-di-rete-per-aiutare-i-tecnici-nella-progettazione-di-reti-industriali-pi%c3%b9-sicure-ed-affidabili-2\/"},"author":{"name":"Redazione Comunicati Stampa","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"headline":"Rockwell Automation amplia il suo portafoglio di prodotti dedicati alle infrastrutture di rete per aiutare i tecnici nella progettazione di reti industriali pi\u00f9 sicure ed affidabili","datePublished":"2014-01-22T11:40:54+00:00","mainEntityOfPage":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/computer\/software\/rockwell-automation-amplia-il-suo-portafoglio-di-prodotti-dedicati-alle-infrastrutture-di-rete-per-aiutare-i-tecnici-nella-progettazione-di-reti-industriali-pi%c3%b9-sicure-ed-affidabili-2\/"},"wordCount":1177,"commentCount":0,"keywords":["allen","Automation","automazione","big","bradley","cloud","data","fibra","Ottica","power over the internet","reti","Rockwell","statix"],"articleSection":["Software"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.article-marketing.eu\/comunicati\/computer\/software\/rockwell-automation-amplia-il-suo-portafoglio-di-prodotti-dedicati-alle-infrastrutture-di-rete-per-aiutare-i-tecnici-nella-progettazione-di-reti-industriali-pi%c3%b9-sicure-ed-affidabili-2\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.article-marketing.eu\/comunicati\/computer\/software\/rockwell-automation-amplia-il-suo-portafoglio-di-prodotti-dedicati-alle-infrastrutture-di-rete-per-aiutare-i-tecnici-nella-progettazione-di-reti-industriali-pi%c3%b9-sicure-ed-affidabili-2\/","url":"https:\/\/www.article-marketing.eu\/comunicati\/computer\/software\/rockwell-automation-amplia-il-suo-portafoglio-di-prodotti-dedicati-alle-infrastrutture-di-rete-per-aiutare-i-tecnici-nella-progettazione-di-reti-industriali-pi%c3%b9-sicure-ed-affidabili-2\/","name":"Rockwell Automation amplia il suo portafoglio di prodotti dedicati alle infrastrutture di rete per aiutare i tecnici nella progettazione di reti industriali pi\u00f9 sicure ed affidabili - Article Marketing","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website"},"datePublished":"2014-01-22T11:40:54+00:00","author":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"breadcrumb":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/computer\/software\/rockwell-automation-amplia-il-suo-portafoglio-di-prodotti-dedicati-alle-infrastrutture-di-rete-per-aiutare-i-tecnici-nella-progettazione-di-reti-industriali-pi%c3%b9-sicure-ed-affidabili-2\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.article-marketing.eu\/comunicati\/computer\/software\/rockwell-automation-amplia-il-suo-portafoglio-di-prodotti-dedicati-alle-infrastrutture-di-rete-per-aiutare-i-tecnici-nella-progettazione-di-reti-industriali-pi%c3%b9-sicure-ed-affidabili-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.article-marketing.eu\/comunicati\/computer\/software\/rockwell-automation-amplia-il-suo-portafoglio-di-prodotti-dedicati-alle-infrastrutture-di-rete-per-aiutare-i-tecnici-nella-progettazione-di-reti-industriali-pi%c3%b9-sicure-ed-affidabili-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.article-marketing.eu\/comunicati\/"},{"@type":"ListItem","position":2,"name":"Rockwell Automation amplia il suo portafoglio di prodotti dedicati alle infrastrutture di rete per aiutare i tecnici nella progettazione di reti industriali pi\u00f9 sicure ed affidabili"}]},{"@type":"WebSite","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website","url":"https:\/\/www.article-marketing.eu\/comunicati\/","name":"Article Marketing","description":"article marketing &amp; press release","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.article-marketing.eu\/comunicati\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017","name":"Redazione Comunicati Stampa","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","caption":"Redazione Comunicati Stampa"},"url":"https:\/\/www.article-marketing.eu\/comunicati\/author\/redazione-comunicati-stampa\/"}]}},"_links":{"self":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/38428","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/comments?post=38428"}],"version-history":[{"count":0,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/38428\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/media?parent=38428"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/categories?post=38428"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/tags?post=38428"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}