{"id":38603,"date":"2014-01-21T09:21:05","date_gmt":"2014-01-21T08:21:05","guid":{"rendered":"http:\/\/www.article-marketing.eu\/comunicati\/senza-categoria\/nuovi-frigoriferi-combinati-no-frost-di-gorenje-mai-piu-condensa-grazie-allinnovativa-tecnologia-nofrost-plus-2\/"},"modified":"2018-10-25T22:20:20","modified_gmt":"2018-10-25T20:20:20","slug":"nuovi-frigoriferi-combinati-no-frost-di-gorenje-mai-piu-condensa-grazie-allinnovativa-tecnologia-nofrost-plus-2","status":"publish","type":"post","link":"https:\/\/www.article-marketing.eu\/comunicati\/casa\/cucina\/nuovi-frigoriferi-combinati-no-frost-di-gorenje-mai-piu-condensa-grazie-allinnovativa-tecnologia-nofrost-plus-2\/","title":{"rendered":"NUOVI FRIGORIFERI COMBINATI NO FROST DI GORENJE: MAI PIU&#8217; CONDENSA GRAZIE ALL&#8217;INNOVATIVA TECNOLOGIA NOFROST PLUS!"},"content":{"rendered":"<p>Gorenje presenta la nuova collezione di frigoriferi combinati da libera installazione No Frost: massima funzionalit&agrave; con un&#8217;estitca pulita ed elegante in 5 colori (beige, rosso fuoco, bordeaux, cioccolato e nero). Elemento distintivo di questa nuova collezione &egrave; l&#8217;innovativa tecnologia NoFrost Plus che permette di evitare la formazione di condensa nel comparto congelatore e la conseguente formazione di brina e ghiaccio. In questo modo, grazie alla ventilazione forzata, il raffreddamento &egrave; pi&ugrave; veloce e uniforme in ogni scomparto, eliminando del tutto la formazione di ghiaccio su ripiani e pareti che porta infatti ad un aumento dei consumi elettrici, a ostruzioni dei condottti di aerazione, a una diminuzione dello spazio utile e obbliga ogni tanto a sbrinare l&rsquo;elettrodomestico, operazione alquanto fastidiosa.  Gli elementi tecnologici della Collezione No Frost di Gorenje sono numerosi e tutti studiati per offrire un prodotto di qualit&agrave; e che sappia rispondere alle esigenze pi&ugrave; particolari: &bull; MultiFlow 360&deg;: sistema di ventilazione che permette un bilanciamento perfetto tra l&#8217;aria, l&#8217;umidit&agrave; e la temperatura all&#8217;interno del frigorifero, rendendo l&#8217;ambiente ideale per la conservazione dei cibi. Le 14 fenditure di ventilazione poste lungo la parete del frigorifero assicurano una temperatura uniforme su tutti i livelli evitando in tal modo la formazione di condensa sugli alimenti. &bull; Tecnologia Ion Air: permette di creare un microclima che funziona sul principio del naturale processo di ionizzazione. Il suo prodotto &egrave; l&#8217;ozono che elimina naturalmente i batteri, le muffe e i cattivi odori, fornendo la migliore protezione per il cibo e la sua freschezza. Il processo di ionizzazzione elimina infatti fino al 95% dei microrganismi dannosi e dei forti odori di alcuni alimenti (come le cipolle). &bull; Tecnologia AdaptCool: tecnologia avanzata dei sensori con funzione di memoria che contribuisce a creare l&#8217;ambiente ideale all&#8217;interno del frigorifero. Si tratta di un programma speciale che registra la frequenza di apertura della porta nell&#8217;arco di una settimana. Esso memorizza continuamente i dati e di conseguenza imposta i programmi del frigorifero secondo i dati raccolti. Quando il frigorifero sa che le porte saranno aperte pi&ugrave; frequentamente, aumenta automaticamente il raffreddamento. In questo modo ver&agrave; sempre mantenuta una temperatura stabile nel frigorifero. &bull; Funzione FastFreeze: funzione di congelamento rapido, particolarmente adatta per il congelamento di grandi quantit&agrave; di cibo. Dopo l&#8217;attivazione, dura per 50 ore e mantiene la temperatura a -24&deg;C. <strong>NRK 6192 J &ndash; Frigorifero combinato da libera installazione<\/strong> &bull; Colore: beige, rosso fuoco, bordeaux, cioccolato e nero &bull; Classe energetica: A++, 4 stelle &bull; Capacit&agrave; lorda\/netta: 329 \/ 306 l &bull; Volume frigo lordo\/netto: 231 \/221 l &bull; Volume congelatore lordo\/netto: 98 \/ 85 l &bull; Capacit&agrave; di congelazione: 5 kg\/24 h &bull; Autonomia di conservazione in caso di black out: 18 h &bull; Illuminazione: striscia LED sulla parte superiore &bull; Ripiani in vetro: 4 regolabili &bull; Cassettino per formaggio e burro &bull; Cassetto Fresh Zone &bull; Regolatore di umidit&agrave; per cassetto verdure &bull; Griglia portabottiglie: in acciaio inox &bull; 3 cassetti per la conservazione degli alimenti surgelati &bull; Rumorosit&agrave;: 42 dB(A) &bull; Dimensioni: 185x60x64 cm Per informazioni: Gorenje www.gorenje.it Digital pr a cura di Blu Wom Milano www.bluwom-milano.com 02 87384640 p.fabretti@bluwom-milano<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Gorenje presenta la nuova collezione di frigoriferi combinati da libera installazione No Frost: massima funzionalit&agrave; con un&#8217;estitca pulita ed elegante in 5 colori (beige, rosso fuoco, bordeaux, cioccolato e nero). Elemento distintivo di questa nuova collezione &egrave; l&#8217;innovativa tecnologia NoFrost Plus che permette di evitare la formazione di condensa nel comparto congelatore e la conseguente formazione di brina e ghiaccio. In questo modo, grazie alla ventilazione forzata, il raffreddamento &egrave;<\/p>\n<p><a class=\"continue-reading\" href=\"https:\/\/www.article-marketing.eu\/comunicati\/casa\/cucina\/nuovi-frigoriferi-combinati-no-frost-di-gorenje-mai-piu-condensa-grazie-allinnovativa-tecnologia-nofrost-plus-2\/\">Continue reading&#8230;<\/a><\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"","footnotes":""},"categories":[944],"tags":[],"class_list":["post-38603","post","type-post","status-publish","format-standard","hentry","category-cucina"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>NUOVI FRIGORIFERI COMBINATI NO FROST DI GORENJE: MAI PIU&#039; CONDENSA GRAZIE ALL&#039;INNOVATIVA TECNOLOGIA NOFROST PLUS! - Article Marketing<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.article-marketing.eu\/comunicati\/casa\/cucina\/nuovi-frigoriferi-combinati-no-frost-di-gorenje-mai-piu-condensa-grazie-allinnovativa-tecnologia-nofrost-plus-2\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"NUOVI FRIGORIFERI COMBINATI NO FROST DI GORENJE: MAI PIU&#039; CONDENSA GRAZIE ALL&#039;INNOVATIVA TECNOLOGIA NOFROST PLUS! - Article Marketing\" \/>\n<meta property=\"og:description\" content=\"Gorenje presenta la nuova collezione di frigoriferi combinati da libera installazione No Frost: massima funzionalit&agrave; con un&#8217;estitca pulita ed elegante in 5 colori (beige, rosso fuoco, bordeaux, cioccolato e nero). Elemento distintivo di questa nuova collezione &egrave; l&#8217;innovativa tecnologia NoFrost Plus che permette di evitare la formazione di condensa nel comparto congelatore e la conseguente formazione di brina e ghiaccio. In questo modo, grazie alla ventilazione forzata, il raffreddamento &egrave;Continue reading...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.article-marketing.eu\/comunicati\/casa\/cucina\/nuovi-frigoriferi-combinati-no-frost-di-gorenje-mai-piu-condensa-grazie-allinnovativa-tecnologia-nofrost-plus-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Article Marketing\" \/>\n<meta property=\"article:published_time\" content=\"2014-01-21T08:21:05+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-10-25T20:20:20+00:00\" \/>\n<meta name=\"author\" content=\"Redazione Comunicati Stampa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione Comunicati Stampa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/casa\\\/cucina\\\/nuovi-frigoriferi-combinati-no-frost-di-gorenje-mai-piu-condensa-grazie-allinnovativa-tecnologia-nofrost-plus-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/casa\\\/cucina\\\/nuovi-frigoriferi-combinati-no-frost-di-gorenje-mai-piu-condensa-grazie-allinnovativa-tecnologia-nofrost-plus-2\\\/\"},\"author\":{\"name\":\"Redazione Comunicati Stampa\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"headline\":\"NUOVI FRIGORIFERI COMBINATI NO FROST DI GORENJE: MAI PIU&#8217; CONDENSA GRAZIE ALL&#8217;INNOVATIVA TECNOLOGIA NOFROST PLUS!\",\"datePublished\":\"2014-01-21T08:21:05+00:00\",\"dateModified\":\"2018-10-25T20:20:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/casa\\\/cucina\\\/nuovi-frigoriferi-combinati-no-frost-di-gorenje-mai-piu-condensa-grazie-allinnovativa-tecnologia-nofrost-plus-2\\\/\"},\"wordCount\":535,\"commentCount\":0,\"articleSection\":[\"Cucina\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/casa\\\/cucina\\\/nuovi-frigoriferi-combinati-no-frost-di-gorenje-mai-piu-condensa-grazie-allinnovativa-tecnologia-nofrost-plus-2\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/casa\\\/cucina\\\/nuovi-frigoriferi-combinati-no-frost-di-gorenje-mai-piu-condensa-grazie-allinnovativa-tecnologia-nofrost-plus-2\\\/\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/casa\\\/cucina\\\/nuovi-frigoriferi-combinati-no-frost-di-gorenje-mai-piu-condensa-grazie-allinnovativa-tecnologia-nofrost-plus-2\\\/\",\"name\":\"NUOVI FRIGORIFERI COMBINATI NO FROST DI GORENJE: MAI PIU' CONDENSA GRAZIE ALL'INNOVATIVA TECNOLOGIA NOFROST PLUS! - Article Marketing\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\"},\"datePublished\":\"2014-01-21T08:21:05+00:00\",\"dateModified\":\"2018-10-25T20:20:20+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/casa\\\/cucina\\\/nuovi-frigoriferi-combinati-no-frost-di-gorenje-mai-piu-condensa-grazie-allinnovativa-tecnologia-nofrost-plus-2\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/casa\\\/cucina\\\/nuovi-frigoriferi-combinati-no-frost-di-gorenje-mai-piu-condensa-grazie-allinnovativa-tecnologia-nofrost-plus-2\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/casa\\\/cucina\\\/nuovi-frigoriferi-combinati-no-frost-di-gorenje-mai-piu-condensa-grazie-allinnovativa-tecnologia-nofrost-plus-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"NUOVI FRIGORIFERI COMBINATI NO FROST DI GORENJE: MAI PIU&#8217; CONDENSA GRAZIE ALL&#8217;INNOVATIVA TECNOLOGIA NOFROST PLUS!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\",\"name\":\"Article Marketing\",\"description\":\"article marketing &amp; press release\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\",\"name\":\"Redazione Comunicati Stampa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"caption\":\"Redazione Comunicati Stampa\"},\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/author\\\/redazione-comunicati-stampa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"NUOVI FRIGORIFERI COMBINATI NO FROST DI GORENJE: MAI PIU' CONDENSA GRAZIE ALL'INNOVATIVA TECNOLOGIA NOFROST PLUS! - Article Marketing","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.article-marketing.eu\/comunicati\/casa\/cucina\/nuovi-frigoriferi-combinati-no-frost-di-gorenje-mai-piu-condensa-grazie-allinnovativa-tecnologia-nofrost-plus-2\/","og_locale":"it_IT","og_type":"article","og_title":"NUOVI FRIGORIFERI COMBINATI NO FROST DI GORENJE: MAI PIU' CONDENSA GRAZIE ALL'INNOVATIVA TECNOLOGIA NOFROST PLUS! - Article Marketing","og_description":"Gorenje presenta la nuova collezione di frigoriferi combinati da libera installazione No Frost: massima funzionalit&agrave; con un&#8217;estitca pulita ed elegante in 5 colori (beige, rosso fuoco, bordeaux, cioccolato e nero). Elemento distintivo di questa nuova collezione &egrave; l&#8217;innovativa tecnologia NoFrost Plus che permette di evitare la formazione di condensa nel comparto congelatore e la conseguente formazione di brina e ghiaccio. In questo modo, grazie alla ventilazione forzata, il raffreddamento &egrave;Continue reading...","og_url":"https:\/\/www.article-marketing.eu\/comunicati\/casa\/cucina\/nuovi-frigoriferi-combinati-no-frost-di-gorenje-mai-piu-condensa-grazie-allinnovativa-tecnologia-nofrost-plus-2\/","og_site_name":"Article Marketing","article_published_time":"2014-01-21T08:21:05+00:00","article_modified_time":"2018-10-25T20:20:20+00:00","author":"Redazione Comunicati Stampa","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione Comunicati Stampa","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.article-marketing.eu\/comunicati\/casa\/cucina\/nuovi-frigoriferi-combinati-no-frost-di-gorenje-mai-piu-condensa-grazie-allinnovativa-tecnologia-nofrost-plus-2\/#article","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/casa\/cucina\/nuovi-frigoriferi-combinati-no-frost-di-gorenje-mai-piu-condensa-grazie-allinnovativa-tecnologia-nofrost-plus-2\/"},"author":{"name":"Redazione Comunicati Stampa","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"headline":"NUOVI FRIGORIFERI COMBINATI NO FROST DI GORENJE: MAI PIU&#8217; CONDENSA GRAZIE ALL&#8217;INNOVATIVA TECNOLOGIA NOFROST PLUS!","datePublished":"2014-01-21T08:21:05+00:00","dateModified":"2018-10-25T20:20:20+00:00","mainEntityOfPage":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/casa\/cucina\/nuovi-frigoriferi-combinati-no-frost-di-gorenje-mai-piu-condensa-grazie-allinnovativa-tecnologia-nofrost-plus-2\/"},"wordCount":535,"commentCount":0,"articleSection":["Cucina"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.article-marketing.eu\/comunicati\/casa\/cucina\/nuovi-frigoriferi-combinati-no-frost-di-gorenje-mai-piu-condensa-grazie-allinnovativa-tecnologia-nofrost-plus-2\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.article-marketing.eu\/comunicati\/casa\/cucina\/nuovi-frigoriferi-combinati-no-frost-di-gorenje-mai-piu-condensa-grazie-allinnovativa-tecnologia-nofrost-plus-2\/","url":"https:\/\/www.article-marketing.eu\/comunicati\/casa\/cucina\/nuovi-frigoriferi-combinati-no-frost-di-gorenje-mai-piu-condensa-grazie-allinnovativa-tecnologia-nofrost-plus-2\/","name":"NUOVI FRIGORIFERI COMBINATI NO FROST DI GORENJE: MAI PIU' CONDENSA GRAZIE ALL'INNOVATIVA TECNOLOGIA NOFROST PLUS! - Article Marketing","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website"},"datePublished":"2014-01-21T08:21:05+00:00","dateModified":"2018-10-25T20:20:20+00:00","author":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"breadcrumb":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/casa\/cucina\/nuovi-frigoriferi-combinati-no-frost-di-gorenje-mai-piu-condensa-grazie-allinnovativa-tecnologia-nofrost-plus-2\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.article-marketing.eu\/comunicati\/casa\/cucina\/nuovi-frigoriferi-combinati-no-frost-di-gorenje-mai-piu-condensa-grazie-allinnovativa-tecnologia-nofrost-plus-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.article-marketing.eu\/comunicati\/casa\/cucina\/nuovi-frigoriferi-combinati-no-frost-di-gorenje-mai-piu-condensa-grazie-allinnovativa-tecnologia-nofrost-plus-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.article-marketing.eu\/comunicati\/"},{"@type":"ListItem","position":2,"name":"NUOVI FRIGORIFERI COMBINATI NO FROST DI GORENJE: MAI PIU&#8217; CONDENSA GRAZIE ALL&#8217;INNOVATIVA TECNOLOGIA NOFROST PLUS!"}]},{"@type":"WebSite","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website","url":"https:\/\/www.article-marketing.eu\/comunicati\/","name":"Article Marketing","description":"article marketing &amp; press release","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.article-marketing.eu\/comunicati\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017","name":"Redazione Comunicati Stampa","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","caption":"Redazione Comunicati Stampa"},"url":"https:\/\/www.article-marketing.eu\/comunicati\/author\/redazione-comunicati-stampa\/"}]}},"_links":{"self":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/38603","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/comments?post=38603"}],"version-history":[{"count":3,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/38603\/revisions"}],"predecessor-version":[{"id":63704,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/38603\/revisions\/63704"}],"wp:attachment":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/media?parent=38603"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/categories?post=38603"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/tags?post=38603"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}