{"id":39592,"date":"2014-05-05T13:42:05","date_gmt":"2014-05-05T11:42:05","guid":{"rendered":"http:\/\/www.article-marketing.eu\/comunicati\/senza-categoria\/centric-software-lancia-altre-due-app-mobile-ampliando-la-propria-offerta-per-il-product-lifecycle-management-2\/"},"modified":"2014-05-05T13:42:05","modified_gmt":"2014-05-05T11:42:05","slug":"centric-software-lancia-altre-due-app-mobile-ampliando-la-propria-offerta-per-il-product-lifecycle-management-2","status":"publish","type":"post","link":"https:\/\/www.article-marketing.eu\/comunicati\/computer\/software\/centric-software-lancia-altre-due-app-mobile-ampliando-la-propria-offerta-per-il-product-lifecycle-management-2\/","title":{"rendered":"Centric Software Lancia Altre Due App Mobile Ampliando La Propria Offerta Per il Product Lifecycle Management"},"content":{"rendered":"<p>Grazie a due innovative app mobile in attesa di brevetto che vanno ad arricchire il portafoglio applicazioni mobile di Centric Software, le aziende di beni di consumo potranno rendere pi&ugrave; rapido, facile, accurato e produttivo il processo di ideazione e sviluppo del prodotto.<\/p>\n<p>Switchboard Mobile App e Material Sample Mobile App sono le pi&ugrave; recenti app mobile per la soluzione di Product Lifecycle Management (PLM), Centric 8. Per le aziende di beni di consumo la presenza di un&rsquo;enorme variet&agrave; di prodotti e l&rsquo;esigenza pressante di arrivare sul mercato in tempi sempre pi&ugrave; compressi, rendono estremamente critico dal punto di vista dei profitti il momento del lancio di ogni nuovo articolo. Afferma Chris Groves, presidente e CEO di Centric &#8220;Grazie a queste nuove app mobile, un designer che abbia un&#8217;ispirazione improvvisa in qualsiasi momento, sia che si trovi in un bar, in viaggio su un treno o nel corso di una visita ad una mostra tessile, &egrave; in grado di catturare immediatamente questo input creativo, portarlo pi&ugrave; velocemente a compimento e innescare il processo di sviluppo del prodotto. Le app, grazie alla loro facilit&agrave; d&rsquo;uso, rappresentano per le aziende di beni di consumo un modo immediato per trasferire i benefici delle mobile enterprise nei processi di progettazione e sviluppo, senza compromettere il talento creativo&rdquo; spiega Groves.<\/p>\n<p><strong>Sw<\/strong><strong>itchboard Mobile App<\/strong>: La App Switchboard Mobile sfrutta la potenza di applicazioni Apple iOS di terze parti consentendo di caricare immagini e contenuti, come ad esempio ispirazioni, stili, temi e materiali, direttamente sugli oggetti gestiti da Centric 8 PLM. Ad esempio, i designer possono abbozzare le loro idee di prodotto utilizzando l&rsquo;app di disegno iOS preferita, e poi trasferirle su Centric 8 utilizzando Switchboard Mobile App &#8211; tutto questo facilmente e con pochi click.<\/p>\n<p>La App Switchboard Mobile consente ai collaboratori chiave nello sviluppo prodotto di utilizzare degli strumenti a loro familiari, promuove livelli di creativit&agrave; elevati e permette di ridurre la dipendenza da una miriade di tavole e schizzi su carta. &#8221; Il ruolo fondamentale del PLM come &#8216;unica fonte di verit&agrave;&#8217; di un prodotto &egrave; pienamente soddisfatto, sfruttando una vasta gamma di contenuti app iOS di terze parti e con una facilit&agrave; d&#8217;uso senza precedenti.&#8221; sostiene Groves.<\/p>\n<p><strong>Material Sample Mobile App<\/strong>: La App Material Sample Mobile consente ai designer e ad altri attori coinvolti di catturare e condividere le proprie ispirazioni in tempo reale. Usando i loro iPhone, i designer possono acquisire rapidamente i dettagli relativi ad un materiale come immagini, informazioni sui fornitori e propriet&agrave; dei materiali stessi. Queste informazioni vengono poi caricate automaticamente su Centric 8 PLM, consentendo ai membri del team di accedervi immediatamente per calcolare i costi, effettuare test di qualit&agrave; e altri valutazioni.<\/p>\n<p>&ldquo;La App Material Sample Mobile sar&agrave; di particolare interesse soprattutto per quei brand che utilizzano i materiali come principale fattore di differenziazione competitiva&rdquo; sostiene Groves. Tra questi ci sono i produttori di articoli di fascia alta, le aziende che cercano di esercitare un grande controllo sui materiali e quelle per le quali le prestazioni del materiale sono parte integrante del marchio stesso, come i produttori di abbigliamento tecnico. <\/p>\n<p>Centric &egrave; stata la prima a lanciare sul mercato delle app mobile per il PLM. &ldquo;L&#8217;azienda continua ad innovare e ha introdotto il maggior numero di app mobile rispetto a qualsiasi altro fornitore di soluzioni di PLM che opera nel settore&rdquo;, sostiene Groves. Le app mobile di Centric per Centric 8 PLM sono disponibili su <a href=\"https:\/\/itunes.apple.com\/us\/artist\/centric-software-inc\/id811683089\">Apple App Store<\/a>. Tra le altre app offerte da Centric ci sono:<\/p>\n<p>&middot; Capture It per iPhone Mobile App, che consente di scattare foto e caricarle direttamente su Centric 8 per revisione, mark-up e analisi immediata;<br \/>\n&middot; Collection Book iPad Mobile App, che permette di creare cataloghi di vendita o abilitare la presa ordini da dispositivi iOS<br \/>\n&middot; Sample Review Mobile App, che fornisce di effettuare sessioni di sdifettamento \/review tecniche;<br \/>\n&middot; Factory Audit Mobile App, che consente ai brand di condurre e documentare in loco audit di fabbrica utilizzando qualsiasi dispositivo mobile abilitato iOS, e di collegare le informazioni dell&rsquo;audit alla valutazione fornitori nel software Centric 8 .<\/p>\n<p>&ldquo;Switchboard Mobile App e Material Sample Mobile App rinforzano ulteriormente il posizionamento di Centric come leader innovativo di soluzioni software PLM dedicate ai settori retail, moda, calzature, lusso e beni di consumo&#8221;, dichiara Groves. &#8220;Switchboard Mobile App e Material Sample Mobile App sono gli ultimi esempi di come Centric stia potenziando il ruolo del PLM portando il consumatore pi&ugrave; vicino che mai al design e alle ultime tendenze.&rdquo;<\/p>\n<p><strong>Centric Software<\/strong>(www.centricsoftware.it)<br \/> Centric Software &egrave; un fornitore di soluzioni di Product Lifecycle Management (PLM) dedicate ai settori moda, lusso e beni di largo consumo. La soluzione Centric 8 offre funzionalit&agrave; dedicate per gestire in maniera integrata i processi di business relativi al ciclo di vita del prodotto: sviluppo prodotto e materiali, sourcing, pianificazione temporale ed economica della collezione, qualit&agrave;. L&rsquo;approccio modulare e user-friendly, associato alla metodologia di implementazione Agile Deployment SM, permette di ottenere benefici rapidamente. Centric ha ricevuto il riconoscimento Frost &amp; Sullivan 2012 Global Product Differentiation Excellence Award come migliore tra le soluzioni PLM dedicate ai settori moda, fashion e retail, ha vinto le Top 100 North America e Top 100 Global Red Herring 2013 ed &egrave; stata nominata Market Leader nel PLM per il Fashion nella Annual Review 2012-213 di WhichPLM.<\/p>\n<p><strong><em>Centric &egrave; un marchio registrato di Centric Software. Tutti gli altri marchi e nomi di prodotto possono essere marchi dei rispettivi proprietari.<\/em><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il fornitore leader di soluzioni software di PLM dedicate ai settori retail, moda, calzature, lusso e beni di consumo presenta due applicazioni innovative<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"","footnotes":""},"categories":[123],"tags":[12511,46457,46454,46458,46456,17796,46455,2136,3953,1638,19049,1937],"class_list":["post-39592","post","type-post","status-publish","format-standard","hentry","category-software","tag-app","tag-apple-store","tag-centric","tag-centric8","tag-ciclo","tag-collezioni","tag-material","tag-plm","tag-prodotto","tag-software","tag-suite","tag-vita"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Centric Software Lancia Altre Due App Mobile Ampliando La Propria Offerta Per il Product Lifecycle Management - Article Marketing<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.article-marketing.eu\/comunicati\/computer\/software\/centric-software-lancia-altre-due-app-mobile-ampliando-la-propria-offerta-per-il-product-lifecycle-management-2\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Centric Software Lancia Altre Due App Mobile Ampliando La Propria Offerta Per il Product Lifecycle Management - Article Marketing\" \/>\n<meta property=\"og:description\" content=\"Il fornitore leader di soluzioni software di PLM dedicate ai settori retail, moda, calzature, lusso e beni di consumo presenta due applicazioni innovative\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.article-marketing.eu\/comunicati\/computer\/software\/centric-software-lancia-altre-due-app-mobile-ampliando-la-propria-offerta-per-il-product-lifecycle-management-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Article Marketing\" \/>\n<meta property=\"article:published_time\" content=\"2014-05-05T11:42:05+00:00\" \/>\n<meta name=\"author\" content=\"Redazione Comunicati Stampa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione Comunicati Stampa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/computer\\\/software\\\/centric-software-lancia-altre-due-app-mobile-ampliando-la-propria-offerta-per-il-product-lifecycle-management-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/computer\\\/software\\\/centric-software-lancia-altre-due-app-mobile-ampliando-la-propria-offerta-per-il-product-lifecycle-management-2\\\/\"},\"author\":{\"name\":\"Redazione Comunicati Stampa\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"headline\":\"Centric Software Lancia Altre Due App Mobile Ampliando La Propria Offerta Per il Product Lifecycle Management\",\"datePublished\":\"2014-05-05T11:42:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/computer\\\/software\\\/centric-software-lancia-altre-due-app-mobile-ampliando-la-propria-offerta-per-il-product-lifecycle-management-2\\\/\"},\"wordCount\":942,\"commentCount\":0,\"keywords\":[\"app\",\"apple store\",\"centric\",\"centric8\",\"ciclo\",\"collezioni\",\"material\",\"PLM\",\"prodotto\",\"software\",\"Suite\",\"vita\"],\"articleSection\":[\"Software\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/computer\\\/software\\\/centric-software-lancia-altre-due-app-mobile-ampliando-la-propria-offerta-per-il-product-lifecycle-management-2\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/computer\\\/software\\\/centric-software-lancia-altre-due-app-mobile-ampliando-la-propria-offerta-per-il-product-lifecycle-management-2\\\/\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/computer\\\/software\\\/centric-software-lancia-altre-due-app-mobile-ampliando-la-propria-offerta-per-il-product-lifecycle-management-2\\\/\",\"name\":\"Centric Software Lancia Altre Due App Mobile Ampliando La Propria Offerta Per il Product Lifecycle Management - Article Marketing\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\"},\"datePublished\":\"2014-05-05T11:42:05+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/computer\\\/software\\\/centric-software-lancia-altre-due-app-mobile-ampliando-la-propria-offerta-per-il-product-lifecycle-management-2\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/computer\\\/software\\\/centric-software-lancia-altre-due-app-mobile-ampliando-la-propria-offerta-per-il-product-lifecycle-management-2\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/computer\\\/software\\\/centric-software-lancia-altre-due-app-mobile-ampliando-la-propria-offerta-per-il-product-lifecycle-management-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Centric Software Lancia Altre Due App Mobile Ampliando La Propria Offerta Per il Product Lifecycle Management\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\",\"name\":\"Article Marketing\",\"description\":\"article marketing &amp; press release\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\",\"name\":\"Redazione Comunicati Stampa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"caption\":\"Redazione Comunicati Stampa\"},\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/author\\\/redazione-comunicati-stampa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Centric Software Lancia Altre Due App Mobile Ampliando La Propria Offerta Per il Product Lifecycle Management - Article Marketing","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.article-marketing.eu\/comunicati\/computer\/software\/centric-software-lancia-altre-due-app-mobile-ampliando-la-propria-offerta-per-il-product-lifecycle-management-2\/","og_locale":"it_IT","og_type":"article","og_title":"Centric Software Lancia Altre Due App Mobile Ampliando La Propria Offerta Per il Product Lifecycle Management - Article Marketing","og_description":"Il fornitore leader di soluzioni software di PLM dedicate ai settori retail, moda, calzature, lusso e beni di consumo presenta due applicazioni innovative","og_url":"https:\/\/www.article-marketing.eu\/comunicati\/computer\/software\/centric-software-lancia-altre-due-app-mobile-ampliando-la-propria-offerta-per-il-product-lifecycle-management-2\/","og_site_name":"Article Marketing","article_published_time":"2014-05-05T11:42:05+00:00","author":"Redazione Comunicati Stampa","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione Comunicati Stampa","Tempo di lettura stimato":"5 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.article-marketing.eu\/comunicati\/computer\/software\/centric-software-lancia-altre-due-app-mobile-ampliando-la-propria-offerta-per-il-product-lifecycle-management-2\/#article","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/computer\/software\/centric-software-lancia-altre-due-app-mobile-ampliando-la-propria-offerta-per-il-product-lifecycle-management-2\/"},"author":{"name":"Redazione Comunicati Stampa","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"headline":"Centric Software Lancia Altre Due App Mobile Ampliando La Propria Offerta Per il Product Lifecycle Management","datePublished":"2014-05-05T11:42:05+00:00","mainEntityOfPage":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/computer\/software\/centric-software-lancia-altre-due-app-mobile-ampliando-la-propria-offerta-per-il-product-lifecycle-management-2\/"},"wordCount":942,"commentCount":0,"keywords":["app","apple store","centric","centric8","ciclo","collezioni","material","PLM","prodotto","software","Suite","vita"],"articleSection":["Software"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.article-marketing.eu\/comunicati\/computer\/software\/centric-software-lancia-altre-due-app-mobile-ampliando-la-propria-offerta-per-il-product-lifecycle-management-2\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.article-marketing.eu\/comunicati\/computer\/software\/centric-software-lancia-altre-due-app-mobile-ampliando-la-propria-offerta-per-il-product-lifecycle-management-2\/","url":"https:\/\/www.article-marketing.eu\/comunicati\/computer\/software\/centric-software-lancia-altre-due-app-mobile-ampliando-la-propria-offerta-per-il-product-lifecycle-management-2\/","name":"Centric Software Lancia Altre Due App Mobile Ampliando La Propria Offerta Per il Product Lifecycle Management - Article Marketing","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website"},"datePublished":"2014-05-05T11:42:05+00:00","author":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"breadcrumb":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/computer\/software\/centric-software-lancia-altre-due-app-mobile-ampliando-la-propria-offerta-per-il-product-lifecycle-management-2\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.article-marketing.eu\/comunicati\/computer\/software\/centric-software-lancia-altre-due-app-mobile-ampliando-la-propria-offerta-per-il-product-lifecycle-management-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.article-marketing.eu\/comunicati\/computer\/software\/centric-software-lancia-altre-due-app-mobile-ampliando-la-propria-offerta-per-il-product-lifecycle-management-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.article-marketing.eu\/comunicati\/"},{"@type":"ListItem","position":2,"name":"Centric Software Lancia Altre Due App Mobile Ampliando La Propria Offerta Per il Product Lifecycle Management"}]},{"@type":"WebSite","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website","url":"https:\/\/www.article-marketing.eu\/comunicati\/","name":"Article Marketing","description":"article marketing &amp; press release","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.article-marketing.eu\/comunicati\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017","name":"Redazione Comunicati Stampa","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","caption":"Redazione Comunicati Stampa"},"url":"https:\/\/www.article-marketing.eu\/comunicati\/author\/redazione-comunicati-stampa\/"}]}},"_links":{"self":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/39592","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/comments?post=39592"}],"version-history":[{"count":0,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/39592\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/media?parent=39592"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/categories?post=39592"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/tags?post=39592"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}