{"id":39747,"date":"2014-03-14T14:54:27","date_gmt":"2014-03-14T13:54:27","guid":{"rendered":"http:\/\/www.article-marketing.eu\/comunicati\/senza-categoria\/defibrillatore-gratis-ecco-come-fare-con-lista-del-cuore\/"},"modified":"2014-03-14T14:54:27","modified_gmt":"2014-03-14T13:54:27","slug":"defibrillatore-gratis-ecco-come-fare-con-lista-del-cuore","status":"publish","type":"post","link":"https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/medicina\/defibrillatore-gratis-ecco-come-fare-con-lista-del-cuore\/","title":{"rendered":"Defibrillatore Gratis? Ecco come fare con Lista del Cuore"},"content":{"rendered":"<p><strong class=\"titolo\">Defibrillatore Gratis? Ecco come fare con Lista del Cuore<\/strong> <em>La prima piattaforma di foundrising per donare o ricevere un Defibrillatore Gratis.Crea la tua lista ora su ListadelCuore.<\/em> 14\/03\/2014 &#8211; La Lista del Cuore &egrave; un sistema di incentivazione ideato allo scopo di favorire la realizzazione di progetti di cardioprotezione in ambito privato e pubblico.<br \/> Attivare subito la tua Lista del Cuore &egrave; semplice! Basta entrare nel sito www.listadelcuore.com e seguire la nostra guida. Subito il tuo progetto di cardioprotezione potr&agrave; essere diffuso on-line ed inziare a ricevere i primi contributi!<\/p>\n<p> COME FUNZIONA<\/p>\n<p> Su ListadelCuore.com &egrave; possibile creare e pubblicare delle &ldquo;Liste&rdquo;, ossia dei progetti di cardioprotezione e promuovere la richiesta di contributi da parte di soggetti privati e pubblici attraverso una serie di strumenti gratuiti che sono disponibili sulla piattaforma stessa.<br \/> Ecco come funziona listadelcuore &ndash; e come donare o ricevere un Defibrillatore Gratis.<\/p>\n<p> Inserisci il tuo progetto di cardioprotezione<br \/> 2 &#8211; L&#8217;ufficio fundraising pubblica online il tuo progetto<br \/> 3 &#8211; Se vuoi puoi utilizzare il materiale promozionale<br \/> 4 &#8211; Il tuo progetto riceve il contributo dai visitatori<\/p>\n<p> ListadelCuore.com &egrave; un progetto ideato e realizzato da EMD118 &ndash; Echoes Medical Division, divisione medicale di Echoes Communications Sas, distributore esclusivo per l&rsquo;Italia dei defibrillatori Dae HEARTSINE, azienda leader mondiale nella progettazione e produzione di defibrillatori ad accesso pubblico.<\/p>\n<p> EMD118, nel rispetto della propria mission, promuove ed incentiva la diffusione della cultura della defibrillazione precoce attraverso un servizio gratuito di consulenza offerto a tutti coloro che sono interessati a dotarsi di defibrillatore DAE e di personale addestrato all&rsquo;utilizzo dello stesso. CREA LA TUA LISTA! AVRAI GRATIS UN DEFIBRILLATORE!<\/p>\n<p> Attraverso la compilazione di un form potrai rapidamente procedere all&rsquo;attivazione della tua Lista sul nostro sito, ossia alla pubblicazione del tuo progetto di cardioprotezione che potr&agrave; essere completato grazie ai contributi che soggetti privati o pubblici potranno versare direttamente sul nostro sito. Inserisci tutte le informazioni richieste, quante postazioni di cardioprotezione hai scelto, il nome del destinatario del progetto ed il luogo di collocazione della soluzione di cardioprotezione. Se vorrai, potrai inoltre caricare il logo della tua organizzazione oppure altre immagini che serviranno a rendere pi&ugrave; accattivante la pagina di presentazione della tua Lista. Al ricevimento della tua richiesta, il nostro staff provveder&agrave; in breve tempo per definire tutti i dettagli necessari all&rsquo;attivazione della Lista. <strong>DONA UN DEFIBRILLATORE!<\/strong> <strong>Il tuo prezioso contributo permetter&agrave; di completare un progetto di fondamentale importanza<\/strong>: la dotazione di un defibrillatore e la formazione di personale addetto al primo soccorso con l&rsquo;utilizzo del defibrillatore e di manovre di rianimazione cardiopolmonare. Il tuo pagamento verr&agrave; immediatamente contabilizzato dalla Echoes Communications Sas, titolare del sito <a href=\"http:\/\/www.listadelcuore.com\">www.listadelcuore.com<\/a>, e il promotore del progetto ricever&agrave; in tempo reale la comunicazione del tuo contributo, che potr&agrave; comodamente visualizzare sul proprio sistema di gestione della Lista del Cuore creata. link per info http:\/\/www.listadelcuore.com\/<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Defibrillatore Gratis? Ecco come fare con Lista del Cuore<\/p>\n<p>La prima piattaforma di foundrising per donare o ricevere un Defibrillatore Gratis.Crea la tua lista ora su ListadelCuore.<\/p>\n<p>14\/03\/2014 &#8211; La Lista del Cuore \u00e8 un sistema di incentivazione ideato allo scopo di favorire la realizzazione di progetti di cardioprotezione in ambito privato e pubblico.<br \/>Attivare subito la tua Lista del Cuore \u00e8 semplice! Basta entrare nel sito listadelcuore.com e seguire la nostra guida. Subito il tuo progetto di cardioprotezione potr\u00e0 essere diffuso on-line ed inziare a ricevere i primi contributi!<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"","footnotes":""},"categories":[70],"tags":[46587,46588,46586],"class_list":["post-39747","post","type-post","status-publish","format-standard","hentry","category-medicina","tag-defibrillatore-gratis","tag-dona-un-defibrillatore","tag-lista-del-cuore"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Defibrillatore Gratis? Ecco come fare con Lista del Cuore - Article Marketing<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/medicina\/defibrillatore-gratis-ecco-come-fare-con-lista-del-cuore\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Defibrillatore Gratis? Ecco come fare con Lista del Cuore - Article Marketing\" \/>\n<meta property=\"og:description\" content=\"Defibrillatore Gratis? Ecco come fare con Lista del CuoreLa prima piattaforma di foundrising per donare o ricevere un Defibrillatore Gratis.Crea la tua lista ora su ListadelCuore.14\/03\/2014 - La Lista del Cuore \u00e8 un sistema di incentivazione ideato allo scopo di favorire la realizzazione di progetti di cardioprotezione in ambito privato e pubblico.Attivare subito la tua Lista del Cuore \u00e8 semplice! Basta entrare nel sito listadelcuore.com e seguire la nostra guida. Subito il tuo progetto di cardioprotezione potr\u00e0 essere diffuso on-line ed inziare a ricevere i primi contributi!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/medicina\/defibrillatore-gratis-ecco-come-fare-con-lista-del-cuore\/\" \/>\n<meta property=\"og:site_name\" content=\"Article Marketing\" \/>\n<meta property=\"article:published_time\" content=\"2014-03-14T13:54:27+00:00\" \/>\n<meta name=\"author\" content=\"Redazione Comunicati Stampa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione Comunicati Stampa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/salute-e-benessere\\\/medicina\\\/defibrillatore-gratis-ecco-come-fare-con-lista-del-cuore\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/salute-e-benessere\\\/medicina\\\/defibrillatore-gratis-ecco-come-fare-con-lista-del-cuore\\\/\"},\"author\":{\"name\":\"Redazione Comunicati Stampa\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"headline\":\"Defibrillatore Gratis? Ecco come fare con Lista del Cuore\",\"datePublished\":\"2014-03-14T13:54:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/salute-e-benessere\\\/medicina\\\/defibrillatore-gratis-ecco-come-fare-con-lista-del-cuore\\\/\"},\"wordCount\":501,\"commentCount\":0,\"keywords\":[\"defibrillatore gratis\",\"dona un defibrillatore\",\"lista del cuore\"],\"articleSection\":[\"Medicina\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/salute-e-benessere\\\/medicina\\\/defibrillatore-gratis-ecco-come-fare-con-lista-del-cuore\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/salute-e-benessere\\\/medicina\\\/defibrillatore-gratis-ecco-come-fare-con-lista-del-cuore\\\/\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/salute-e-benessere\\\/medicina\\\/defibrillatore-gratis-ecco-come-fare-con-lista-del-cuore\\\/\",\"name\":\"Defibrillatore Gratis? Ecco come fare con Lista del Cuore - Article Marketing\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\"},\"datePublished\":\"2014-03-14T13:54:27+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/salute-e-benessere\\\/medicina\\\/defibrillatore-gratis-ecco-come-fare-con-lista-del-cuore\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/salute-e-benessere\\\/medicina\\\/defibrillatore-gratis-ecco-come-fare-con-lista-del-cuore\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/salute-e-benessere\\\/medicina\\\/defibrillatore-gratis-ecco-come-fare-con-lista-del-cuore\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Defibrillatore Gratis? Ecco come fare con Lista del Cuore\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\",\"name\":\"Article Marketing\",\"description\":\"article marketing &amp; press release\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\",\"name\":\"Redazione Comunicati Stampa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"caption\":\"Redazione Comunicati Stampa\"},\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/author\\\/redazione-comunicati-stampa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Defibrillatore Gratis? Ecco come fare con Lista del Cuore - Article Marketing","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/medicina\/defibrillatore-gratis-ecco-come-fare-con-lista-del-cuore\/","og_locale":"it_IT","og_type":"article","og_title":"Defibrillatore Gratis? Ecco come fare con Lista del Cuore - Article Marketing","og_description":"Defibrillatore Gratis? Ecco come fare con Lista del CuoreLa prima piattaforma di foundrising per donare o ricevere un Defibrillatore Gratis.Crea la tua lista ora su ListadelCuore.14\/03\/2014 - La Lista del Cuore \u00e8 un sistema di incentivazione ideato allo scopo di favorire la realizzazione di progetti di cardioprotezione in ambito privato e pubblico.Attivare subito la tua Lista del Cuore \u00e8 semplice! Basta entrare nel sito listadelcuore.com e seguire la nostra guida. Subito il tuo progetto di cardioprotezione potr\u00e0 essere diffuso on-line ed inziare a ricevere i primi contributi!","og_url":"https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/medicina\/defibrillatore-gratis-ecco-come-fare-con-lista-del-cuore\/","og_site_name":"Article Marketing","article_published_time":"2014-03-14T13:54:27+00:00","author":"Redazione Comunicati Stampa","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione Comunicati Stampa","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/medicina\/defibrillatore-gratis-ecco-come-fare-con-lista-del-cuore\/#article","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/medicina\/defibrillatore-gratis-ecco-come-fare-con-lista-del-cuore\/"},"author":{"name":"Redazione Comunicati Stampa","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"headline":"Defibrillatore Gratis? Ecco come fare con Lista del Cuore","datePublished":"2014-03-14T13:54:27+00:00","mainEntityOfPage":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/medicina\/defibrillatore-gratis-ecco-come-fare-con-lista-del-cuore\/"},"wordCount":501,"commentCount":0,"keywords":["defibrillatore gratis","dona un defibrillatore","lista del cuore"],"articleSection":["Medicina"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/medicina\/defibrillatore-gratis-ecco-come-fare-con-lista-del-cuore\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/medicina\/defibrillatore-gratis-ecco-come-fare-con-lista-del-cuore\/","url":"https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/medicina\/defibrillatore-gratis-ecco-come-fare-con-lista-del-cuore\/","name":"Defibrillatore Gratis? Ecco come fare con Lista del Cuore - Article Marketing","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website"},"datePublished":"2014-03-14T13:54:27+00:00","author":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"breadcrumb":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/medicina\/defibrillatore-gratis-ecco-come-fare-con-lista-del-cuore\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/medicina\/defibrillatore-gratis-ecco-come-fare-con-lista-del-cuore\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/medicina\/defibrillatore-gratis-ecco-come-fare-con-lista-del-cuore\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.article-marketing.eu\/comunicati\/"},{"@type":"ListItem","position":2,"name":"Defibrillatore Gratis? Ecco come fare con Lista del Cuore"}]},{"@type":"WebSite","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website","url":"https:\/\/www.article-marketing.eu\/comunicati\/","name":"Article Marketing","description":"article marketing &amp; press release","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.article-marketing.eu\/comunicati\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017","name":"Redazione Comunicati Stampa","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","caption":"Redazione Comunicati Stampa"},"url":"https:\/\/www.article-marketing.eu\/comunicati\/author\/redazione-comunicati-stampa\/"}]}},"_links":{"self":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/39747","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/comments?post=39747"}],"version-history":[{"count":0,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/39747\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/media?parent=39747"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/categories?post=39747"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/tags?post=39747"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}