{"id":39766,"date":"2014-03-17T09:55:05","date_gmt":"2014-03-17T08:55:05","guid":{"rendered":"http:\/\/www.article-marketing.eu\/comunicati\/senza-categoria\/epipoli-vince-il-global-prepaid-award-2014\/"},"modified":"2014-03-17T09:55:05","modified_gmt":"2014-03-17T08:55:05","slug":"epipoli-vince-il-global-prepaid-award-2014","status":"publish","type":"post","link":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/marketing\/epipoli-vince-il-global-prepaid-award-2014\/","title":{"rendered":"Epipoli vince il Global Prepaid Award 2014"},"content":{"rendered":"<p>Quest&rsquo;anno il <strong>grande riconoscimento mondiale<\/strong> nel campo del prepagato &ndash; categoria &ldquo;<strong>Market Mover<\/strong>&rdquo; &egrave; stato assegnato a un progetto di Social CRM tutto italiano di <strong><a href=\"http:\/\/www.epipoli.com\">Epipoli<\/a><\/strong>. Las Vegas 6 marzo 2014 &ndash; <strong>Paybefore<\/strong>, la testata internazionale di informazione pi&ugrave; autorevole nel mondo del &ldquo;prepagato&rdquo; e dei metodi di pagamento innovativi, <strong>premia Epipoli<\/strong> nella categoria &ldquo;<strong>Market Mover<\/strong>&rdquo; che comprende tutte le iniziative legate al mondo digital e mobile. <strong>Epipoli<\/strong> diventa cos&igrave; uno dei protagonisti internazionali della cosiddetta &ldquo;gamification&rdquo;, il nuovo trend di engagement del consumatore che fonde i pi&ugrave; innovativi strumenti di marketing come la fidelizzazione, le Gift Card, il couponing e l&rsquo;in-store execution. La piattaforma mobile realizzata da Epipoli, &egrave;, infatti, la prima applicazione di rewarding che premia i consumatori per le azioni e le attivit&agrave; social che migliorano la relazione con le aziende: dallo scatto di foto a prodotti e situazioni, alla scansione di codici a barre, al check-in nei negozi, acquisti, caccia al tesoro, etc&hellip; La <em>gamification<\/em> migliora la shopping experience del consumatore e il suo grado di affiliazione al brand perch&eacute;, attraverso attivit&agrave; ludiche da condividere sui social network, lo trasforma in un vero e proprio promoter del brand e del prodotto.<br \/> Le aziende godranno, cos&igrave;, di una attivit&agrave; di comunicazione inedita e avranno anche la possibilit&agrave; di analizzare in maniera pi&ugrave; precisa il consumatore nei suoi comportamenti social e d&rsquo;acquisto. Il progetto parte nel 2004 quando <strong>Epipoli brevetta<\/strong>, insieme all&rsquo;<strong>Universit&agrave; di Parma, GordioTM<\/strong>: il primo sistema europeo di tracciatura dei percorsi all&rsquo;interno dei punti vendita. Lo strumento consentiva di effettuare promozioni 1 to 1 nel momento di maggiore propensione all&rsquo;acquisto, quando il consumatore era proprio di fronte allo scaffale.<br \/> Il progetto fu lanciato in Conad Centro Nord con il supporto iniziale di Procter&amp;Gamble, Kraft, Granarolo e Barilla.<br \/> Oggi, con l&rsquo;evoluzione tecnologica e lo sviluppo dei social media, il progetto si &egrave; evoluto nella nuova piattaforma abbattendo costi e tempi di implementazione. <strong>Epipoli,<\/strong> dopo essere entrata nella short list dei 3 finalisti superando una dura selezione con decine di progetti internazionali, <strong>ha prevalso in finale su Citibank<\/strong> che ha sviluppato un progetto con H3G e la citt&agrave; di Hong Kong e Deniz Bank, una delle principali banche turche. A ritirare l&rsquo;ambito riconoscimento, durante la cerimonia che si &egrave; tenuta a Las Vegas il 5 marzo, &egrave; stato <strong>Gaetano Giannetto, CEO &amp; Founder di Epipoli<\/strong> : &ldquo;Arrivare in nomination al Paybefore Awards 2014 &egrave; gi&agrave; un onore. Avere vinto il primo premio in una categoria cos&igrave; importante conferma la nostra vocazione all&rsquo;innovazione non solo nel mercato italiano ma anche in quello mondiale. Epipoli ha creato un ponte diretto tra loyalty program e le Gift Card innovando la customer experience del consumatore nel momento dell&rsquo;acquisto. &Egrave; stato un anno molto importante per la nostra azienda ed essere considerata una delle 20 societ&agrave; innovative dell&rsquo;anno &egrave; una enorme soddisfazione. Le altre aziende che hanno vinto le rispettive categorie sono i grandi player mondiali come Walmart, MasterCard, Discover, Visa, Western Union solo per citarne alcune&rdquo;. <strong>Loraine DeBonis<\/strong>, Paybefore editor-in-chief e Presidente della giuria <strong>ha dichiarato<\/strong>: &ldquo;Quest&rsquo;anno i Paybefore Awards hanno dimostrato che le <strong>societ&agrave; che operano nel campo dei metodi di pagamento innovativi e attraverso mobile trovano sempre nuove strade per indirizzare i bisogni dei consumatori, dei governi e delle aziende.<\/strong> Noi siamo orgogliosi di riconoscere il contributo fornito da Epipoli in questo campo&rdquo;. Con questo passo Epipoli traccia la via che porta alla modernizzazione e democratizzazione delle attivit&agrave; di rewarding dal momento che qualsiasi consumatore pu&ograve; partecipare al programma, a prescindere dal suo comportamento di acquisto e si qualifica come una delle 20 aziende al mondo pi&ugrave; innovative dell&rsquo;anno. &mdash;&mdash;&mdash;&mdash;&mdash;&mdash;&mdash;&mdash;-<br \/> <em><strong>Epipoli<\/strong>: fondata nel 2000, &egrave; una delle societ&agrave; leader nel marketing relazionale, specializzata in CRM, analisi dati e Gift Card. Queste competenze la rendono un punto di riferimento nell&rsquo;area della customer insight. In quanto leader europeo nella gestione dei Gift Card program, Epipoli ha accesso a oltre 50.000 punti vendita.<br \/> La sede centrale &egrave; a Milano ma, attraverso filiali e partner internazionali, opera in tutti i paesi europei.<br \/> www.epipoli.com\t\twww.mygiftcard.it <\/em> <em> <\/em> <em><strong>Paybefore<\/strong>: con le sue opinioni, analisi e ultime notizie, &egrave; la maggiore testata di informazione nel campo del prepagato e dei metodi di pagamento innovativi. La famiglia Paybefore &egrave; composta da: Paybefore.com, Pay NewsTM, Pay GovTM, Pay WeekTM, Pay Op-EdTM, Pay MagazineTM &ndash; una rivista semestrale con articoli di approfondimento sulle opportunit&agrave;, le sfide e le tendenze nel settore dei pagamenti globali &ndash; e la guida Pay ConnectTM buyer, disponibile online e in formato cartaceo.<br \/> www.paybefore.com<\/em> Per ulteriori info: <strong>Epipoli S.p.A.:<\/strong><br \/> Dr.ssa Pina Panunzio<br \/> Dir. Marketing e Comunicazione Epipoli S.p.A.<br \/> pina.panunzio@epipoli.com cell +39 3939542601 Ufficio Stampa:<br \/> <strong>Blu Wom Milano srl<\/strong><br \/> Via Sant&rsquo;Agnese 14<br \/> 20123 Milano<br \/> p.fabretti@bluwom-milano.com tel 02 87384640 <img decoding=\"async\" src=\"\/uploads\/images\/u_15288\/thumb_logopayawards1.gif\" border=\"0\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Quest\u2019anno il grande riconoscimento mondiale nel campo del prepagato \u2013 categoria \u201cMarket Mover\u201d \u00e8 stato assegnato a un progetto di Social CRM tutto italiano di Epipoli. Las Vegas 6 marzo 2014 \u2013 Paybefore, la testata internazionale di informazione pi\u00f9 autorevole nel mondo del \u201cprepagato\u201d e dei metodi di pagamento innovativi, premia Epipoli nella categoria \u201cMarket Mover\u201d che comprende tutte le iniziative legate al mondo digital e mobile.<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"","footnotes":""},"categories":[103],"tags":[38526,46597,46598,912,42423],"class_list":["post-39766","post","type-post","status-publish","format-standard","hentry","category-marketing","tag-awards","tag-epipoli","tag-gamification","tag-premio","tag-social-crm"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Epipoli vince il Global Prepaid Award 2014 - Article Marketing<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/marketing\/epipoli-vince-il-global-prepaid-award-2014\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Epipoli vince il Global Prepaid Award 2014 - Article Marketing\" \/>\n<meta property=\"og:description\" content=\"Quest\u2019anno il grande riconoscimento mondiale nel campo del prepagato \u2013 categoria \u201cMarket Mover\u201d \u00e8 stato assegnato a un progetto di Social CRM tutto italiano di Epipoli. Las Vegas 6 marzo 2014 \u2013 Paybefore, la testata internazionale di informazione pi\u00f9 autorevole nel mondo del \u201cprepagato\u201d e dei metodi di pagamento innovativi, premia Epipoli nella categoria \u201cMarket Mover\u201d che comprende tutte le iniziative legate al mondo digital e mobile.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/marketing\/epipoli-vince-il-global-prepaid-award-2014\/\" \/>\n<meta property=\"og:site_name\" content=\"Article Marketing\" \/>\n<meta property=\"article:published_time\" content=\"2014-03-17T08:55:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.article-marketing.eu\/uploads\/images\/u_15288\/thumb_logopayawards1.gif\" \/>\n<meta name=\"author\" content=\"Redazione Comunicati Stampa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione Comunicati Stampa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/economia-e-lavoro\\\/marketing\\\/epipoli-vince-il-global-prepaid-award-2014\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/economia-e-lavoro\\\/marketing\\\/epipoli-vince-il-global-prepaid-award-2014\\\/\"},\"author\":{\"name\":\"Redazione Comunicati Stampa\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"headline\":\"Epipoli vince il Global Prepaid Award 2014\",\"datePublished\":\"2014-03-17T08:55:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/economia-e-lavoro\\\/marketing\\\/epipoli-vince-il-global-prepaid-award-2014\\\/\"},\"wordCount\":859,\"commentCount\":0,\"keywords\":[\"Awards\",\"Epipoli\",\"Gamification\",\"premio\",\"social crm\"],\"articleSection\":[\"Marketing\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/economia-e-lavoro\\\/marketing\\\/epipoli-vince-il-global-prepaid-award-2014\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/economia-e-lavoro\\\/marketing\\\/epipoli-vince-il-global-prepaid-award-2014\\\/\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/economia-e-lavoro\\\/marketing\\\/epipoli-vince-il-global-prepaid-award-2014\\\/\",\"name\":\"Epipoli vince il Global Prepaid Award 2014 - Article Marketing\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\"},\"datePublished\":\"2014-03-17T08:55:05+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/economia-e-lavoro\\\/marketing\\\/epipoli-vince-il-global-prepaid-award-2014\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/economia-e-lavoro\\\/marketing\\\/epipoli-vince-il-global-prepaid-award-2014\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/economia-e-lavoro\\\/marketing\\\/epipoli-vince-il-global-prepaid-award-2014\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Epipoli vince il Global Prepaid Award 2014\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\",\"name\":\"Article Marketing\",\"description\":\"article marketing &amp; press release\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\",\"name\":\"Redazione Comunicati Stampa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"caption\":\"Redazione Comunicati Stampa\"},\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/author\\\/redazione-comunicati-stampa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Epipoli vince il Global Prepaid Award 2014 - Article Marketing","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/marketing\/epipoli-vince-il-global-prepaid-award-2014\/","og_locale":"it_IT","og_type":"article","og_title":"Epipoli vince il Global Prepaid Award 2014 - Article Marketing","og_description":"Quest\u2019anno il grande riconoscimento mondiale nel campo del prepagato \u2013 categoria \u201cMarket Mover\u201d \u00e8 stato assegnato a un progetto di Social CRM tutto italiano di Epipoli. Las Vegas 6 marzo 2014 \u2013 Paybefore, la testata internazionale di informazione pi\u00f9 autorevole nel mondo del \u201cprepagato\u201d e dei metodi di pagamento innovativi, premia Epipoli nella categoria \u201cMarket Mover\u201d che comprende tutte le iniziative legate al mondo digital e mobile.","og_url":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/marketing\/epipoli-vince-il-global-prepaid-award-2014\/","og_site_name":"Article Marketing","article_published_time":"2014-03-17T08:55:05+00:00","og_image":[{"url":"https:\/\/www.article-marketing.eu\/uploads\/images\/u_15288\/thumb_logopayawards1.gif","type":"","width":"","height":""}],"author":"Redazione Comunicati Stampa","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione Comunicati Stampa","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/marketing\/epipoli-vince-il-global-prepaid-award-2014\/#article","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/marketing\/epipoli-vince-il-global-prepaid-award-2014\/"},"author":{"name":"Redazione Comunicati Stampa","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"headline":"Epipoli vince il Global Prepaid Award 2014","datePublished":"2014-03-17T08:55:05+00:00","mainEntityOfPage":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/marketing\/epipoli-vince-il-global-prepaid-award-2014\/"},"wordCount":859,"commentCount":0,"keywords":["Awards","Epipoli","Gamification","premio","social crm"],"articleSection":["Marketing"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/marketing\/epipoli-vince-il-global-prepaid-award-2014\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/marketing\/epipoli-vince-il-global-prepaid-award-2014\/","url":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/marketing\/epipoli-vince-il-global-prepaid-award-2014\/","name":"Epipoli vince il Global Prepaid Award 2014 - Article Marketing","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website"},"datePublished":"2014-03-17T08:55:05+00:00","author":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"breadcrumb":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/marketing\/epipoli-vince-il-global-prepaid-award-2014\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/marketing\/epipoli-vince-il-global-prepaid-award-2014\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/marketing\/epipoli-vince-il-global-prepaid-award-2014\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.article-marketing.eu\/comunicati\/"},{"@type":"ListItem","position":2,"name":"Epipoli vince il Global Prepaid Award 2014"}]},{"@type":"WebSite","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website","url":"https:\/\/www.article-marketing.eu\/comunicati\/","name":"Article Marketing","description":"article marketing &amp; press release","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.article-marketing.eu\/comunicati\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017","name":"Redazione Comunicati Stampa","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","caption":"Redazione Comunicati Stampa"},"url":"https:\/\/www.article-marketing.eu\/comunicati\/author\/redazione-comunicati-stampa\/"}]}},"_links":{"self":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/39766","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/comments?post=39766"}],"version-history":[{"count":0,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/39766\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/media?parent=39766"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/categories?post=39766"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/tags?post=39766"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}