{"id":39778,"date":"2014-03-17T16:39:55","date_gmt":"2014-03-17T15:39:55","guid":{"rendered":"http:\/\/www.article-marketing.eu\/comunicati\/senza-categoria\/passione-tradizione-e-innovazione-il-frantoio-bonamini-porta-in-tavola-la-genuinit%25c3%2580-della%2580%2599olio-extra-vergine-da%2580%2599oliva\/"},"modified":"2014-03-17T16:39:55","modified_gmt":"2014-03-17T15:39:55","slug":"passione-tradizione-e-innovazione-il-frantoio-bonamini-porta-in-tavola-la-genuinit%25c3%2580-della%2580%2599olio-extra-vergine-da%2580%2599oliva","status":"publish","type":"post","link":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/passione-tradizione-e-innovazione-il-frantoio-bonamini-porta-in-tavola-la-genuinit%25c3%2580-della%2580%2599olio-extra-vergine-da%2580%2599oliva\/","title":{"rendered":"PASSIONE, TRADIZIONE E INNOVAZIONE: IL FRANTOIO BONAMINI PORTA IN TAVOLA LA GENUINIT\u00c0 DELL\u2019OLIO EXTRA VERGINE D\u2019OLIVA"},"content":{"rendered":"<p>Verona, Marzo 2014 &#8211; Rispetto delle tradizioni e passione per il territorio, queste le caratteristiche del Frantoio Bonamini che sar&agrave; presente a Sol&amp;Agrifood (Area SOL&amp;AGRIFOOD &#8211; Stand C24), la rassegna internazionale dell&rsquo;agroalimentare di qualit&agrave; in scena a Verona dal 6 al 9 aprile 2014 durante il ben noto Vinitaly.<br \/>Questa la vetrina ufficiale per la presentazione del prestigioso olio extravergine &ldquo;D.O.P. Veneto &#8211; Valpolicella&rdquo;, miglior olio extra vergine d&rsquo;oliva Dop Fruttato Leggero del mondo, secondo la guida Flos Olei 2014, considerata tra le pi&ugrave; influenti a livello mondiale per la valutazione della qualit&agrave; dei migliori oli extra vergine d&#8217;oliva.<\/p>\n<p>Dal legame con il territorio e con le tradizioni passate, il Frantoio Bonamini porta avanti con dedizione il suo amorevole impegno per l&rsquo;olio tramandato di padre in figlio. Una realt&agrave; che conta ormai pi&ugrave; di 40 anni di storia che questa famiglia, custode dell&rsquo;antica tradizione olearia, dedica all&rsquo;oliva in tutte le sue declinazioni. A gestione di questa realt&agrave;, oggi, Giancarlo e Sabrina Bonamini proseguono le lodevoli orme del padre Stefano mantenendo sempre un rispettoso legame con territorio, tradizioni e ambiente locale. Filosofia che ha reso questo brand uno dei pi&ugrave; riconosciuti nel mercato oleario e che continua ad essere il punto di forza di questa famiglia, cresciuta molto negli ultimi anni vantando una produzione di circa 220.000 bottiglie l&rsquo;anno con un&#8217;esportazione pari al 20% all&rsquo;estero.<\/p>\n<p>Tutti i passaggi dell&rsquo;operazione colturale, compresa quindi anche la raccolta, vengono svolti a mano garantendo l&rsquo;integrit&agrave; del frutto fino all&rsquo;arrivo in frantoio dove il tecnologico impianto continuo ad estrazione a freddo trasforma il prodotto in olio extra vergine d&rsquo;oliva dalla particolare finezza e fragranza.<\/p>\n<p>Non solo premi e soddisfazioni aziendali, ma anche un lodevole occhio di riguardo all&rsquo;ambiente e alla natura circostante che accoglie il Frantoio. Da questa vicinanza al territorio nasce il Museo dell&rsquo;Olio Bonamini, testimone di una filosofia alla cui base resta il rispetto per la tradizione italiana, che accoglie il visitatore facendolo inebriare dei sapori e dei profumi di questo prezioso prodotto della natura grazie alle visite guidate che ne raccontano la storia e ai percorsi sensoriali enogastronomici. Inoltre nel punto vendita &egrave; possibile acquistare i migliori prodotti oleari, ma anche gli articoli di cosmesi studiati e preparati con le olive dell&rsquo;azienda stessa.<\/p>\n<p>Un mondo, quello della famiglia Bonamini, che ruota tutto intorno al benessere del consumatore e che spinge la stessa azienda alla ricerca di nuove tecniche per salvaguardare un prodotto e il suo territorio tanto apprezzato anche fuori dai confini nazionali.<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Rispetto delle tradizioni e passione per il territorio, queste le caratteristiche del Frantoio Bonamini che sar\u00e0 presente a Sol&#038;Agrifood (Area SOL&#038;AGRIFOOD &#8211; Stand C24), la rassegna internazionale dell\u2019agroalimentare di qualit\u00e0 in scena a Verona dal 6 al 9 aprile 2014 durante il ben noto Vinitaly.<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"","footnotes":""},"categories":[190],"tags":[45478,46600,709,37,46599,13663],"class_list":["post-39778","post","type-post","status-publish","format-standard","hentry","category-comunicati-stampa","tag-bonamini","tag-genuinita","tag-olio","tag-passione","tag-solagrifood","tag-vinitaly"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>PASSIONE, TRADIZIONE E INNOVAZIONE: IL FRANTOIO BONAMINI PORTA IN TAVOLA LA GENUINIT\u00c0 DELL\u2019OLIO EXTRA VERGINE D\u2019OLIVA - Article Marketing<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/passione-tradizione-e-innovazione-il-frantoio-bonamini-porta-in-tavola-la-genuinit%c3%80-della%80%99olio-extra-vergine-da%80%99oliva\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"PASSIONE, TRADIZIONE E INNOVAZIONE: IL FRANTOIO BONAMINI PORTA IN TAVOLA LA GENUINIT\u00c0 DELL\u2019OLIO EXTRA VERGINE D\u2019OLIVA - Article Marketing\" \/>\n<meta property=\"og:description\" content=\"Rispetto delle tradizioni e passione per il territorio, queste le caratteristiche del Frantoio Bonamini che sar\u00e0 presente a Sol&amp;Agrifood (Area SOL&amp;AGRIFOOD - Stand C24), la rassegna internazionale dell\u2019agroalimentare di qualit\u00e0 in scena a Verona dal 6 al 9 aprile 2014 durante il ben noto Vinitaly.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/passione-tradizione-e-innovazione-il-frantoio-bonamini-porta-in-tavola-la-genuinit%c3%80-della%80%99olio-extra-vergine-da%80%99oliva\/\" \/>\n<meta property=\"og:site_name\" content=\"Article Marketing\" \/>\n<meta property=\"article:published_time\" content=\"2014-03-17T15:39:55+00:00\" \/>\n<meta name=\"author\" content=\"Redazione Comunicati Stampa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione Comunicati Stampa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/passione-tradizione-e-innovazione-il-frantoio-bonamini-porta-in-tavola-la-genuinit%25c3%2580-della%2580%2599olio-extra-vergine-da%2580%2599oliva\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/passione-tradizione-e-innovazione-il-frantoio-bonamini-porta-in-tavola-la-genuinit%25c3%2580-della%2580%2599olio-extra-vergine-da%2580%2599oliva\\\/\"},\"author\":{\"name\":\"Redazione Comunicati Stampa\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"headline\":\"PASSIONE, TRADIZIONE E INNOVAZIONE: IL FRANTOIO BONAMINI PORTA IN TAVOLA LA GENUINIT\u00c0 DELL\u2019OLIO EXTRA VERGINE D\u2019OLIVA\",\"datePublished\":\"2014-03-17T15:39:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/passione-tradizione-e-innovazione-il-frantoio-bonamini-porta-in-tavola-la-genuinit%25c3%2580-della%2580%2599olio-extra-vergine-da%2580%2599oliva\\\/\"},\"wordCount\":465,\"commentCount\":0,\"keywords\":[\"bonamini\",\"genuinit\u00e0\",\"olio\",\"passione\",\"sol&amp;agrifood\",\"Vinitaly\"],\"articleSection\":[\"Comunicati stampa\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/passione-tradizione-e-innovazione-il-frantoio-bonamini-porta-in-tavola-la-genuinit%25c3%2580-della%2580%2599olio-extra-vergine-da%2580%2599oliva\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/passione-tradizione-e-innovazione-il-frantoio-bonamini-porta-in-tavola-la-genuinit%25c3%2580-della%2580%2599olio-extra-vergine-da%2580%2599oliva\\\/\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/passione-tradizione-e-innovazione-il-frantoio-bonamini-porta-in-tavola-la-genuinit%25c3%2580-della%2580%2599olio-extra-vergine-da%2580%2599oliva\\\/\",\"name\":\"PASSIONE, TRADIZIONE E INNOVAZIONE: IL FRANTOIO BONAMINI PORTA IN TAVOLA LA GENUINIT\u00c0 DELL\u2019OLIO EXTRA VERGINE D\u2019OLIVA - Article Marketing\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\"},\"datePublished\":\"2014-03-17T15:39:55+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/passione-tradizione-e-innovazione-il-frantoio-bonamini-porta-in-tavola-la-genuinit%25c3%2580-della%2580%2599olio-extra-vergine-da%2580%2599oliva\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/passione-tradizione-e-innovazione-il-frantoio-bonamini-porta-in-tavola-la-genuinit%25c3%2580-della%2580%2599olio-extra-vergine-da%2580%2599oliva\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/passione-tradizione-e-innovazione-il-frantoio-bonamini-porta-in-tavola-la-genuinit%25c3%2580-della%2580%2599olio-extra-vergine-da%2580%2599oliva\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"PASSIONE, TRADIZIONE E INNOVAZIONE: IL FRANTOIO BONAMINI PORTA IN TAVOLA LA GENUINIT\u00c0 DELL\u2019OLIO EXTRA VERGINE D\u2019OLIVA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\",\"name\":\"Article Marketing\",\"description\":\"article marketing &amp; press release\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\",\"name\":\"Redazione Comunicati Stampa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"caption\":\"Redazione Comunicati Stampa\"},\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/author\\\/redazione-comunicati-stampa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"PASSIONE, TRADIZIONE E INNOVAZIONE: IL FRANTOIO BONAMINI PORTA IN TAVOLA LA GENUINIT\u00c0 DELL\u2019OLIO EXTRA VERGINE D\u2019OLIVA - Article Marketing","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/passione-tradizione-e-innovazione-il-frantoio-bonamini-porta-in-tavola-la-genuinit%c3%80-della%80%99olio-extra-vergine-da%80%99oliva\/","og_locale":"it_IT","og_type":"article","og_title":"PASSIONE, TRADIZIONE E INNOVAZIONE: IL FRANTOIO BONAMINI PORTA IN TAVOLA LA GENUINIT\u00c0 DELL\u2019OLIO EXTRA VERGINE D\u2019OLIVA - Article Marketing","og_description":"Rispetto delle tradizioni e passione per il territorio, queste le caratteristiche del Frantoio Bonamini che sar\u00e0 presente a Sol&Agrifood (Area SOL&AGRIFOOD - Stand C24), la rassegna internazionale dell\u2019agroalimentare di qualit\u00e0 in scena a Verona dal 6 al 9 aprile 2014 durante il ben noto Vinitaly.","og_url":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/passione-tradizione-e-innovazione-il-frantoio-bonamini-porta-in-tavola-la-genuinit%c3%80-della%80%99olio-extra-vergine-da%80%99oliva\/","og_site_name":"Article Marketing","article_published_time":"2014-03-17T15:39:55+00:00","author":"Redazione Comunicati Stampa","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione Comunicati Stampa","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/passione-tradizione-e-innovazione-il-frantoio-bonamini-porta-in-tavola-la-genuinit%25c3%2580-della%2580%2599olio-extra-vergine-da%2580%2599oliva\/#article","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/passione-tradizione-e-innovazione-il-frantoio-bonamini-porta-in-tavola-la-genuinit%25c3%2580-della%2580%2599olio-extra-vergine-da%2580%2599oliva\/"},"author":{"name":"Redazione Comunicati Stampa","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"headline":"PASSIONE, TRADIZIONE E INNOVAZIONE: IL FRANTOIO BONAMINI PORTA IN TAVOLA LA GENUINIT\u00c0 DELL\u2019OLIO EXTRA VERGINE D\u2019OLIVA","datePublished":"2014-03-17T15:39:55+00:00","mainEntityOfPage":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/passione-tradizione-e-innovazione-il-frantoio-bonamini-porta-in-tavola-la-genuinit%25c3%2580-della%2580%2599olio-extra-vergine-da%2580%2599oliva\/"},"wordCount":465,"commentCount":0,"keywords":["bonamini","genuinit\u00e0","olio","passione","sol&amp;agrifood","Vinitaly"],"articleSection":["Comunicati stampa"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/passione-tradizione-e-innovazione-il-frantoio-bonamini-porta-in-tavola-la-genuinit%25c3%2580-della%2580%2599olio-extra-vergine-da%2580%2599oliva\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/passione-tradizione-e-innovazione-il-frantoio-bonamini-porta-in-tavola-la-genuinit%25c3%2580-della%2580%2599olio-extra-vergine-da%2580%2599oliva\/","url":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/passione-tradizione-e-innovazione-il-frantoio-bonamini-porta-in-tavola-la-genuinit%25c3%2580-della%2580%2599olio-extra-vergine-da%2580%2599oliva\/","name":"PASSIONE, TRADIZIONE E INNOVAZIONE: IL FRANTOIO BONAMINI PORTA IN TAVOLA LA GENUINIT\u00c0 DELL\u2019OLIO EXTRA VERGINE D\u2019OLIVA - Article Marketing","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website"},"datePublished":"2014-03-17T15:39:55+00:00","author":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"breadcrumb":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/passione-tradizione-e-innovazione-il-frantoio-bonamini-porta-in-tavola-la-genuinit%25c3%2580-della%2580%2599olio-extra-vergine-da%2580%2599oliva\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/passione-tradizione-e-innovazione-il-frantoio-bonamini-porta-in-tavola-la-genuinit%25c3%2580-della%2580%2599olio-extra-vergine-da%2580%2599oliva\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/passione-tradizione-e-innovazione-il-frantoio-bonamini-porta-in-tavola-la-genuinit%25c3%2580-della%2580%2599olio-extra-vergine-da%2580%2599oliva\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.article-marketing.eu\/comunicati\/"},{"@type":"ListItem","position":2,"name":"PASSIONE, TRADIZIONE E INNOVAZIONE: IL FRANTOIO BONAMINI PORTA IN TAVOLA LA GENUINIT\u00c0 DELL\u2019OLIO EXTRA VERGINE D\u2019OLIVA"}]},{"@type":"WebSite","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website","url":"https:\/\/www.article-marketing.eu\/comunicati\/","name":"Article Marketing","description":"article marketing &amp; press release","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.article-marketing.eu\/comunicati\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017","name":"Redazione Comunicati Stampa","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","caption":"Redazione Comunicati Stampa"},"url":"https:\/\/www.article-marketing.eu\/comunicati\/author\/redazione-comunicati-stampa\/"}]}},"_links":{"self":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/39778","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/comments?post=39778"}],"version-history":[{"count":0,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/39778\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/media?parent=39778"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/categories?post=39778"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/tags?post=39778"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}