{"id":4190,"date":"2010-02-19T11:51:31","date_gmt":"2010-02-19T10:51:31","guid":{"rendered":"http:\/\/www.article-marketing.eu\/comunicati\/senza-categoria\/successo-di-downoad-dal-sito-blackberry-per-la-nuova-release-di-ubinav-il-primo-software-di-navigazione-mobile-tutto-italiano\/"},"modified":"2010-02-19T11:51:31","modified_gmt":"2010-02-19T10:51:31","slug":"successo-di-downoad-dal-sito-blackberry-per-la-nuova-release-di-ubinav-il-primo-software-di-navigazione-mobile-tutto-italiano","status":"publish","type":"post","link":"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/ricerca-e-sviluppo\/successo-di-downoad-dal-sito-blackberry-per-la-nuova-release-di-ubinav-il-primo-software-di-navigazione-mobile-tutto-italiano\/","title":{"rendered":"Successo di downoad dal sito Blackberry per la nuova release di UbiNav, il primo software di navigazione mobile tutto italiano."},"content":{"rendered":"<p class=\"MsoNormal\"><strong><a href=\"www.ubinav.com\">UbiNav<\/a>, il software made in Italy per la<br \/>\nnavigazione mobile di UbiEst ora disponibile per il download gratuito trial dal<br \/>\nsito Blackberry: trasforma il famoso smartphone in un navigatore GPS di design.<\/strong><\/p>\n<p class=\"MsoNormal\">A seguito<br \/>\ndell accordo tra RIM Blackberry e<br \/>\nUbiEst Spa, leader italiano nel software per la localizzazione, \u00e8 stata<br \/>\nrilasciata sul sito Blackberry la versione trial gratuita di UbiNav, <strong>la prima soluzione  design appealed  di off board navigation.<\/strong><\/p>\n<p class=\"MsoNormal\">UBINAV \u00e8 una <strong>applicazione scaricabile on line che trasforma <\/strong><strong> un<br \/>\ncellulare o uno smartphone in un navigatore satellitare completo<\/strong> per il calcolo percorsi e navigazione, punti di<br \/>\ninteresse, ricerca indirizzi, navigazione assistita grafica e vocale al<br \/>\ndettaglio della manovra.<\/p>\n<p class=\"MsoNormal\"><strong><u>UBINAV<\/u><\/strong><strong> offre tutte le funzionalit\u00e0 di un tradizionale<br \/>\nnavigatore satellitare<\/strong>: mappe digitali a colori<br \/>\ncon visualizzazione 2d, 3d e panoramica, zoom, spostamento, ricentratura;<br \/>\nindicazioni di viabilit\u00e0 e nomi delle strade, assistenza grafica e vocale alla<br \/>\nguida basata sulla localizzazione.\n<\/p>\n<p class=\"MsoNormal\">Ci\u00f2 che distingue UBINAV da ogni altro applicativo, <strong>\u00e8 la sua innovativa interfaccia grafica: un concept mutuato dall Italian fashion design,<\/strong><br \/>\nche porta per la prima volta l inconfondibile gusto del made in Italy nel mondo<br \/>\ndelle applicazioni per la telefonia mobile.<\/p>\n<p class=\"MsoNormal\"><strong>L interfaccia utente, infatti,<br \/>\n\u00e8 stata disegnata in collaborazione con un team di designer<\/strong> e creativi di moda italiani, che si sono<br \/>\nfocalizzati su look futuristico e funzionalit\u00e0.<\/p>\n<p class=\"MsoNormal\">Lo sfondo total black con il men\u00f9 dinamico a rotazione ha un look&amp;<br \/>\nfeel pulito e minimale. Il banner delle info e la barra dei comandi in<br \/>\ntrasparenza, scorrono piacevolmente senza coprire il main screen di<br \/>\nnavigazione.<\/p>\n<p class=\"MsoNormal\">L applicazione \u00e8 semplicemente bella e user friendly.<\/p>\n<p class=\"MsoNormal\"><em> Volevamo allontanarci dal<br \/>\nlook &amp; feel prettamente tecnico e portare la user experience pi\u00f9 vicina<br \/>\nalla sensibilit\u00e0 del grande pubblico. Le applicazioni devono essere anche un<br \/>\npiacere per gli occhi e noi pensiamo che oggi molte compagnie trascurino questo<br \/>\naspetto. <\/em> Dichiara Nicola De Mattia, CEO di UbiEst S.p.A.<\/p>\n<p class=\"MsoNormal\"><strong>Una piacevolezza che \u00e8 stata<br \/>\npremiata dagli utenti Blackberry<\/strong>, che confermano UBINAV l applicativo pi\u00f9 cliccato nel segmento GPS<br \/>\nper smartphone.<\/p>\n<p class=\"MsoNormal\">UbiNav infatti &#8211; gi\u00e0 lanciata con successo da un selezionato numero di<br \/>\noperatori di telefonia in Europa &#8211; \u00e8 oggi disponibile sul sito Blackberry App<br \/>\nStore, anche nella<br \/>\nversione free trial al sito appworld.blackberry.com<\/p>\n<\/p>\n<p class=\"MsoNormal\"><strong>UBIEST SPA:<\/strong><\/p>\n<p class=\"MsoNormal\">UbiEst S.p.A.<br \/>\nfornisce soluzioni di <strong>Location Intelligence<\/strong>: mappe online,<br \/>\nstrumenti di navigazione, servizi basati sulla localizzazione e geomarketing,<br \/>\naccessibili attraverso Internet e connessioni mobili per mercati Business e<br \/>\nConsumer. <\/p>\n<p class=\"MsoNormal\">La Societ\u00e0, con<br \/>\nsede a Treviso, nasce nel 2001 , risultato della sinergia tra competenze<br \/>\nnell&#8217;Information Technology e l&#8217;expertise del Gruppo Elda (di cui fa parte)<br \/>\nnella produzione di software per la gestione del territorio e la cartografia<br \/>\nvettoriale. Sin dall&#8217;inizio UbiEst ha concentrato oltre l&#8217;80% del proprio<br \/>\norganico sulla Ricerca e Sviluppo, implementando soluzioni di cartografia<br \/>\ninterattiva su tecnologia proprietaria disponibili sia in modalit\u00e0 ASP che<br \/>\nin-house. <\/p>\n<p class=\"MsoNormal\">L&#8217;alleanza<br \/>\nstrategica con Navteq consente a UbiEst di adottare il miglior supporto<br \/>\ncartografico disponibile sul mercato per le proprie soluzioni.<\/p>\n<p class=\"MsoNormal\">La societ\u00e0 \u00e8<br \/>\npresente anche sul mass market con prodotti e soluzioni innovative consumer,<br \/>\ncome UBISAFE, il localizzatore per la sicurezza familiare visualizzabile sul PC o su cellulare. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mobile World Congress: UbiEst ha presentato la nuova release di UbiNav, il noto software di navigazione per smartphone con una nuova interfaccia grafica che promette una piacevolezza di utilizzo mai provata prima.<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"","footnotes":""},"categories":[77],"tags":[],"class_list":["post-4190","post","type-post","status-publish","format-standard","hentry","category-ricerca-e-sviluppo"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Successo di downoad dal sito Blackberry per la nuova release di UbiNav, il primo software di navigazione mobile tutto italiano. - Article Marketing<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/ricerca-e-sviluppo\/successo-di-downoad-dal-sito-blackberry-per-la-nuova-release-di-ubinav-il-primo-software-di-navigazione-mobile-tutto-italiano\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Successo di downoad dal sito Blackberry per la nuova release di UbiNav, il primo software di navigazione mobile tutto italiano. - Article Marketing\" \/>\n<meta property=\"og:description\" content=\"Mobile World Congress: UbiEst ha presentato la nuova release di UbiNav, il noto software di navigazione per smartphone con una nuova interfaccia grafica che promette una piacevolezza di utilizzo mai provata prima.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/ricerca-e-sviluppo\/successo-di-downoad-dal-sito-blackberry-per-la-nuova-release-di-ubinav-il-primo-software-di-navigazione-mobile-tutto-italiano\/\" \/>\n<meta property=\"og:site_name\" content=\"Article Marketing\" \/>\n<meta property=\"article:published_time\" content=\"2010-02-19T10:51:31+00:00\" \/>\n<meta name=\"author\" content=\"Redazione Comunicati Stampa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione Comunicati Stampa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/arte-e-cultura\\\/ricerca-e-sviluppo\\\/successo-di-downoad-dal-sito-blackberry-per-la-nuova-release-di-ubinav-il-primo-software-di-navigazione-mobile-tutto-italiano\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/arte-e-cultura\\\/ricerca-e-sviluppo\\\/successo-di-downoad-dal-sito-blackberry-per-la-nuova-release-di-ubinav-il-primo-software-di-navigazione-mobile-tutto-italiano\\\/\"},\"author\":{\"name\":\"Redazione Comunicati Stampa\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"headline\":\"Successo di downoad dal sito Blackberry per la nuova release di UbiNav, il primo software di navigazione mobile tutto italiano.\",\"datePublished\":\"2010-02-19T10:51:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/arte-e-cultura\\\/ricerca-e-sviluppo\\\/successo-di-downoad-dal-sito-blackberry-per-la-nuova-release-di-ubinav-il-primo-software-di-navigazione-mobile-tutto-italiano\\\/\"},\"wordCount\":530,\"commentCount\":0,\"articleSection\":[\"Ricerca e sviluppo\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/arte-e-cultura\\\/ricerca-e-sviluppo\\\/successo-di-downoad-dal-sito-blackberry-per-la-nuova-release-di-ubinav-il-primo-software-di-navigazione-mobile-tutto-italiano\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/arte-e-cultura\\\/ricerca-e-sviluppo\\\/successo-di-downoad-dal-sito-blackberry-per-la-nuova-release-di-ubinav-il-primo-software-di-navigazione-mobile-tutto-italiano\\\/\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/arte-e-cultura\\\/ricerca-e-sviluppo\\\/successo-di-downoad-dal-sito-blackberry-per-la-nuova-release-di-ubinav-il-primo-software-di-navigazione-mobile-tutto-italiano\\\/\",\"name\":\"Successo di downoad dal sito Blackberry per la nuova release di UbiNav, il primo software di navigazione mobile tutto italiano. - Article Marketing\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\"},\"datePublished\":\"2010-02-19T10:51:31+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/arte-e-cultura\\\/ricerca-e-sviluppo\\\/successo-di-downoad-dal-sito-blackberry-per-la-nuova-release-di-ubinav-il-primo-software-di-navigazione-mobile-tutto-italiano\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/arte-e-cultura\\\/ricerca-e-sviluppo\\\/successo-di-downoad-dal-sito-blackberry-per-la-nuova-release-di-ubinav-il-primo-software-di-navigazione-mobile-tutto-italiano\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/arte-e-cultura\\\/ricerca-e-sviluppo\\\/successo-di-downoad-dal-sito-blackberry-per-la-nuova-release-di-ubinav-il-primo-software-di-navigazione-mobile-tutto-italiano\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Successo di downoad dal sito Blackberry per la nuova release di UbiNav, il primo software di navigazione mobile tutto italiano.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\",\"name\":\"Article Marketing\",\"description\":\"article marketing &amp; press release\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\",\"name\":\"Redazione Comunicati Stampa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"caption\":\"Redazione Comunicati Stampa\"},\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/author\\\/redazione-comunicati-stampa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Successo di downoad dal sito Blackberry per la nuova release di UbiNav, il primo software di navigazione mobile tutto italiano. - Article Marketing","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/ricerca-e-sviluppo\/successo-di-downoad-dal-sito-blackberry-per-la-nuova-release-di-ubinav-il-primo-software-di-navigazione-mobile-tutto-italiano\/","og_locale":"it_IT","og_type":"article","og_title":"Successo di downoad dal sito Blackberry per la nuova release di UbiNav, il primo software di navigazione mobile tutto italiano. - Article Marketing","og_description":"Mobile World Congress: UbiEst ha presentato la nuova release di UbiNav, il noto software di navigazione per smartphone con una nuova interfaccia grafica che promette una piacevolezza di utilizzo mai provata prima.","og_url":"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/ricerca-e-sviluppo\/successo-di-downoad-dal-sito-blackberry-per-la-nuova-release-di-ubinav-il-primo-software-di-navigazione-mobile-tutto-italiano\/","og_site_name":"Article Marketing","article_published_time":"2010-02-19T10:51:31+00:00","author":"Redazione Comunicati Stampa","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione Comunicati Stampa","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/ricerca-e-sviluppo\/successo-di-downoad-dal-sito-blackberry-per-la-nuova-release-di-ubinav-il-primo-software-di-navigazione-mobile-tutto-italiano\/#article","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/ricerca-e-sviluppo\/successo-di-downoad-dal-sito-blackberry-per-la-nuova-release-di-ubinav-il-primo-software-di-navigazione-mobile-tutto-italiano\/"},"author":{"name":"Redazione Comunicati Stampa","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"headline":"Successo di downoad dal sito Blackberry per la nuova release di UbiNav, il primo software di navigazione mobile tutto italiano.","datePublished":"2010-02-19T10:51:31+00:00","mainEntityOfPage":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/ricerca-e-sviluppo\/successo-di-downoad-dal-sito-blackberry-per-la-nuova-release-di-ubinav-il-primo-software-di-navigazione-mobile-tutto-italiano\/"},"wordCount":530,"commentCount":0,"articleSection":["Ricerca e sviluppo"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/ricerca-e-sviluppo\/successo-di-downoad-dal-sito-blackberry-per-la-nuova-release-di-ubinav-il-primo-software-di-navigazione-mobile-tutto-italiano\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/ricerca-e-sviluppo\/successo-di-downoad-dal-sito-blackberry-per-la-nuova-release-di-ubinav-il-primo-software-di-navigazione-mobile-tutto-italiano\/","url":"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/ricerca-e-sviluppo\/successo-di-downoad-dal-sito-blackberry-per-la-nuova-release-di-ubinav-il-primo-software-di-navigazione-mobile-tutto-italiano\/","name":"Successo di downoad dal sito Blackberry per la nuova release di UbiNav, il primo software di navigazione mobile tutto italiano. - Article Marketing","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website"},"datePublished":"2010-02-19T10:51:31+00:00","author":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"breadcrumb":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/ricerca-e-sviluppo\/successo-di-downoad-dal-sito-blackberry-per-la-nuova-release-di-ubinav-il-primo-software-di-navigazione-mobile-tutto-italiano\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/ricerca-e-sviluppo\/successo-di-downoad-dal-sito-blackberry-per-la-nuova-release-di-ubinav-il-primo-software-di-navigazione-mobile-tutto-italiano\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/ricerca-e-sviluppo\/successo-di-downoad-dal-sito-blackberry-per-la-nuova-release-di-ubinav-il-primo-software-di-navigazione-mobile-tutto-italiano\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.article-marketing.eu\/comunicati\/"},{"@type":"ListItem","position":2,"name":"Successo di downoad dal sito Blackberry per la nuova release di UbiNav, il primo software di navigazione mobile tutto italiano."}]},{"@type":"WebSite","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website","url":"https:\/\/www.article-marketing.eu\/comunicati\/","name":"Article Marketing","description":"article marketing &amp; press release","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.article-marketing.eu\/comunicati\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017","name":"Redazione Comunicati Stampa","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","caption":"Redazione Comunicati Stampa"},"url":"https:\/\/www.article-marketing.eu\/comunicati\/author\/redazione-comunicati-stampa\/"}]}},"_links":{"self":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/4190","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/comments?post=4190"}],"version-history":[{"count":0,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/4190\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/media?parent=4190"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/categories?post=4190"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/tags?post=4190"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}