{"id":42007,"date":"2014-06-12T14:27:03","date_gmt":"2014-06-12T12:27:03","guid":{"rendered":"http:\/\/www.article-marketing.eu\/comunicati\/senza-categoria\/artisti-e-scienziati-stelle-del-chianti\/"},"modified":"2014-06-12T14:27:03","modified_gmt":"2014-06-12T12:27:03","slug":"artisti-e-scienziati-stelle-del-chianti","status":"publish","type":"post","link":"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/artisti-e-scienziati-stelle-del-chianti\/","title":{"rendered":"Artisti e scienziati stelle del Chianti"},"content":{"rendered":"<p><img decoding=\"async\" src=\"http:\/\/www.comunicati-stampa.com\/img\/2014\/06\/William-Braemer-Athena-ChiantiStarFestival.org_.jpg\" border=\"0\" alt=\"William Braemer - Athena - ChiantiStarFestival.org\" width=\"250\" align=\"right\" \/>L&#8217;inaugurazione si terr&agrave; venerd&igrave; 13 giugno alle ore 18.30 al Palazzo Malaspina di San Donato in Poggio con una performance musicale dei Benko Brothers e l&#8217;apertura della mostra di artisti internazionali che esporranno le loro opere pi&ugrave; recenti: dipinti, sculture, fotografie e arte digitale.<br \/>\nSabato 14 giugno alle ore 17.30 la giuria presieduta da Roberto Casalbuoni, assegner&agrave; agli artisti partecipanti tre premi. La premiazione si terr&agrave; nell&rsquo;Auditorium della <strong>Cantina Antinori<\/strong> nel Chianti Classico, progettata da Marco Casamonti a Bargino.<br \/>\nNel ricco programma dedicato al rapporto tra arte e scienza, mostre, installazioni, spettacoli e, grazie alla collaborazione con Openlab, struttura dell&rsquo;area comunicazione dell&rsquo;Universit&agrave; di Firenze, numerosi incontri con scienziati e ricercatori impegnanti a promuovere la cultura scientifica. Alcuni esempi: il professor <strong>Luigi Dei<\/strong> luned&igrave; 16 giugno alle ore 21.30 presenter&agrave; lo spettacolo\/conferenza &ldquo;Da Schubert a De Andr&eacute;: i misteri della voce in musica&rdquo;; marted&igrave; 17 giugno alle 21.30 il professor <strong>Giuseppe Conti<\/strong> parler&agrave; della &ldquo;Geometria segreta dei monumenti fiorentini&rdquo;; gioved&igrave; 19 giugno alle 20.30 il professor <strong>Giovanni Mattii<\/strong> parler&agrave; della &ldquo;Vite attraverso la storia: dagli albori della coltivazione all&#8217;et&agrave; moderna&#8221; e a seguire, alle 22, la dottoressa <strong>Maria Grazia Giovannini<\/strong> introdurr&agrave; una dimostrazione di tango spiegando &ldquo;Il ballo di coppia dal punto di vista medico-scientifico&rdquo;; l&rsquo;architetto <strong>Massimo Ricci<\/strong> sabato 21 giugno alle ore 21.30 sveler&agrave; i segreti della costruzione della Cupola del Brunelleschi.<br \/>\nIl Festival, oltre a Palazzo Malaspina, coinvolger&agrave; altri luoghi del Chianti: dall&rsquo;Osservatorio Polifunzionale del Chianti, alla <strong>Fattoria Montecchio<\/strong> che, con la sua fornace artistica, ospiter&agrave; opere di artisti che si sono cimentati con la terracotta, tra cui Agneta Gynning ed Eugenio Riotto, fino all&#8217;<strong>Abbazia di Badia a Passignano<\/strong>, che oltre ad ospitare concerti, tra cui quello di pianoforte di Bruno Canino accoglier&agrave; un&rsquo;installazione di Giovanna Lysy che verr&agrave; inaugurata domenica 15 giugno alle ore 16.00.<br \/>\n<strong>Gabriele Rizza, Gianna Bandini e Alessandra Sarri<\/strong> dell&rsquo;Associazione An&egrave;mic cureranno un video e foto contest suddiviso in tre sezioni: 1) Arte e Scienza 2) il Paesaggio Toscano 3) Vine and wine.<br \/>&ldquo;Star&rdquo; del Festival, oltre agli astri che si potranno osservare dall&rsquo;Osservatorio Astronomico del Chianti, saranno anche i prodotti tipici del territorio, a partire dall&rsquo;olio e dal vino.<br \/>\nLa giuria &egrave; composta da:<br \/><strong>Roberto Casalbuoni<\/strong>, fisico teorico<br \/><strong>Anchise Tempestini<\/strong>, storico dell&#8217;arte<br \/><strong>Satoru Yamada<\/strong>, critico d&rsquo;arte e giornalista<br \/><strong>Giada Rodani<\/strong>, curatrice di mostre di arte contemporanea<br \/><strong>Alberto Righini<\/strong>, professore di Astronomia<br \/><strong>Gabriele Rizza<\/strong>, giornalista, esperto di cinema e teatro<br \/><strong>Luigi Dei<\/strong>, professore di Chimica, presidente di OpenLab<br \/><strong>Massimo Ricci<\/strong>, architetto, Membro del Forum Centrale UNESCO<br \/><strong>David Baroncelli<\/strong>, Sindaco di Tavarnelle Val di Pesa<\/p>\n<p>Artisti Partecipanti:<br \/>William Braemer WilliamBraemer.com<br \/>Catherine Daubresse CatherineDaubresse.wordpress.com<br \/>Emmanuel De Brito <br \/>Anna Maria Giraudo <br \/>Agneta Gynning AgnetaGynning.com<br \/>David Harry davidharryFineArt.com<br \/>Evelyne Huet EvelyneHuet.com<br \/>Sumio Inoue SumioInoue.com<br \/>Alexander Lee AlexanderLee.artspan.com<br \/>Charlotte Lisboa CharlotteLisboaFineArt.com<br \/>Giovanna Lysy GiovannaLysy.com<br \/>Sara Palleria SaraPalleria.com<br \/>Santina Panetta santinasemadarpanetta.com<br \/>Edward Rilke EdwardRilke.com<br \/>Eugenio Riotto EugenioRiotto.com<br \/>Kensuke Shimizu www4.ocn.ne.jp\/~kensuke<br \/>Linda K. &amp; Theodore M. Shinkle shinklefineart.com<br \/>Savannah Tate Cuff<br \/>Tiril artbytiril.com<br \/>Max Werner MaxWernerArt.com<\/p>\n<p><strong>CHIANTI STAR FESTIVAL<\/strong><br \/>\nSan Donato in Poggio e altri luoghi dal 13 giugno al 20 luglio<br \/>\n<strong>Inaugurazione<\/strong>: 13 giugno ore 18.30 <br \/>Palazzo Malaspina, Via del Giglio 31, San Donato in Poggio (Fi) 50028<\/p>\n<p><strong>Orari di Palazzo Malaspina<\/strong>: tutti i giorni 10.00-12.30 | 16.00-23.30 (ad eccezione dei giorni dal 13 luglio al 18 luglio: 18.30 &ndash; 23.30)<br \/>Ingresso gratuito a tutti gli eventi ad eccezione del concerto di Bruno Canino (biglietto 15 euro) e di alcuni eventi all&rsquo;Osservatorio del Chianti.<br \/>Tutto il programma su: <a href=\"http:\/\/www.chiantistarfestival.org\">www.chiantistarfestival.org<\/a><\/p>\n<p>Per le conferenze e gli incontri si consiglia la prenotazione<br \/>Per prenotazioni, informazioni sulla mostra e sugli eventi collaterali:<br \/>Studio Abba 055292082 info@studioabba.com <br \/>Per prenotazioni e informazioni sugli eventi dell&rsquo;Osservatorio del Chianti: 3397554145 info@osservatoriodelchianti.it<br \/>Per visite a Badia a Passignano &lsquo;Ticket for Chianti&rsquo;, info@ticketforchianti.com Tel. 0558072341 Cell. 3663781037<br \/>Per informazioni sul territorio: Pro Loco di San Donato: 0558072338 &#8211; info@sandonatoinpoggio.it<br \/>Tavarnelle Chianti da Vivere: info@tavarnellechiantidavivere.it<br \/>Ufficio stampa: Studio Ester Di Leo T. +39 055223907 mail: esterdileo@gmail.com<br \/>\n<strong>Calendario Eventi<\/strong><\/p>\n<ul>\n<li><strong>Venerd&igrave; 13 giugno h 18.30<\/strong> Palazzo Malaspina: Inaugurazione Festival, musica dei Benko Brothers<br \/><strong>h 21.00<\/strong> Badia a Passignano: Concerto Bruno Canino &ndash; pianoforte<\/li>\n<li><strong>Sabato 14 giugno h 17.30<\/strong> Auditorium Cantine Antinori: Premiazione Artisti<\/li>\n<li><strong>Domenica 15 giugno h. 16.00<\/strong> Badia a Passignano: visita all&rsquo;abazia, solo su prenotazione; inaugurazione installazione &ldquo;Radici&rdquo; di Giovanna Lysy<\/li>\n<li><strong>Luned&igrave; 16 giugno h. 17.00<\/strong> Fattoria Montecchio: Visita all&rsquo;antica fornace e alla fattoria <strong>h. 21.30<\/strong> Palazzo Malaspina: Conferenza &ldquo;Da Schubert a De Andr&eacute;: i misteri della voce in musica&rdquo; a cura del Prof. Luigi Dei<\/li>\n<li><strong>Marted&igrave; 17 giugno h. 21.30<\/strong> Palazzo Malaspina: Conferenza &ldquo;La geometria segreta dei monumenti fiorentini&rdquo; a cura del Prof. Giuseppe Conti<\/li>\n<li><strong>Mercoled&igrave; 18 giugno h. 21.30<\/strong> Osservatorio Polifunzionale del Chianti: Dialoghi sullo spazio &ldquo;StarTea&rdquo; (in italiano e inglese) a cura di Emanuele Pace<\/li>\n<li><strong>Gioved&igrave; 19 giugno h. 20.30<\/strong> Palazzo Malaspina: Conferenza &ldquo;La vite attraverso i secoli&rdquo; a cura del Prof. Giovanni Mattii (in italiano e inglese)<br \/><strong>h. 22.00<\/strong> Palazzo Malaspina: Conferenza &ldquo;Tango, Il ballo di coppia dal punto di vista medico-scientifico&rdquo; a cura della Dott.ssa Maria Grazia Giovannini (in italiano e inglese), intervengono Giorgio Jr Giorgi e Daniela Conte di LiberandoTango Nuevo<\/li>\n<li><strong>Venerd&igrave; 20 giugno h. 21.30<\/strong> Palazzo Malaspina: Conferenza &ldquo;Viaggiare nel Cosmo&rdquo; a cura di Emanuele Pace (in italiano e inglese)<\/li>\n<li><strong>Sabato 21 giugno h. 18.30<\/strong> San Donato in Poggio: Concerto itinerante della Banda Norvegese Br&oslash;nn&oslash;ysund Musikkorps <br \/><strong>h. 19.30<\/strong> Osservatorio Polifunzionale del Chianti: Inaugurazione mostra &#8220;Galileo in Accademia&#8221;<br \/><strong>h. 21.30<\/strong> Fattoria Montecchio: Conferenza arch. Massimo Ricci &ldquo;La costruzione della Cupola del Brunelleschi&rdquo;<\/li>\n<li><strong>Domenica 22 giugno a partire dalle 18.30<\/strong> Badia a Passignano: Conferenza di Riccardo Pratesi e Emanuele Pace; concerto di Angela Tomei violino, Roberta Malavolti violino, Nicol&ograve; Degl&#8217;Innocenti violoncello; musiche di: D. Gallo Trio sonata n.1; J. B. Lully Suite da balletto; H. Purcell Golden Sonata; M. Marais Suite rinascimentale. Osservazione astronomica per il 450&#8242; anniversario della nascita di Galileo Galilei<\/li>\n<li><strong>Luned&igrave; 23 giugno h. 21.30<\/strong> Palazzo Malaspina: Conferenza &ldquo;Rifiuti o Risorse: Quale futuro?&rdquo; del Dott. Danilo Pulvirenti <\/li>\n<li><strong>Mercoled&igrave; 25 giugno h. 21.30<\/strong> Osservatorio Polifunzionale del Chianti: Dialoghi sullo spazio &ldquo;StarTea&rdquo; <\/li>\n<li><strong>Gioved&igrave; 26 giugno h. 21.30<\/strong> San Donato: Spettacolo &ldquo;E uscimmo a riveder le Stelle&rdquo; Declamazione canti della Divina Commedia (G. Terreni) con accompagnamento di arpa (A. Natangelo)<\/li>\n<li><strong>Venerd&igrave; 27 giugno h 21.30<\/strong> Cinema Societ&agrave; Filarmonica: &ldquo;Bruscello&rdquo; Spettacolo popolare toscano<\/li>\n<li><strong>Sabato 28 giugno dalle 16<\/strong> San Donato: Eventi Bruscello<\/li>\n<li><strong>Domenica 29 giugno tutto il giorno<\/strong> San Donato: Fierucola della Polvere e Sfilata storica con mercatinoi<br \/><strong>h. 17.30; 21.30; 22.30<\/strong> Osservatorio Polifunzionale del Chianti: Visite Open dayi<br \/><strong>h. 18.00<\/strong> &ldquo;Bruscello&rdquo; Spettacolo popolare toscano<\/li>\n<li><strong>Mercoled&igrave; 2 luglio h. 21.30<\/strong> Osservatorio Polifunzionale del Chianti: Dialoghi sullo spazio &ldquo;StarTea&rdquo; <\/li>\n<li><strong>Gioved&igrave; 3 luglio h. 20.30<\/strong> Osservatorio Polifunzionale del Chianti, CineScience: &ldquo;Trash&rdquo;<br \/><strong>h. 21.30<\/strong> Cinema Societ&agrave; Filarmonica: &ldquo;Bruscello&rdquo; Spettacolo popolare toscano<\/li>\n<li><strong>Sabato 5 luglio h. 22<\/strong> San Donato: &ldquo;Quartagramma Vocal Project&rdquo;, concerto del quartetto vocale a cappella<\/li>\n<li><strong>Domenica 6 luglio h. 9.00<\/strong> San Donato: Fierucola della Polvere<br \/><strong>h. 17.30<\/strong> Osservatorio Polifunzionale del Chianti: Visite Open day <br \/><strong>h. 21.30<\/strong> e a mezzanotte presso Cinema Societ&agrave; Filarmonica: &ldquo;Bruscello&rdquo; Spettacolo popolare toscano<\/li>\n<li><strong>Mercoled&igrave; 9 luglio h. 21.30<\/strong> Osservatorio Polifunzionale del Chianti: Dialoghi sullo spazio &ldquo;StarTea&rdquo; <\/li>\n<li><strong>Gioved&igrave; 10 luglio h. 20.30<\/strong> Osservatorio Polifunzionale del Chianti, CineScience: &ldquo;Uomini veri&rdquo;<\/li>\n<li><strong>Venerd&igrave; 11 luglio ore 21.30<\/strong> San Donato, Fondazione Cianti Orselli, &ldquo;Incontro notturno&rdquo; concerto lirico<\/li>\n<li><strong>Sabato 12 luglio h. 21.00<\/strong> Osservatorio Polifunzionale del Chianti : Conferenza &#8220;Conversazioni con la Natura&#8221; a cura di Isabella Devetta<\/li>\n<li><strong>Domenica 13 luglio h. 18.30<\/strong> Palazzo Malaspina: Concerto Chianti in Musica UECA<br \/><strong>h. 17.30; 21.30; 22.30<\/strong> Osservatorio Polifunzionale del Chianti: Visite Open day<br \/><strong>h. 21.30<\/strong> Palazzo Malaspina, Conferenza di Daniele Rossi, restauratore: &#8220;Da Giotto a Pontormo. Viaggio di un restauratore di capolavori d&#8217;arte&#8221;<\/li>\n<li><strong>Luned&igrave; 14 luglio h. 18.30<\/strong> Palazzo Malaspina: Concerto Chianti in Musica UECA<\/li>\n<li><strong>Marted&igrave; 15 luglio h. 21.30<\/strong> Osservatorio del Chianti: Concerto Chianti in Musica UECA<\/li>\n<li><strong>Mercoled&igrave; 16 luglio h. 21.00<\/strong> Palazzo Malaspina: Concerto Chianti in Musica dei Maestri UECA<br \/><strong>h. 21.30<\/strong> Osservatorio Polifunzionale del Chianti: Dialoghi sullo spazio &ldquo;StarTea&rdquo;<\/li>\n<li><strong>Gioved&igrave; 17 luglio h. 18.30<\/strong> presso Palazzo Malaspina: Concerto Chianti in Musica UECA<br \/><strong>h. 20.30<\/strong> presso Osservatorio Polifunzionale del Chianti: CineScience<br \/><strong>h. 21.30<\/strong> Palazzo Malaspina, Conferenza di Luca Palchetti &#8220;Dall&#8217;Italia all&#8217; Antartide: viaggio in un laboratorio naturale a disposizione dell&#8217;umanit&agrave;&#8221; e collegamento con la base Concordia in Antartide<\/li>\n<li><strong>Venerd&igrave; 18 luglio h. 18.30<\/strong> Palazzo Malaspina: Concerto Chianti in Musica UECA<br \/><strong>h. 21.30<\/strong> Osservatorio del Chianti: &ldquo;Pillole di Shakespeare: Romeo e Giulietta<\/li>\n<li><strong>Sabato 19 luglio h. 18.30<\/strong> Palazzo Malaspina: Concerto Chianti in Musica UECA<\/li>\n<li><strong>Domenica 20 luglio h. 18.30<\/strong> San Donato: Concerto Tino Andersen (chitarra classica)<br \/><strong>h. 17.30; 21.30; 22.30<\/strong> Osservatorio Polifunzionale del Chianti: Visite Open day<\/li>\n<\/ul>\n<p><img decoding=\"async\" src=\"http:\/\/www.artartworks.com\/wp-content\/uploads\/ChiantiStarFestival.org_.jpg\" border=\"0\" width=\"98%\" \/><br \/>\n<strong>Organizzazione<\/strong>:<br \/>\n<strong>Studio Abba<\/strong> www.studioabba.com<br \/><strong>Giada Rodani<\/strong> giadarodani@yahoo.it<br \/><strong>OpenLab<\/strong> www.openlab.unifi.it &#8211; Area Comunicazione dell&#8217;Universit&agrave; di Firenze<br \/><strong>Comune di Tavarnelle Val di Pesa<\/strong> www.tavarnellevp.it<br \/><strong>Associazione Culturale Pro Loco San Donato<\/strong> www.sandonatoinpoggio.it<br \/><strong>Osservatorio Polifunzionale del Chianti<\/strong> www.osservatoriodelchianti.it<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dal 13 giugno al 20 luglio 2014 arte e scienza si ritrovano tra le splendide colline del Chianti, nel cuore della Toscana, per la seconda edizione del Chianti Star Festival che ospiter\u00e0 artisti internazionali, ricercatori e scienziati.<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"","footnotes":""},"categories":[27],"tags":[],"class_list":["post-42007","post","type-post","status-publish","format-standard","hentry","category-arte-e-cultura"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Artisti e scienziati stelle del Chianti - Article Marketing<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/artisti-e-scienziati-stelle-del-chianti\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Artisti e scienziati stelle del Chianti - Article Marketing\" \/>\n<meta property=\"og:description\" content=\"Dal 13 giugno al 20 luglio 2014 arte e scienza si ritrovano tra le splendide colline del Chianti, nel cuore della Toscana, per la seconda edizione del Chianti Star Festival che ospiter\u00e0 artisti internazionali, ricercatori e scienziati.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/artisti-e-scienziati-stelle-del-chianti\/\" \/>\n<meta property=\"og:site_name\" content=\"Article Marketing\" \/>\n<meta property=\"article:published_time\" content=\"2014-06-12T12:27:03+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.comunicati-stampa.com\/img\/2014\/06\/William-Braemer-Athena-ChiantiStarFestival.org_.jpg\" \/>\n<meta name=\"author\" content=\"Redazione Comunicati Stampa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione Comunicati Stampa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/arte-e-cultura\\\/artisti-e-scienziati-stelle-del-chianti\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/arte-e-cultura\\\/artisti-e-scienziati-stelle-del-chianti\\\/\"},\"author\":{\"name\":\"Redazione Comunicati Stampa\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"headline\":\"Artisti e scienziati stelle del Chianti\",\"datePublished\":\"2014-06-12T12:27:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/arte-e-cultura\\\/artisti-e-scienziati-stelle-del-chianti\\\/\"},\"wordCount\":1487,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/arte-e-cultura\\\/artisti-e-scienziati-stelle-del-chianti\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.comunicati-stampa.com\\\/img\\\/2014\\\/06\\\/William-Braemer-Athena-ChiantiStarFestival.org_.jpg\",\"articleSection\":[\"Arte e cultura\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/arte-e-cultura\\\/artisti-e-scienziati-stelle-del-chianti\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/arte-e-cultura\\\/artisti-e-scienziati-stelle-del-chianti\\\/\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/arte-e-cultura\\\/artisti-e-scienziati-stelle-del-chianti\\\/\",\"name\":\"Artisti e scienziati stelle del Chianti - Article Marketing\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/arte-e-cultura\\\/artisti-e-scienziati-stelle-del-chianti\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/arte-e-cultura\\\/artisti-e-scienziati-stelle-del-chianti\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.comunicati-stampa.com\\\/img\\\/2014\\\/06\\\/William-Braemer-Athena-ChiantiStarFestival.org_.jpg\",\"datePublished\":\"2014-06-12T12:27:03+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/arte-e-cultura\\\/artisti-e-scienziati-stelle-del-chianti\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/arte-e-cultura\\\/artisti-e-scienziati-stelle-del-chianti\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/arte-e-cultura\\\/artisti-e-scienziati-stelle-del-chianti\\\/#primaryimage\",\"url\":\"http:\\\/\\\/www.comunicati-stampa.com\\\/img\\\/2014\\\/06\\\/William-Braemer-Athena-ChiantiStarFestival.org_.jpg\",\"contentUrl\":\"http:\\\/\\\/www.comunicati-stampa.com\\\/img\\\/2014\\\/06\\\/William-Braemer-Athena-ChiantiStarFestival.org_.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/arte-e-cultura\\\/artisti-e-scienziati-stelle-del-chianti\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Artisti e scienziati stelle del Chianti\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\",\"name\":\"Article Marketing\",\"description\":\"article marketing &amp; press release\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\",\"name\":\"Redazione Comunicati Stampa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"caption\":\"Redazione Comunicati Stampa\"},\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/author\\\/redazione-comunicati-stampa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Artisti e scienziati stelle del Chianti - Article Marketing","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/artisti-e-scienziati-stelle-del-chianti\/","og_locale":"it_IT","og_type":"article","og_title":"Artisti e scienziati stelle del Chianti - Article Marketing","og_description":"Dal 13 giugno al 20 luglio 2014 arte e scienza si ritrovano tra le splendide colline del Chianti, nel cuore della Toscana, per la seconda edizione del Chianti Star Festival che ospiter\u00e0 artisti internazionali, ricercatori e scienziati.","og_url":"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/artisti-e-scienziati-stelle-del-chianti\/","og_site_name":"Article Marketing","article_published_time":"2014-06-12T12:27:03+00:00","og_image":[{"url":"http:\/\/www.comunicati-stampa.com\/img\/2014\/06\/William-Braemer-Athena-ChiantiStarFestival.org_.jpg","type":"","width":"","height":""}],"author":"Redazione Comunicati Stampa","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione Comunicati Stampa","Tempo di lettura stimato":"7 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/artisti-e-scienziati-stelle-del-chianti\/#article","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/artisti-e-scienziati-stelle-del-chianti\/"},"author":{"name":"Redazione Comunicati Stampa","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"headline":"Artisti e scienziati stelle del Chianti","datePublished":"2014-06-12T12:27:03+00:00","mainEntityOfPage":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/artisti-e-scienziati-stelle-del-chianti\/"},"wordCount":1487,"commentCount":0,"image":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/artisti-e-scienziati-stelle-del-chianti\/#primaryimage"},"thumbnailUrl":"http:\/\/www.comunicati-stampa.com\/img\/2014\/06\/William-Braemer-Athena-ChiantiStarFestival.org_.jpg","articleSection":["Arte e cultura"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/artisti-e-scienziati-stelle-del-chianti\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/artisti-e-scienziati-stelle-del-chianti\/","url":"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/artisti-e-scienziati-stelle-del-chianti\/","name":"Artisti e scienziati stelle del Chianti - Article Marketing","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/artisti-e-scienziati-stelle-del-chianti\/#primaryimage"},"image":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/artisti-e-scienziati-stelle-del-chianti\/#primaryimage"},"thumbnailUrl":"http:\/\/www.comunicati-stampa.com\/img\/2014\/06\/William-Braemer-Athena-ChiantiStarFestival.org_.jpg","datePublished":"2014-06-12T12:27:03+00:00","author":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"breadcrumb":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/artisti-e-scienziati-stelle-del-chianti\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/artisti-e-scienziati-stelle-del-chianti\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/artisti-e-scienziati-stelle-del-chianti\/#primaryimage","url":"http:\/\/www.comunicati-stampa.com\/img\/2014\/06\/William-Braemer-Athena-ChiantiStarFestival.org_.jpg","contentUrl":"http:\/\/www.comunicati-stampa.com\/img\/2014\/06\/William-Braemer-Athena-ChiantiStarFestival.org_.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/artisti-e-scienziati-stelle-del-chianti\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.article-marketing.eu\/comunicati\/"},{"@type":"ListItem","position":2,"name":"Artisti e scienziati stelle del Chianti"}]},{"@type":"WebSite","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website","url":"https:\/\/www.article-marketing.eu\/comunicati\/","name":"Article Marketing","description":"article marketing &amp; press release","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.article-marketing.eu\/comunicati\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017","name":"Redazione Comunicati Stampa","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","caption":"Redazione Comunicati Stampa"},"url":"https:\/\/www.article-marketing.eu\/comunicati\/author\/redazione-comunicati-stampa\/"}]}},"_links":{"self":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/42007","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/comments?post=42007"}],"version-history":[{"count":0,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/42007\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/media?parent=42007"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/categories?post=42007"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/tags?post=42007"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}