{"id":42162,"date":"2014-06-17T12:01:05","date_gmt":"2014-06-17T10:01:05","guid":{"rendered":"http:\/\/www.article-marketing.eu\/comunicati\/senza-categoria\/il-percorso-professionale-del-dott-antonio-mastrapasqua\/"},"modified":"2014-06-17T12:01:05","modified_gmt":"2014-06-17T10:01:05","slug":"il-percorso-professionale-del-dott-antonio-mastrapasqua","status":"publish","type":"post","link":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/professionisti\/il-percorso-professionale-del-dott-antonio-mastrapasqua\/","title":{"rendered":"Il percorso professionale del Dott. Antonio Mastrapasqua"},"content":{"rendered":"<p><em><strong><a href=\"http:\/\/www.economiaoggi.it\/Antonio-Mastrapasqua\/antonio-mastrapasqua-biografia-incarichi.html \" title=\"Antonio Mastrapasqua Economiaoggi\">Antonio Mastrapasqua<\/a>, manager dalla rinomata esperienza nel settore economico-finanziario, ha ricoperto numerosi ruoli prestigiosi del panorama nazionale italiano ed internazionale. Attualmente &egrave; anche Direttore Generale dell&#8217;Ospedale Israelitico e della casa di riposo Ebraica a Roma.<\/strong><\/em><br \/>\n<img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.h2biz.eu\/public\/crop_min_10452-i-dsc_0203.jpg\" border=\"0\" alt=\"Antonio Mastrapasqua foto\" title=\"Antonio Mastrapasqua foto\" width=\"137\" height=\"137\" \/><br \/>\nLa carriera professionale di Antonio Mastrapasqua<br \/>\n<strong>Antonio Mastrapasqua<\/strong> si laurea in Economia e Commercio presso l&#8217;universit&agrave; La Sapienza di Roma, frequenta i corsi di Inglese e finanza al Simmons College di Boston e quello sui fondi strutturali comunitari alla sede dell&#8217;Unione Europea di Bruxelles. Successivamente ottiene l&#8217;iscrizione all&#8217;Ordine dei Dottori Commercialisti di Roma, al Registro dei Revisori Contabili e all&#8217;Ordine Nazionale dei Giornalisti Pubblicisti. Il percorso professionale del Dott. Mastrapasqua inizia nel 1987 con la nomina di Amministratore Unico della MA.TI. SERVICE S.r.l., azienda operante nel settore delle telecomunicazioni, in cui rimarr&agrave; fino al 1991. Nel 1992 inizia la colaborazione, come Vice Presidente Vicario e membro della Giunta Esecutiva, con ENPSDI, Ente Nazionale Promozione Sportiva Disabili. Negli anni successivi ricoprir&agrave; gli incarichi di Consulente della Banca Nazionale del Lavoro (1996-2000), consigliere della societ&agrave; Termosud S.p.a. (1997-2000), sindaco effettivo Coni Servizi (dal 2002) e Autostrade per l&#8217;Italia S.p.a. (dal 2003), presidente del Consiglio di Amministrazione per Idea Fimit sgr S.p.a. (2012-2014), Consigliere e Vice Presidente di Equitalia S.p.a. (2005-2014), Presidente e Commissario Straordinario INPS (2008-2014).<br \/>\nAntonio Mastrapasqua e Gtech S.p.a.<br \/>\nDa maggio 2014, <strong>Antonio Mastrapasqua<\/strong> ricopre l&#8217;incarico di Consigliere Indipendente e Presidente del Comitato per la Remunerazione e le Nomine di Gtech S.p.a.. L&#8217;azienda &egrave; leader mondiale per tutto ci&ograve; che riguarda le lotterie online, i concorsi, le scommesse e i giochi interattivi; si occupano anche della creazione e della fornitura di sistemi centrali di controllo e software, avvalendosi delle pi&ugrave; moderne innovazioni tecnologiche per proporre soluzioni di gioco all&#8217;avanguardia. Per tutta questa gamma di servizi disponibili, Gtech si pone come l&#8217;unico operatore del mercato dei giochi capace di offrire una gamma completa di servizi a clienti privati e pubblici, come i governi nazionali e federali.<br \/>\n<br \/><em>Per visualizzare la biografia completa di <strong>Antonio Mastrapasqua<\/strong> visita la sua pagina personale su Economiaoggi. <\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Antonio Mastrapasqua \u00e8 una figura di spicco nel panorama manageriale pubblico italiano, gi\u00e0 presidente di INPS e Vice Presidente Esecutivo presso Equitalia<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"","footnotes":""},"categories":[429],"tags":[47974],"class_list":["post-42162","post","type-post","status-publish","format-standard","hentry","category-professionisti","tag-antonio-mastrapasqua"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Il percorso professionale del Dott. Antonio Mastrapasqua - Article Marketing<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/professionisti\/il-percorso-professionale-del-dott-antonio-mastrapasqua\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Il percorso professionale del Dott. Antonio Mastrapasqua - Article Marketing\" \/>\n<meta property=\"og:description\" content=\"Antonio Mastrapasqua \u00e8 una figura di spicco nel panorama manageriale pubblico italiano, gi\u00e0 presidente di INPS e Vice Presidente Esecutivo presso Equitalia\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/professionisti\/il-percorso-professionale-del-dott-antonio-mastrapasqua\/\" \/>\n<meta property=\"og:site_name\" content=\"Article Marketing\" \/>\n<meta property=\"article:published_time\" content=\"2014-06-17T10:01:05+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.h2biz.eu\/public\/crop_min_10452-i-dsc_0203.jpg\" \/>\n<meta name=\"author\" content=\"Redazione Comunicati Stampa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione Comunicati Stampa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/economia-e-lavoro\\\/professionisti\\\/il-percorso-professionale-del-dott-antonio-mastrapasqua\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/economia-e-lavoro\\\/professionisti\\\/il-percorso-professionale-del-dott-antonio-mastrapasqua\\\/\"},\"author\":{\"name\":\"Redazione Comunicati Stampa\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"headline\":\"Il percorso professionale del Dott. Antonio Mastrapasqua\",\"datePublished\":\"2014-06-17T10:01:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/economia-e-lavoro\\\/professionisti\\\/il-percorso-professionale-del-dott-antonio-mastrapasqua\\\/\"},\"wordCount\":357,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/economia-e-lavoro\\\/professionisti\\\/il-percorso-professionale-del-dott-antonio-mastrapasqua\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.h2biz.eu\\\/public\\\/crop_min_10452-i-dsc_0203.jpg\",\"keywords\":[\"Antonio Mastrapasqua\"],\"articleSection\":[\"Professionisti\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/economia-e-lavoro\\\/professionisti\\\/il-percorso-professionale-del-dott-antonio-mastrapasqua\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/economia-e-lavoro\\\/professionisti\\\/il-percorso-professionale-del-dott-antonio-mastrapasqua\\\/\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/economia-e-lavoro\\\/professionisti\\\/il-percorso-professionale-del-dott-antonio-mastrapasqua\\\/\",\"name\":\"Il percorso professionale del Dott. Antonio Mastrapasqua - Article Marketing\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/economia-e-lavoro\\\/professionisti\\\/il-percorso-professionale-del-dott-antonio-mastrapasqua\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/economia-e-lavoro\\\/professionisti\\\/il-percorso-professionale-del-dott-antonio-mastrapasqua\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.h2biz.eu\\\/public\\\/crop_min_10452-i-dsc_0203.jpg\",\"datePublished\":\"2014-06-17T10:01:05+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/economia-e-lavoro\\\/professionisti\\\/il-percorso-professionale-del-dott-antonio-mastrapasqua\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/economia-e-lavoro\\\/professionisti\\\/il-percorso-professionale-del-dott-antonio-mastrapasqua\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/economia-e-lavoro\\\/professionisti\\\/il-percorso-professionale-del-dott-antonio-mastrapasqua\\\/#primaryimage\",\"url\":\"http:\\\/\\\/www.h2biz.eu\\\/public\\\/crop_min_10452-i-dsc_0203.jpg\",\"contentUrl\":\"http:\\\/\\\/www.h2biz.eu\\\/public\\\/crop_min_10452-i-dsc_0203.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/economia-e-lavoro\\\/professionisti\\\/il-percorso-professionale-del-dott-antonio-mastrapasqua\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Il percorso professionale del Dott. Antonio Mastrapasqua\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\",\"name\":\"Article Marketing\",\"description\":\"article marketing &amp; press release\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\",\"name\":\"Redazione Comunicati Stampa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"caption\":\"Redazione Comunicati Stampa\"},\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/author\\\/redazione-comunicati-stampa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Il percorso professionale del Dott. Antonio Mastrapasqua - Article Marketing","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/professionisti\/il-percorso-professionale-del-dott-antonio-mastrapasqua\/","og_locale":"it_IT","og_type":"article","og_title":"Il percorso professionale del Dott. Antonio Mastrapasqua - Article Marketing","og_description":"Antonio Mastrapasqua \u00e8 una figura di spicco nel panorama manageriale pubblico italiano, gi\u00e0 presidente di INPS e Vice Presidente Esecutivo presso Equitalia","og_url":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/professionisti\/il-percorso-professionale-del-dott-antonio-mastrapasqua\/","og_site_name":"Article Marketing","article_published_time":"2014-06-17T10:01:05+00:00","og_image":[{"url":"http:\/\/www.h2biz.eu\/public\/crop_min_10452-i-dsc_0203.jpg","type":"","width":"","height":""}],"author":"Redazione Comunicati Stampa","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione Comunicati Stampa","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/professionisti\/il-percorso-professionale-del-dott-antonio-mastrapasqua\/#article","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/professionisti\/il-percorso-professionale-del-dott-antonio-mastrapasqua\/"},"author":{"name":"Redazione Comunicati Stampa","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"headline":"Il percorso professionale del Dott. Antonio Mastrapasqua","datePublished":"2014-06-17T10:01:05+00:00","mainEntityOfPage":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/professionisti\/il-percorso-professionale-del-dott-antonio-mastrapasqua\/"},"wordCount":357,"commentCount":0,"image":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/professionisti\/il-percorso-professionale-del-dott-antonio-mastrapasqua\/#primaryimage"},"thumbnailUrl":"http:\/\/www.h2biz.eu\/public\/crop_min_10452-i-dsc_0203.jpg","keywords":["Antonio Mastrapasqua"],"articleSection":["Professionisti"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/professionisti\/il-percorso-professionale-del-dott-antonio-mastrapasqua\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/professionisti\/il-percorso-professionale-del-dott-antonio-mastrapasqua\/","url":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/professionisti\/il-percorso-professionale-del-dott-antonio-mastrapasqua\/","name":"Il percorso professionale del Dott. Antonio Mastrapasqua - Article Marketing","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/professionisti\/il-percorso-professionale-del-dott-antonio-mastrapasqua\/#primaryimage"},"image":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/professionisti\/il-percorso-professionale-del-dott-antonio-mastrapasqua\/#primaryimage"},"thumbnailUrl":"http:\/\/www.h2biz.eu\/public\/crop_min_10452-i-dsc_0203.jpg","datePublished":"2014-06-17T10:01:05+00:00","author":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"breadcrumb":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/professionisti\/il-percorso-professionale-del-dott-antonio-mastrapasqua\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/professionisti\/il-percorso-professionale-del-dott-antonio-mastrapasqua\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/professionisti\/il-percorso-professionale-del-dott-antonio-mastrapasqua\/#primaryimage","url":"http:\/\/www.h2biz.eu\/public\/crop_min_10452-i-dsc_0203.jpg","contentUrl":"http:\/\/www.h2biz.eu\/public\/crop_min_10452-i-dsc_0203.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/professionisti\/il-percorso-professionale-del-dott-antonio-mastrapasqua\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.article-marketing.eu\/comunicati\/"},{"@type":"ListItem","position":2,"name":"Il percorso professionale del Dott. Antonio Mastrapasqua"}]},{"@type":"WebSite","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website","url":"https:\/\/www.article-marketing.eu\/comunicati\/","name":"Article Marketing","description":"article marketing &amp; press release","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.article-marketing.eu\/comunicati\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017","name":"Redazione Comunicati Stampa","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","caption":"Redazione Comunicati Stampa"},"url":"https:\/\/www.article-marketing.eu\/comunicati\/author\/redazione-comunicati-stampa\/"}]}},"_links":{"self":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/42162","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/comments?post=42162"}],"version-history":[{"count":0,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/42162\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/media?parent=42162"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/categories?post=42162"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/tags?post=42162"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}