{"id":42172,"date":"2014-06-17T12:54:34","date_gmt":"2014-06-17T10:54:34","guid":{"rendered":"http:\/\/www.article-marketing.eu\/comunicati\/senza-categoria\/poli-design-e-ruffino-il-design-applicato-al-nuovo-fiasco-ruffino-il-design-come-strumento-di-valorizzazione-di-una%80%99icona-storica-italiana\/"},"modified":"2014-06-17T12:54:34","modified_gmt":"2014-06-17T10:54:34","slug":"poli-design-e-ruffino-il-design-applicato-al-nuovo-fiasco-ruffino-il-design-come-strumento-di-valorizzazione-di-una%80%99icona-storica-italiana","status":"publish","type":"post","link":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/poli-design-e-ruffino-il-design-applicato-al-nuovo-fiasco-ruffino-il-design-come-strumento-di-valorizzazione-di-una%80%99icona-storica-italiana\/","title":{"rendered":"POLI.design e Ruffino : il design applicato al nuovo Fiasco Ruffino"},"content":{"rendered":"<p><em>Milano, giugno 2014<\/em> &ndash; Compie un anno di vita la collaborazione tra <strong>POLI.design<\/strong>,<strong> Consorzio del Politecnico di Milano<\/strong>, e <strong>Ruffino<\/strong>, una delle aziende vitivinicole italiane pi&ugrave; importanti a livello internazionale. Una collaborazione che ha portato alla nascita di <strong>un vero e proprio team di progettazione formato da junior designer e creato ad hoc per Ruffino. <\/strong><\/p>\n<p>I giovani progettisti &#8211; professionisti laureati presso il Politecnico di Milano in Disegno Industriale con esperienze nell&rsquo;ambito della progettazione di prodotti industriali &ndash; dopo mesi di studio hanno definito <strong><em>design concept<\/em> riguardanti il sistema prodotto del Fiasco Ruffino in grado di valorizzare lo spirito innovativo che ha guidato il recente rilancio sul mercato di questo prodotto. <\/strong>E&rsquo; cos&igrave; che sono nati un nuovo <strong>gift pack per l&rsquo;asporto del Fiasco Ruffino<\/strong>, una <strong>lampada <\/strong>che valorizza le forme sinuose del <strong>fiasco e un tagliere <\/strong>che accoglie la bottiglia al momento della merenda toscana. <strong><\/strong><br \/><strong> <\/strong><br \/>Un lavoro molto importante e appassionante sia per la societ&agrave; che per i giovani designer che vi hanno partecipato. L&rsquo;avvio del progetto si &egrave; concretizzato con una visita nella storica tenuta Ruffino di Poggio Casciano alle porte di Firenze che ha consentito ai designer di vivere un&rsquo;autentica <strong><em>Ruffino Experience<\/em><\/strong>, immergendosi nel mondo del vino e nei valori che l&rsquo;azienda rappresenta.<\/p>\n<p>Il lavoro dei progettisti si &egrave; svolto seguendo un percorso di analisi di nuovi trend e dell&rsquo;evoluzione del settore, degli stili di consumo e dei nuovi format di convivialit&agrave;<strong> <\/strong>per arrivare a proporre degli scenari di progetto da cui trarre ispirazione per<strong> <\/strong>la definizione di <em>design concept<\/em> per il sistema prodotto del Fiasco Ruffino.<br \/>Dai risultati presentati, l&rsquo;azienda ha individuato i tre progetti migliori che sono stati ulteriormente sviluppati dai designer per valutarne la produzione. Premiati <strong>per l&rsquo;innovativit&agrave;, la congruenza e l&rsquo;efficacia della proposta <\/strong>sono stati tre progetti: un nuovo Gift Pack, una lampada<strong> <\/strong>e<strong> <\/strong>un tagliere. Idee<strong> <\/strong>che<strong> <\/strong>hanno saputo <strong>tradurre le esigenze di Ruffino in prodotti altamente innovativi e consistenti rispetto ai valori di una azienda radicata sul territorio. <\/strong><\/p>\n<p>Il <strong>Moccolo, <\/strong>una lampada<strong> <\/strong>proposta dai designer di <strong>About_blank Project, <\/strong>progettata a partire dall&rsquo;uso di una parte del fiasco, che Ruffino ha deciso di produrre in un numero limitato ed esclusivo di esemplari<strong> <\/strong>e che ha scelto come migliore proposta per la promozione del fiasco Ruffino: un modo divertente per utilizzare la luce a LED e ripensare il fiasco riutilizzato come candelabro. Il concetto &egrave; stato quindi ribaltato e letto in chiave contemporanea, seguendo il percorso tracciato dal fiasco stesso.<\/p>\n<p>E&rsquo; del giovane designer<strong> Fabio Caresi <\/strong>il progetto di un<strong> tagliere alimentare speciale, <\/strong>realizzato in faggio<strong> <\/strong>con incisioni laser e capace di contenere il Nuovo Fiasco. L&rsquo;accessorio da tavola ideale per una riproposizione della merenda-cena di una volta a base dei prelibati salumi e formaggi toscani.<\/p>\n<p>Infine, un nuovo <strong>Gift Pack<\/strong>: la confezione regalo, progettata sulla geometria del fiasco Ruffino da <strong>MAF&amp;CO<\/strong> (<strong>Marta Alice Fattorossi e Corina Macnovit)<\/strong>, &egrave; stata realizzata in cartone color avana accoppiato ad una pellicola pvc blu: estremamente semplice nella forma, pu&ograve; essere riutilizzata senza difficolt&agrave; grazie ad una chiusura posteriore a incastro. Cartone e pellicola pvc sono, inoltre, separabili l&rsquo;uno dall&rsquo;altra grazie a una linguetta: questo garantisce una dismissione della confezione conforme alle norme vigenti e una perfetta riciclabilit&agrave;. Lo speciale packaging, attualmente prodotto ed utilizzato da Ruffino, &egrave; stato utilizzato per un&rsquo;occasione speciale nell&rsquo;ambito di <strong>ZERO Design Festival 2014<\/strong>, la tre giorni di eventi all&rsquo;insegna del design organizzata da <strong>ZERO Editore<\/strong> <strong>in partnership con POLI.design<\/strong>. I fiaschi Ruffino, presentati nella loro nuova confezione, sono stati infatti battuti durante l&rsquo;asta benefica &ldquo;<strong><em>Pr d&#8217;incanto<\/em><\/strong>&rdquo;, uno dei momenti pi&ugrave; attesi della manifestazione organizzata lo scorso marzo presso il Museo della Scienza e della Tecnologia Leonardo Da Vinci di Milano.<\/p>\n<p><strong>Per informazioni<\/strong> sul progetto, si prega di contattare la Dott.ssa Roberta Gorno: <a href=\"mailto:competitions@polidesign.net\">roberta.gorno@polidesign.net<\/a> +39 02 2399 7207.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dalla collaborazione tra Ruffino e POLI.design nascono tre progetti innovativi che accompagnano e raccontano l\u2019icona italiana del vino nel mondo recentemente rilanciata da Ruffino: il Fiasco. <br \/>Design, sostenibilit\u00e0 ed efficienza per rilanciare un pezzo di storia italiana.<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"","footnotes":""},"categories":[190],"tags":[7025],"class_list":["post-42172","post","type-post","status-publish","format-standard","hentry","category-comunicati-stampa","tag-wine"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>POLI.design e Ruffino : il design applicato al nuovo Fiasco Ruffino - Article Marketing<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/poli-design-e-ruffino-il-design-applicato-al-nuovo-fiasco-ruffino-il-design-come-strumento-di-valorizzazione-di-una??icona-storica-italiana\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"POLI.design e Ruffino : il design applicato al nuovo Fiasco Ruffino - Article Marketing\" \/>\n<meta property=\"og:description\" content=\"Dalla collaborazione tra Ruffino e POLI.design nascono tre progetti innovativi che accompagnano e raccontano l\u2019icona italiana del vino nel mondo recentemente rilanciata da Ruffino: il Fiasco. Design, sostenibilit\u00e0 ed efficienza per rilanciare un pezzo di storia italiana.\" \/>\n<meta property=\"og:url\" content=\"\" \/>\n<meta property=\"og:site_name\" content=\"Article Marketing\" \/>\n<meta property=\"article:published_time\" content=\"2014-06-17T10:54:34+00:00\" \/>\n<meta name=\"author\" content=\"Redazione Comunicati Stampa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione Comunicati Stampa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/poli-design-e-ruffino-il-design-applicato-al-nuovo-fiasco-ruffino-il-design-come-strumento-di-valorizzazione-di-una%80%99icona-storica-italiana\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/poli-design-e-ruffino-il-design-applicato-al-nuovo-fiasco-ruffino-il-design-come-strumento-di-valorizzazione-di-una%80%99icona-storica-italiana\\\/\"},\"author\":{\"name\":\"Redazione Comunicati Stampa\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"headline\":\"POLI.design e Ruffino : il design applicato al nuovo Fiasco Ruffino\",\"datePublished\":\"2014-06-17T10:54:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/poli-design-e-ruffino-il-design-applicato-al-nuovo-fiasco-ruffino-il-design-come-strumento-di-valorizzazione-di-una%80%99icona-storica-italiana\\\/\"},\"wordCount\":687,\"commentCount\":0,\"keywords\":[\"wine\"],\"articleSection\":[\"Comunicati stampa\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/poli-design-e-ruffino-il-design-applicato-al-nuovo-fiasco-ruffino-il-design-come-strumento-di-valorizzazione-di-una%80%99icona-storica-italiana\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/poli-design-e-ruffino-il-design-applicato-al-nuovo-fiasco-ruffino-il-design-come-strumento-di-valorizzazione-di-una%80%99icona-storica-italiana\\\/\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/poli-design-e-ruffino-il-design-applicato-al-nuovo-fiasco-ruffino-il-design-come-strumento-di-valorizzazione-di-una%80%99icona-storica-italiana\\\/\",\"name\":\"POLI.design e Ruffino : il design applicato al nuovo Fiasco Ruffino - Article Marketing\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\"},\"datePublished\":\"2014-06-17T10:54:34+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/poli-design-e-ruffino-il-design-applicato-al-nuovo-fiasco-ruffino-il-design-come-strumento-di-valorizzazione-di-una%80%99icona-storica-italiana\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/poli-design-e-ruffino-il-design-applicato-al-nuovo-fiasco-ruffino-il-design-come-strumento-di-valorizzazione-di-una%80%99icona-storica-italiana\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/poli-design-e-ruffino-il-design-applicato-al-nuovo-fiasco-ruffino-il-design-come-strumento-di-valorizzazione-di-una%80%99icona-storica-italiana\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"POLI.design e Ruffino : il design applicato al nuovo Fiasco Ruffino\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\",\"name\":\"Article Marketing\",\"description\":\"article marketing &amp; press release\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\",\"name\":\"Redazione Comunicati Stampa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"caption\":\"Redazione Comunicati Stampa\"},\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/author\\\/redazione-comunicati-stampa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"POLI.design e Ruffino : il design applicato al nuovo Fiasco Ruffino - Article Marketing","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/poli-design-e-ruffino-il-design-applicato-al-nuovo-fiasco-ruffino-il-design-come-strumento-di-valorizzazione-di-una??icona-storica-italiana\/","og_locale":"it_IT","og_type":"article","og_title":"POLI.design e Ruffino : il design applicato al nuovo Fiasco Ruffino - Article Marketing","og_description":"Dalla collaborazione tra Ruffino e POLI.design nascono tre progetti innovativi che accompagnano e raccontano l\u2019icona italiana del vino nel mondo recentemente rilanciata da Ruffino: il Fiasco. Design, sostenibilit\u00e0 ed efficienza per rilanciare un pezzo di storia italiana.","og_url":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/poli-design-e-ruffino-il-design-applicato-al-nuovo-fiasco-ruffino-il-design-come-strumento-di-valorizzazione-di-una??icona-storica-italiana\/","og_site_name":"Article Marketing","article_published_time":"2014-06-17T10:54:34+00:00","author":"Redazione Comunicati Stampa","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione Comunicati Stampa","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/poli-design-e-ruffino-il-design-applicato-al-nuovo-fiasco-ruffino-il-design-come-strumento-di-valorizzazione-di-una%80%99icona-storica-italiana\/#article","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/poli-design-e-ruffino-il-design-applicato-al-nuovo-fiasco-ruffino-il-design-come-strumento-di-valorizzazione-di-una%80%99icona-storica-italiana\/"},"author":{"name":"Redazione Comunicati Stampa","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"headline":"POLI.design e Ruffino : il design applicato al nuovo Fiasco Ruffino","datePublished":"2014-06-17T10:54:34+00:00","mainEntityOfPage":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/poli-design-e-ruffino-il-design-applicato-al-nuovo-fiasco-ruffino-il-design-come-strumento-di-valorizzazione-di-una%80%99icona-storica-italiana\/"},"wordCount":687,"commentCount":0,"keywords":["wine"],"articleSection":["Comunicati stampa"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/poli-design-e-ruffino-il-design-applicato-al-nuovo-fiasco-ruffino-il-design-come-strumento-di-valorizzazione-di-una%80%99icona-storica-italiana\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/poli-design-e-ruffino-il-design-applicato-al-nuovo-fiasco-ruffino-il-design-come-strumento-di-valorizzazione-di-una%80%99icona-storica-italiana\/","url":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/poli-design-e-ruffino-il-design-applicato-al-nuovo-fiasco-ruffino-il-design-come-strumento-di-valorizzazione-di-una%80%99icona-storica-italiana\/","name":"POLI.design e Ruffino : il design applicato al nuovo Fiasco Ruffino - Article Marketing","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website"},"datePublished":"2014-06-17T10:54:34+00:00","author":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"breadcrumb":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/poli-design-e-ruffino-il-design-applicato-al-nuovo-fiasco-ruffino-il-design-come-strumento-di-valorizzazione-di-una%80%99icona-storica-italiana\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/poli-design-e-ruffino-il-design-applicato-al-nuovo-fiasco-ruffino-il-design-come-strumento-di-valorizzazione-di-una%80%99icona-storica-italiana\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/poli-design-e-ruffino-il-design-applicato-al-nuovo-fiasco-ruffino-il-design-come-strumento-di-valorizzazione-di-una%80%99icona-storica-italiana\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.article-marketing.eu\/comunicati\/"},{"@type":"ListItem","position":2,"name":"POLI.design e Ruffino : il design applicato al nuovo Fiasco Ruffino"}]},{"@type":"WebSite","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website","url":"https:\/\/www.article-marketing.eu\/comunicati\/","name":"Article Marketing","description":"article marketing &amp; press release","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.article-marketing.eu\/comunicati\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017","name":"Redazione Comunicati Stampa","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","caption":"Redazione Comunicati Stampa"},"url":"https:\/\/www.article-marketing.eu\/comunicati\/author\/redazione-comunicati-stampa\/"}]}},"_links":{"self":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/42172","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/comments?post=42172"}],"version-history":[{"count":0,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/42172\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/media?parent=42172"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/categories?post=42172"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/tags?post=42172"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}