{"id":4279,"date":"2010-03-01T17:59:56","date_gmt":"2010-03-01T16:59:56","guid":{"rendered":"http:\/\/www.article-marketing.eu\/comunicati\/senza-categoria\/sulla-riviera-del-conero-nasce-adamo-ed-eva-resort\/"},"modified":"2018-07-10T04:44:57","modified_gmt":"2018-07-10T02:44:57","slug":"sulla-riviera-del-conero-nasce-adamo-ed-eva-resort","status":"publish","type":"post","link":"https:\/\/www.article-marketing.eu\/comunicati\/casa\/sulla-riviera-del-conero-nasce-adamo-ed-eva-resort\/","title":{"rendered":"Sulla Riviera del Conero nasce Adamo ed Eva Resort"},"content":{"rendered":"<p style=\"margin-bottom: 0.0001pt;\" class=\"MsoNormal\">Nel<br \/>\nnuovo parco residenziale&nbsp;Adamo ed Eva<br \/>\nResort&nbsp;abitazioni e villette da sogno, di varia metratura per<br \/>\naccogliere uno, due o tre nuclei familiari, con giardino e possibilit\u00e0 di<br \/>\npiscina privata. Case intelligenti in linea con le pi\u00f9 evolute tendenze<br \/>\ndell\u2019abitare: domotica, climatizzazione, satellite e wi-fi.<strong><\/strong><\/p>\n<p style=\"margin-bottom: 0.0001pt;\" class=\"MsoNormal\"><strong>&nbsp;<\/strong><\/p>\n<p style=\"margin-bottom: 0.0001pt;\" class=\"MsoNormal\"><strong>Per<br \/>\nscoprire Adamo ed Eva Resort sul web bastano pochi click<\/strong><\/p>\n<p style=\"margin-bottom: 0.0001pt;\" class=\"MsoNormal\">Per<br \/>\nconoscere davvero tutto su Adamo ed Eva Resort basta visitare il sito&nbsp;www.adamoedevaresort.com.<br \/>\nIl video sulla home page mostra le varie fasi della costruzione e le attrattive<br \/>\ndello splendido territorio delle Marche. Alla pagina Masterplan \u00e8 disponibile<br \/>\nl&#8217;intera pianta del parco residenziale, navigabile in modo interattivo. E&#8217;<br \/>\naddirittura possibile visualizzare le planimetrie e scaricare il capitolato dei<br \/>\nsingoli appartamenti, case e ville.<\/p>\n<p style=\"margin-bottom: 0.0001pt;\" class=\"MsoNormal\">&nbsp;<\/p>\n<p style=\"margin-bottom: 0.0001pt;\" class=\"MsoNormal\"><strong>Una<br \/>\nperla tra verde e blu<\/strong><\/p>\n<p style=\"margin-bottom: 0.0001pt;\" class=\"MsoNormal\">Il<br \/>\nresort Adamo ed Eva si trova a Numana, vivace cittadina della Riviera del<br \/>\nConero. Il litorale di Numana \u00e8 da anni apprezzato e frequentato da turisti<br \/>\nnazionali ed internazionali per le sue bellezze naturali e per le attivit\u00e0 che<br \/>\nogni giorno si possono praticare, in spiaggia e nelle colline limitrofe. Il<br \/>\nluogo incantevole e le numerose associazioni sportive richiamano ogni anno<br \/>\namanti della vela e del sub. Ogni giorno uscite ed escursioni in mare aperto<br \/>\nsoddisfano professionisti, appassionati e meno esperti. Ideale per chi ama<br \/>\ntrascorrere giornate tranquille e per chi desidera scoprire un territorio<br \/>\nancora incontaminato.<\/p>\n<p style=\"margin-bottom: 0.0001pt;\" class=\"MsoNormal\">&nbsp;<\/p>\n<p style=\"margin-bottom: 0.0001pt;\" class=\"MsoNormal\"><strong>La<br \/>\nsicurezza:&nbsp;Vivere nella&nbsp;natura&nbsp;con l&#8217;hi-tech&nbsp;pi\u00f9 avanzato<\/strong><\/p>\n<p style=\"margin-bottom: 0.0001pt;\" class=\"MsoNormal\">Adamo<br \/>\ned Eva Resort \u00e8 molto pi\u00f9 di un complesso residenziale: \u00e8 un vero e proprio<br \/>\nstile di vita.<\/p>\n<p style=\"margin-bottom: 0.0001pt;\" class=\"MsoNormal\">Firmato<br \/>\ndall\u2019architetto Pasquale Piscitelli, il nuovo complesso residenziale e<br \/>\nturistico Adamo ed Eva Resort \u00e8 racchiuso da un perimetro di sicurezza dotato<br \/>\ndi avanzati sistemi di videosorveglianza e antintrusione, con un servizio<br \/>\nprivato di vigilanza attivo 24 ore su 24. Un\u2019oasi protetta dove puoi sentirti<br \/>\ndavvero al sicuro e dove i bambini possono giocare in tutta serenit\u00e0.<\/p>\n<p style=\"margin-bottom: 0.0001pt;\" class=\"MsoNormal\">&nbsp;<\/p>\n<p style=\"margin-bottom: 0.0001pt;\" class=\"MsoNormal\"><strong>Ecocompatibilit\u00e0<\/strong><\/p>\n<p style=\"margin-bottom: 0.0001pt;\" class=\"MsoNormal\">Pensare,<br \/>\nprogettare, costruire in armonia con l\u2019uomo e la natura integrando e mantenendo<br \/>\nle risorse, secondo il concetto di sviluppo sostenibile. Adamo ed Eva Resort \u00e8<br \/>\nstato creato secondo questi principi, in un\u2019ottica di economia proiettata nel<br \/>\nfuturo, che permette di limitare al massimo il dispendio delle energie,<br \/>\nsfruttando contemporaneamente le fonti naturali rinnovabili e pulite. Le<br \/>\nabitazioni sono realizzate utilizzando materiali e procedimenti costruttivi<br \/>\nsecondo i criteri del massimo risparmio energetico e del minimo impatto<br \/>\nambientale, secondo i principi della bioedilizia.<\/p>\n<p style=\"margin-bottom: 0.0001pt;\" class=\"MsoNormal\">&nbsp;<\/p>\n<p style=\"margin-bottom: 0.0001pt;\" class=\"MsoNormal\"><strong>Mare,<br \/>\nsole e tanto sport nel&nbsp;verde&nbsp;protetto&nbsp;per vivere sempre<br \/>\nin&nbsp;vacanza<\/strong><\/p>\n<p style=\"margin-bottom: 0.0001pt;\" class=\"MsoNormal\">Scogliere<br \/>\nmozzafiato a picco sul mare, esclusive calette e ampie spiagge attrezzate<br \/>\ncaratterizzano il litorale di Numana e Sirolo.&nbsp;<\/p>\n<p style=\"margin-bottom: 0.0001pt;\" class=\"MsoNormal\">A<br \/>\npochi metri dal Resort, un splendido beach club con spiaggia e servizi<br \/>\nriservati vi aspetta. Nella bella stagione concediti il relax della spiaggia a<br \/>\npochi metri da casa tua e un bel tuffo nel magnifico mare di Numana, insignito<br \/>\ndella Bandiera Blu d\u2019Europa.<\/p>\n<p style=\"margin-bottom: 0.0001pt;\" class=\"MsoNormal\">Il<br \/>\nbeach club offre una spiaggia attrezzata con ombrelloni, lettini relax e<br \/>\nspogliatoi riservati, uno spazio giochi attrezzato e sicuro per i bambini,<br \/>\nparcheggio, bar e ristorante per vivere la spiaggia davvero tutto il giorno.<br \/>\nVivere all\u2019Adamo ed Eva Resort \u00e8 un po\u2019 come sentirsi in vacanza tutto l\u2019anno.<\/p>\n<p style=\"margin-bottom: 0.0001pt;\" class=\"MsoNormal\"><strong>&nbsp;<\/strong><\/p>\n<p style=\"margin-bottom: 0.0001pt;\" class=\"MsoNormal\"><strong>La<br \/>\nqualit\u00e0 della vita all&#8217;Adamo ed Eva Resort \u00e8 anche relax<\/strong><\/p>\n<p style=\"margin-bottom: 0.0001pt;\" class=\"MsoNormal\">Concediti<br \/>\npiacevoli momenti di relax nella Spa interna dell\u2019Adamo ed Eva Resort. A tua<br \/>\ndisposizione rigeneranti massaggi benessere, percorso benessere con sauna,<br \/>\nbagno turco e idromassaggio dinamico. Percorso kneipp, trattamenti estetici per<br \/>\nlui e per lei, consigli nutrizionali personalizzati.<\/p>\n<p style=\"margin-bottom: 0.0001pt;\" class=\"MsoNormal\">&nbsp;<\/p>\n<p><strong><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>In linea con le pi\u00f9 moderne tendenze dell&#8217;abitare, nasce a Numana il parco residenziale Adamo ed Eva Resort, immerso in 10 ettari di verde, a pochi metri dalla spiaggia.<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"","footnotes":""},"categories":[390],"tags":[11854,1157,12591,12590,11856,11855,12589,12588],"class_list":["post-4279","post","type-post","status-publish","format-standard","hentry","category-casa","tag-adamo-ed-eva-resort","tag-casa","tag-casa-marcelli","tag-casa-sirolo","tag-conero","tag-numana","tag-parco-residenziale","tag-riviera-del-conero"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sulla Riviera del Conero nasce Adamo ed Eva Resort - Article Marketing<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.article-marketing.eu\/comunicati\/casa\/sulla-riviera-del-conero-nasce-adamo-ed-eva-resort\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sulla Riviera del Conero nasce Adamo ed Eva Resort - Article Marketing\" \/>\n<meta property=\"og:description\" content=\"In linea con le pi\u00f9 moderne tendenze dell&#039;abitare, nasce a Numana il parco residenziale Adamo ed Eva Resort, immerso in 10 ettari di verde, a pochi metri dalla spiaggia.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.article-marketing.eu\/comunicati\/casa\/sulla-riviera-del-conero-nasce-adamo-ed-eva-resort\/\" \/>\n<meta property=\"og:site_name\" content=\"Article Marketing\" \/>\n<meta property=\"article:published_time\" content=\"2010-03-01T16:59:56+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-07-10T02:44:57+00:00\" \/>\n<meta name=\"author\" content=\"Redazione Comunicati Stampa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione Comunicati Stampa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/casa\\\/sulla-riviera-del-conero-nasce-adamo-ed-eva-resort\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/casa\\\/sulla-riviera-del-conero-nasce-adamo-ed-eva-resort\\\/\"},\"author\":{\"name\":\"Redazione Comunicati Stampa\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"headline\":\"Sulla Riviera del Conero nasce Adamo ed Eva Resort\",\"datePublished\":\"2010-03-01T16:59:56+00:00\",\"dateModified\":\"2018-07-10T02:44:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/casa\\\/sulla-riviera-del-conero-nasce-adamo-ed-eva-resort\\\/\"},\"wordCount\":596,\"commentCount\":0,\"keywords\":[\"Adamo ed eva Resort\",\"casa\",\"casa marcelli\",\"casa sirolo\",\"Conero\",\"Numana\",\"parco residenziale\",\"riviera del conero\"],\"articleSection\":[\"Casa\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/casa\\\/sulla-riviera-del-conero-nasce-adamo-ed-eva-resort\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/casa\\\/sulla-riviera-del-conero-nasce-adamo-ed-eva-resort\\\/\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/casa\\\/sulla-riviera-del-conero-nasce-adamo-ed-eva-resort\\\/\",\"name\":\"Sulla Riviera del Conero nasce Adamo ed Eva Resort - Article Marketing\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\"},\"datePublished\":\"2010-03-01T16:59:56+00:00\",\"dateModified\":\"2018-07-10T02:44:57+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/casa\\\/sulla-riviera-del-conero-nasce-adamo-ed-eva-resort\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/casa\\\/sulla-riviera-del-conero-nasce-adamo-ed-eva-resort\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/casa\\\/sulla-riviera-del-conero-nasce-adamo-ed-eva-resort\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sulla Riviera del Conero nasce Adamo ed Eva Resort\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\",\"name\":\"Article Marketing\",\"description\":\"article marketing &amp; press release\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\",\"name\":\"Redazione Comunicati Stampa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"caption\":\"Redazione Comunicati Stampa\"},\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/author\\\/redazione-comunicati-stampa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sulla Riviera del Conero nasce Adamo ed Eva Resort - Article Marketing","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.article-marketing.eu\/comunicati\/casa\/sulla-riviera-del-conero-nasce-adamo-ed-eva-resort\/","og_locale":"it_IT","og_type":"article","og_title":"Sulla Riviera del Conero nasce Adamo ed Eva Resort - Article Marketing","og_description":"In linea con le pi\u00f9 moderne tendenze dell'abitare, nasce a Numana il parco residenziale Adamo ed Eva Resort, immerso in 10 ettari di verde, a pochi metri dalla spiaggia.","og_url":"https:\/\/www.article-marketing.eu\/comunicati\/casa\/sulla-riviera-del-conero-nasce-adamo-ed-eva-resort\/","og_site_name":"Article Marketing","article_published_time":"2010-03-01T16:59:56+00:00","article_modified_time":"2018-07-10T02:44:57+00:00","author":"Redazione Comunicati Stampa","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione Comunicati Stampa","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.article-marketing.eu\/comunicati\/casa\/sulla-riviera-del-conero-nasce-adamo-ed-eva-resort\/#article","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/casa\/sulla-riviera-del-conero-nasce-adamo-ed-eva-resort\/"},"author":{"name":"Redazione Comunicati Stampa","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"headline":"Sulla Riviera del Conero nasce Adamo ed Eva Resort","datePublished":"2010-03-01T16:59:56+00:00","dateModified":"2018-07-10T02:44:57+00:00","mainEntityOfPage":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/casa\/sulla-riviera-del-conero-nasce-adamo-ed-eva-resort\/"},"wordCount":596,"commentCount":0,"keywords":["Adamo ed eva Resort","casa","casa marcelli","casa sirolo","Conero","Numana","parco residenziale","riviera del conero"],"articleSection":["Casa"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.article-marketing.eu\/comunicati\/casa\/sulla-riviera-del-conero-nasce-adamo-ed-eva-resort\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.article-marketing.eu\/comunicati\/casa\/sulla-riviera-del-conero-nasce-adamo-ed-eva-resort\/","url":"https:\/\/www.article-marketing.eu\/comunicati\/casa\/sulla-riviera-del-conero-nasce-adamo-ed-eva-resort\/","name":"Sulla Riviera del Conero nasce Adamo ed Eva Resort - Article Marketing","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website"},"datePublished":"2010-03-01T16:59:56+00:00","dateModified":"2018-07-10T02:44:57+00:00","author":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"breadcrumb":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/casa\/sulla-riviera-del-conero-nasce-adamo-ed-eva-resort\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.article-marketing.eu\/comunicati\/casa\/sulla-riviera-del-conero-nasce-adamo-ed-eva-resort\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.article-marketing.eu\/comunicati\/casa\/sulla-riviera-del-conero-nasce-adamo-ed-eva-resort\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.article-marketing.eu\/comunicati\/"},{"@type":"ListItem","position":2,"name":"Sulla Riviera del Conero nasce Adamo ed Eva Resort"}]},{"@type":"WebSite","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website","url":"https:\/\/www.article-marketing.eu\/comunicati\/","name":"Article Marketing","description":"article marketing &amp; press release","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.article-marketing.eu\/comunicati\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017","name":"Redazione Comunicati Stampa","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","caption":"Redazione Comunicati Stampa"},"url":"https:\/\/www.article-marketing.eu\/comunicati\/author\/redazione-comunicati-stampa\/"}]}},"_links":{"self":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/4279","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/comments?post=4279"}],"version-history":[{"count":2,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/4279\/revisions"}],"predecessor-version":[{"id":59764,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/4279\/revisions\/59764"}],"wp:attachment":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/media?parent=4279"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/categories?post=4279"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/tags?post=4279"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}