{"id":43215,"date":"2014-07-28T14:54:56","date_gmt":"2014-07-28T12:54:56","guid":{"rendered":"http:\/\/www.article-marketing.eu\/comunicati\/senza-categoria\/le-eccellenze-da%80%99irpinia-nella-napoli-della-dieta-mediterranea\/"},"modified":"2014-07-28T14:54:56","modified_gmt":"2014-07-28T12:54:56","slug":"le-eccellenze-da%80%99irpinia-nella-napoli-della-dieta-mediterranea","status":"publish","type":"post","link":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/le-eccellenze-da%80%99irpinia-nella-napoli-della-dieta-mediterranea\/","title":{"rendered":"Le eccellenze d\u2019Irpinia nella Napoli della dieta mediterranea"},"content":{"rendered":"<p>Napoli, citt&agrave; simbolo della dieta mediterranea, ospiter&agrave; nella suggestiva location del Maschio Angioino la presentazione del Progetto Integrato di Promozione del Territorio <strong>&ldquo;Trionfo di sapori mediterranei delle terre del Cervaro e del Miscano&rdquo;.<\/strong> L&rsquo;evento, in programma marted&igrave; 29 luglio 2014, a partire dalle ore 10,30, nella Sala della Fondazione Valenzi presso il Castel Nuovo di Napoli, avr&agrave; per protagonisti i sei comuni appartenenti alle valli del Cervaro e del Miscano coinvolti nella realizzazione del progetto. <strong>Savignano Irpino (comune capofila), Casalbore, Greci, Montaguto, Montecalvo Irpino e Zungoli<\/strong> hanno scelto di lavorare in sinergia, ponendo le basi per una programmazione comune tesa alla valorizzazione e promozione dei rispettivi territori. Il progetto <strong>&ldquo;Trionfo di sapori mediterranei delle terre del Cervaro e del Miscano&rdquo;,<\/strong> finanziato nell&rsquo;ambito del <strong>PSR Campania 2007\/2013 &#8211; Interventi cofinanziati dal FEASR, Piano di Sviluppo Locale del GAL IRPINIA &#8211; MISURA 313 <em>&ldquo;Incentivazione di attivit&agrave; turistiche&rdquo;<\/em><\/strong>, ha il suo cardine nella realizzazione di laboratori del gusto che racconteranno la cultura alimentare del territorio interessato, individuato per la naturale adesione allo stile di vita insito nella dieta mediterranea. Ciascun paese ospiter&agrave; un laboratorio incentrato su un prodotto o un piatto della cucina tipica, sapientemente elaborati dai custodi della genuina tradizione irpina e protagonisti anche di degustazioni guidate, in concomitanza con una manifestazione appartenente alla tradizione socio-culturale del luogo, secondo un calendario che animer&agrave; l&#8217;intero mese di agosto, per concludersi poi negli ultimi giorni di settembre. I mestieri di un tempo affiancheranno, in una rievocazione scenica che prevede stand espositivi di prodotti ed elementi legati alla loro lavorazione e\/o coltivazione, i laboratori tenuti da esperti del settore. Le valli del Cervaro e del Miscano saranno cos&igrave; illustrate attraverso la ricchezza naturalistica, culturale ma soprattutto agroalimentare, enfatizzando i sapori tipici della dieta mediterranea, che garantiscono da sempre un elevato livello di benessere e che mirano a favorire l&rsquo;approccio del turista verso alimenti presenti nella tradizione antica, in grado di evocare uno stile di vita a misura d&rsquo;uomo. Oltre all&rsquo;organizzazione dell&rsquo;evento itinerante, il progetto<strong> &ldquo;Trionfo di sapori mediterranei delle terre del Cervaro e del Miscano&rdquo; <\/strong>prevede l&rsquo;implementazione di un piano di promozione dedicato allo stesso ed anche la realizzazione di utili strumenti divulgativi dei percorsi turistici dell&rsquo;area, quali segnaletica per ipovedenti, brochure e cartine, un portale web e un&rsquo;audioguida dedicati alla conoscenza del territorio. La condivisione del progetto con la <strong>Fondazione Valenzi<\/strong>, sempre attenta ai temi della valorizzazione del bello e del buono della Campania, e che offre la prestigiosa location di Castel Nuovo per la presentazione dell&rsquo;iniziativa, &egrave; volta a conferire un ampio respiro regionale alle attivit&agrave; che saranno messe in campo a partire da questa estate, uscendo dai confini della provincia di Avellino e comunicando cos&igrave; ad un pubblico molto pi&ugrave; vasto l&#8217;offerta turistica di una peculiare zona interna della Campania. All&rsquo;evento di presentazione, che sar&agrave; aperto dai saluti di<strong> Lucia Valenzi<\/strong>, Presidente della Fondazione Valenzi, interverranno: <strong>Alfonso Tartaglia<\/strong>, dirigente UOD Servizio Territoriale Provinciale Avellino, <strong>Fabio Della Marra Scarpone<\/strong>, sindaco di Savignano Irpino, <strong>Michele Barbato<\/strong>, direttore dell&#8217;esecuzione, <strong>Giuseppe Ottaiano<\/strong>, art director Sema, la societ&agrave; che fornir&agrave; i servizi necessari alla realizzazione del progetto. Introdurr&agrave; i lavori <strong>Carmela Maietta<\/strong>, giornalista de Il Mattino di Napoli, mentre <strong>Marzio Di Mezza<\/strong>, direttore di Otto Channel moderer&agrave; l&rsquo;incontro. Saranno presenti i sindaci dei sei comuni aderenti al progetto. La conferenza stampa si concluder&agrave; con una degustazione di prodotti tipici irpini.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Marted\u00ec 29 luglio, presso la Sala Conferenze della Fondazione Valenzi al Maschio Angioino, presentazione del Progetto Integrato di Promozione del Territorio \u201cTrionfo di sapori mediterranei delle Terre del Cervaro e del Miscano\u201d<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"","footnotes":""},"categories":[190],"tags":[596,9213,48495,597,48496,48494,253],"class_list":["post-43215","post","type-post","status-publish","format-standard","hentry","category-comunicati-stampa","tag-cultura","tag-dieta-mediterranea","tag-maschio-angioino","tag-napoli","tag-sapori","tag-trionfo-di-sapori","tag-turismo"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Le eccellenze d\u2019Irpinia nella Napoli della dieta mediterranea - Article Marketing<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/le-eccellenze-da??irpinia-nella-napoli-della-dieta-mediterranea\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le eccellenze d\u2019Irpinia nella Napoli della dieta mediterranea - Article Marketing\" \/>\n<meta property=\"og:description\" content=\"Marted\u00ec 29 luglio, presso la Sala Conferenze della Fondazione Valenzi al Maschio Angioino, presentazione del Progetto Integrato di Promozione del Territorio \u201cTrionfo di sapori mediterranei delle Terre del Cervaro e del Miscano\u201d\" \/>\n<meta property=\"og:url\" content=\"\" \/>\n<meta property=\"og:site_name\" content=\"Article Marketing\" \/>\n<meta property=\"article:published_time\" content=\"2014-07-28T12:54:56+00:00\" \/>\n<meta name=\"author\" content=\"Redazione Comunicati Stampa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione Comunicati Stampa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/le-eccellenze-da%80%99irpinia-nella-napoli-della-dieta-mediterranea\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/le-eccellenze-da%80%99irpinia-nella-napoli-della-dieta-mediterranea\\\/\"},\"author\":{\"name\":\"Redazione Comunicati Stampa\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"headline\":\"Le eccellenze d\u2019Irpinia nella Napoli della dieta mediterranea\",\"datePublished\":\"2014-07-28T12:54:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/le-eccellenze-da%80%99irpinia-nella-napoli-della-dieta-mediterranea\\\/\"},\"wordCount\":607,\"commentCount\":0,\"keywords\":[\"cultura\",\"dieta mediterranea\",\"maschio angioino\",\"napoli\",\"sapori\",\"trionfo di sapori\",\"turismo\"],\"articleSection\":[\"Comunicati stampa\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/le-eccellenze-da%80%99irpinia-nella-napoli-della-dieta-mediterranea\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/le-eccellenze-da%80%99irpinia-nella-napoli-della-dieta-mediterranea\\\/\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/le-eccellenze-da%80%99irpinia-nella-napoli-della-dieta-mediterranea\\\/\",\"name\":\"Le eccellenze d\u2019Irpinia nella Napoli della dieta mediterranea - Article Marketing\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\"},\"datePublished\":\"2014-07-28T12:54:56+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/le-eccellenze-da%80%99irpinia-nella-napoli-della-dieta-mediterranea\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/le-eccellenze-da%80%99irpinia-nella-napoli-della-dieta-mediterranea\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/le-eccellenze-da%80%99irpinia-nella-napoli-della-dieta-mediterranea\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Le eccellenze d\u2019Irpinia nella Napoli della dieta mediterranea\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\",\"name\":\"Article Marketing\",\"description\":\"article marketing &amp; press release\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\",\"name\":\"Redazione Comunicati Stampa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"caption\":\"Redazione Comunicati Stampa\"},\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/author\\\/redazione-comunicati-stampa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Le eccellenze d\u2019Irpinia nella Napoli della dieta mediterranea - Article Marketing","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/le-eccellenze-da??irpinia-nella-napoli-della-dieta-mediterranea\/","og_locale":"it_IT","og_type":"article","og_title":"Le eccellenze d\u2019Irpinia nella Napoli della dieta mediterranea - Article Marketing","og_description":"Marted\u00ec 29 luglio, presso la Sala Conferenze della Fondazione Valenzi al Maschio Angioino, presentazione del Progetto Integrato di Promozione del Territorio \u201cTrionfo di sapori mediterranei delle Terre del Cervaro e del Miscano\u201d","og_url":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/le-eccellenze-da??irpinia-nella-napoli-della-dieta-mediterranea\/","og_site_name":"Article Marketing","article_published_time":"2014-07-28T12:54:56+00:00","author":"Redazione Comunicati Stampa","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione Comunicati Stampa","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/le-eccellenze-da%80%99irpinia-nella-napoli-della-dieta-mediterranea\/#article","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/le-eccellenze-da%80%99irpinia-nella-napoli-della-dieta-mediterranea\/"},"author":{"name":"Redazione Comunicati Stampa","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"headline":"Le eccellenze d\u2019Irpinia nella Napoli della dieta mediterranea","datePublished":"2014-07-28T12:54:56+00:00","mainEntityOfPage":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/le-eccellenze-da%80%99irpinia-nella-napoli-della-dieta-mediterranea\/"},"wordCount":607,"commentCount":0,"keywords":["cultura","dieta mediterranea","maschio angioino","napoli","sapori","trionfo di sapori","turismo"],"articleSection":["Comunicati stampa"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/le-eccellenze-da%80%99irpinia-nella-napoli-della-dieta-mediterranea\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/le-eccellenze-da%80%99irpinia-nella-napoli-della-dieta-mediterranea\/","url":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/le-eccellenze-da%80%99irpinia-nella-napoli-della-dieta-mediterranea\/","name":"Le eccellenze d\u2019Irpinia nella Napoli della dieta mediterranea - Article Marketing","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website"},"datePublished":"2014-07-28T12:54:56+00:00","author":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"breadcrumb":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/le-eccellenze-da%80%99irpinia-nella-napoli-della-dieta-mediterranea\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/le-eccellenze-da%80%99irpinia-nella-napoli-della-dieta-mediterranea\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/le-eccellenze-da%80%99irpinia-nella-napoli-della-dieta-mediterranea\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.article-marketing.eu\/comunicati\/"},{"@type":"ListItem","position":2,"name":"Le eccellenze d\u2019Irpinia nella Napoli della dieta mediterranea"}]},{"@type":"WebSite","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website","url":"https:\/\/www.article-marketing.eu\/comunicati\/","name":"Article Marketing","description":"article marketing &amp; press release","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.article-marketing.eu\/comunicati\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017","name":"Redazione Comunicati Stampa","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","caption":"Redazione Comunicati Stampa"},"url":"https:\/\/www.article-marketing.eu\/comunicati\/author\/redazione-comunicati-stampa\/"}]}},"_links":{"self":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/43215","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/comments?post=43215"}],"version-history":[{"count":0,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/43215\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/media?parent=43215"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/categories?post=43215"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/tags?post=43215"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}