{"id":44053,"date":"2014-09-16T12:24:57","date_gmt":"2014-09-16T10:24:57","guid":{"rendered":"http:\/\/www.article-marketing.eu\/comunicati\/senza-categoria\/piano-b-e-ab-comunicazioni-si-aggiudicano-la-gara-eventi-expo-2015-padiglione-italia\/"},"modified":"2014-09-16T12:24:57","modified_gmt":"2014-09-16T10:24:57","slug":"piano-b-e-ab-comunicazioni-si-aggiudicano-la-gara-eventi-expo-2015-padiglione-italia","status":"publish","type":"post","link":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/eventi\/piano-b-e-ab-comunicazioni-si-aggiudicano-la-gara-eventi-expo-2015-padiglione-italia\/","title":{"rendered":"Piano B e Ab comunicazioni si aggiudicano la gara eventi EXPO 2015 Padiglione Italia"},"content":{"rendered":"<p><em>Piano B e Ab comunicazioni si occuperanno del coordinamento, della progettazione e realizzazione di<\/em><br \/><em>eventi e attivit&agrave; connesse per Padiglione Italia<\/em><\/p>\n<p>Milano, 16 settembre 2014 &ndash; Expo 2015, Padiglione Italia affida a Piano B e Ab Comunicazioni lo sviluppo degli eventi e le attivit&agrave; di comunicazione in vista del grande evento.<br \/><em>&#8220;Siamo orgogliosi di essere parte di EXPO 2015. La volont&agrave; del Padiglione Italia di diventare punto di riferimento per giovani talenti, un vivaio di idee dove sperimentare proposte, soluzioni, energie diverse ci ha ispirato fin dal primo momento perch&eacute; rappresenta quello che viviamo quotidianamente in Piano B. Leggiamo come un segnale di innovazione la scelta di affidare a una agenzia non convenzionale e fuori dagli schemi come Piano B la comunicazione di questo determinante progetto di rilancio del nostro Paese. Ci sar&agrave; da divertirsi<\/em>.&rdquo; ha commentato Mario Viscardi, Partner e direttore artistico di Piano B.<br \/><em>&ldquo;Siamo felici di poter proseguire il percorso iniziato con la gestione degli Eventi di Expo Milano 2015. A otto mesi dalla grande manifestazione siamo pronti a iniziare questa avventura per la promozione di Padiglione Italia Expo Milano 2015, l&rsquo;atteso evento del 2015 carico di positive aspettative per la nostra Milano e la nostra Italia.&rdquo;<\/em> ha commentato Andrea Bertoletti, Direttore Generale Ab Comunicazioni Srl.<br \/><em>Piano B e Ab comunicazioni si occuperanno del coordinamento, della progettazione e realizzazione di<\/em><br \/><em>eventi e attivit&agrave; connesse per Padiglione Italia<\/em><\/p>\n<p>Milano, 16 settembre 2014 &ndash; Expo 2015, Padiglione Italia affida a Piano B e Ab Comunicazioni lo sviluppo degli eventi e le attivit&agrave; di comunicazione in vista del grande evento.<br \/><em>&#8220;Siamo orgogliosi di essere parte di EXPO 2015. La volont&agrave; del Padiglione Italia di diventare punto di riferimento per giovani talenti, un vivaio di idee dove sperimentare proposte, soluzioni, energie diverse ci ha ispirato fin dal primo momento perch&eacute; rappresenta quello che viviamo quotidianamente in Piano B. Leggiamo come un segnale di innovazione la scelta di affidare a una agenzia non convenzionale e fuori dagli schemi come Piano B la comunicazione di questo determinante progetto di rilancio del nostro Paese. Ci sar&agrave; da divertirsi<\/em>.&rdquo; ha commentato Mario Viscardi, Partner e direttore artistico di Piano B.<br \/><em>&ldquo;Siamo felici di poter proseguire il percorso iniziato con la gestione degli Eventi di Expo Milano 2015. A otto mesi dalla grande manifestazione siamo pronti a iniziare questa avventura per la promozione di Padiglione Italia Expo Milano 2015, l&rsquo;atteso evento del 2015 carico di positive aspettative per la nostra Milano e la nostra Italia.&rdquo;<\/em> ha commentato Andrea Bertoletti, Direttore Generale Ab Comunicazioni Srl.<\/p>\n<p><strong>Piano B<\/strong><br \/>Stefano Losco<br \/>Email: stefano@pianob.it<br \/>Tel. 025461442<br \/><strong> <\/strong><br \/><strong>AB Comunicazioni<\/strong><br \/>Alice Prencipe<br \/>Email: <a href=\"mailto:prencipe@abcomunicazioni.it\">prencipe@abcomunicazioni.it<\/a><br \/>Tel. 335 6237960<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u201cSiamo orgogliosi di essere parte di Expo 2015. La volont\u00e0 del Padiglione Italia di diventare punto di riferimento per giovani talenti, un vivaio di idee dove sperimentare proposte, soluzioni, energie diverse ci ha ispirato fin dal primo momento perch\u00e9 rappresenta quello che viviamo quotidianamente in Piano B. Leggiamo come un segnale di innovazione la scelta di affidare a una agenzia non convenzionale e fuori dagli schemi come Piano B la comunicazione di questo determinante progetto di rilancio del nostro Paese. Ci sar\u00e0 da divertirsi\u201d, commenta nella nota Mario Viscardi, partner e direttore artistico di Piano B.<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"","footnotes":""},"categories":[388],"tags":[48987,48988,5093,18360,1343,48986,48989],"class_list":["post-44053","post","type-post","status-publish","format-standard","hentry","category-eventi","tag-eventi-expo","tag-eventi-expo-2015","tag-expo","tag-expo-2015","tag-milano","tag-padiglione-italia","tag-pianob"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Piano B e Ab comunicazioni si aggiudicano la gara eventi EXPO 2015 Padiglione Italia - Article Marketing<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/eventi\/piano-b-e-ab-comunicazioni-si-aggiudicano-la-gara-eventi-expo-2015-padiglione-italia\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Piano B e Ab comunicazioni si aggiudicano la gara eventi EXPO 2015 Padiglione Italia - Article Marketing\" \/>\n<meta property=\"og:description\" content=\"\u201cSiamo orgogliosi di essere parte di Expo 2015. La volont\u00e0 del Padiglione Italia di diventare punto di riferimento per giovani talenti, un vivaio di idee dove sperimentare proposte, soluzioni, energie diverse ci ha ispirato fin dal primo momento perch\u00e9 rappresenta quello che viviamo quotidianamente in Piano B. Leggiamo come un segnale di innovazione la scelta di affidare a una agenzia non convenzionale e fuori dagli schemi come Piano B la comunicazione di questo determinante progetto di rilancio del nostro Paese. Ci sar\u00e0 da divertirsi\u201d, commenta nella nota Mario Viscardi, partner e direttore artistico di Piano B.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/eventi\/piano-b-e-ab-comunicazioni-si-aggiudicano-la-gara-eventi-expo-2015-padiglione-italia\/\" \/>\n<meta property=\"og:site_name\" content=\"Article Marketing\" \/>\n<meta property=\"article:published_time\" content=\"2014-09-16T10:24:57+00:00\" \/>\n<meta name=\"author\" content=\"Redazione Comunicati Stampa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione Comunicati Stampa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/eventi\\\/piano-b-e-ab-comunicazioni-si-aggiudicano-la-gara-eventi-expo-2015-padiglione-italia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/eventi\\\/piano-b-e-ab-comunicazioni-si-aggiudicano-la-gara-eventi-expo-2015-padiglione-italia\\\/\"},\"author\":{\"name\":\"Redazione Comunicati Stampa\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"headline\":\"Piano B e Ab comunicazioni si aggiudicano la gara eventi EXPO 2015 Padiglione Italia\",\"datePublished\":\"2014-09-16T10:24:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/eventi\\\/piano-b-e-ab-comunicazioni-si-aggiudicano-la-gara-eventi-expo-2015-padiglione-italia\\\/\"},\"wordCount\":452,\"commentCount\":0,\"keywords\":[\"eventi expo\",\"eventi expo 2015\",\"expo\",\"Expo 2015\",\"milano\",\"padiglione italia\",\"pianob\"],\"articleSection\":[\"Eventi\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/eventi\\\/piano-b-e-ab-comunicazioni-si-aggiudicano-la-gara-eventi-expo-2015-padiglione-italia\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/eventi\\\/piano-b-e-ab-comunicazioni-si-aggiudicano-la-gara-eventi-expo-2015-padiglione-italia\\\/\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/eventi\\\/piano-b-e-ab-comunicazioni-si-aggiudicano-la-gara-eventi-expo-2015-padiglione-italia\\\/\",\"name\":\"Piano B e Ab comunicazioni si aggiudicano la gara eventi EXPO 2015 Padiglione Italia - Article Marketing\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\"},\"datePublished\":\"2014-09-16T10:24:57+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/eventi\\\/piano-b-e-ab-comunicazioni-si-aggiudicano-la-gara-eventi-expo-2015-padiglione-italia\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/eventi\\\/piano-b-e-ab-comunicazioni-si-aggiudicano-la-gara-eventi-expo-2015-padiglione-italia\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/eventi\\\/piano-b-e-ab-comunicazioni-si-aggiudicano-la-gara-eventi-expo-2015-padiglione-italia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Piano B e Ab comunicazioni si aggiudicano la gara eventi EXPO 2015 Padiglione Italia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\",\"name\":\"Article Marketing\",\"description\":\"article marketing &amp; press release\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\",\"name\":\"Redazione Comunicati Stampa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"caption\":\"Redazione Comunicati Stampa\"},\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/author\\\/redazione-comunicati-stampa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Piano B e Ab comunicazioni si aggiudicano la gara eventi EXPO 2015 Padiglione Italia - Article Marketing","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/eventi\/piano-b-e-ab-comunicazioni-si-aggiudicano-la-gara-eventi-expo-2015-padiglione-italia\/","og_locale":"it_IT","og_type":"article","og_title":"Piano B e Ab comunicazioni si aggiudicano la gara eventi EXPO 2015 Padiglione Italia - Article Marketing","og_description":"\u201cSiamo orgogliosi di essere parte di Expo 2015. La volont\u00e0 del Padiglione Italia di diventare punto di riferimento per giovani talenti, un vivaio di idee dove sperimentare proposte, soluzioni, energie diverse ci ha ispirato fin dal primo momento perch\u00e9 rappresenta quello che viviamo quotidianamente in Piano B. Leggiamo come un segnale di innovazione la scelta di affidare a una agenzia non convenzionale e fuori dagli schemi come Piano B la comunicazione di questo determinante progetto di rilancio del nostro Paese. Ci sar\u00e0 da divertirsi\u201d, commenta nella nota Mario Viscardi, partner e direttore artistico di Piano B.","og_url":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/eventi\/piano-b-e-ab-comunicazioni-si-aggiudicano-la-gara-eventi-expo-2015-padiglione-italia\/","og_site_name":"Article Marketing","article_published_time":"2014-09-16T10:24:57+00:00","author":"Redazione Comunicati Stampa","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione Comunicati Stampa","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/eventi\/piano-b-e-ab-comunicazioni-si-aggiudicano-la-gara-eventi-expo-2015-padiglione-italia\/#article","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/eventi\/piano-b-e-ab-comunicazioni-si-aggiudicano-la-gara-eventi-expo-2015-padiglione-italia\/"},"author":{"name":"Redazione Comunicati Stampa","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"headline":"Piano B e Ab comunicazioni si aggiudicano la gara eventi EXPO 2015 Padiglione Italia","datePublished":"2014-09-16T10:24:57+00:00","mainEntityOfPage":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/eventi\/piano-b-e-ab-comunicazioni-si-aggiudicano-la-gara-eventi-expo-2015-padiglione-italia\/"},"wordCount":452,"commentCount":0,"keywords":["eventi expo","eventi expo 2015","expo","Expo 2015","milano","padiglione italia","pianob"],"articleSection":["Eventi"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/eventi\/piano-b-e-ab-comunicazioni-si-aggiudicano-la-gara-eventi-expo-2015-padiglione-italia\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/eventi\/piano-b-e-ab-comunicazioni-si-aggiudicano-la-gara-eventi-expo-2015-padiglione-italia\/","url":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/eventi\/piano-b-e-ab-comunicazioni-si-aggiudicano-la-gara-eventi-expo-2015-padiglione-italia\/","name":"Piano B e Ab comunicazioni si aggiudicano la gara eventi EXPO 2015 Padiglione Italia - Article Marketing","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website"},"datePublished":"2014-09-16T10:24:57+00:00","author":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"breadcrumb":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/eventi\/piano-b-e-ab-comunicazioni-si-aggiudicano-la-gara-eventi-expo-2015-padiglione-italia\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/eventi\/piano-b-e-ab-comunicazioni-si-aggiudicano-la-gara-eventi-expo-2015-padiglione-italia\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/eventi\/piano-b-e-ab-comunicazioni-si-aggiudicano-la-gara-eventi-expo-2015-padiglione-italia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.article-marketing.eu\/comunicati\/"},{"@type":"ListItem","position":2,"name":"Piano B e Ab comunicazioni si aggiudicano la gara eventi EXPO 2015 Padiglione Italia"}]},{"@type":"WebSite","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website","url":"https:\/\/www.article-marketing.eu\/comunicati\/","name":"Article Marketing","description":"article marketing &amp; press release","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.article-marketing.eu\/comunicati\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017","name":"Redazione Comunicati Stampa","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","caption":"Redazione Comunicati Stampa"},"url":"https:\/\/www.article-marketing.eu\/comunicati\/author\/redazione-comunicati-stampa\/"}]}},"_links":{"self":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/44053","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/comments?post=44053"}],"version-history":[{"count":0,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/44053\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/media?parent=44053"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/categories?post=44053"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/tags?post=44053"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}