{"id":44101,"date":"2014-09-18T12:46:46","date_gmt":"2014-09-18T10:46:46","guid":{"rendered":"http:\/\/www.article-marketing.eu\/comunicati\/senza-categoria\/direct-line-una-mostra-itinerante-analizza-la-a%80cconvivenzaa%80%9d-tra-pedoni-automobilisti-ciclisti-e-motociclisti-sulle-strade-italiane-2\/"},"modified":"2014-09-18T12:46:46","modified_gmt":"2014-09-18T10:46:46","slug":"direct-line-una-mostra-itinerante-analizza-la-a%80cconvivenzaa%80%9d-tra-pedoni-automobilisti-ciclisti-e-motociclisti-sulle-strade-italiane-2","status":"publish","type":"post","link":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/direct-line-una-mostra-itinerante-analizza-la-a%80cconvivenzaa%80%9d-tra-pedoni-automobilisti-ciclisti-e-motociclisti-sulle-strade-italiane-2\/","title":{"rendered":"Direct Line: una mostra itinerante analizza la \u201cconvivenza\u201d tra pedoni, automobilisti, ciclisti e motociclisti sulle strade italiane"},"content":{"rendered":"<p><strong style=\"mso-bidi-font-weight: normal;\">Direct Line<\/strong> http:\/\/www.directline.it &ndash; la pi&ugrave; grande compagnia di assicurazione auto on line &ndash; da sempre impegnata nella creazione e nella promozione di una <strong style=\"mso-bidi-font-weight: normal;\">cultura della guida sicura<\/strong>, d&agrave; il via alla fase conclusiva di <strong style=\"mso-bidi-font-weight: normal;\">Share the Road<\/strong>, il progetto volto a promuovere l&rsquo;<strong style=\"mso-bidi-font-weight: normal;\">educazione stradale <\/strong>intesa come rispetto delle regole, ma, soprattutto, come <strong style=\"mso-bidi-font-weight: normal;\">rispetto delle persone<\/strong>. <\/p>\n<p>Una <strong style=\"mso-bidi-font-weight: normal;\">mostra itinerante<\/strong>, inaugurata il <strong style=\"mso-bidi-font-weight: normal;\">17 settembre al Superstudio Pi&ugrave; di Via Tortona 2 a Milano <\/strong>con un vernissage in anteprima, mostra quanta educazione c&rsquo;&egrave; sulle strade italiane, rielaborando in maniera <strong style=\"mso-bidi-font-weight: normal;\">originale<\/strong> e d&rsquo;impatto i dati raccolti dalla viva voce degli italiani durante tutto il progetto. Da aprile a maggio un&rsquo;auto rossa Direct Line guidata da un team composto da intervistatore, fotografo e videomaker, ha infatti attraversato lo Stivale alla ricerca di autisti, centauri, ciclisti e pedoni per raccogliere testimonianze, opinioni e punti di vista sul tema della <strong style=\"mso-bidi-font-weight: normal;\">convivenza su strada <\/strong>attraverso l&rsquo;iniziativa denominata <a href=\"http:\/\/blog.directline.it\/share-the-road\/\">Share the Road<\/a>. La mostra del 17 settembre &egrave; stata arricchita anche dalle immagini realizzate ad hoc che hanno come soggetto alcuni tra gli <strong style=\"mso-bidi-font-weight: normal;\">influencer pi&ugrave; seguiti della rete<\/strong> alle prese con pose e situazioni che interpretano in maniera divertente e diretta alcune tra le situazioni di vita comune su strada.<\/p>\n<p>Il viaggio di Share the Road iniziato ad aprile non finisce e continua attraverso tre tappe che mostreranno a tutti i protagonisti della strada la <strong style=\"mso-bidi-font-weight: normal;\">rappresentazione fotografica dei dati raccolti durante le prime 6 tappe del progetto<\/strong> &ldquo;<em style=\"mso-bidi-font-style: normal;\">on the road<\/em>&rdquo;<strong style=\"mso-bidi-font-weight: normal;\"> <\/strong>(Milano,<strong style=\"mso-bidi-font-weight: normal;\"> <\/strong>Torino, Verona, Bologna Firenze e Roma). Ma a rendere ancora pi&ugrave; innovativa l&rsquo;esposizioni saranno le <strong style=\"mso-bidi-font-weight: normal;\">istallazioni<\/strong>, che vedranno 5 Fiat 500L rosse utilizzate da Direct Line come speciali cavalletti per sostenere le immagini realizzate. <\/p>\n<p>Scoprire chi sono i pi&ugrave; indisciplinati al volante, quali sono i comportamenti pi&ugrave; consueti di ciclisti, pedoni, automobilisti e motociclisti e quali consigli di sicurezza i protagonisti della strada si raccomandano l&rsquo;un l&rsquo;altro, &egrave; facile, basta partecipare ai tre eventi aperti al pubblico:<\/p>\n<ul style=\"margin-top: 0cm;\" type=\"disc\"><\/p>\n<li class=\"MsoNormal\" style=\"color: black; text-align: justify; mso-list: l0 level1 lfo1;\"><strong style=\"mso-bidi-font-weight: normal;\">Firenze<\/strong> &ndash; 20 settembre, piazza Ognissanti<\/li>\n<p><\/ul>\n<ul style=\"margin-top: 0cm;\" type=\"disc\"><\/p>\n<li class=\"MsoNormal\" style=\"color: black; text-align: justify; mso-list: l0 level1 lfo1;\"><strong style=\"mso-bidi-font-weight: normal;\">Verona<\/strong> &ndash; 27 settembre, piazza San Zeno<\/li>\n<p><\/ul>\n<ul style=\"margin-top: 0cm;\" type=\"disc\"><\/p>\n<li class=\"MsoNormal\" style=\"color: black; text-align: justify; mso-list: l0 level1 lfo1;\"><strong style=\"mso-bidi-font-weight: normal;\">Milano<\/strong> &ndash; 28 settembre, piazza Gae Aulenti<\/li>\n<p><\/ul>\n<p><strong style=\"mso-bidi-font-weight: normal;\"> <\/strong><br \/>Le mostre, come l&rsquo;intero progetto Share the Road, rivive sui principali <strong style=\"mso-bidi-font-weight: normal;\">Social Network<\/strong> grazie ai profili ufficiali di Direct Line, che hanno raccontato <em style=\"mso-bidi-font-style: normal;\">step by step<\/em> questo viaggio attraverso l&rsquo;hashtag <strong style=\"mso-bidi-font-weight: normal;\">#sharetheroad<\/strong><\/p>\n<p>&ldquo;<em style=\"mso-bidi-font-style: normal;\">Siamo molto orgogliosi di questo progetto<\/em>, <em style=\"mso-bidi-font-style: normal;\">Share the Road ha rappresentato per noi un grande impegno ancora pi&ugrave; concreto in favore della guida sicura, educata e civile. <\/em>&#8211; commenta <strong style=\"mso-bidi-font-weight: normal;\">Barbara Panzeri, Direttore Marketing Direct Line<\/strong> &ndash; <em style=\"mso-bidi-font-style: normal;\">Il nostro contributo su questo tema &egrave; da sempre molto forte, ma grazie a questo progetto itinerante abbiamo potuto e voluto incontrare direttamente sul campo coloro che la strada la vivono da tutti i punti di vista. Ascoltare le voci degli automobilisti, ciclisti, motociclisti e pedoni italiani in giro per lo Stivale ci ha permesso di avere una fotografia definita e chiara di quello che accade sulle nostre strade. La mostra &egrave; la degna conclusione di questo viaggio alla scoperta dell&rsquo;educazione e del rispetto che, come in ogni aspetto della vita, non pu&ograve; mancare nemmeno on the road. Con l&rsquo;esposizione dei dati raccolti nelle piazze<\/em> <em style=\"mso-bidi-font-style: normal;\">italiane speriamo di poter svolgere un servizio pubblico che possa rendere i cittadini consapevoli di quelli che sono i comportamenti da evitare e quelli da adottare nel rispetto di tutti coloro che vivono la strada. Il tutto presentato in maniera originale, divertente e diretto in perfetto stile Direct Line&rdquo;.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Direct Line http:\/\/www.directline.it &ndash; la pi&ugrave; grande compagnia di assicurazione auto on line &ndash; da sempre impegnata nella creazione e nella promozione di una cultura della guida sicura, d&agrave; il via alla fase conclusiva di Share the Road, il progetto volto a promuovere l&rsquo;educazione stradale intesa come rispetto delle regole, ma, soprattutto, come rispetto delle persone. Una mostra itinerante, inaugurata il 17 settembre al Superstudio Pi&ugrave; di Via Tortona 2<\/p>\n<p><a class=\"continue-reading\" href=\"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/direct-line-una-mostra-itinerante-analizza-la-a%80cconvivenzaa%80%9d-tra-pedoni-automobilisti-ciclisti-e-motociclisti-sulle-strade-italiane-2\/\">Continue reading&#8230;<\/a><\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"","footnotes":""},"categories":[190],"tags":[47508],"class_list":["post-44101","post","type-post","status-publish","format-standard","hentry","category-comunicati-stampa","tag-share-the-road"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Direct Line: una mostra itinerante analizza la \u201cconvivenza\u201d tra pedoni, automobilisti, ciclisti e motociclisti sulle strade italiane - Article Marketing<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/direct-line-una-mostra-itinerante-analizza-la-a?cconvivenzaa??-tra-pedoni-automobilisti-ciclisti-e-motociclisti-sulle-strade-italiane-2\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Direct Line: una mostra itinerante analizza la \u201cconvivenza\u201d tra pedoni, automobilisti, ciclisti e motociclisti sulle strade italiane - Article Marketing\" \/>\n<meta property=\"og:description\" content=\"Direct Line http:\/\/www.directline.it &ndash; la pi&ugrave; grande compagnia di assicurazione auto on line &ndash; da sempre impegnata nella creazione e nella promozione di una cultura della guida sicura, d&agrave; il via alla fase conclusiva di Share the Road, il progetto volto a promuovere l&rsquo;educazione stradale intesa come rispetto delle regole, ma, soprattutto, come rispetto delle persone. Una mostra itinerante, inaugurata il 17 settembre al Superstudio Pi&ugrave; di Via Tortona 2Continue reading...\" \/>\n<meta property=\"og:url\" content=\"\" \/>\n<meta property=\"og:site_name\" content=\"Article Marketing\" \/>\n<meta property=\"article:published_time\" content=\"2014-09-18T10:46:46+00:00\" \/>\n<meta name=\"author\" content=\"Redazione Comunicati Stampa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione Comunicati Stampa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/direct-line-una-mostra-itinerante-analizza-la-a%80cconvivenzaa%80%9d-tra-pedoni-automobilisti-ciclisti-e-motociclisti-sulle-strade-italiane-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/direct-line-una-mostra-itinerante-analizza-la-a%80cconvivenzaa%80%9d-tra-pedoni-automobilisti-ciclisti-e-motociclisti-sulle-strade-italiane-2\\\/\"},\"author\":{\"name\":\"Redazione Comunicati Stampa\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"headline\":\"Direct Line: una mostra itinerante analizza la \u201cconvivenza\u201d tra pedoni, automobilisti, ciclisti e motociclisti sulle strade italiane\",\"datePublished\":\"2014-09-18T10:46:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/direct-line-una-mostra-itinerante-analizza-la-a%80cconvivenzaa%80%9d-tra-pedoni-automobilisti-ciclisti-e-motociclisti-sulle-strade-italiane-2\\\/\"},\"wordCount\":609,\"commentCount\":0,\"keywords\":[\"share the road\"],\"articleSection\":[\"Comunicati stampa\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/direct-line-una-mostra-itinerante-analizza-la-a%80cconvivenzaa%80%9d-tra-pedoni-automobilisti-ciclisti-e-motociclisti-sulle-strade-italiane-2\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/direct-line-una-mostra-itinerante-analizza-la-a%80cconvivenzaa%80%9d-tra-pedoni-automobilisti-ciclisti-e-motociclisti-sulle-strade-italiane-2\\\/\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/direct-line-una-mostra-itinerante-analizza-la-a%80cconvivenzaa%80%9d-tra-pedoni-automobilisti-ciclisti-e-motociclisti-sulle-strade-italiane-2\\\/\",\"name\":\"Direct Line: una mostra itinerante analizza la \u201cconvivenza\u201d tra pedoni, automobilisti, ciclisti e motociclisti sulle strade italiane - Article Marketing\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\"},\"datePublished\":\"2014-09-18T10:46:46+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/direct-line-una-mostra-itinerante-analizza-la-a%80cconvivenzaa%80%9d-tra-pedoni-automobilisti-ciclisti-e-motociclisti-sulle-strade-italiane-2\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/direct-line-una-mostra-itinerante-analizza-la-a%80cconvivenzaa%80%9d-tra-pedoni-automobilisti-ciclisti-e-motociclisti-sulle-strade-italiane-2\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/direct-line-una-mostra-itinerante-analizza-la-a%80cconvivenzaa%80%9d-tra-pedoni-automobilisti-ciclisti-e-motociclisti-sulle-strade-italiane-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Direct Line: una mostra itinerante analizza la \u201cconvivenza\u201d tra pedoni, automobilisti, ciclisti e motociclisti sulle strade italiane\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\",\"name\":\"Article Marketing\",\"description\":\"article marketing &amp; press release\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\",\"name\":\"Redazione Comunicati Stampa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"caption\":\"Redazione Comunicati Stampa\"},\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/author\\\/redazione-comunicati-stampa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Direct Line: una mostra itinerante analizza la \u201cconvivenza\u201d tra pedoni, automobilisti, ciclisti e motociclisti sulle strade italiane - Article Marketing","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/direct-line-una-mostra-itinerante-analizza-la-a?cconvivenzaa??-tra-pedoni-automobilisti-ciclisti-e-motociclisti-sulle-strade-italiane-2\/","og_locale":"it_IT","og_type":"article","og_title":"Direct Line: una mostra itinerante analizza la \u201cconvivenza\u201d tra pedoni, automobilisti, ciclisti e motociclisti sulle strade italiane - Article Marketing","og_description":"Direct Line http:\/\/www.directline.it &ndash; la pi&ugrave; grande compagnia di assicurazione auto on line &ndash; da sempre impegnata nella creazione e nella promozione di una cultura della guida sicura, d&agrave; il via alla fase conclusiva di Share the Road, il progetto volto a promuovere l&rsquo;educazione stradale intesa come rispetto delle regole, ma, soprattutto, come rispetto delle persone. Una mostra itinerante, inaugurata il 17 settembre al Superstudio Pi&ugrave; di Via Tortona 2Continue reading...","og_url":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/direct-line-una-mostra-itinerante-analizza-la-a?cconvivenzaa??-tra-pedoni-automobilisti-ciclisti-e-motociclisti-sulle-strade-italiane-2\/","og_site_name":"Article Marketing","article_published_time":"2014-09-18T10:46:46+00:00","author":"Redazione Comunicati Stampa","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione Comunicati Stampa","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/direct-line-una-mostra-itinerante-analizza-la-a%80cconvivenzaa%80%9d-tra-pedoni-automobilisti-ciclisti-e-motociclisti-sulle-strade-italiane-2\/#article","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/direct-line-una-mostra-itinerante-analizza-la-a%80cconvivenzaa%80%9d-tra-pedoni-automobilisti-ciclisti-e-motociclisti-sulle-strade-italiane-2\/"},"author":{"name":"Redazione Comunicati Stampa","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"headline":"Direct Line: una mostra itinerante analizza la \u201cconvivenza\u201d tra pedoni, automobilisti, ciclisti e motociclisti sulle strade italiane","datePublished":"2014-09-18T10:46:46+00:00","mainEntityOfPage":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/direct-line-una-mostra-itinerante-analizza-la-a%80cconvivenzaa%80%9d-tra-pedoni-automobilisti-ciclisti-e-motociclisti-sulle-strade-italiane-2\/"},"wordCount":609,"commentCount":0,"keywords":["share the road"],"articleSection":["Comunicati stampa"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/direct-line-una-mostra-itinerante-analizza-la-a%80cconvivenzaa%80%9d-tra-pedoni-automobilisti-ciclisti-e-motociclisti-sulle-strade-italiane-2\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/direct-line-una-mostra-itinerante-analizza-la-a%80cconvivenzaa%80%9d-tra-pedoni-automobilisti-ciclisti-e-motociclisti-sulle-strade-italiane-2\/","url":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/direct-line-una-mostra-itinerante-analizza-la-a%80cconvivenzaa%80%9d-tra-pedoni-automobilisti-ciclisti-e-motociclisti-sulle-strade-italiane-2\/","name":"Direct Line: una mostra itinerante analizza la \u201cconvivenza\u201d tra pedoni, automobilisti, ciclisti e motociclisti sulle strade italiane - Article Marketing","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website"},"datePublished":"2014-09-18T10:46:46+00:00","author":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"breadcrumb":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/direct-line-una-mostra-itinerante-analizza-la-a%80cconvivenzaa%80%9d-tra-pedoni-automobilisti-ciclisti-e-motociclisti-sulle-strade-italiane-2\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/direct-line-una-mostra-itinerante-analizza-la-a%80cconvivenzaa%80%9d-tra-pedoni-automobilisti-ciclisti-e-motociclisti-sulle-strade-italiane-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/direct-line-una-mostra-itinerante-analizza-la-a%80cconvivenzaa%80%9d-tra-pedoni-automobilisti-ciclisti-e-motociclisti-sulle-strade-italiane-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.article-marketing.eu\/comunicati\/"},{"@type":"ListItem","position":2,"name":"Direct Line: una mostra itinerante analizza la \u201cconvivenza\u201d tra pedoni, automobilisti, ciclisti e motociclisti sulle strade italiane"}]},{"@type":"WebSite","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website","url":"https:\/\/www.article-marketing.eu\/comunicati\/","name":"Article Marketing","description":"article marketing &amp; press release","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.article-marketing.eu\/comunicati\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017","name":"Redazione Comunicati Stampa","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","caption":"Redazione Comunicati Stampa"},"url":"https:\/\/www.article-marketing.eu\/comunicati\/author\/redazione-comunicati-stampa\/"}]}},"_links":{"self":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/44101","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/comments?post=44101"}],"version-history":[{"count":0,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/44101\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/media?parent=44101"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/categories?post=44101"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/tags?post=44101"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}