{"id":44164,"date":"2014-09-26T12:23:24","date_gmt":"2014-09-26T10:23:24","guid":{"rendered":"http:\/\/www.article-marketing.eu\/comunicati\/senza-categoria\/a-scuola-con-hera-e-la-a%80cla-grande-macchina-del-mondoa%80%9d\/"},"modified":"2014-09-26T12:23:24","modified_gmt":"2014-09-26T10:23:24","slug":"a-scuola-con-hera-e-la-a%80cla-grande-macchina-del-mondoa%80%9d","status":"publish","type":"post","link":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/aziende\/a-scuola-con-hera-e-la-a%80cla-grande-macchina-del-mondoa%80%9d\/","title":{"rendered":"A scuola con Hera e la \u201cLa Grande Macchina del Mondo\u201d"},"content":{"rendered":"<p><a href=\"\/uploads\/images\/u_17465\/thumb_macchinadelmondo_1.gif\" class=\"image\"><img decoding=\"async\" src=\"\/uploads\/images\/u_17465\/thumb_macchinadelmondo_1.gif\" border=\"0\" \/><\/a><br \/><em style=\"line-height: 125%;\">Al via le iscrizioni on line ai progetti di educazione ambientale della multiutility. Tra le novit&agrave; di questa quinta edizione, due nuovi percorsi dedicati al mare.<\/em><br \/><strong> <\/strong><br \/>Torna la <strong>Grande Macchina del Mondo<\/strong>, il <strong>progetto di educazione ambientale<\/strong> del Gruppo Hera rivolto alle scuole di ogni ordine e grado del territorio, con tanti progetti e laboratori gratuiti dedicati all&rsquo;<strong>ambiente<\/strong>. La Grande Macchina del Mondo di Hera lo scorso anno ha coinvolto <strong>oltre 60 mila studenti<\/strong>. Il tema dell&rsquo;<strong>acqua<\/strong> si &egrave; confermato in pole position tra quelli pi&ugrave; scelti, mentre l&rsquo;ambiente si &egrave; classificato al secondo posto seguito dall&rsquo;energia.<\/p>\n<p>Per l&rsquo;anno scolastico appena iniziato, la Grande Macchina del Mondo attiver&agrave; <strong>due nuovi progetti<\/strong> dedicati al <strong>mare <\/strong>e al suo habitat. Su www.gruppohera.it\/scuole gli insegnanti possono <strong>prenotare <\/strong><strong>fino al 31 ottobre l&rsquo;adesione<\/strong> per la propria classe. I progetti per le scuole di Hera della Grande Macchina del Mondo, giunto quest&rsquo;anno alla quinta edizione, propongono <strong>percorsi su acqua, energia e ambiente <\/strong>e sono<strong> interamente gratuiti<\/strong>. Da quest&rsquo;anno, inoltre, l&rsquo;<strong>Ufficio Scolastico Regionale<\/strong> ha concesso il <strong>patrocinio<\/strong> all&rsquo;iniziativa: un riconoscimento alla qualit&agrave; del progetto e all&rsquo;impegno di Hera a sostegno delle scuole nel territorio in cui opera.<\/p>\n<p>Per tutti i docenti, soprattutto per quelli che non riusciranno ad accedere ai laboratori, Hera ha previsto le &ldquo;<strong>Bacheche virtuali<\/strong>&rdquo; sul sito www.gruppohera.it\/scuole : veri e propri contenitori di notizie, dispense, argomenti, link, curiosit&agrave;, che potranno essere utili a <strong>creare autonomamente un percorso di approfondimento con i propri alunni.<\/strong><\/p>\n<p>La Grande Macchina del Mondo &egrave; un progetto molto articolato, che comprende anche <strong><em>Itinherario Invisibile<\/em>,<\/strong> cio&egrave; le <strong>visite delle classi ai principali impianti gestiti da Hera<\/strong> dove gli alunni possono vivere da vicino la gestione di servizi importanti per la vita dei cittadini.. Altro progetto importante &egrave; <strong><em>Un Pozzo di Scienza<\/em><\/strong>, percorso didattico di <strong>divulgazione scientifica<\/strong> dedicato ai ragazzi pi&ugrave; grandi: l&rsquo;anno scorso ha visto la partecipazione di <strong>oltre 14 mila ragazzi delle scuole superiori<\/strong> di tutto il territorio servito. Il tema del <em>Pozzo<\/em> di quest&rsquo;anno sar&agrave; il cibo e il titolo &egrave; gi&agrave; deciso: <strong>&ldquo;Fooding. Allenare la mente per nutrirsi meglio&rdquo;.<\/strong> Si tratta di un percorso di laboratori e dialoghi, in cui i ragazzi si confronteranno sui grandi temi legati al cibo e sulla corretta gestione delle risorse alimentari mondiali.<\/p>\n<p> &ldquo;Da molti anni rivolgiamo la nostra attenzione e il nostro impegno al mondo della scuola &#8211; spiega <strong>Tomaso Tommasi di Vignano,<\/strong> Presidente del Gruppo Hera &#8211; perch&eacute; crediamo nella possibilit&agrave; di far crescere le nuove generazioni nella consapevolezza del rispetto verso l&rsquo;ambiente, che &egrave; il luogo del vivere comune e parte fondamentale della vita di tutti. I giovani sono il futuro: informarli e fornire loro strumenti utili a salvaguardare le risorse che ci circondano &egrave; di grande importanza&rdquo;.<\/p>\n<p>Scopri tutte le iniziative di Hera per le scuole<br \/>www.gruppohera.it\/scuole<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Al via le iscrizioni on line ai progetti di educazione ambientale della multiutility. Tra le novit\u00e0 di questa quinta edizione, due nuovi percorsi dedicati al mare.<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"","footnotes":""},"categories":[129],"tags":[45887,49046],"class_list":["post-44164","post","type-post","status-publish","format-standard","hentry","category-aziende","tag-hera","tag-la-grande-macchina-del-mondo"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>A scuola con Hera e la \u201cLa Grande Macchina del Mondo\u201d - Article Marketing<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/aziende\/a-scuola-con-hera-e-la-a?cla-grande-macchina-del-mondoa??\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"A scuola con Hera e la \u201cLa Grande Macchina del Mondo\u201d - Article Marketing\" \/>\n<meta property=\"og:description\" content=\"Al via le iscrizioni on line ai progetti di educazione ambientale della multiutility. Tra le novit\u00e0 di questa quinta edizione, due nuovi percorsi dedicati al mare.\" \/>\n<meta property=\"og:url\" content=\"\" \/>\n<meta property=\"og:site_name\" content=\"Article Marketing\" \/>\n<meta property=\"article:published_time\" content=\"2014-09-26T10:23:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.article-marketing.eu\/uploads\/images\/u_17465\/thumb_macchinadelmondo_1.gif\" \/>\n<meta name=\"author\" content=\"Redazione Comunicati Stampa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione Comunicati Stampa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/economia-e-lavoro\\\/aziende\\\/a-scuola-con-hera-e-la-a%80cla-grande-macchina-del-mondoa%80%9d\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/economia-e-lavoro\\\/aziende\\\/a-scuola-con-hera-e-la-a%80cla-grande-macchina-del-mondoa%80%9d\\\/\"},\"author\":{\"name\":\"Redazione Comunicati Stampa\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"headline\":\"A scuola con Hera e la \u201cLa Grande Macchina del Mondo\u201d\",\"datePublished\":\"2014-09-26T10:23:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/economia-e-lavoro\\\/aziende\\\/a-scuola-con-hera-e-la-a%80cla-grande-macchina-del-mondoa%80%9d\\\/\"},\"wordCount\":519,\"commentCount\":0,\"keywords\":[\"Hera\",\"La Grande macchina del Mondo\"],\"articleSection\":[\"Aziende\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/economia-e-lavoro\\\/aziende\\\/a-scuola-con-hera-e-la-a%80cla-grande-macchina-del-mondoa%80%9d\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/economia-e-lavoro\\\/aziende\\\/a-scuola-con-hera-e-la-a%80cla-grande-macchina-del-mondoa%80%9d\\\/\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/economia-e-lavoro\\\/aziende\\\/a-scuola-con-hera-e-la-a%80cla-grande-macchina-del-mondoa%80%9d\\\/\",\"name\":\"A scuola con Hera e la \u201cLa Grande Macchina del Mondo\u201d - Article Marketing\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\"},\"datePublished\":\"2014-09-26T10:23:24+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/economia-e-lavoro\\\/aziende\\\/a-scuola-con-hera-e-la-a%80cla-grande-macchina-del-mondoa%80%9d\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/economia-e-lavoro\\\/aziende\\\/a-scuola-con-hera-e-la-a%80cla-grande-macchina-del-mondoa%80%9d\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/economia-e-lavoro\\\/aziende\\\/a-scuola-con-hera-e-la-a%80cla-grande-macchina-del-mondoa%80%9d\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"A scuola con Hera e la \u201cLa Grande Macchina del Mondo\u201d\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\",\"name\":\"Article Marketing\",\"description\":\"article marketing &amp; press release\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\",\"name\":\"Redazione Comunicati Stampa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"caption\":\"Redazione Comunicati Stampa\"},\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/author\\\/redazione-comunicati-stampa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"A scuola con Hera e la \u201cLa Grande Macchina del Mondo\u201d - Article Marketing","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/aziende\/a-scuola-con-hera-e-la-a?cla-grande-macchina-del-mondoa??\/","og_locale":"it_IT","og_type":"article","og_title":"A scuola con Hera e la \u201cLa Grande Macchina del Mondo\u201d - Article Marketing","og_description":"Al via le iscrizioni on line ai progetti di educazione ambientale della multiutility. Tra le novit\u00e0 di questa quinta edizione, due nuovi percorsi dedicati al mare.","og_url":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/aziende\/a-scuola-con-hera-e-la-a?cla-grande-macchina-del-mondoa??\/","og_site_name":"Article Marketing","article_published_time":"2014-09-26T10:23:24+00:00","og_image":[{"url":"https:\/\/www.article-marketing.eu\/uploads\/images\/u_17465\/thumb_macchinadelmondo_1.gif","type":"","width":"","height":""}],"author":"Redazione Comunicati Stampa","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione Comunicati Stampa","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/aziende\/a-scuola-con-hera-e-la-a%80cla-grande-macchina-del-mondoa%80%9d\/#article","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/aziende\/a-scuola-con-hera-e-la-a%80cla-grande-macchina-del-mondoa%80%9d\/"},"author":{"name":"Redazione Comunicati Stampa","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"headline":"A scuola con Hera e la \u201cLa Grande Macchina del Mondo\u201d","datePublished":"2014-09-26T10:23:24+00:00","mainEntityOfPage":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/aziende\/a-scuola-con-hera-e-la-a%80cla-grande-macchina-del-mondoa%80%9d\/"},"wordCount":519,"commentCount":0,"keywords":["Hera","La Grande macchina del Mondo"],"articleSection":["Aziende"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/aziende\/a-scuola-con-hera-e-la-a%80cla-grande-macchina-del-mondoa%80%9d\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/aziende\/a-scuola-con-hera-e-la-a%80cla-grande-macchina-del-mondoa%80%9d\/","url":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/aziende\/a-scuola-con-hera-e-la-a%80cla-grande-macchina-del-mondoa%80%9d\/","name":"A scuola con Hera e la \u201cLa Grande Macchina del Mondo\u201d - Article Marketing","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website"},"datePublished":"2014-09-26T10:23:24+00:00","author":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"breadcrumb":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/aziende\/a-scuola-con-hera-e-la-a%80cla-grande-macchina-del-mondoa%80%9d\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/aziende\/a-scuola-con-hera-e-la-a%80cla-grande-macchina-del-mondoa%80%9d\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/aziende\/a-scuola-con-hera-e-la-a%80cla-grande-macchina-del-mondoa%80%9d\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.article-marketing.eu\/comunicati\/"},{"@type":"ListItem","position":2,"name":"A scuola con Hera e la \u201cLa Grande Macchina del Mondo\u201d"}]},{"@type":"WebSite","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website","url":"https:\/\/www.article-marketing.eu\/comunicati\/","name":"Article Marketing","description":"article marketing &amp; press release","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.article-marketing.eu\/comunicati\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017","name":"Redazione Comunicati Stampa","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","caption":"Redazione Comunicati Stampa"},"url":"https:\/\/www.article-marketing.eu\/comunicati\/author\/redazione-comunicati-stampa\/"}]}},"_links":{"self":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/44164","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/comments?post=44164"}],"version-history":[{"count":0,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/44164\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/media?parent=44164"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/categories?post=44164"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/tags?post=44164"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}