{"id":44232,"date":"2014-09-29T10:04:38","date_gmt":"2014-09-29T08:04:38","guid":{"rendered":"http:\/\/www.article-marketing.eu\/comunicati\/senza-categoria\/formazione-rls-e-sicurezza-sul-lavoro\/"},"modified":"2014-09-29T10:04:38","modified_gmt":"2014-09-29T08:04:38","slug":"formazione-rls-e-sicurezza-sul-lavoro","status":"publish","type":"post","link":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/formazione-rls-e-sicurezza-sul-lavoro\/","title":{"rendered":"Formazione RLS e sicurezza sul lavoro"},"content":{"rendered":"<p>Ogni Azienda deve avere per legge il proprio Rappresentante dei Lavoratori per la Sicurezza (RLS) eletto o designato dai suoi colleghi di lavoro.<br \/>Tale elezione deve essere verbalizzata ed il nominativo del RLS deve essere comunicato telematicamente all&rsquo;INAIL territorialmente competente. <br \/>Nelle aziende con pi&ugrave; di 15 lavoratori, il RLS &egrave; eletto o designato dai colleghi nell&rsquo;ambito delle rappresentanze sindacali in azienda. <br \/>In assenza di tali rappresentanze, il RLS &egrave; eletto o designato dai lavoratori dell&rsquo;azienda al loro interno.<\/p>\n<p>Il numero minimo dei RLS &egrave;:<br \/>n. 1 RLS in tutte le aziende sino a 200 lavoratori;<br \/>n. 3 RLS in tutte le aziende da 201 a 1.000 lavoratori;<br \/>n. 6 RLS in tutte le aziende oltre i 1.000 lavoratori. <br \/>La durata del mandato del\/degli RLS coincide con la durata in carica delle RSU (generalmente 3 anni).<br \/>Nel caso l&#8217;RLS sia eletto direttamente all&#8217;interno dell&#8217;Azienda, la durata del mandato non ha scadenza o &egrave; subordinata a particolari accordi contrattuali di settore.<\/p>\n<p>Il ruolo del Rappresentante dei Lavoratori per la Sicurezza <br \/>Il RLS &egrave; figura centrale e strategica nel panorama della sicurezza aziendale e collabora direttamente in tale campo a fianco del Responsabile del Servizio Prevenzione e Protezione (RSPP) e del Medico Competente (MC). <br \/>Ha un ruolo solo consultivo (non decisionale) praticamente su ogni aspetto della vita aziendale per quanto concerne il settore sicurezza e igiene del lavoro. <br \/>A titolo di esempio: <br \/>&bull; collabora e prende visione del Documento di Valutazione dei Rischi; <br \/>&bull; ha accesso alle schede di sicurezza dei prodotti e a tutto il materiale inerente la sicurezza (es. registro infortuni);<br \/>&bull; controlla l&#8217;applicazione delle leggi in materia di sicurezza;<br \/>&bull; partecipa alla riunione annuale per la programmazione dei piani di sicurezza;<br \/>&bull; segnala al servizio di prevenzione aziendale i fattori di rischio riscontrati nell&#8217;azienda;<br \/>&bull; pu&ograve; ricorrere all&#8217;organo di vigilanza;<\/p>\n<p>Ed &egrave; consultato preventivamente riguardo a:<br \/>&bull; nomina degli addetti al servizio di prevenzione e protezione;<br \/>&bull; nomina della squadra antincendio;<br \/>&bull; nomina della squadra primo soccorso;<br \/>&bull; valutazione dei rischi;<br \/>&bull; programmazione-realizzazione-verifica dei piani di prevenzione;<br \/>&bull; formazione e informazione dei lavoratori.<\/p>\n<p>La formazione del Rappresentante dei Lavoratori per la Sicurezza (<a href=\"http:\/\/www.gruppoerrepisrl.com\/rls.html\" target=\"_blank\" title=\"Corsi RLS - Gruppo Errepi srl\">corso RLS<\/a>)<br \/>Tutti i RLS devono avere, per legge e in base agli Accordi Stato &#8211; Regioni &#8211; Province autonome, una formazione obbligatoria e specifica di base di durata minima di 32 ore conclusa da esame qualificante soggetta ad aggiornamenti annuali di durata variabile secondo le dimensioni aziendali (4 ore per aziende fino a 50 dipendenti e 8 ore per aziende con pi&ugrave; di 50 dipendenti).<br \/>L&rsquo;azienda &egrave; tenuta a fornire questa formazione agli RLS durante l&rsquo;orario di lavoro con oneri a totale carico del Datore di Lavoro.<br \/>Il RLS dispone altres&igrave; di un adeguato monte ore da utilizzare per svolgere il suo ruolo: detto monte ore &egrave; definito di norma in sede di pattuizione contrattuale e pu&ograve; variare da un minimo di 15 ad un massimo di 40 ore.<br \/>In linea di massima la formazione del RLS, durante il corso sulla sicurezza sul lavoro, si articola come segue: <br \/>&bull; principi costituzionali e di diritto civile;<br \/>&bull; legislazione generale e speciale in materia di prevenzione infortuni e igiene del lavoro;<br \/>&bull; soggetti protagonisti della sicurezza in azienda e relativi obblighi;<br \/>&bull; definizione ed individuazione dei fattori di rischio;<br \/>&bull; valutazione dei rischi;<br \/>&bull; individuazione delle misure di prevenzione e protezione;<br \/>&bull; aspetti normativi dell&rsquo;attivit&agrave; di rappresentanza dei lavoratori;<br \/>&bull; nozioni di tecnica della comunicazione;<br \/>&bull; rischi specifici della tipologia aziendale di appartenenza.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il Rappresentante dei Lavoratori per la Sicurezza, capiamo mansioni e doveri del RLS e l&#8217;iter di formazione di questa figura<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"","footnotes":""},"categories":[59],"tags":[3176,44268,49100,46837,2975],"class_list":["post-44232","post","type-post","status-publish","format-standard","hentry","category-economia-e-lavoro","tag-3176","tag-corsi-sicurezza","tag-d-lgs-81-08","tag-rls","tag-sicurezza-sul-lavoro"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Formazione RLS e sicurezza sul lavoro - Article Marketing<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/formazione-rls-e-sicurezza-sul-lavoro\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Formazione RLS e sicurezza sul lavoro - Article Marketing\" \/>\n<meta property=\"og:description\" content=\"Il Rappresentante dei Lavoratori per la Sicurezza, capiamo mansioni e doveri del RLS e l&#039;iter di formazione di questa figura\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/formazione-rls-e-sicurezza-sul-lavoro\/\" \/>\n<meta property=\"og:site_name\" content=\"Article Marketing\" \/>\n<meta property=\"article:published_time\" content=\"2014-09-29T08:04:38+00:00\" \/>\n<meta name=\"author\" content=\"Redazione Comunicati Stampa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione Comunicati Stampa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/economia-e-lavoro\\\/formazione-rls-e-sicurezza-sul-lavoro\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/economia-e-lavoro\\\/formazione-rls-e-sicurezza-sul-lavoro\\\/\"},\"author\":{\"name\":\"Redazione Comunicati Stampa\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"headline\":\"Formazione RLS e sicurezza sul lavoro\",\"datePublished\":\"2014-09-29T08:04:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/economia-e-lavoro\\\/formazione-rls-e-sicurezza-sul-lavoro\\\/\"},\"wordCount\":583,\"commentCount\":0,\"keywords\":[\"626\",\"corsi sicurezza\",\"D.lgs 81\\\/08\",\"RLS\",\"sicurezza sul lavoro\"],\"articleSection\":[\"Economia e lavoro\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/economia-e-lavoro\\\/formazione-rls-e-sicurezza-sul-lavoro\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/economia-e-lavoro\\\/formazione-rls-e-sicurezza-sul-lavoro\\\/\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/economia-e-lavoro\\\/formazione-rls-e-sicurezza-sul-lavoro\\\/\",\"name\":\"Formazione RLS e sicurezza sul lavoro - Article Marketing\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\"},\"datePublished\":\"2014-09-29T08:04:38+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/economia-e-lavoro\\\/formazione-rls-e-sicurezza-sul-lavoro\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/economia-e-lavoro\\\/formazione-rls-e-sicurezza-sul-lavoro\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/economia-e-lavoro\\\/formazione-rls-e-sicurezza-sul-lavoro\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Formazione RLS e sicurezza sul lavoro\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\",\"name\":\"Article Marketing\",\"description\":\"article marketing &amp; press release\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\",\"name\":\"Redazione Comunicati Stampa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"caption\":\"Redazione Comunicati Stampa\"},\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/author\\\/redazione-comunicati-stampa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Formazione RLS e sicurezza sul lavoro - Article Marketing","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/formazione-rls-e-sicurezza-sul-lavoro\/","og_locale":"it_IT","og_type":"article","og_title":"Formazione RLS e sicurezza sul lavoro - Article Marketing","og_description":"Il Rappresentante dei Lavoratori per la Sicurezza, capiamo mansioni e doveri del RLS e l'iter di formazione di questa figura","og_url":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/formazione-rls-e-sicurezza-sul-lavoro\/","og_site_name":"Article Marketing","article_published_time":"2014-09-29T08:04:38+00:00","author":"Redazione Comunicati Stampa","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione Comunicati Stampa","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/formazione-rls-e-sicurezza-sul-lavoro\/#article","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/formazione-rls-e-sicurezza-sul-lavoro\/"},"author":{"name":"Redazione Comunicati Stampa","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"headline":"Formazione RLS e sicurezza sul lavoro","datePublished":"2014-09-29T08:04:38+00:00","mainEntityOfPage":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/formazione-rls-e-sicurezza-sul-lavoro\/"},"wordCount":583,"commentCount":0,"keywords":["626","corsi sicurezza","D.lgs 81\/08","RLS","sicurezza sul lavoro"],"articleSection":["Economia e lavoro"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/formazione-rls-e-sicurezza-sul-lavoro\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/formazione-rls-e-sicurezza-sul-lavoro\/","url":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/formazione-rls-e-sicurezza-sul-lavoro\/","name":"Formazione RLS e sicurezza sul lavoro - Article Marketing","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website"},"datePublished":"2014-09-29T08:04:38+00:00","author":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"breadcrumb":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/formazione-rls-e-sicurezza-sul-lavoro\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/formazione-rls-e-sicurezza-sul-lavoro\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/formazione-rls-e-sicurezza-sul-lavoro\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.article-marketing.eu\/comunicati\/"},{"@type":"ListItem","position":2,"name":"Formazione RLS e sicurezza sul lavoro"}]},{"@type":"WebSite","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website","url":"https:\/\/www.article-marketing.eu\/comunicati\/","name":"Article Marketing","description":"article marketing &amp; press release","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.article-marketing.eu\/comunicati\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017","name":"Redazione Comunicati Stampa","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","caption":"Redazione Comunicati Stampa"},"url":"https:\/\/www.article-marketing.eu\/comunicati\/author\/redazione-comunicati-stampa\/"}]}},"_links":{"self":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/44232","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/comments?post=44232"}],"version-history":[{"count":0,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/44232\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/media?parent=44232"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/categories?post=44232"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/tags?post=44232"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}