{"id":44287,"date":"2014-09-30T14:49:58","date_gmt":"2014-09-30T12:49:58","guid":{"rendered":"http:\/\/www.article-marketing.eu\/comunicati\/senza-categoria\/carrera-podium-presenta-la-nuova-collezione-2015-la%80%99eccellenza-del-gusto-italiano-unico-e-inimitabile-2\/"},"modified":"2014-09-30T14:49:58","modified_gmt":"2014-09-30T12:49:58","slug":"carrera-podium-presenta-la-nuova-collezione-2015-la%80%99eccellenza-del-gusto-italiano-unico-e-inimitabile-2","status":"publish","type":"post","link":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/prodotti\/carrera-podium-presenta-la-nuova-collezione-2015-la%80%99eccellenza-del-gusto-italiano-unico-e-inimitabile-2\/","title":{"rendered":"Carrera Podium presenta la nuova collezione 2015. L\u2019eccellenza del gusto italiano, unico e inimitabile."},"content":{"rendered":"<p><strong style=\"line-height: 150%;\">Anticipare<\/strong> e <strong>innovare<\/strong>: queste le parole chiave dell&rsquo;<strong>azienda player di riferimento del settore ciclistico <\/strong>che ha saputo conquistare oltre 500 vittorie nelle competizioni pi&ugrave; prestigiose, mettendo in pista la qualit&agrave; italiana. Grazie alla costante ricerca, la messa a punto di nuove tecnologie per la strutturazione di materiali performanti e all&rsquo;utilizzo di nuove metodologie di lavoro, ancora una volta <strong><a href=\"http:\/\/www.carrera-podium.it\/\">Carrera Podium<\/a><\/strong> disegna l&rsquo;eccellenza del mondo bike, racchiudendola nella <strong>nuova collezione 2015<\/strong>.<br \/>Tante le <strong style=\"mso-bidi-font-weight: normal;\">novit&agrave;<\/strong> studiate dal brand: dall&rsquo;introduzione di nuovi modelli alla proposta di versioni pi&ugrave; economiche, dai miglioramenti estetici quanto funzionali &#8211; fatti di colori e telai all&rsquo;avanguardia &#8211; sino ad accattivanti vesti grafiche che rendono <strong style=\"mso-bidi-font-weight: normal;\">la collezione Carrera un must-have per appassionati professionisti e amatori<\/strong>. <br \/>Un assaggio? Il modello <strong style=\"mso-bidi-font-weight: normal;\">VELENO<\/strong> fodera i cavi da esterni ad interni, adottando sistema ICRS; <strong style=\"mso-bidi-font-weight: normal;\">ERAKLE e CLIMB<\/strong> si coprono di una nuova veste grafica, mentre i modelli <strong style=\"mso-bidi-font-weight: normal;\">SL 750 e NITRO<\/strong> propongono nuove versioni colore;<strong style=\"mso-bidi-font-weight: normal;\"> ONE-D<\/strong> cambia telaio, mantenendo il freno a disco come principale caratteristica e, infine, <strong style=\"mso-bidi-font-weight: normal;\">PHIBRA<\/strong> oltre alla versione colore rinnovata mostra un telaio pi&ugrave; performante e leggero grazie a forcellini in carbonio. <br \/>Tuttavia il vero <strong style=\"mso-bidi-font-weight: normal;\">modello di punta di questa stagione 2015<\/strong> deve essere qui ancora svelato. E&rsquo; <strong style=\"mso-bidi-font-weight: normal;\">Carrera SL 950: <\/strong>esteticamente identica al top di gamma SL 730, ma con qualche grammo in pi&ugrave; che la rendono ancora pi&ugrave; confortevole sulle lunghe distanze e vantaggiosa nel prezzo. Il telaio &egrave; realizzato in materiali compositi, con speciali fibre formate da graphite\/resina epossidiaca &#8211; tecnologia sviluppata nella produzione di materiali aeronautici, aerospaziali e nel settore automotive &ndash; che la rende altamente performante, mentre il modulo T700 Sc Carbonio Pre-Preg da 24Tons+30Tons crea resistenza agli urti e alla fatica meccanica. La SL 950 si conferma cos&igrave; molto adatta alle granfondo, estremamente veloce e reattiva, divenendo la bici ideale per chi ricerca l&rsquo;esclusivit&agrave; ad un prezzo pi&ugrave; contenuto.<\/p>\n<p>Protagonista di un viaggio oltreoceano, la nuova collezione dopo aver presenziato a Interbike (Las Vegas) rientra in terra d&rsquo;origine per la 7&deg; edizione di <strong style=\"mso-bidi-font-weight: normal;\">ExpoBici<\/strong> di <strong style=\"mso-bidi-font-weight: normal;\">Padova<\/strong>. <strong style=\"mso-bidi-font-weight: normal;\">Da sabato 20 a luned&igrave; 22 settembre<\/strong> la nuova gamma Carrera 2015 ancora pi&ugrave; versatile, innovativa e performante, ti aspetta presso la <strong style=\"mso-bidi-font-weight: normal;\">Fiera di Padova (Padiglione 5B &#8211; Stand 315). <\/strong><\/p>\n<p><strong style=\"mso-bidi-font-weight: normal;\">Lasciati conquistare dalle novit&agrave; da Carrera: un prodotto capace di trasmettere un gusto tutto italiano. <\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Anticipare e innovare: queste le parole chiave dell\u2019azienda player di riferimento del settore ciclistico che ha saputo conquistare oltre 500 vittorie nelle competizioni pi\u00f9 prestigiose, mettendo in pista la qualit\u00e0 italiana. Grazie alla costante ricerca, la messa a punto di nuove tecnologie per la strutturazione di materiali performanti e all\u2019utilizzo di nuove metodologie di lavoro, ancora una volta Carrera Podium disegna l\u2019eccellenza del mondo bike, racchiudendola nella nuova collezione 2015.<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"","footnotes":""},"categories":[212],"tags":[25450,49112,42930,49111],"class_list":["post-44287","post","type-post","status-publish","format-standard","hentry","category-prodotti","tag-carrera","tag-collezione-2015","tag-podium","tag-telai-bici"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Carrera Podium presenta la nuova collezione 2015. L\u2019eccellenza del gusto italiano, unico e inimitabile. - Article Marketing<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/prodotti\/carrera-podium-presenta-la-nuova-collezione-2015-la??eccellenza-del-gusto-italiano-unico-e-inimitabile-2\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Carrera Podium presenta la nuova collezione 2015. L\u2019eccellenza del gusto italiano, unico e inimitabile. - Article Marketing\" \/>\n<meta property=\"og:description\" content=\"Anticipare e innovare: queste le parole chiave dell\u2019azienda player di riferimento del settore ciclistico che ha saputo conquistare oltre 500 vittorie nelle competizioni pi\u00f9 prestigiose, mettendo in pista la qualit\u00e0 italiana. Grazie alla costante ricerca, la messa a punto di nuove tecnologie per la strutturazione di materiali performanti e all\u2019utilizzo di nuove metodologie di lavoro, ancora una volta Carrera Podium disegna l\u2019eccellenza del mondo bike, racchiudendola nella nuova collezione 2015.\" \/>\n<meta property=\"og:url\" content=\"\" \/>\n<meta property=\"og:site_name\" content=\"Article Marketing\" \/>\n<meta property=\"article:published_time\" content=\"2014-09-30T12:49:58+00:00\" \/>\n<meta name=\"author\" content=\"Redazione Comunicati Stampa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione Comunicati Stampa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/prodotti\\\/carrera-podium-presenta-la-nuova-collezione-2015-la%80%99eccellenza-del-gusto-italiano-unico-e-inimitabile-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/prodotti\\\/carrera-podium-presenta-la-nuova-collezione-2015-la%80%99eccellenza-del-gusto-italiano-unico-e-inimitabile-2\\\/\"},\"author\":{\"name\":\"Redazione Comunicati Stampa\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"headline\":\"Carrera Podium presenta la nuova collezione 2015. L\u2019eccellenza del gusto italiano, unico e inimitabile.\",\"datePublished\":\"2014-09-30T12:49:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/prodotti\\\/carrera-podium-presenta-la-nuova-collezione-2015-la%80%99eccellenza-del-gusto-italiano-unico-e-inimitabile-2\\\/\"},\"wordCount\":411,\"commentCount\":0,\"keywords\":[\"carrera\",\"collezione 2015\",\"podium\",\"telai bici\"],\"articleSection\":[\"Prodotti\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/prodotti\\\/carrera-podium-presenta-la-nuova-collezione-2015-la%80%99eccellenza-del-gusto-italiano-unico-e-inimitabile-2\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/prodotti\\\/carrera-podium-presenta-la-nuova-collezione-2015-la%80%99eccellenza-del-gusto-italiano-unico-e-inimitabile-2\\\/\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/prodotti\\\/carrera-podium-presenta-la-nuova-collezione-2015-la%80%99eccellenza-del-gusto-italiano-unico-e-inimitabile-2\\\/\",\"name\":\"Carrera Podium presenta la nuova collezione 2015. L\u2019eccellenza del gusto italiano, unico e inimitabile. - Article Marketing\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\"},\"datePublished\":\"2014-09-30T12:49:58+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/prodotti\\\/carrera-podium-presenta-la-nuova-collezione-2015-la%80%99eccellenza-del-gusto-italiano-unico-e-inimitabile-2\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/prodotti\\\/carrera-podium-presenta-la-nuova-collezione-2015-la%80%99eccellenza-del-gusto-italiano-unico-e-inimitabile-2\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/prodotti\\\/carrera-podium-presenta-la-nuova-collezione-2015-la%80%99eccellenza-del-gusto-italiano-unico-e-inimitabile-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Carrera Podium presenta la nuova collezione 2015. L\u2019eccellenza del gusto italiano, unico e inimitabile.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\",\"name\":\"Article Marketing\",\"description\":\"article marketing &amp; press release\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\",\"name\":\"Redazione Comunicati Stampa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"caption\":\"Redazione Comunicati Stampa\"},\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/author\\\/redazione-comunicati-stampa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Carrera Podium presenta la nuova collezione 2015. L\u2019eccellenza del gusto italiano, unico e inimitabile. - Article Marketing","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/prodotti\/carrera-podium-presenta-la-nuova-collezione-2015-la??eccellenza-del-gusto-italiano-unico-e-inimitabile-2\/","og_locale":"it_IT","og_type":"article","og_title":"Carrera Podium presenta la nuova collezione 2015. L\u2019eccellenza del gusto italiano, unico e inimitabile. - Article Marketing","og_description":"Anticipare e innovare: queste le parole chiave dell\u2019azienda player di riferimento del settore ciclistico che ha saputo conquistare oltre 500 vittorie nelle competizioni pi\u00f9 prestigiose, mettendo in pista la qualit\u00e0 italiana. Grazie alla costante ricerca, la messa a punto di nuove tecnologie per la strutturazione di materiali performanti e all\u2019utilizzo di nuove metodologie di lavoro, ancora una volta Carrera Podium disegna l\u2019eccellenza del mondo bike, racchiudendola nella nuova collezione 2015.","og_url":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/prodotti\/carrera-podium-presenta-la-nuova-collezione-2015-la??eccellenza-del-gusto-italiano-unico-e-inimitabile-2\/","og_site_name":"Article Marketing","article_published_time":"2014-09-30T12:49:58+00:00","author":"Redazione Comunicati Stampa","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione Comunicati Stampa","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/prodotti\/carrera-podium-presenta-la-nuova-collezione-2015-la%80%99eccellenza-del-gusto-italiano-unico-e-inimitabile-2\/#article","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/prodotti\/carrera-podium-presenta-la-nuova-collezione-2015-la%80%99eccellenza-del-gusto-italiano-unico-e-inimitabile-2\/"},"author":{"name":"Redazione Comunicati Stampa","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"headline":"Carrera Podium presenta la nuova collezione 2015. L\u2019eccellenza del gusto italiano, unico e inimitabile.","datePublished":"2014-09-30T12:49:58+00:00","mainEntityOfPage":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/prodotti\/carrera-podium-presenta-la-nuova-collezione-2015-la%80%99eccellenza-del-gusto-italiano-unico-e-inimitabile-2\/"},"wordCount":411,"commentCount":0,"keywords":["carrera","collezione 2015","podium","telai bici"],"articleSection":["Prodotti"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/prodotti\/carrera-podium-presenta-la-nuova-collezione-2015-la%80%99eccellenza-del-gusto-italiano-unico-e-inimitabile-2\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/prodotti\/carrera-podium-presenta-la-nuova-collezione-2015-la%80%99eccellenza-del-gusto-italiano-unico-e-inimitabile-2\/","url":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/prodotti\/carrera-podium-presenta-la-nuova-collezione-2015-la%80%99eccellenza-del-gusto-italiano-unico-e-inimitabile-2\/","name":"Carrera Podium presenta la nuova collezione 2015. L\u2019eccellenza del gusto italiano, unico e inimitabile. - Article Marketing","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website"},"datePublished":"2014-09-30T12:49:58+00:00","author":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"breadcrumb":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/prodotti\/carrera-podium-presenta-la-nuova-collezione-2015-la%80%99eccellenza-del-gusto-italiano-unico-e-inimitabile-2\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/prodotti\/carrera-podium-presenta-la-nuova-collezione-2015-la%80%99eccellenza-del-gusto-italiano-unico-e-inimitabile-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/prodotti\/carrera-podium-presenta-la-nuova-collezione-2015-la%80%99eccellenza-del-gusto-italiano-unico-e-inimitabile-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.article-marketing.eu\/comunicati\/"},{"@type":"ListItem","position":2,"name":"Carrera Podium presenta la nuova collezione 2015. L\u2019eccellenza del gusto italiano, unico e inimitabile."}]},{"@type":"WebSite","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website","url":"https:\/\/www.article-marketing.eu\/comunicati\/","name":"Article Marketing","description":"article marketing &amp; press release","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.article-marketing.eu\/comunicati\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017","name":"Redazione Comunicati Stampa","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","caption":"Redazione Comunicati Stampa"},"url":"https:\/\/www.article-marketing.eu\/comunicati\/author\/redazione-comunicati-stampa\/"}]}},"_links":{"self":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/44287","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/comments?post=44287"}],"version-history":[{"count":0,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/44287\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/media?parent=44287"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/categories?post=44287"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/tags?post=44287"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}