{"id":45330,"date":"2014-11-11T08:56:08","date_gmt":"2014-11-11T07:56:08","guid":{"rendered":"http:\/\/www.article-marketing.eu\/comunicati\/senza-categoria\/tecnologia-ed-agricoltura-linnovazione-nella-produzione-di-macchine-agricole-negli-ultimi-50-anni\/"},"modified":"2014-11-11T08:56:08","modified_gmt":"2014-11-11T07:56:08","slug":"tecnologia-ed-agricoltura-linnovazione-nella-produzione-di-macchine-agricole-negli-ultimi-50-anni","status":"publish","type":"post","link":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/aziende\/tecnologia-ed-agricoltura-linnovazione-nella-produzione-di-macchine-agricole-negli-ultimi-50-anni\/","title":{"rendered":"tecnologia ed agricoltura &#8211; l&#8217;innovazione nella produzione di macchine agricole negli ultimi 50 anni"},"content":{"rendered":"<p>l&#8217;agricoltura &egrave; sicuramente uno dei settori in cui tradizionalmente l&#8217;uomo ha concentrato le proprie energie sin dagli albori delle attivit&agrave; cosidette lavorative.<br \/>Per la propria sopravvivenza , escluso il ricorso alle risorse naturalmente presenti in natura , si &egrave; dovuto orqanizzare per uno sfruttamento sistematico delle risorse alimentari a propria disposizione.<br \/>Come per altre attivit&agrave; anche l&#8217;impegno nella lavorazione del terreno ed in generale in agricoltura ha costituito , per anni, un problema importante.<br \/>Oltre all&#8217;impiego degli animali era comunque necessaria una notevole presenza di forza lavoro in termini umani. La fatica costituita dal lavoro in agricoltura da sempre rappresenta una delle<br \/>problematiche legate a questo settore ed in parte ne ha condizionato lo sviluppo a fasi alterne nel corso degli ultimi 50 anni.<br \/>Lo spopolamento delle campagne nel secondo dopoguerra e l&#8217;avvento della produzione industriale erano fortemente condizionati dalla bassa remunerazione economica generata dal lavoro della terra<br \/>e dalla fatica intrinseca dovuta alle tecniche di lavorazione del periodo e dalla quasi totale assenza di automatismi meccanici rivolti al settore.<br \/>L&#8217;arrivo sul mercato dei primi trattori agricoli e delle successive macchine agricole per la lavorazione del terreno hanno fornito un notevole ed imprescindibile impulso alla ripresa<br \/>del settore , oltre a garantire possibilit&agrave; di sfruttamento sino a quel momento impensabili.<br \/>Se si considera che il territorio del nostro Paese &egrave; rappresentato da un 23,2% di terreno pianeggiante, di un 41,6% di terreno collinare e di un restante 35,2% di terreno montuoso si puo&#8217; ben capire che <br \/>anche orograficamente il contributo delle <a href=\"http:\/\/www.maschionet.com\" target=\"_blank\" title=\"macchine agricole\">macchine agricole<\/a> sia stato determinante per lo sviluppo del settore.<br \/>Gi&agrave; la sola sostituzione della trazione animale con quella meccanica motorizzata ha rappresentato un punto di svolta nel modo di concepire l&#8217;agricoltura ed in particolare l&#8217;agricoltura moderna<br \/>che si &egrave; affermata progressivamente con l&#8217;avvento di altri strumenti dedicati alla lavorazione del terreno quali ad esempio le seminatrici, gli aratri, le fresatrici, le trinciatrici ecc..<br \/>macchine agricole sempre pi&ugrave; sofisticate ed efficienti in grado di assolvere i compiti pi&ugrave; gravosi con tempistiche inarrivabili dalle metodologie di lavorazione precedenti.<br \/>Il concetto di agricoltura intensiva si &egrave; progressivamente affermato grazie all&#8217;apporto fornito dalla tecnologia che non deve necessariamente venir interpretato come una sorta<br \/>di sfruttamento indiscriminato del terreno ma pi&ugrave; semplicemente come una forma di razionalizzazione ed ottimizzazione dei processi produttivi con conseguenti benefici per la popolazione<br \/>in particolare , per quella dei paesi pi&ugrave; poveri e bisognosi di approvvigionamento alimentare.<br \/>Sicuramente in alcune aree del mondo, l&#8217;innovazione tecnologica in agricoltura, potrebbe modificare la qualit&agrave; della vita delle popolazioni locali garantendo maggiori possibilit&agrave; di<br \/>sopravvivenza anche di fronte a problematiche alimentari particolarmente complesse.<br \/>Maggior tecnologia in campo agricolo rappresenta anche un ricorso minore alla manodopera , una semplificazione nei processi produttivi (raccolta, semina del terreno ecc&#8230;)<br \/>oltre ad significativo contenimento dei costi che di per s&egrave; aiuta a non erodere una marginalit&agrave; gi&agrave; di per s&egrave; piuttosto bassa in questo partiolare settore produttivo.<br \/>Qualunque sia il futuro del progresso tecnologico sicuramente non potr&agrave; prescindere dall&#8217;impegno nella ricerca e nello sviluppo di nuove attrezzature e macchine agricole dato che <br \/>n&egrave; la rivoluzione industriale n&egrave; la new economy potranno mai dare risposte alternative alle esigenze alimentari del genere umano.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&#8217;evoluzione tecnologica negli ultimi 50 anni ha portato una serie di benefici in ambito produttivo particolarmente importanti nel settore agricolo, modificando radicalmente i modi e le problematiche legate alle difficolt\u00e0 della lavorazione del terreno. La semplificazione nelle lavorazioni e le ottimizzazioni in termini di quantit\u00e0 di prodotto ottenuto ne sono la riprova.<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"","footnotes":""},"categories":[129],"tags":[14282,49642],"class_list":["post-45330","post","type-post","status-publish","format-standard","hentry","category-aziende","tag-macchine-agricole","tag-manutenzione-del-verde"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>tecnologia ed agricoltura - l&#039;innovazione nella produzione di macchine agricole negli ultimi 50 anni - Article Marketing<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/aziende\/tecnologia-ed-agricoltura-linnovazione-nella-produzione-di-macchine-agricole-negli-ultimi-50-anni\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"tecnologia ed agricoltura - l&#039;innovazione nella produzione di macchine agricole negli ultimi 50 anni - Article Marketing\" \/>\n<meta property=\"og:description\" content=\"L&#039;evoluzione tecnologica negli ultimi 50 anni ha portato una serie di benefici in ambito produttivo particolarmente importanti nel settore agricolo, modificando radicalmente i modi e le problematiche legate alle difficolt\u00e0 della lavorazione del terreno. La semplificazione nelle lavorazioni e le ottimizzazioni in termini di quantit\u00e0 di prodotto ottenuto ne sono la riprova.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/aziende\/tecnologia-ed-agricoltura-linnovazione-nella-produzione-di-macchine-agricole-negli-ultimi-50-anni\/\" \/>\n<meta property=\"og:site_name\" content=\"Article Marketing\" \/>\n<meta property=\"article:published_time\" content=\"2014-11-11T07:56:08+00:00\" \/>\n<meta name=\"author\" content=\"Redazione Comunicati Stampa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione Comunicati Stampa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/economia-e-lavoro\\\/aziende\\\/tecnologia-ed-agricoltura-linnovazione-nella-produzione-di-macchine-agricole-negli-ultimi-50-anni\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/economia-e-lavoro\\\/aziende\\\/tecnologia-ed-agricoltura-linnovazione-nella-produzione-di-macchine-agricole-negli-ultimi-50-anni\\\/\"},\"author\":{\"name\":\"Redazione Comunicati Stampa\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"headline\":\"tecnologia ed agricoltura &#8211; l&#8217;innovazione nella produzione di macchine agricole negli ultimi 50 anni\",\"datePublished\":\"2014-11-11T07:56:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/economia-e-lavoro\\\/aziende\\\/tecnologia-ed-agricoltura-linnovazione-nella-produzione-di-macchine-agricole-negli-ultimi-50-anni\\\/\"},\"wordCount\":538,\"commentCount\":0,\"keywords\":[\"macchine agricole\",\"manutenzione del verde\"],\"articleSection\":[\"Aziende\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/economia-e-lavoro\\\/aziende\\\/tecnologia-ed-agricoltura-linnovazione-nella-produzione-di-macchine-agricole-negli-ultimi-50-anni\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/economia-e-lavoro\\\/aziende\\\/tecnologia-ed-agricoltura-linnovazione-nella-produzione-di-macchine-agricole-negli-ultimi-50-anni\\\/\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/economia-e-lavoro\\\/aziende\\\/tecnologia-ed-agricoltura-linnovazione-nella-produzione-di-macchine-agricole-negli-ultimi-50-anni\\\/\",\"name\":\"tecnologia ed agricoltura - l'innovazione nella produzione di macchine agricole negli ultimi 50 anni - Article Marketing\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\"},\"datePublished\":\"2014-11-11T07:56:08+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/economia-e-lavoro\\\/aziende\\\/tecnologia-ed-agricoltura-linnovazione-nella-produzione-di-macchine-agricole-negli-ultimi-50-anni\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/economia-e-lavoro\\\/aziende\\\/tecnologia-ed-agricoltura-linnovazione-nella-produzione-di-macchine-agricole-negli-ultimi-50-anni\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/economia-e-lavoro\\\/aziende\\\/tecnologia-ed-agricoltura-linnovazione-nella-produzione-di-macchine-agricole-negli-ultimi-50-anni\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"tecnologia ed agricoltura &#8211; l&#8217;innovazione nella produzione di macchine agricole negli ultimi 50 anni\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\",\"name\":\"Article Marketing\",\"description\":\"article marketing &amp; press release\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\",\"name\":\"Redazione Comunicati Stampa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"caption\":\"Redazione Comunicati Stampa\"},\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/author\\\/redazione-comunicati-stampa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"tecnologia ed agricoltura - l'innovazione nella produzione di macchine agricole negli ultimi 50 anni - Article Marketing","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/aziende\/tecnologia-ed-agricoltura-linnovazione-nella-produzione-di-macchine-agricole-negli-ultimi-50-anni\/","og_locale":"it_IT","og_type":"article","og_title":"tecnologia ed agricoltura - l'innovazione nella produzione di macchine agricole negli ultimi 50 anni - Article Marketing","og_description":"L'evoluzione tecnologica negli ultimi 50 anni ha portato una serie di benefici in ambito produttivo particolarmente importanti nel settore agricolo, modificando radicalmente i modi e le problematiche legate alle difficolt\u00e0 della lavorazione del terreno. La semplificazione nelle lavorazioni e le ottimizzazioni in termini di quantit\u00e0 di prodotto ottenuto ne sono la riprova.","og_url":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/aziende\/tecnologia-ed-agricoltura-linnovazione-nella-produzione-di-macchine-agricole-negli-ultimi-50-anni\/","og_site_name":"Article Marketing","article_published_time":"2014-11-11T07:56:08+00:00","author":"Redazione Comunicati Stampa","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione Comunicati Stampa","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/aziende\/tecnologia-ed-agricoltura-linnovazione-nella-produzione-di-macchine-agricole-negli-ultimi-50-anni\/#article","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/aziende\/tecnologia-ed-agricoltura-linnovazione-nella-produzione-di-macchine-agricole-negli-ultimi-50-anni\/"},"author":{"name":"Redazione Comunicati Stampa","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"headline":"tecnologia ed agricoltura &#8211; l&#8217;innovazione nella produzione di macchine agricole negli ultimi 50 anni","datePublished":"2014-11-11T07:56:08+00:00","mainEntityOfPage":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/aziende\/tecnologia-ed-agricoltura-linnovazione-nella-produzione-di-macchine-agricole-negli-ultimi-50-anni\/"},"wordCount":538,"commentCount":0,"keywords":["macchine agricole","manutenzione del verde"],"articleSection":["Aziende"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/aziende\/tecnologia-ed-agricoltura-linnovazione-nella-produzione-di-macchine-agricole-negli-ultimi-50-anni\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/aziende\/tecnologia-ed-agricoltura-linnovazione-nella-produzione-di-macchine-agricole-negli-ultimi-50-anni\/","url":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/aziende\/tecnologia-ed-agricoltura-linnovazione-nella-produzione-di-macchine-agricole-negli-ultimi-50-anni\/","name":"tecnologia ed agricoltura - l'innovazione nella produzione di macchine agricole negli ultimi 50 anni - Article Marketing","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website"},"datePublished":"2014-11-11T07:56:08+00:00","author":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"breadcrumb":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/aziende\/tecnologia-ed-agricoltura-linnovazione-nella-produzione-di-macchine-agricole-negli-ultimi-50-anni\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/aziende\/tecnologia-ed-agricoltura-linnovazione-nella-produzione-di-macchine-agricole-negli-ultimi-50-anni\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/aziende\/tecnologia-ed-agricoltura-linnovazione-nella-produzione-di-macchine-agricole-negli-ultimi-50-anni\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.article-marketing.eu\/comunicati\/"},{"@type":"ListItem","position":2,"name":"tecnologia ed agricoltura &#8211; l&#8217;innovazione nella produzione di macchine agricole negli ultimi 50 anni"}]},{"@type":"WebSite","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website","url":"https:\/\/www.article-marketing.eu\/comunicati\/","name":"Article Marketing","description":"article marketing &amp; press release","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.article-marketing.eu\/comunicati\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017","name":"Redazione Comunicati Stampa","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","caption":"Redazione Comunicati Stampa"},"url":"https:\/\/www.article-marketing.eu\/comunicati\/author\/redazione-comunicati-stampa\/"}]}},"_links":{"self":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/45330","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/comments?post=45330"}],"version-history":[{"count":0,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/45330\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/media?parent=45330"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/categories?post=45330"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/tags?post=45330"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}