{"id":45332,"date":"2014-11-11T10:26:31","date_gmt":"2014-11-11T09:26:31","guid":{"rendered":"http:\/\/www.article-marketing.eu\/comunicati\/senza-categoria\/i-colori-delle-ombre-2\/"},"modified":"2014-11-11T10:26:31","modified_gmt":"2014-11-11T09:26:31","slug":"i-colori-delle-ombre-2","status":"publish","type":"post","link":"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/i-colori-delle-ombre-2\/","title":{"rendered":"I colori delle ombre"},"content":{"rendered":"<p>Non tutti sanno che all&rsquo;inizio dell&rsquo;Ottocento, nel campo della pittura, gli artisti pi&ugrave; impegnati ed esigenti furono costretti a risolvere alcuni problemi fondamentali relativi al cromatismo e, pi&ugrave; specificatamente, ai colori delle ombre. Prima in Italia e poi in Francia, divamp&ograve; in quel periodo l&rsquo;entusiasmante ricerca del tono giusto delle ombre, proposto appena qualche decennio prima da alcuni famosi &ldquo;SCIENZIATI DELLA LUCE&rdquo; come Robert Boyle, Arthur Schopenhauer e Wolfgang Goethe, eredi delle scoperte di Newton.<br \/>\nIntorno al 1830, pertanto, nella foresta di Fontainebleau, ad una sessantina di chilometri da Parigi, nei pressi del villaggio di Barbizon, un gruppo di artisti ( Daubigny, Diaz, Troyon, Dupr&egrave;, Millet, gli italiani Nicola e Giuseppe Palizzi, Serafino d&egrave; Tivoli, Nino Costa e tanti altri) elabor&ograve; un diverso modo di accostarsi alla natura. Quegli artisti avevano scoperto che dipingendo il paesaggio dal vero, in particolare il bosco con tutte le sue fantasmagoriche tinte, l&rsquo;opera d&rsquo;arte risultava pi&ugrave; affascinante e realistica.<br \/>\nCos&igrave;, in poco tempo, la foresta divenne la grande Madre nelle cui braccia l&#8217;artista si rifugiava smarrito per penetrarne l&#8217;armonia misteriosa. Proprio mentre le affamate popolazioni della campagna invadevano le grandi metropoli industrializzate, l&#8217;armonia pastorale dei pittori di Barbizon difendeva, con toccante poesia, l&#8217;immagine di un&#8217; Arcadia prossima a scomparire.<br \/>\nE&rsquo; l&#8217;epoca della nascita della pittura all&rsquo;aria aperta, il cosiddetto &#8220;pleinairisme&#8221;; ma gi&agrave; molto tempo prima del 1830, in Italia, il fenomeno dell&#8217;improvviso turismo dovuto alle scoperte archeologiche degli scavi di Pompei, che da quasi un secolo erano al centro dell&#8217;attenzione, aveva generato, nelle localit&agrave; pi&ugrave; frequentate del golfo di Napoli, l&#8217;invenzione di paesaggini dipinti su tavolette eseguiti dal vero in rapidissime sedute, da vendere come souvenirs e come immagini di luoghi felici.<br \/>\nL&#8217;appellativo di &#8220;Scuola di Posillipo&#8221; fu coniato dai pittori vicini alla corte borbonica, intenzionati sia a mantenere le distanze dai &#8220;pittori di piazza&#8221; che a disinteressarsi completamente del paesaggio. Ma le spiagge incantate ed i ruderi suggestivi, con il Vesuvio sullo sfondo, finirono per attirare le simpatie del Re, che prefer&igrave; presto i giovani ai vecchi accademici. Pitloo, Smargiassi e Ducl&egrave;re occuparono cattedre di prestigio; solo Giacinto Gigante rest&ograve; sempre fuori dal giro, non fu allievo n&eacute; docente, ma pur sempre stimato artista di corte e maestro esclusivo delle principesse. In ogni modo, fu Jean-Baptiste Camille Corot a portare le novit&agrave; italiane e la &#8220;luce mediterranea&#8221; a Barbizon, ma a Napoli soggiornarono in quegli anni pure Wilhelm Tischbein, Bonington e altri. Anche Reynolds venne in Italia per cercare di scoprire i meccanismi che sono alla base dei colori delle ombre; ma ce n&#8217;&egrave; tutta una nutrita schiera.<br \/>\nDove c&#8217;&egrave; la luce pallida le ombre hanno colori pi&ugrave; spenti e quasi illegibili. Lo studio del paesaggio dal vero inizia subito dopo Poussin e Lorrain, nel Settecento, in Italia, quando il paesaggio era ancora un genere pittorico poco apprezzato. Solo agli inizi dell&#8217;Ottocento, con l&#8217;inglese Constable, il genere paesaggistico si imporr&agrave; all&#8217;attenzione dei collezionisti e della critica del tempo. Con l&#8217;aiuto della fotografia, inoltre, riprodurre con maggiore realismo la natura diventa meno arduo: alberi, foglie, nuvole, tramonti, stagioni, zefiri, brezze, turbini ed acquazzoni non avranno pi&ugrave; segreti per gli artisti.<br \/>\nIn quegli anni Nic&egrave;phore Niepce stava perfezionando la fotografia, e le sue scoperte non lasciarono gli artisti indifferenti, dal momento che erano continuamente interessati anche ai problemi legati alla costruzione grafica del dipinto, oltre che al complesso studio dei colori complementari. La dagherrotipia fu resa pubblica nel 1839, ma gi&agrave; da parecchio tempo molti pittori se ne servivano. Dopo Newton non pochi scienziati aprirono lo &#8220;scrigno del Sole&#8221;, tra questi Boyle e Goethe; Maxwell fu, poi, il primo a capire che la carica elettrica forniva colori, addirittura sapori e soprattutto forme agli oggetti. Scopr&igrave; che la luce &egrave; costituita da onde elettromagnetiche che producono calore e il calore causa un movimento molecolare, una vibrazione.<br \/>\nIn pratica, Chardin non avrebbe potuto cogliere il fascino che c&#8217;&egrave; in un paiolo di rame, se Dio avesse dimenticato di creare la carica elettrica. Il Sole genera i colori, li accende e muove l&#8217;ombra; l&#8217;esattezza dei volumi vale poco se non &egrave; accompagnata da un&#8217;analisi cromatica altrettanto attenta, e la verit&agrave; dei toni, che accresce il piacere di guardare, dipende proprio dalla finezza dei colori delle luci e delle ombre. Siccome la fotografia permetteva di sintetizzare e disegnare meglio ogni complicata struttura della natura, l&#8217;attenzione di molti paesaggisti si rivers&ograve; tutta sullo studio dei rapporti cromatici.<br \/>\nI colori che vediamo in natura appartengono soprattutto alla nostra mente; nell&#8217;occhio che li percepisce avvengono dei processi complicatissimi, adatti a captare tutti i fenomeni luminosi che si svolgono intorno a noi. Perci&ograve;, una teoria dei colori, in fondo non &egrave; che lo studio delle percezioni dell&#8217;occhio.<br \/>\nDiceva Goethe: &#8221; L&#8217;orecchio &egrave; muto, la bocca &egrave; sorda, ma l&#8217;occhio sente e parla&#8221;. Bisogna sapere che l&#8217;uomo &egrave; &#8220;fototropico&#8221;, viene &#8220;attratto dalla luce&#8221; come le falene e prova un gran piacere nel vedere i colori, ne ha bisogno come dell&#8217;aria che respira; per questo motivo le vetrine dei negozi sono sempre illuminatissime, appunto per &#8220;catturare&#8221; i passanti .<br \/>\nLa luminosit&agrave; di un colore, per&ograve;, non va intesa come chiarezza bens&igrave; come purezza di colore; il tono, poi, &egrave; un&#8217;altra cosa; anche un colore scuro, usato puro, pu&ograve; essere luminoso. Colori e luci sono in strettissimo rapporto, non vanno considerati come tinte solamente, ma anche come luci colorate; un oggetto pi&ugrave; scuro appare pi&ugrave; piccolo di uno chiaro di uguale grandezza, e questo fenomeno era noto fin dall&#8217;antichit&agrave;.<br \/>\nI grandi artisti del Partenone, Fidia, Ictino e Callicrate, conoscevano perfettamente l&#8217;influenza della luce sulle superfici piene e vuote e le distorsioni ottiche che provocava. Per questa ragione studiarono attentamente il sistema dell&#8217;intervallo delle colonne in rapporto all&#8217;altezza, l&#8217;inclinazione dei loro assi per farle apparire visivamente pi&ugrave; stabili e inventarono l&#8217;&egrave;ntasi per evitare la percezione degli effetti di &#8220;strozzatura&#8221;. Avevano scoperto che il colore scuro dell&#8217;intercolumnio lasciava l&#8217;occhio in condizione di quiete, mentre il bianco della colonna lo poneva in attivit&agrave; facendola sembrare pi&ugrave; grande di quanto in effetti fosse.<br \/>\nLe colonne del Partenone non furono costruite perfettamente a piombo perch&eacute;, se fossero state erette in quel modo, proprio per le distorsioni ottiche che la luce provocava sul candore del marmo, avrebbero dato l&#8217;impressione di divergere verso l&#8217;alto fornendo una sgradevole sensazione di instabilit&agrave;. Cos&igrave; furono progettate con gli assi convergenti.<br \/>\nNel Rinascimento Leonardo aveva scoperto che le ombre hanno colori ben leggibili, ma l&#8217;importanza che oggi viene attribuita alla questione dei complementari comincia con Goethe. I colori primari, come sappiamo, sono tre: rosso, giallo e blu; i colori secondari sono anch&#8217;essi tre e si ottengono mescolando a due a due i colori primari. Sicch&eacute;, mescolando giallo e rosso si ottiene l&#8217;arancione, col giallo e blu il verde e col rosso e blu il viola.<br \/>\nOgni colore primario &egrave; complementare (o antagonista) del colore risultante dalla mescolanza degli altri due: il rosso &egrave; complementare del verde, il giallo del viola e il blu dell&#8217;arancione. Accostando due colori complementari tra loro si ha il massimo risalto cromatico e, come esiste un&#8217;armonia dei colori puri, esiste anche un&#8217;armonia dei contrasti cromatici.<br \/>\nDopo &#8220;La teoria dei colori&#8221; di Goethe, Schopenhauer nel 1816 compose uno scritto &#8220;Sulla vista e sui colori&#8221; in difesa delle teorie scientifiche di Goethe, del quale era amico. In seguito, Eugene Chevreul, riassumendo i suoi studi e le scoperte di Young, Boyle e degli altri scienziati, scrisse nel 1838 il primo trattato sui contrasti cromatici. La tesi centrale era che i colori contigui si influenzano reciprocamente e, per questo motivo, sono in stretta relazione. Egli aveva osservato che ogni colore, visto da solo, era circondato da una debole aureola del suo complementare; cos&igrave;, ad esempio, una macchia rossa su fondo bianco sarebbe stata circondata dal verde. Molti pittori furono influenzati da quelle teorie e i risultati di tanti sforzi portarono a dare all&#8217;ombra un colore non pi&ugrave; neutro, come faceva Poussin, ma quello pi&ugrave; giusto, composto anche con il complementare del colore su cui &egrave; proiettata, come aveva intuito Constable.<br \/>\nInoltre, in presenza di molta luce, come accade nei Paesi mediterranei, le ombre vengono &#8220;illuminate&#8221; da una seconda sorgente luminosa proveniente dagli altri oggetti vicini alle ombre in esame, i quali, oltre a schiarirle, ne mutano il tono e le caricano di ulteriori e piacevoli vibrazioni. Fu proprio la scoperta di questa seconda fonte luminosa che affascin&ograve; molti artisti, tanto da spingerli a cercare al Sud le luci giuste. Il &#8220;pointillisme&#8221; di Seurat e il &#8220;divisionismo&#8221; di Previati erano collegati a tali studi e tendevano ad una esatta applicazione dell&#8217;influenza reciproca dei colori limitrofi.<br \/>\nIn poche parole, le ombre dipinte dopo Goethe erano, secondo alcuni, pi&ugrave; luminose delle luci dipinte prima. Comunque, Leonardo, cinque secoli or sono, scriveva: &#8220;Le ombre delle piante non son mai nere, perch&eacute;, dove l&#8217;aria penetra, non p&ograve; essere tenebre&#8221;; e ancora: &#8220;L&#8217;ombra partecipa sempre del color del suo obbietto&#8221;. &#8220;Noterai nel tuo ritrarre come infra le ombre son ombre insensibili d&#8217;oscurit&agrave;&#8221;. &#8220;In tutte le ombre c&#8217;&egrave; sempre dell&#8217;azzurro&#8221; (&ldquo;Pensieri sull&rsquo;universo&rdquo;).<br \/>\nQuindi, la conquista dell&#8217;atmosfera, da molti attribuita ai barbizonniers prima ancora che a Monet e compagni, non fu affatto una questione impostata e risolta in quegli anni; i primi tentativi cominciarono in realt&agrave; nel 1500 a Venezia, dopo che Leonardo vi soggiorn&ograve;. Giorgione, seguendo gli insegnamenti dell&#8217;artista toscano, ne imit&ograve; lo sfumato, contrariamente alle consuetudini degli altri pittori veneti. Molti suoi dipinti, infatti, mostrano le figure avvolte in un &#8220;flou&#8221; atmosferico che smaterializza i contorni immergendo volti e panneggi in una penombra, dalla quale emergono solo le luci con effetti del tutto nuovi e sorprendenti.<br \/>\nLa pittura di Michelangelo era fatta di colori secchi e duri, mentre quelli di Leonardo erano dolci e morbidi. E appunto nella pittura, che &egrave; pi&ugrave; che altro un&#8217;arte della visione, non potevano essere trascurati gli effetti cromatici prodotti dai vapori dell&#8217;aria nello studio del paesaggio. Sicch&eacute;, con la nascita della pittura en plein air, riemerge anche questo antico problema. La prospettiva aerea si occupa dei colori in lontananza tendenti all&#8217;azzurro, proprio per il velo dell&#8217;aria interposta: &#8220;In lunga distanzia tutte l&#8217;ombre delli vari colori appariscono d&#8217;una medesima oscurit&agrave;; li paesi [in lontananza] son pi&ugrave; azzurri di state che di verno&#8221; (&ldquo;Pensieri sull&rsquo;universo&rdquo;).<br \/>\nA Leonardo l&#8217;arte deve moltissimo. Nel suo &#8220;Trattato della pittura&#8221; il grande artista esamin&ograve; con geniale acutezza le nebbie, l&#8217;aria sottile, le atmosfere basse e dense, il pulviscolo umido dell&#8217;atmosfera che tutto avvolge e addolcisce in un manto misterioso. Le leggi della prospettiva lineare (ben diverse ovviamente da quelle della prospettiva aerea), furono studiate per la prima volta da Agatarco nel dipingere gli scenari delle tragedie di Eschilo.<br \/>\nComunque, dal 1830, con gli artisti abruzzesi in prima fila, furono realizzate molte importanti conquiste artistiche; quando arrivarono gli impressionisti Monet, Pissarro, Renoir, Degas, Sisley ed altri, tutto era gi&agrave; stato risolto.<br \/>\nwww.napoleonenicodemo.com<br \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>I primi pleinairisti, la scoperta della &#8220;luce mediterranea&#8221;, i pittori abruzzesi a Barbizon, la Scuola di Posillipo,le scoperte degli &#8220;Scienziati della luce&#8221; e la teoria dei colori complementari<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"","footnotes":""},"categories":[27],"tags":[49643,49646,49647,49644,49645],"class_list":["post-45332","post","type-post","status-publish","format-standard","hentry","category-arte-e-cultura","tag-artisti-abruzzesi-a-barbizon","tag-colori-complementari","tag-la-luce-mediterranea","tag-pittura-en-plein-air","tag-prospettiva-aerea"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>I colori delle ombre - Article Marketing<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/i-colori-delle-ombre-2\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"I colori delle ombre - Article Marketing\" \/>\n<meta property=\"og:description\" content=\"I primi pleinairisti, la scoperta della &quot;luce mediterranea&quot;, i pittori abruzzesi a Barbizon, la Scuola di Posillipo,le scoperte degli &quot;Scienziati della luce&quot; e la teoria dei colori complementari\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/i-colori-delle-ombre-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Article Marketing\" \/>\n<meta property=\"article:published_time\" content=\"2014-11-11T09:26:31+00:00\" \/>\n<meta name=\"author\" content=\"Redazione Comunicati Stampa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione Comunicati Stampa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/arte-e-cultura\\\/i-colori-delle-ombre-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/arte-e-cultura\\\/i-colori-delle-ombre-2\\\/\"},\"author\":{\"name\":\"Redazione Comunicati Stampa\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"headline\":\"I colori delle ombre\",\"datePublished\":\"2014-11-11T09:26:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/arte-e-cultura\\\/i-colori-delle-ombre-2\\\/\"},\"wordCount\":1870,\"commentCount\":0,\"keywords\":[\"Artisti abruzzesi a Barbizon\",\"colori complementari\",\"la luce mediterranea\",\"pittura en plein air\",\"prospettiva aerea\"],\"articleSection\":[\"Arte e cultura\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/arte-e-cultura\\\/i-colori-delle-ombre-2\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/arte-e-cultura\\\/i-colori-delle-ombre-2\\\/\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/arte-e-cultura\\\/i-colori-delle-ombre-2\\\/\",\"name\":\"I colori delle ombre - Article Marketing\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\"},\"datePublished\":\"2014-11-11T09:26:31+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/arte-e-cultura\\\/i-colori-delle-ombre-2\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/arte-e-cultura\\\/i-colori-delle-ombre-2\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/arte-e-cultura\\\/i-colori-delle-ombre-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"I colori delle ombre\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\",\"name\":\"Article Marketing\",\"description\":\"article marketing &amp; press release\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\",\"name\":\"Redazione Comunicati Stampa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"caption\":\"Redazione Comunicati Stampa\"},\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/author\\\/redazione-comunicati-stampa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"I colori delle ombre - Article Marketing","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/i-colori-delle-ombre-2\/","og_locale":"it_IT","og_type":"article","og_title":"I colori delle ombre - Article Marketing","og_description":"I primi pleinairisti, la scoperta della \"luce mediterranea\", i pittori abruzzesi a Barbizon, la Scuola di Posillipo,le scoperte degli \"Scienziati della luce\" e la teoria dei colori complementari","og_url":"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/i-colori-delle-ombre-2\/","og_site_name":"Article Marketing","article_published_time":"2014-11-11T09:26:31+00:00","author":"Redazione Comunicati Stampa","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione Comunicati Stampa","Tempo di lettura stimato":"9 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/i-colori-delle-ombre-2\/#article","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/i-colori-delle-ombre-2\/"},"author":{"name":"Redazione Comunicati Stampa","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"headline":"I colori delle ombre","datePublished":"2014-11-11T09:26:31+00:00","mainEntityOfPage":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/i-colori-delle-ombre-2\/"},"wordCount":1870,"commentCount":0,"keywords":["Artisti abruzzesi a Barbizon","colori complementari","la luce mediterranea","pittura en plein air","prospettiva aerea"],"articleSection":["Arte e cultura"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/i-colori-delle-ombre-2\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/i-colori-delle-ombre-2\/","url":"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/i-colori-delle-ombre-2\/","name":"I colori delle ombre - Article Marketing","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website"},"datePublished":"2014-11-11T09:26:31+00:00","author":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"breadcrumb":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/i-colori-delle-ombre-2\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/i-colori-delle-ombre-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/i-colori-delle-ombre-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.article-marketing.eu\/comunicati\/"},{"@type":"ListItem","position":2,"name":"I colori delle ombre"}]},{"@type":"WebSite","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website","url":"https:\/\/www.article-marketing.eu\/comunicati\/","name":"Article Marketing","description":"article marketing &amp; press release","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.article-marketing.eu\/comunicati\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017","name":"Redazione Comunicati Stampa","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","caption":"Redazione Comunicati Stampa"},"url":"https:\/\/www.article-marketing.eu\/comunicati\/author\/redazione-comunicati-stampa\/"}]}},"_links":{"self":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/45332","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/comments?post=45332"}],"version-history":[{"count":0,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/45332\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/media?parent=45332"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/categories?post=45332"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/tags?post=45332"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}