{"id":45413,"date":"2014-11-12T17:30:39","date_gmt":"2014-11-12T16:30:39","guid":{"rendered":"http:\/\/www.article-marketing.eu\/comunicati\/senza-categoria\/trasparenza-e-comodit%c3%a0-a%80-arcobaleno-adotta-la-soluzione-easydrive-di-fela\/"},"modified":"2020-08-10T01:03:12","modified_gmt":"2020-08-09T23:03:12","slug":"trasparenza-e-comodit%c3%a0-a%80-arcobaleno-adotta-la-soluzione-easydrive-di-fela","status":"publish","type":"post","link":"https:\/\/www.article-marketing.eu\/comunicati\/societa\/news-e-attualita\/trasparenza-e-comodit%c3%a0-a%80-arcobaleno-adotta-la-soluzione-easydrive-di-fela\/","title":{"rendered":"Trasparenza e comodit\u00e0 \u2013 Arcobaleno adotta la soluzione EasyDrive di FELA"},"content":{"rendered":"<p>La FELA Management AG (www.fela.ch), produttore di componenti elettroniche e soluzioni telematiche per la gestione del traffico con sede a Diessenhofen, Svizzera, ha sviluppato e implementato il sistema di ticketing all&rsquo;avanguardia, basato sulla soluzione EasyDrive, in uso presso il consorzio tariffario Arcobaleno (www.arcobaleno.ch). La comunit&agrave; tariffale Arcobaleno riunisce dodici aziende del trasporto pubblico del Canton Ticino e del Moesano (Circoli di Mesocco e Calanca). All&rsquo;interno del consorzio vige una tariffazione unificata per treni, autobus e battelli. Con l&rsquo;intento di uniformare anche il sistema commerciale, offrendo ai passeggeri una maggior trasparenza e comfort, il consorzio ha incaricato la FELA Management AG di produrre una soluzione completa per la produzione dei biglietti. FELA ha quindi fornito un sistema di backend ridondato, l&rsquo;infrastruttura per numerose autorimesse, oltre 400 distributori automatici di biglietti e 350 sistemi per la vendita dei biglietti sia allo sportello sia direttamente sul mezzo di trasporto, incluse casse adeguate. I sistemi sono dotati di lettori RFID al fine di consentire ai passeggeri di acquistare i biglietti comodamente e &ldquo;contactless&rdquo; con l&rsquo;innovativa carta APE (Arcobaleno-Prepaid-EasyDrive). La carta per pi&ugrave; corse di FELA, dotata di chip RFID, &egrave; utilizzabile in tutta la comunit&agrave; tariffale Arcobaleno.<\/p>\n<p>Sia i clienti del consorzio tariffario integrato sia le aziende di trasporto pubblico riunite da Arcobaleno beneficiano dell&rsquo;unificazione dei sistemi di frontend e backend. Gli autisti si avvalgono di una piattaforma contabile uniforme mediante un badge fornito a tutte le aziende, personalizzabile evidentemente per singolo autista. Oltre ad una chiara riduzione dei costi di acquisto e gestione dei materiali, in questo modo anche l&rsquo;esborso per la formazione degli utenti risulta notevolmente ridotto. Per semplificare ulteriormente la quotidiana erogazione dei servizi di trasporto, tutti i dispositivi frontend svolgono in modo autonomo tutte le funzioni necessarie. Solo all&rsquo;inizio della giornata e al rientro nell&rsquo;autorimessa ha luogo un trasferimento di dati via WLAN con i server del deposito e il relativo backend, ove le transazioni della giornata vengono aggregate e i dati di base come quelli tariffari sono gestiti centralmente. Infine, il sistema di backend fornito da FELA consente di effettuare uno scambio dei dati contabili con altri partner della rete di trasporti pubblici.<\/p>\n<p>NOTE per gli editori:<br \/>\n1) Il processo di uniformazione delle tariffe per la fruizione dei mezzi di trasporto, indipendentemente dal tipo di vettore impiegato per giungere da A a B, come avviato e attualmente condotto dal consorzio tariffario Arcobaleno, trova fondamento nella recente normativa svizzera che prevede l&rsquo;emissione di un solo biglietto con cui sia possibile impiegare qualsivoglia mezzo di trasporto necessario per giungere a destinazione, idealmente ovunque nel Paese. In Italia non &egrave; presente una normativa simile, sebbene numerose aziende operanti nel trasporto pubblico conoscano i benefici derivanti da tale uniformazione. Sebbene in forma embrionale, in Italia esistono esempi di consorzi tariffari sia su base regionale (cfr. Unico Campania), sia legati alle singole citt&agrave; o a specifici gruppi di vettori. Uniformando le tariffe a livello interregionale, sia i passeggeri, sia le stesse aziende presenti in tali consorzi avrebbero modo di avvalersi di numerosi benefici, tra cui una forte riduzione dell&rsquo;impatto economico per l&rsquo;acquisto di soluzioni telematiche per la commercializzazione dei biglietti, e, lato passeggero, una trasparenza e comodit&agrave; senza pari nella fruizione dei mezzi pubblici.<\/p>\n<p>2) Rispetto alla modalit&agrave; di pagamento &ldquo;contactless&rdquo; con carta di credito, introdotta di recente dagli istituti bancari e particolarmente trendy in Italia, la carta APE dotata di chip RFID riserva sia agli utenti sia ai vettori del consorzio numerosi benefici. Per i clienti la carta APE assicura la mobilit&agrave; di qualsiasi membro di un nucleo familiare, poich&eacute; pu&ograve; essere utilizzata da chiunque, cosa difficilmente realizzabile con una carta di credito. In secondo luogo, i dati degli utenti vengono trattati esclusivamente dal consorzio, non sono trasmessi a terze parti, come invece accadrebbe impiegando la carta di credito. Infine, perdere una carta APE comporta un danno minimo, perdere una carta di credito &egrave; invece un gran fastidio.<br \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>FELA fornisce una soluzione di ticketing completa con tecnologia RFID per il servizio di trasporto pubblico del consorzio tariffario Arcobaleno. La soluzione completa per la produzione dei biglietti, un sistema di backend ridondato, l\u2019infrastruttura IT per numerose autorimesse, oltre 400 distributori automatici di biglietti e 350 sistemi per la vendita dei biglietti sia allo sportello sia direttamente sul mezzo di trasporto, incluse casse adeguate, quanto implementato dall&#8217;integratore svizzero. <\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"","footnotes":""},"categories":[81],"tags":[],"class_list":["post-45413","post","type-post","status-publish","format-standard","hentry","category-news-e-attualita"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Trasparenza e comodit\u00e0 \u2013 Arcobaleno adotta la soluzione EasyDrive di FELA - Article Marketing<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.article-marketing.eu\/comunicati\/societa\/news-e-attualita\/trasparenza-e-comodit\u00e0-a?-arcobaleno-adotta-la-soluzione-easydrive-di-fela\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Trasparenza e comodit\u00e0 \u2013 Arcobaleno adotta la soluzione EasyDrive di FELA - Article Marketing\" \/>\n<meta property=\"og:description\" content=\"FELA fornisce una soluzione di ticketing completa con tecnologia RFID per il servizio di trasporto pubblico del consorzio tariffario Arcobaleno. La soluzione completa per la produzione dei biglietti, un sistema di backend ridondato, l\u2019infrastruttura IT per numerose autorimesse, oltre 400 distributori automatici di biglietti e 350 sistemi per la vendita dei biglietti sia allo sportello sia direttamente sul mezzo di trasporto, incluse casse adeguate, quanto implementato dall&#039;integratore svizzero.\" \/>\n<meta property=\"og:url\" content=\"\" \/>\n<meta property=\"og:site_name\" content=\"Article Marketing\" \/>\n<meta property=\"article:published_time\" content=\"2014-11-12T16:30:39+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-08-09T23:03:12+00:00\" \/>\n<meta name=\"author\" content=\"Redazione Comunicati Stampa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione Comunicati Stampa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/societa\\\/news-e-attualita\\\/trasparenza-e-comodit%c3%a0-a%80-arcobaleno-adotta-la-soluzione-easydrive-di-fela\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/societa\\\/news-e-attualita\\\/trasparenza-e-comodit%c3%a0-a%80-arcobaleno-adotta-la-soluzione-easydrive-di-fela\\\/\"},\"author\":{\"name\":\"Redazione Comunicati Stampa\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"headline\":\"Trasparenza e comodit\u00e0 \u2013 Arcobaleno adotta la soluzione EasyDrive di FELA\",\"datePublished\":\"2014-11-12T16:30:39+00:00\",\"dateModified\":\"2020-08-09T23:03:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/societa\\\/news-e-attualita\\\/trasparenza-e-comodit%c3%a0-a%80-arcobaleno-adotta-la-soluzione-easydrive-di-fela\\\/\"},\"wordCount\":692,\"commentCount\":0,\"articleSection\":[\"News e Attualit\u00e0\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/societa\\\/news-e-attualita\\\/trasparenza-e-comodit%c3%a0-a%80-arcobaleno-adotta-la-soluzione-easydrive-di-fela\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/societa\\\/news-e-attualita\\\/trasparenza-e-comodit%c3%a0-a%80-arcobaleno-adotta-la-soluzione-easydrive-di-fela\\\/\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/societa\\\/news-e-attualita\\\/trasparenza-e-comodit%c3%a0-a%80-arcobaleno-adotta-la-soluzione-easydrive-di-fela\\\/\",\"name\":\"Trasparenza e comodit\u00e0 \u2013 Arcobaleno adotta la soluzione EasyDrive di FELA - Article Marketing\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\"},\"datePublished\":\"2014-11-12T16:30:39+00:00\",\"dateModified\":\"2020-08-09T23:03:12+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/societa\\\/news-e-attualita\\\/trasparenza-e-comodit%c3%a0-a%80-arcobaleno-adotta-la-soluzione-easydrive-di-fela\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/societa\\\/news-e-attualita\\\/trasparenza-e-comodit%c3%a0-a%80-arcobaleno-adotta-la-soluzione-easydrive-di-fela\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/societa\\\/news-e-attualita\\\/trasparenza-e-comodit%c3%a0-a%80-arcobaleno-adotta-la-soluzione-easydrive-di-fela\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Trasparenza e comodit\u00e0 \u2013 Arcobaleno adotta la soluzione EasyDrive di FELA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\",\"name\":\"Article Marketing\",\"description\":\"article marketing &amp; press release\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\",\"name\":\"Redazione Comunicati Stampa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"caption\":\"Redazione Comunicati Stampa\"},\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/author\\\/redazione-comunicati-stampa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Trasparenza e comodit\u00e0 \u2013 Arcobaleno adotta la soluzione EasyDrive di FELA - Article Marketing","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.article-marketing.eu\/comunicati\/societa\/news-e-attualita\/trasparenza-e-comodit\u00e0-a?-arcobaleno-adotta-la-soluzione-easydrive-di-fela\/","og_locale":"it_IT","og_type":"article","og_title":"Trasparenza e comodit\u00e0 \u2013 Arcobaleno adotta la soluzione EasyDrive di FELA - Article Marketing","og_description":"FELA fornisce una soluzione di ticketing completa con tecnologia RFID per il servizio di trasporto pubblico del consorzio tariffario Arcobaleno. La soluzione completa per la produzione dei biglietti, un sistema di backend ridondato, l\u2019infrastruttura IT per numerose autorimesse, oltre 400 distributori automatici di biglietti e 350 sistemi per la vendita dei biglietti sia allo sportello sia direttamente sul mezzo di trasporto, incluse casse adeguate, quanto implementato dall'integratore svizzero.","og_url":"https:\/\/www.article-marketing.eu\/comunicati\/societa\/news-e-attualita\/trasparenza-e-comodit\u00e0-a?-arcobaleno-adotta-la-soluzione-easydrive-di-fela\/","og_site_name":"Article Marketing","article_published_time":"2014-11-12T16:30:39+00:00","article_modified_time":"2020-08-09T23:03:12+00:00","author":"Redazione Comunicati Stampa","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione Comunicati Stampa","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.article-marketing.eu\/comunicati\/societa\/news-e-attualita\/trasparenza-e-comodit%c3%a0-a%80-arcobaleno-adotta-la-soluzione-easydrive-di-fela\/#article","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/societa\/news-e-attualita\/trasparenza-e-comodit%c3%a0-a%80-arcobaleno-adotta-la-soluzione-easydrive-di-fela\/"},"author":{"name":"Redazione Comunicati Stampa","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"headline":"Trasparenza e comodit\u00e0 \u2013 Arcobaleno adotta la soluzione EasyDrive di FELA","datePublished":"2014-11-12T16:30:39+00:00","dateModified":"2020-08-09T23:03:12+00:00","mainEntityOfPage":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/societa\/news-e-attualita\/trasparenza-e-comodit%c3%a0-a%80-arcobaleno-adotta-la-soluzione-easydrive-di-fela\/"},"wordCount":692,"commentCount":0,"articleSection":["News e Attualit\u00e0"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.article-marketing.eu\/comunicati\/societa\/news-e-attualita\/trasparenza-e-comodit%c3%a0-a%80-arcobaleno-adotta-la-soluzione-easydrive-di-fela\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.article-marketing.eu\/comunicati\/societa\/news-e-attualita\/trasparenza-e-comodit%c3%a0-a%80-arcobaleno-adotta-la-soluzione-easydrive-di-fela\/","url":"https:\/\/www.article-marketing.eu\/comunicati\/societa\/news-e-attualita\/trasparenza-e-comodit%c3%a0-a%80-arcobaleno-adotta-la-soluzione-easydrive-di-fela\/","name":"Trasparenza e comodit\u00e0 \u2013 Arcobaleno adotta la soluzione EasyDrive di FELA - Article Marketing","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website"},"datePublished":"2014-11-12T16:30:39+00:00","dateModified":"2020-08-09T23:03:12+00:00","author":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"breadcrumb":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/societa\/news-e-attualita\/trasparenza-e-comodit%c3%a0-a%80-arcobaleno-adotta-la-soluzione-easydrive-di-fela\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.article-marketing.eu\/comunicati\/societa\/news-e-attualita\/trasparenza-e-comodit%c3%a0-a%80-arcobaleno-adotta-la-soluzione-easydrive-di-fela\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.article-marketing.eu\/comunicati\/societa\/news-e-attualita\/trasparenza-e-comodit%c3%a0-a%80-arcobaleno-adotta-la-soluzione-easydrive-di-fela\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.article-marketing.eu\/comunicati\/"},{"@type":"ListItem","position":2,"name":"Trasparenza e comodit\u00e0 \u2013 Arcobaleno adotta la soluzione EasyDrive di FELA"}]},{"@type":"WebSite","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website","url":"https:\/\/www.article-marketing.eu\/comunicati\/","name":"Article Marketing","description":"article marketing &amp; press release","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.article-marketing.eu\/comunicati\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017","name":"Redazione Comunicati Stampa","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","caption":"Redazione Comunicati Stampa"},"url":"https:\/\/www.article-marketing.eu\/comunicati\/author\/redazione-comunicati-stampa\/"}]}},"_links":{"self":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/45413","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/comments?post=45413"}],"version-history":[{"count":1,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/45413\/revisions"}],"predecessor-version":[{"id":66913,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/45413\/revisions\/66913"}],"wp:attachment":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/media?parent=45413"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/categories?post=45413"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/tags?post=45413"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}