{"id":45665,"date":"2014-12-04T12:06:57","date_gmt":"2014-12-04T11:06:57","guid":{"rendered":"http:\/\/www.article-marketing.eu\/comunicati\/senza-categoria\/dagli-stati-uniti-alla%252580%252599italia-cmc-certified-mental-coach\/"},"modified":"2018-10-25T23:09:46","modified_gmt":"2018-10-25T21:09:46","slug":"dagli-stati-uniti-alla%252580%252599italia-cmc-certified-mental-coach","status":"publish","type":"post","link":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/professionisti\/dagli-stati-uniti-alla%252580%252599italia-cmc-certified-mental-coach\/","title":{"rendered":"Dagli Stati Uniti all\u2019Italia: CMC Certified Mental Coach"},"content":{"rendered":"<p><strong style=\"mso-bidi-font-weight: normal;\"><em style=\"mso-bidi-font-style: normal;\">Robert Neff e CMC Italia <\/em><\/strong><br \/><strong>CMC Italia<\/strong> nasce dall&rsquo;incontro tra <strong style=\"mso-bidi-font-weight: normal;\">Robert Neff<\/strong>, uno tra i principali mental coach americani, e <strong style=\"mso-bidi-font-weight: normal;\">Alberto Biffi<\/strong>, allenatore e mental coach sportivo italiano. <strong style=\"mso-bidi-font-weight: normal;\">CMC Italia<\/strong> &egrave; una scuola italiana di formazione rivolta a professionisti che vogliono imparare nuove tecniche di mental coaching. <br \/>L&rsquo;obbiettivo di CMC Italia &egrave; quello di formare in soli due anni ben <strong style=\"mso-bidi-font-weight: normal;\">100 mental coach<\/strong> in tutto il territorio nazionale, diffondendo tecniche di coaching facili da apprendere e applicare per ottenere migliori risultati.<br \/><strong style=\"mso-bidi-font-weight: normal;\">Robert Neff<\/strong> &egrave; uno dei principali mental coach americani specializzati in ambito sportivo e <strong style=\"mso-bidi-font-weight: normal;\">ispiratore di CMC Italia.<\/strong><br \/>Negli anni &rsquo;70, quando era ancora un giocatore di tennis in Canada, inizia ad interessarsi al neo mondo del Mental Coaching e inizia a leggere tutto ci&ograve; di allora scritto sull&rsquo;argomento.<br \/>Nel corso della sua carriera sportiva si presentano una serie di occasioni durante le quali metter&agrave; in pratica tecniche di Mental Coaching ricavate dalle sue letture, riuscendo a <strong style=\"mso-bidi-font-weight: normal;\">migliorare la propria performance e ottenendo risultati vincenti<\/strong>. Tuttavia non esistevano ancora scuole o professionisti di riferimento che gli indicassero una metodologia per l&rsquo;apprendimento e l&rsquo;applicazione di tecniche di Mental coaching: cos&igrave; nel corso degli anni Robert Neff <strong style=\"mso-bidi-font-weight: normal;\">ha sviluppato un vero e proprio metodo di coaching<\/strong> fino a fondare <strong style=\"mso-bidi-font-weight: normal;\">Mental Inc<\/strong>, scuola americana di mental coaching che ha sviluppato innovative metodologie di Mental training, riconosciute dalle principali universit&agrave; americane e applicate con successo su campioni sportivi di alto livello. Nel 2012 riconosce la certificazione di Mental Coach ad Alberto Biffi e nel 2013 &egrave; <strong style=\"mso-bidi-font-weight: normal;\">promotore della nascita di CMC Italia. <\/strong><br \/>Laureato all&rsquo;Universit&agrave; del Michigan in psicologia sportiva, dal 2004 &egrave; anche psicologo della squadra olimpica americana e guru del mental coach riconosciuto in tutti gli Stati Uniti. <\/p>\n<p><strong style=\"mso-bidi-font-weight: normal;\"><em style=\"mso-bidi-font-style: normal;\">Alberto Biffi: fondatore e responsabile di CMC Italia<\/em><\/strong><br \/><strong style=\"mso-bidi-font-weight: normal;\">Alberto Biffi<\/strong> &egrave; allenatore, mental coach sportivo e <strong style=\"mso-bidi-font-weight: normal;\">primo mental trainer italiano riconosciuto e certificato da Robert Neff<\/strong>.<br \/>Da oltre 20 anni Alberto Biffi &egrave; un allenatore di pallavolo <strong style=\"mso-bidi-font-weight: normal;\">FIPAV<\/strong>, sia maschile che femminile.<br \/>In numerosi anni come allenatore Alberto Biffi, insieme all&rsquo;attenzione per la tecnica, ha sempre tenuto conto dell&rsquo;<strong style=\"mso-bidi-font-weight: normal;\">aspetto psicologico <\/strong>come fattore determinante per l&rsquo;esito della performance sportiva. <br \/>Si avvicina molto presto al mondo del Mental Coaching attraverso letture personali e partecipazioni ad alcuni corsi dedicati, finch&eacute; nel 2012 decide di affidare la sua preparazione in Mental coaching al guru americano Robert Neff. Un anno dopo <strong style=\"mso-bidi-font-weight: normal;\">fonda CMC Italia<\/strong>.<br \/>Alberto Biffi &egrave; tutt&rsquo;ora impegnato nell&rsquo;applicare con successo e trasmettere tecniche di Mental Coaching come Sport &amp; Business Coach. <br \/><strong style=\"mso-bidi-font-weight: normal;\"><em style=\"mso-bidi-font-style: normal;\"> <\/em><\/strong><br \/><strong style=\"mso-bidi-font-weight: normal;\"><em style=\"mso-bidi-font-style: normal;\">Il Metodo CMC Italia<\/em><\/strong><br \/>Il metodo di CMC Italia si contraddistingue per un taglio <strong style=\"mso-bidi-font-weight: normal;\">pratico ed esperienziale<\/strong>: gli utenti vengono seguiti da trainer esperti che gli trasmetteranno delle tecniche da applicare su se stessi e sugli altri con benefici immediati.<br \/>Il servizio personalizzato, l&rsquo;esperienza, la capacit&agrave; di ascoltare, insieme a trasparenza e coinvolgimento fanno di CMC Italia una <strong style=\"mso-bidi-font-weight: normal;\">scuola di formazione efficace e vincente<\/strong>.<br \/>Migliorare se stessi e gli altri per rendere il mondo un luogo migliore con entusiasmo e passione sono elementi essenziali nella visione dei trainer di CMC Italia.<\/p>\n<p>CMC Italia si rivolge non solo a professionisti sportivi, manager, imprenditori ma anche a tutti gli appassionati che vogliono aiutare gli altri a migliorarsi grazie alle tecniche di Mental Coaching.<br \/>Inoltre grazie ai moderni servizi di video conferenza &egrave; possibile seguire un corso di Mental Coaching a tutti gli effetti direttamente dal proprio ufficio o dalla propria casa, in modo pratico, veloce e ad un prezzo accessibile.<\/p>\n<p>I servizi di formazione offerti da CMC Italia sono importanti non solo per arricchire e migliorare la propria professione ma anche per una crescita personale e un miglioramento della prioria vita e quella di altre persone.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Scopri come diventare un mental coach certificate grazie a CMC Italia.<br \/>CMC Italia si rivolge non solo a professionisti sportivi, manager, imprenditori ma anche a tutti gli appassionati che vogliono aiutare gli altri a migliorarsi grazie alle tecniche di Mental Coaching.<br \/>Inoltre grazie ai moderni servizi di video conferenza \u00e8 possibile seguire un corso di Mental Coaching a tutti gli effetti direttamente dal proprio ufficio o dalla propria casa, in modo pratico, veloce e ad un prezzo accessibile.<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"","footnotes":""},"categories":[429],"tags":[49799],"class_list":["post-45665","post","type-post","status-publish","format-standard","hentry","category-professionisti","tag-cmc-italia"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Dagli Stati Uniti all\u2019Italia: CMC Certified Mental Coach - Article Marketing<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/professionisti\/dagli-stati-uniti-alla%2580%2599italia-cmc-certified-mental-coach\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dagli Stati Uniti all\u2019Italia: CMC Certified Mental Coach - Article Marketing\" \/>\n<meta property=\"og:description\" content=\"Scopri come diventare un mental coach certificate grazie a CMC Italia.CMC Italia si rivolge non solo a professionisti sportivi, manager, imprenditori ma anche a tutti gli appassionati che vogliono aiutare gli altri a migliorarsi grazie alle tecniche di Mental Coaching.Inoltre grazie ai moderni servizi di video conferenza \u00e8 possibile seguire un corso di Mental Coaching a tutti gli effetti direttamente dal proprio ufficio o dalla propria casa, in modo pratico, veloce e ad un prezzo accessibile.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/professionisti\/dagli-stati-uniti-alla%2580%2599italia-cmc-certified-mental-coach\/\" \/>\n<meta property=\"og:site_name\" content=\"Article Marketing\" \/>\n<meta property=\"article:published_time\" content=\"2014-12-04T11:06:57+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-10-25T21:09:46+00:00\" \/>\n<meta name=\"author\" content=\"Redazione Comunicati Stampa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione Comunicati Stampa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/economia-e-lavoro\\\/professionisti\\\/dagli-stati-uniti-alla%252580%252599italia-cmc-certified-mental-coach\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/economia-e-lavoro\\\/professionisti\\\/dagli-stati-uniti-alla%252580%252599italia-cmc-certified-mental-coach\\\/\"},\"author\":{\"name\":\"Redazione Comunicati Stampa\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"headline\":\"Dagli Stati Uniti all\u2019Italia: CMC Certified Mental Coach\",\"datePublished\":\"2014-12-04T11:06:57+00:00\",\"dateModified\":\"2018-10-25T21:09:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/economia-e-lavoro\\\/professionisti\\\/dagli-stati-uniti-alla%252580%252599italia-cmc-certified-mental-coach\\\/\"},\"wordCount\":642,\"commentCount\":0,\"keywords\":[\"cmc italia\"],\"articleSection\":[\"Professionisti\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/economia-e-lavoro\\\/professionisti\\\/dagli-stati-uniti-alla%252580%252599italia-cmc-certified-mental-coach\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/economia-e-lavoro\\\/professionisti\\\/dagli-stati-uniti-alla%252580%252599italia-cmc-certified-mental-coach\\\/\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/economia-e-lavoro\\\/professionisti\\\/dagli-stati-uniti-alla%252580%252599italia-cmc-certified-mental-coach\\\/\",\"name\":\"Dagli Stati Uniti all\u2019Italia: CMC Certified Mental Coach - Article Marketing\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\"},\"datePublished\":\"2014-12-04T11:06:57+00:00\",\"dateModified\":\"2018-10-25T21:09:46+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/economia-e-lavoro\\\/professionisti\\\/dagli-stati-uniti-alla%252580%252599italia-cmc-certified-mental-coach\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/economia-e-lavoro\\\/professionisti\\\/dagli-stati-uniti-alla%252580%252599italia-cmc-certified-mental-coach\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/economia-e-lavoro\\\/professionisti\\\/dagli-stati-uniti-alla%252580%252599italia-cmc-certified-mental-coach\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Dagli Stati Uniti all\u2019Italia: CMC Certified Mental Coach\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\",\"name\":\"Article Marketing\",\"description\":\"article marketing &amp; press release\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\",\"name\":\"Redazione Comunicati Stampa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"caption\":\"Redazione Comunicati Stampa\"},\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/author\\\/redazione-comunicati-stampa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dagli Stati Uniti all\u2019Italia: CMC Certified Mental Coach - Article Marketing","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/professionisti\/dagli-stati-uniti-alla%2580%2599italia-cmc-certified-mental-coach\/","og_locale":"it_IT","og_type":"article","og_title":"Dagli Stati Uniti all\u2019Italia: CMC Certified Mental Coach - Article Marketing","og_description":"Scopri come diventare un mental coach certificate grazie a CMC Italia.CMC Italia si rivolge non solo a professionisti sportivi, manager, imprenditori ma anche a tutti gli appassionati che vogliono aiutare gli altri a migliorarsi grazie alle tecniche di Mental Coaching.Inoltre grazie ai moderni servizi di video conferenza \u00e8 possibile seguire un corso di Mental Coaching a tutti gli effetti direttamente dal proprio ufficio o dalla propria casa, in modo pratico, veloce e ad un prezzo accessibile.","og_url":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/professionisti\/dagli-stati-uniti-alla%2580%2599italia-cmc-certified-mental-coach\/","og_site_name":"Article Marketing","article_published_time":"2014-12-04T11:06:57+00:00","article_modified_time":"2018-10-25T21:09:46+00:00","author":"Redazione Comunicati Stampa","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione Comunicati Stampa","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/professionisti\/dagli-stati-uniti-alla%252580%252599italia-cmc-certified-mental-coach\/#article","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/professionisti\/dagli-stati-uniti-alla%252580%252599italia-cmc-certified-mental-coach\/"},"author":{"name":"Redazione Comunicati Stampa","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"headline":"Dagli Stati Uniti all\u2019Italia: CMC Certified Mental Coach","datePublished":"2014-12-04T11:06:57+00:00","dateModified":"2018-10-25T21:09:46+00:00","mainEntityOfPage":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/professionisti\/dagli-stati-uniti-alla%252580%252599italia-cmc-certified-mental-coach\/"},"wordCount":642,"commentCount":0,"keywords":["cmc italia"],"articleSection":["Professionisti"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/professionisti\/dagli-stati-uniti-alla%252580%252599italia-cmc-certified-mental-coach\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/professionisti\/dagli-stati-uniti-alla%252580%252599italia-cmc-certified-mental-coach\/","url":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/professionisti\/dagli-stati-uniti-alla%252580%252599italia-cmc-certified-mental-coach\/","name":"Dagli Stati Uniti all\u2019Italia: CMC Certified Mental Coach - Article Marketing","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website"},"datePublished":"2014-12-04T11:06:57+00:00","dateModified":"2018-10-25T21:09:46+00:00","author":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"breadcrumb":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/professionisti\/dagli-stati-uniti-alla%252580%252599italia-cmc-certified-mental-coach\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/professionisti\/dagli-stati-uniti-alla%252580%252599italia-cmc-certified-mental-coach\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/professionisti\/dagli-stati-uniti-alla%252580%252599italia-cmc-certified-mental-coach\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.article-marketing.eu\/comunicati\/"},{"@type":"ListItem","position":2,"name":"Dagli Stati Uniti all\u2019Italia: CMC Certified Mental Coach"}]},{"@type":"WebSite","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website","url":"https:\/\/www.article-marketing.eu\/comunicati\/","name":"Article Marketing","description":"article marketing &amp; press release","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.article-marketing.eu\/comunicati\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017","name":"Redazione Comunicati Stampa","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","caption":"Redazione Comunicati Stampa"},"url":"https:\/\/www.article-marketing.eu\/comunicati\/author\/redazione-comunicati-stampa\/"}]}},"_links":{"self":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/45665","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/comments?post=45665"}],"version-history":[{"count":1,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/45665\/revisions"}],"predecessor-version":[{"id":64372,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/45665\/revisions\/64372"}],"wp:attachment":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/media?parent=45665"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/categories?post=45665"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/tags?post=45665"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}